{"id":4072,"date":"2014-02-14T02:15:25","date_gmt":"2014-02-14T03:15:25","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=4072"},"modified":"2014-02-14T02:15:25","modified_gmt":"2014-02-14T03:15:25","slug":"calle-de-la-muerte-y-la-vida","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/","title":{"rendered":"Calle de la muerte y la vida"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-large wp-image-4073\" alt=\"cartel calle\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/DSC_0136-650x613.jpg\" width=\"640\" height=\"603\" \/>Galer\u00eda365 es una recopilaci\u00f3n de las im\u00e1genes m\u00e1s curiosas y destacadas de la actualidad mundial, junto a una colecci\u00f3n de fotograf\u00edas de nuestro medio, queda prohibida la descarga de las mismas, siendo sus leg\u00edtimos propietarios El Digital de Asturias \u2013 Magazine 365, las Agencias de noticias BercodiPress, EFE, DPA, Xanina y nuestros colaboradores, todas y cada una de ellas tienen sus respectivos derechos de autor.<\/p>\n<p>Est\u00e1 permitido compartirlas en redes sociales, pero no su descarga, venta, redistribuci\u00f3n o copia, para m\u00e1s informaci\u00f3n consultar nuestro aviso Legal.<\/p>\n<p>Fotograf\u00eda: Xanina<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Galer\u00eda365 es una recopilaci\u00f3n de las im\u00e1genes m\u00e1s curiosas y destacadas de la actualidad mundial, junto a una colecci\u00f3n de fotograf\u00edas de nuestro medio, queda prohibida la descarga de las mismas, siendo sus leg\u00edtimos propietarios El Digital de Asturias \u2013 Magazine 365, las Agencias de noticias BercodiPress, EFE, DPA, Xanina y nuestros colaboradores, todas y<\/p>\n","protected":false},"author":1,"featured_media":4073,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[199],"tags":[],"class_list":["post-4072","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mundo-curioso"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Galer\u00eda365 es una recopilaci\u00f3n de las im\u00e1genes m\u00e1s curiosas y destacadas de la actualidad mundial, junto a una colecci\u00f3n de fotograf\u00edas de nuestro medio, queda prohibida la descarga de las mismas, siendo sus leg\u00edtimos propietarios El Digital de Asturias \u2013 Magazine 365, las Agencias de noticias BercodiPress, EFE, DPA, Xanina y nuestros colaboradores, todas y\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"mundo curioso\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Calle de la muerte y la vida | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Galer\u00eda365 es una recopilaci\u00f3n de las im\u00e1genes m\u00e1s curiosas y destacadas de la actualidad mundial, junto a una colecci\u00f3n de fotograf\u00edas de nuestro medio, queda prohibida la descarga de las mismas, siendo sus leg\u00edtimos propietarios El Digital de Asturias \u2013 Magazine 365, las Agencias de noticias BercodiPress, EFE, DPA, Xanina y nuestros colaboradores, todas y\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/DSC_0136.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/DSC_0136.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1363\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1287\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-14T03:15:25+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-14T03:15:25+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Calle de la muerte y la vida | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Galer\u00eda365 es una recopilaci\u00f3n de las im\u00e1genes m\u00e1s curiosas y destacadas de la actualidad mundial, junto a una colecci\u00f3n de fotograf\u00edas de nuestro medio, queda prohibida la descarga de las mismas, siendo sus leg\u00edtimos propietarios El Digital de Asturias \u2013 Magazine 365, las Agencias de noticias BercodiPress, EFE, DPA, Xanina y nuestros colaboradores, todas y\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/DSC_0136.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/calle-de-la-muerte-y-la-vida\\\/#article\",\"name\":\"Calle de la muerte y la vida | El Digital de Asturias\",\"headline\":\"Calle de la muerte y la vida\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/DSC_0136.jpg\",\"width\":1363,\"height\":1287},\"datePublished\":\"2014-02-14T02:15:25+01:00\",\"dateModified\":\"2014-02-14T02:15:25+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/calle-de-la-muerte-y-la-vida\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/calle-de-la-muerte-y-la-vida\\\/#webpage\"},\"articleSection\":\"Mundo Curioso\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/calle-de-la-muerte-y-la-vida\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/mundo-curioso\\\/#listItem\",\"name\":\"Mundo Curioso\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/mundo-curioso\\\/#listItem\",\"position\":2,\"name\":\"Mundo Curioso\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/mundo-curioso\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/calle-de-la-muerte-y-la-vida\\\/#listItem\",\"name\":\"Calle de la muerte y la vida\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/calle-de-la-muerte-y-la-vida\\\/#listItem\",\"position\":3,\"name\":\"Calle de la muerte y la vida\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/mundo-curioso\\\/#listItem\",\"name\":\"Mundo Curioso\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/calle-de-la-muerte-y-la-vida\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/calle-de-la-muerte-y-la-vida\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/calle-de-la-muerte-y-la-vida\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/calle-de-la-muerte-y-la-vida\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/calle-de-la-muerte-y-la-vida\\\/\",\"name\":\"Calle de la muerte y la vida | El Digital de Asturias\",\"description\":\"Galer\\u00eda365 es una recopilaci\\u00f3n de las im\\u00e1genes m\\u00e1s curiosas y destacadas de la actualidad mundial, junto a una colecci\\u00f3n de fotograf\\u00edas de nuestro medio, queda prohibida la descarga de las mismas, siendo sus leg\\u00edtimos propietarios El Digital de Asturias \\u2013 Magazine 365, las Agencias de noticias BercodiPress, EFE, DPA, Xanina y nuestros colaboradores, todas y\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/calle-de-la-muerte-y-la-vida\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/DSC_0136.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/calle-de-la-muerte-y-la-vida\\\/#mainImage\",\"width\":1363,\"height\":1287},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/calle-de-la-muerte-y-la-vida\\\/#mainImage\"},\"datePublished\":\"2014-02-14T02:15:25+01:00\",\"dateModified\":\"2014-02-14T02:15:25+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Calle de la muerte y la vida | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Calle de la muerte y la vida | El Digital de Asturias","description":"Galer\u00eda365 es una recopilaci\u00f3n de las im\u00e1genes m\u00e1s curiosas y destacadas de la actualidad mundial, junto a una colecci\u00f3n de fotograf\u00edas de nuestro medio, queda prohibida la descarga de las mismas, siendo sus leg\u00edtimos propietarios El Digital de Asturias \u2013 Magazine 365, las Agencias de noticias BercodiPress, EFE, DPA, Xanina y nuestros colaboradores, todas y","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/","robots":"max-image-preview:large","keywords":"mundo curioso","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/#article","name":"Calle de la muerte y la vida | El Digital de Asturias","headline":"Calle de la muerte y la vida","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/DSC_0136.jpg","width":1363,"height":1287},"datePublished":"2014-02-14T02:15:25+01:00","dateModified":"2014-02-14T02:15:25+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/#webpage"},"articleSection":"Mundo Curioso"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/mundo-curioso\/#listItem","name":"Mundo Curioso"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/mundo-curioso\/#listItem","position":2,"name":"Mundo Curioso","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/mundo-curioso\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/#listItem","name":"Calle de la muerte y la vida"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/#listItem","position":3,"name":"Calle de la muerte y la vida","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/mundo-curioso\/#listItem","name":"Mundo Curioso"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/","name":"Calle de la muerte y la vida | El Digital de Asturias","description":"Galer\u00eda365 es una recopilaci\u00f3n de las im\u00e1genes m\u00e1s curiosas y destacadas de la actualidad mundial, junto a una colecci\u00f3n de fotograf\u00edas de nuestro medio, queda prohibida la descarga de las mismas, siendo sus leg\u00edtimos propietarios El Digital de Asturias \u2013 Magazine 365, las Agencias de noticias BercodiPress, EFE, DPA, Xanina y nuestros colaboradores, todas y","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/DSC_0136.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/#mainImage","width":1363,"height":1287},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/#mainImage"},"datePublished":"2014-02-14T02:15:25+01:00","dateModified":"2014-02-14T02:15:25+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Calle de la muerte y la vida | El Digital de Asturias","og:description":"Galer\u00eda365 es una recopilaci\u00f3n de las im\u00e1genes m\u00e1s curiosas y destacadas de la actualidad mundial, junto a una colecci\u00f3n de fotograf\u00edas de nuestro medio, queda prohibida la descarga de las mismas, siendo sus leg\u00edtimos propietarios El Digital de Asturias \u2013 Magazine 365, las Agencias de noticias BercodiPress, EFE, DPA, Xanina y nuestros colaboradores, todas y","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/DSC_0136.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/DSC_0136.jpg","og:image:width":1363,"og:image:height":1287,"article:published_time":"2014-02-14T03:15:25+00:00","article:modified_time":"2014-02-14T03:15:25+00:00","twitter:card":"summary_large_image","twitter:title":"Calle de la muerte y la vida | El Digital de Asturias","twitter:description":"Galer\u00eda365 es una recopilaci\u00f3n de las im\u00e1genes m\u00e1s curiosas y destacadas de la actualidad mundial, junto a una colecci\u00f3n de fotograf\u00edas de nuestro medio, queda prohibida la descarga de las mismas, siendo sus leg\u00edtimos propietarios El Digital de Asturias \u2013 Magazine 365, las Agencias de noticias BercodiPress, EFE, DPA, Xanina y nuestros colaboradores, todas y","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/DSC_0136.jpg"},"aioseo_meta_data":{"post_id":"4072","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 11:30:20","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:52:38","updated":"2026-05-15 11:30:20"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/mundo-curioso\/\" title=\"Mundo Curioso\">Mundo Curioso<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/\" title=\"Calle de la muerte y la vida\">Calle de la muerte y la vida<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Mundo Curioso","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/mundo-curioso\/"},{"label":"Calle de la muerte y la vida","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/calle-de-la-muerte-y-la-vida\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/4072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=4072"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/4072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/4073"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=4072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=4072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=4072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}