{"id":3946,"date":"2014-02-13T02:52:31","date_gmt":"2014-02-13T03:52:31","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=3946"},"modified":"2014-02-13T02:52:31","modified_gmt":"2014-02-13T03:52:31","slug":"recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/","title":{"rendered":"Recuperar puntos del carn\u00e9 requerir\u00e1 una prueba en Tr\u00e1fico adem\u00e1s del curso"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3947\" alt=\"5938211w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5938211w-360x239.jpg\" width=\"360\" height=\"239\" \/>Madrid, 12 feb (EFE).- Los conductores que quieran recuperar parcialmente puntos de su carn\u00e9 no s\u00f3lo tendr\u00e1n que realizar un curso de sensibilizaci\u00f3n y reeducaci\u00f3n vial, sino que adem\u00e1s deber\u00e1n superar una prueba en la Jefatura Provincial de Tr\u00e1fico correspondiente.<\/p>\n<p>As\u00ed ser\u00e1 si prospera la enmienda que en este sentido ha presentado el grupo popular en el Senado a la reforma de la Ley de Tr\u00e1fico, que comienza a debatirse en la C\u00e1mara Alta tras haber superado el tr\u00e1mite del Congreso.<\/p>\n<p>Hasta ahora, para la recuperaci\u00f3n parcial de puntos hasta un m\u00e1ximo de seis, los conductores deben acudir a un curso de sensibilizaci\u00f3n que imparten determinados centros, que despu\u00e9s certifican su superaci\u00f3n e inmediatamente Tr\u00e1fico los incorpora a su saldo.<\/p>\n<p>Sin embargo, el PP no quiere que el tr\u00e1mite quede ah\u00ed y ha propuesto que tras ese curso el conductor pase una prueba espec\u00edfica en la Jefatura Provincial de Tr\u00e1fico que regular\u00e1 el Ministerio del Interior, aunque distinta a la que se exige para la obtenci\u00f3n del permiso.<\/p>\n<p>El PP ha presentado tambi\u00e9n otra enmienda para abrir a m\u00e1s centros la posibilidad de impartir los cursos de recuperaci\u00f3n, hasta ahora limitados a un n\u00famero concreto mediante la f\u00f3rmula de concesi\u00f3n.<\/p>\n<p>Para el PP, el sistema actual supone una restricci\u00f3n a la libre competencia, por lo que considera oportuna pasar del actual r\u00e9gimen de concesi\u00f3n a uno de autorizaci\u00f3n previa que abrir\u00e1 a m\u00e1s centros los cursos, lo que \u00abno puede suponer una merma en la calidad\u00bb de los mismos.<\/p>\n<p>Otra de las enmiendas de los populares tiene como objetivo facilitar el cobro de las multas impuestas a conductores extranjeros en Espa\u00f1a y, para ello, incorpora la directiva de la Uni\u00f3n Europea sobre el intercambio transfronterizo de informaci\u00f3n relativo a infracciones de tr\u00e1fico.<\/p>\n<p>Durante el tr\u00e1mite del Congreso, los grupos llegaron a un acuerdo para modificar las multas por consumo de alcohol al volante. Aunque el texto inicial las cuantificaba en 1.000 euros, finalmente se acord\u00f3 rebajar a 500 y que solo fuera el doble de esta cifra cuando la tasa duplicara la permitida o el conductor fuera reincidente en un periodo de un a\u00f1o.<\/p>\n<p>Como no qued\u00f3 claro si este criterio se iba a aplicar al consumo de drogas, el PP ha querido concretarlo y a trav\u00e9s de otra enmienda que especifica que conducir bajo los efectos de estupefacientes estar\u00e1 multado con 1.000 euros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 12 feb (EFE).- Los conductores que quieran recuperar parcialmente puntos de su carn\u00e9 no s\u00f3lo tendr\u00e1n que realizar un curso de sensibilizaci\u00f3n y reeducaci\u00f3n vial, sino que adem\u00e1s deber\u00e1n superar una prueba en la Jefatura Provincial de Tr\u00e1fico correspondiente. As\u00ed ser\u00e1 si prospera la enmienda que en este sentido ha presentado el grupo popular<\/p>\n","protected":false},"author":1,"featured_media":3947,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-3946","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 12 feb (EFE).- Los conductores que quieran recuperar parcialmente puntos de su carn\u00e9 no s\u00f3lo tendr\u00e1n que realizar un curso de sensibilizaci\u00f3n y reeducaci\u00f3n vial, sino que adem\u00e1s deber\u00e1n superar una prueba en la Jefatura Provincial de Tr\u00e1fico correspondiente. As\u00ed ser\u00e1 si prospera la enmienda que en este sentido ha presentado el grupo popular\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Recuperar puntos del carn\u00e9 requerir\u00e1 una prueba en Tr\u00e1fico adem\u00e1s del curso | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 12 feb (EFE).- Los conductores que quieran recuperar parcialmente puntos de su carn\u00e9 no s\u00f3lo tendr\u00e1n que realizar un curso de sensibilizaci\u00f3n y reeducaci\u00f3n vial, sino que adem\u00e1s deber\u00e1n superar una prueba en la Jefatura Provincial de Tr\u00e1fico correspondiente. As\u00ed ser\u00e1 si prospera la enmienda que en este sentido ha presentado el grupo popular\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5938211w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5938211w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-13T03:52:31+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-13T03:52:31+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Recuperar puntos del carn\u00e9 requerir\u00e1 una prueba en Tr\u00e1fico adem\u00e1s del curso | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 12 feb (EFE).- Los conductores que quieran recuperar parcialmente puntos de su carn\u00e9 no s\u00f3lo tendr\u00e1n que realizar un curso de sensibilizaci\u00f3n y reeducaci\u00f3n vial, sino que adem\u00e1s deber\u00e1n superar una prueba en la Jefatura Provincial de Tr\u00e1fico correspondiente. As\u00ed ser\u00e1 si prospera la enmienda que en este sentido ha presentado el grupo popular\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5938211w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\\\/#article\",\"name\":\"Recuperar puntos del carn\\u00e9 requerir\\u00e1 una prueba en Tr\\u00e1fico adem\\u00e1s del curso | El Digital de Asturias\",\"headline\":\"Recuperar puntos del carn\\u00e9 requerir\\u00e1 una prueba en Tr\\u00e1fico adem\\u00e1s del curso\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5938211w.jpg\",\"width\":800,\"height\":533},\"datePublished\":\"2014-02-13T02:52:31+01:00\",\"dateModified\":\"2014-02-13T02:52:31+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\\\/#listItem\",\"name\":\"Recuperar puntos del carn\\u00e9 requerir\\u00e1 una prueba en Tr\\u00e1fico adem\\u00e1s del curso\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\\\/#listItem\",\"position\":3,\"name\":\"Recuperar puntos del carn\\u00e9 requerir\\u00e1 una prueba en Tr\\u00e1fico adem\\u00e1s del curso\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\\\/\",\"name\":\"Recuperar puntos del carn\\u00e9 requerir\\u00e1 una prueba en Tr\\u00e1fico adem\\u00e1s del curso | El Digital de Asturias\",\"description\":\"Madrid, 12 feb (EFE).- Los conductores que quieran recuperar parcialmente puntos de su carn\\u00e9 no s\\u00f3lo tendr\\u00e1n que realizar un curso de sensibilizaci\\u00f3n y reeducaci\\u00f3n vial, sino que adem\\u00e1s deber\\u00e1n superar una prueba en la Jefatura Provincial de Tr\\u00e1fico correspondiente. As\\u00ed ser\\u00e1 si prospera la enmienda que en este sentido ha presentado el grupo popular\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5938211w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\\\/#mainImage\",\"width\":800,\"height\":533},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\\\/#mainImage\"},\"datePublished\":\"2014-02-13T02:52:31+01:00\",\"dateModified\":\"2014-02-13T02:52:31+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Recuperar puntos del carn\u00e9 requerir\u00e1 una prueba en Tr\u00e1fico adem\u00e1s del curso | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Recuperar puntos del carn\u00e9 requerir\u00e1 una prueba en Tr\u00e1fico adem\u00e1s del curso | El Digital de Asturias","description":"Madrid, 12 feb (EFE).- Los conductores que quieran recuperar parcialmente puntos de su carn\u00e9 no s\u00f3lo tendr\u00e1n que realizar un curso de sensibilizaci\u00f3n y reeducaci\u00f3n vial, sino que adem\u00e1s deber\u00e1n superar una prueba en la Jefatura Provincial de Tr\u00e1fico correspondiente. As\u00ed ser\u00e1 si prospera la enmienda que en este sentido ha presentado el grupo popular","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/#article","name":"Recuperar puntos del carn\u00e9 requerir\u00e1 una prueba en Tr\u00e1fico adem\u00e1s del curso | El Digital de Asturias","headline":"Recuperar puntos del carn\u00e9 requerir\u00e1 una prueba en Tr\u00e1fico adem\u00e1s del curso","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5938211w.jpg","width":800,"height":533},"datePublished":"2014-02-13T02:52:31+01:00","dateModified":"2014-02-13T02:52:31+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/#listItem","name":"Recuperar puntos del carn\u00e9 requerir\u00e1 una prueba en Tr\u00e1fico adem\u00e1s del curso"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/#listItem","position":3,"name":"Recuperar puntos del carn\u00e9 requerir\u00e1 una prueba en Tr\u00e1fico adem\u00e1s del curso","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/","name":"Recuperar puntos del carn\u00e9 requerir\u00e1 una prueba en Tr\u00e1fico adem\u00e1s del curso | El Digital de Asturias","description":"Madrid, 12 feb (EFE).- Los conductores que quieran recuperar parcialmente puntos de su carn\u00e9 no s\u00f3lo tendr\u00e1n que realizar un curso de sensibilizaci\u00f3n y reeducaci\u00f3n vial, sino que adem\u00e1s deber\u00e1n superar una prueba en la Jefatura Provincial de Tr\u00e1fico correspondiente. As\u00ed ser\u00e1 si prospera la enmienda que en este sentido ha presentado el grupo popular","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5938211w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/#mainImage","width":800,"height":533},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/#mainImage"},"datePublished":"2014-02-13T02:52:31+01:00","dateModified":"2014-02-13T02:52:31+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Recuperar puntos del carn\u00e9 requerir\u00e1 una prueba en Tr\u00e1fico adem\u00e1s del curso | El Digital de Asturias","og:description":"Madrid, 12 feb (EFE).- Los conductores que quieran recuperar parcialmente puntos de su carn\u00e9 no s\u00f3lo tendr\u00e1n que realizar un curso de sensibilizaci\u00f3n y reeducaci\u00f3n vial, sino que adem\u00e1s deber\u00e1n superar una prueba en la Jefatura Provincial de Tr\u00e1fico correspondiente. As\u00ed ser\u00e1 si prospera la enmienda que en este sentido ha presentado el grupo popular","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5938211w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5938211w.jpg","og:image:width":800,"og:image:height":533,"article:published_time":"2014-02-13T03:52:31+00:00","article:modified_time":"2014-02-13T03:52:31+00:00","twitter:card":"summary_large_image","twitter:title":"Recuperar puntos del carn\u00e9 requerir\u00e1 una prueba en Tr\u00e1fico adem\u00e1s del curso | El Digital de Asturias","twitter:description":"Madrid, 12 feb (EFE).- Los conductores que quieran recuperar parcialmente puntos de su carn\u00e9 no s\u00f3lo tendr\u00e1n que realizar un curso de sensibilizaci\u00f3n y reeducaci\u00f3n vial, sino que adem\u00e1s deber\u00e1n superar una prueba en la Jefatura Provincial de Tr\u00e1fico correspondiente. As\u00ed ser\u00e1 si prospera la enmienda que en este sentido ha presentado el grupo popular","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5938211w.jpg"},"aioseo_meta_data":{"post_id":"3946","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 11:12:13","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:50:31","updated":"2026-05-15 11:12:13"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/\" title=\"Recuperar puntos del carn\u00e9 requerir\u00e1 una prueba en Tr\u00e1fico adem\u00e1s del curso\">Recuperar puntos del carn\u00e9 requerir\u00e1 una prueba en Tr\u00e1fico adem\u00e1s del curso<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Recuperar puntos del carn\u00e9 requerir\u00e1 una prueba en Tr\u00e1fico adem\u00e1s del curso","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/recuperar-puntos-del-carne-requerira-una-prueba-en-trafico-ademas-del-curso\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=3946"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3946\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/3947"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=3946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=3946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=3946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}