{"id":3926,"date":"2014-02-13T02:42:21","date_gmt":"2014-02-13T03:42:21","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=3926"},"modified":"2014-02-13T02:44:36","modified_gmt":"2014-02-13T03:44:36","slug":"el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/","title":{"rendered":"El trovador cubano Santiago Feli\u00fa fallece en La Habana a los 51 a\u00f1os"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3928\" alt=\"5936882w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5936882w-360x216.jpg\" width=\"360\" height=\"216\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5936882w-360x216.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5936882w-650x390.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5936882w-768x461.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5936882w-150x90.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5936882w-450x270.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5936882w-696x418.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5936882w-700x420.jpg 700w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5936882w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La Habana, 12 feb (EFE).- El trovador cubano Santiago Feli\u00fa falleci\u00f3 este mi\u00e9rcoles de madrugada en La Habana a los 51 a\u00f1os de edad, informaron hoy medios cubanos.<\/p>\n<p>\u00abSe lo llev\u00f3 un infarto\u00bb, escribi\u00f3 el cantautor cubano Silvio Rodr\u00edguez en su blog Segunda Cita, en una entrada dedicada a Feli\u00fa y titulada \u00abSanty\u00bb, como era conocido entre sus amigos.<\/p>\n<p>La noticia fue divulgada hoy por medios como la emisora oficial Radio Rebelde, que record\u00f3 que el m\u00fasico ten\u00eda previsto un concierto este s\u00e1bado en La Habana en el espacio F\u00e1brica de Arte Cubano, un proyecto de su colega el m\u00fasico X Alfonso.<\/p>\n<p>Feli\u00fa (La Habana, 1962) era uno de los trovadores cubanos con mayor poder de convocatoria en Latinoam\u00e9rica y acompa\u00f1\u00f3 en sus giras a cantautores como Joan Manuel Serrat, Luis Eduardo Aute, Fito P\u00e1ez, Pablo Milan\u00e9s y Silvio Rodr\u00edguez.<\/p>\n<p>Autor de temas como \u00abAnsias del alba\u00bb, \u00abPara B\u00e1rbara\u00bb y \u00abSin Julieta\u00bb, Feli\u00fa forma parte de la segunda generaci\u00f3n de la Nueva Trova Cubana, junto a otras figuras como Carlos Varela, Gerardo Alfonso y Frank Delgado.<\/p>\n<p>Grab\u00f3 11 discos, el \u00faltimo de ellos titulado \u00abAy la vida\u00bb y publicado en 2010.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Habana, 12 feb (EFE).- El trovador cubano Santiago Feli\u00fa falleci\u00f3 este mi\u00e9rcoles de madrugada en La Habana a los 51 a\u00f1os de edad, informaron hoy medios cubanos. \u00abSe lo llev\u00f3 un infarto\u00bb, escribi\u00f3 el cantautor cubano Silvio Rodr\u00edguez en su blog Segunda Cita, en una entrada dedicada a Feli\u00fa y titulada \u00abSanty\u00bb, como era<\/p>\n","protected":false},"author":1,"featured_media":3928,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-3926","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Habana, 12 feb (EFE).- El trovador cubano Santiago Feli\u00fa falleci\u00f3 este mi\u00e9rcoles de madrugada en La Habana a los 51 a\u00f1os de edad, informaron hoy medios cubanos. &quot;Se lo llev\u00f3 un infarto&quot;, escribi\u00f3 el cantautor cubano Silvio Rodr\u00edguez en su blog Segunda Cita, en una entrada dedicada a Feli\u00fa y titulada &quot;Santy&quot;, como era\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El trovador cubano Santiago Feli\u00fa fallece en La Habana a los 51 a\u00f1os | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"La Habana, 12 feb (EFE).- El trovador cubano Santiago Feli\u00fa falleci\u00f3 este mi\u00e9rcoles de madrugada en La Habana a los 51 a\u00f1os de edad, informaron hoy medios cubanos. &quot;Se lo llev\u00f3 un infarto&quot;, escribi\u00f3 el cantautor cubano Silvio Rodr\u00edguez en su blog Segunda Cita, en una entrada dedicada a Feli\u00fa y titulada &quot;Santy&quot;, como era\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5936882w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5936882w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-13T03:42:21+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-13T03:44:36+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El trovador cubano Santiago Feli\u00fa fallece en La Habana a los 51 a\u00f1os | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Habana, 12 feb (EFE).- El trovador cubano Santiago Feli\u00fa falleci\u00f3 este mi\u00e9rcoles de madrugada en La Habana a los 51 a\u00f1os de edad, informaron hoy medios cubanos. &quot;Se lo llev\u00f3 un infarto&quot;, escribi\u00f3 el cantautor cubano Silvio Rodr\u00edguez en su blog Segunda Cita, en una entrada dedicada a Feli\u00fa y titulada &quot;Santy&quot;, como era\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5936882w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\\\/#article\",\"name\":\"El trovador cubano Santiago Feli\\u00fa fallece en La Habana a los 51 a\\u00f1os | El Digital de Asturias\",\"headline\":\"El trovador cubano Santiago Feli\\u00fa fallece en La Habana a los 51 a\\u00f1os\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5936882w.jpg\",\"width\":800,\"height\":480},\"datePublished\":\"2014-02-13T02:42:21+01:00\",\"dateModified\":\"2014-02-13T02:44:36+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\\\/#listItem\",\"name\":\"El trovador cubano Santiago Feli\\u00fa fallece en La Habana a los 51 a\\u00f1os\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\\\/#listItem\",\"position\":3,\"name\":\"El trovador cubano Santiago Feli\\u00fa fallece en La Habana a los 51 a\\u00f1os\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\\\/\",\"name\":\"El trovador cubano Santiago Feli\\u00fa fallece en La Habana a los 51 a\\u00f1os | El Digital de Asturias\",\"description\":\"La Habana, 12 feb (EFE).- El trovador cubano Santiago Feli\\u00fa falleci\\u00f3 este mi\\u00e9rcoles de madrugada en La Habana a los 51 a\\u00f1os de edad, informaron hoy medios cubanos. \\\"Se lo llev\\u00f3 un infarto\\\", escribi\\u00f3 el cantautor cubano Silvio Rodr\\u00edguez en su blog Segunda Cita, en una entrada dedicada a Feli\\u00fa y titulada \\\"Santy\\\", como era\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5936882w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\\\/#mainImage\",\"width\":800,\"height\":480},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\\\/#mainImage\"},\"datePublished\":\"2014-02-13T02:42:21+01:00\",\"dateModified\":\"2014-02-13T02:44:36+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El trovador cubano Santiago Feli\u00fa fallece en La Habana a los 51 a\u00f1os | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El trovador cubano Santiago Feli\u00fa fallece en La Habana a los 51 a\u00f1os | El Digital de Asturias","description":"La Habana, 12 feb (EFE).- El trovador cubano Santiago Feli\u00fa falleci\u00f3 este mi\u00e9rcoles de madrugada en La Habana a los 51 a\u00f1os de edad, informaron hoy medios cubanos. \"Se lo llev\u00f3 un infarto\", escribi\u00f3 el cantautor cubano Silvio Rodr\u00edguez en su blog Segunda Cita, en una entrada dedicada a Feli\u00fa y titulada \"Santy\", como era","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/#article","name":"El trovador cubano Santiago Feli\u00fa fallece en La Habana a los 51 a\u00f1os | El Digital de Asturias","headline":"El trovador cubano Santiago Feli\u00fa fallece en La Habana a los 51 a\u00f1os","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5936882w.jpg","width":800,"height":480},"datePublished":"2014-02-13T02:42:21+01:00","dateModified":"2014-02-13T02:44:36+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/#listItem","name":"El trovador cubano Santiago Feli\u00fa fallece en La Habana a los 51 a\u00f1os"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/#listItem","position":3,"name":"El trovador cubano Santiago Feli\u00fa fallece en La Habana a los 51 a\u00f1os","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/","name":"El trovador cubano Santiago Feli\u00fa fallece en La Habana a los 51 a\u00f1os | El Digital de Asturias","description":"La Habana, 12 feb (EFE).- El trovador cubano Santiago Feli\u00fa falleci\u00f3 este mi\u00e9rcoles de madrugada en La Habana a los 51 a\u00f1os de edad, informaron hoy medios cubanos. \"Se lo llev\u00f3 un infarto\", escribi\u00f3 el cantautor cubano Silvio Rodr\u00edguez en su blog Segunda Cita, en una entrada dedicada a Feli\u00fa y titulada \"Santy\", como era","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5936882w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/#mainImage","width":800,"height":480},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/#mainImage"},"datePublished":"2014-02-13T02:42:21+01:00","dateModified":"2014-02-13T02:44:36+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"El trovador cubano Santiago Feli\u00fa fallece en La Habana a los 51 a\u00f1os | El Digital de Asturias","og:description":"La Habana, 12 feb (EFE).- El trovador cubano Santiago Feli\u00fa falleci\u00f3 este mi\u00e9rcoles de madrugada en La Habana a los 51 a\u00f1os de edad, informaron hoy medios cubanos. &quot;Se lo llev\u00f3 un infarto&quot;, escribi\u00f3 el cantautor cubano Silvio Rodr\u00edguez en su blog Segunda Cita, en una entrada dedicada a Feli\u00fa y titulada &quot;Santy&quot;, como era","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5936882w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5936882w.jpg","og:image:width":800,"og:image:height":480,"article:published_time":"2014-02-13T03:42:21+00:00","article:modified_time":"2014-02-13T03:44:36+00:00","twitter:card":"summary_large_image","twitter:title":"El trovador cubano Santiago Feli\u00fa fallece en La Habana a los 51 a\u00f1os | El Digital de Asturias","twitter:description":"La Habana, 12 feb (EFE).- El trovador cubano Santiago Feli\u00fa falleci\u00f3 este mi\u00e9rcoles de madrugada en La Habana a los 51 a\u00f1os de edad, informaron hoy medios cubanos. &quot;Se lo llev\u00f3 un infarto&quot;, escribi\u00f3 el cantautor cubano Silvio Rodr\u00edguez en su blog Segunda Cita, en una entrada dedicada a Feli\u00fa y titulada &quot;Santy&quot;, como era","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5936882w.jpg"},"aioseo_meta_data":{"post_id":"3926","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 11:10:10","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:50:30","updated":"2026-05-15 11:10:10"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/\" title=\"El trovador cubano Santiago Feli\u00fa fallece en La Habana a los 51 a\u00f1os\">El trovador cubano Santiago Feli\u00fa fallece en La Habana a los 51 a\u00f1os<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"El trovador cubano Santiago Feli\u00fa fallece en La Habana a los 51 a\u00f1os","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-trovador-cubano-santiago-feliu-fallece-en-la-habana-a-los-51-anos\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=3926"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3926\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/3928"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=3926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=3926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=3926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}