{"id":3910,"date":"2014-02-13T02:33:00","date_gmt":"2014-02-13T03:33:00","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=3910"},"modified":"2014-02-13T02:33:00","modified_gmt":"2014-02-13T03:33:00","slug":"carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/","title":{"rendered":"\u00abCarmina y Am\u00e9n\u00bb se estrenar\u00e1 s\u00f3lo en cines el 30 de abril"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3911\" alt=\"5937645w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5937645w-360x227.jpg\" width=\"360\" height=\"227\" \/>Madrid, 12 feb (EFE).- \u00abCarmina y Am\u00e9n\u00bb, la segunda entrega de las aventuras de Carmina Barrios, dirigida por su hijo Paco Le\u00f3n, se estrenar\u00e1 en cines el pr\u00f3ximo 30 abril, un mes despu\u00e9s de su presentaci\u00f3n oficial en el Festival de M\u00e1laga.<\/p>\n<p>A diferencia de \u00abCarmina o revienta\u00bb, que se estren\u00f3 de forma simult\u00e1nea en cines, internet y DVD y se promocion\u00f3 como una nueva alternativa de distribuci\u00f3n cinematogr\u00e1fica, \u00abCarmina y am\u00e9n\u00bb llegar\u00e1 primero a las salas de cine, tras un acuerdo con A Contracorriente Films.<\/p>\n<p>La pel\u00edcula cuenta adem\u00e1s con un mayor presupuesto y la implicaci\u00f3n de Mediaset y Canal+ en la producci\u00f3n, y tambi\u00e9n se adentra m\u00e1s en el terreno de la ficci\u00f3n, mientras que la primera entrega mezclaba ficci\u00f3n y realidad.<\/p>\n<p>Seg\u00fan Paco Le\u00f3n, \u00abCarmina y Am\u00e9n\u00bb pretende explorar los l\u00edmites entre la comedia y el drama, \u00abexperimentando con un lenguaje m\u00e1s ficcionado, sin perder la autenticidad de los personajes y las situaciones\u00bb.<\/p>\n<p>La trama cuenta c\u00f3mo Carmina, tras la s\u00fabita muerte de su marido, convence a su hija Mar\u00eda de no dar parte de la defunci\u00f3n hasta pasados dos d\u00edas, y as\u00ed poder cobrar la paga doble que \u00e9l ten\u00eda pendiente.<\/p>\n<p>Al reparto, adem\u00e1s de Carmina Barrios, Mar\u00eda Le\u00f3n y Paco Casaus, se han unido otros miembros de la familia Le\u00f3n-Barrios y otros actores como Yolanda Ramos, Estefan\u00eda de los Santos o Manolo Solo.<\/p>\n<p>\u00abCarmina o revienta\u00bb, con un presupuesto de 500.000 euros, super\u00f3 en su momento las expectativas, con una audiencia de 279.531 espectadores y una recaudaci\u00f3n de 664.062 euros entre todas las plataformas, cinco meses despu\u00e9s de su estreno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 12 feb (EFE).- \u00abCarmina y Am\u00e9n\u00bb, la segunda entrega de las aventuras de Carmina Barrios, dirigida por su hijo Paco Le\u00f3n, se estrenar\u00e1 en cines el pr\u00f3ximo 30 abril, un mes despu\u00e9s de su presentaci\u00f3n oficial en el Festival de M\u00e1laga. A diferencia de \u00abCarmina o revienta\u00bb, que se estren\u00f3 de forma simult\u00e1nea en<\/p>\n","protected":false},"author":1,"featured_media":3911,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-3910","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 12 feb (EFE).- &quot;Carmina y Am\u00e9n&quot;, la segunda entrega de las aventuras de Carmina Barrios, dirigida por su hijo Paco Le\u00f3n, se estrenar\u00e1 en cines el pr\u00f3ximo 30 abril, un mes despu\u00e9s de su presentaci\u00f3n oficial en el Festival de M\u00e1laga. A diferencia de &quot;Carmina o revienta&quot;, que se estren\u00f3 de forma simult\u00e1nea en\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00abCarmina y Am\u00e9n\u00bb se estrenar\u00e1 s\u00f3lo en cines el 30 de abril | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 12 feb (EFE).- &quot;Carmina y Am\u00e9n&quot;, la segunda entrega de las aventuras de Carmina Barrios, dirigida por su hijo Paco Le\u00f3n, se estrenar\u00e1 en cines el pr\u00f3ximo 30 abril, un mes despu\u00e9s de su presentaci\u00f3n oficial en el Festival de M\u00e1laga. A diferencia de &quot;Carmina o revienta&quot;, que se estren\u00f3 de forma simult\u00e1nea en\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5937645w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5937645w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-13T03:33:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-13T03:33:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00abCarmina y Am\u00e9n\u00bb se estrenar\u00e1 s\u00f3lo en cines el 30 de abril | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 12 feb (EFE).- &quot;Carmina y Am\u00e9n&quot;, la segunda entrega de las aventuras de Carmina Barrios, dirigida por su hijo Paco Le\u00f3n, se estrenar\u00e1 en cines el pr\u00f3ximo 30 abril, un mes despu\u00e9s de su presentaci\u00f3n oficial en el Festival de M\u00e1laga. A diferencia de &quot;Carmina o revienta&quot;, que se estren\u00f3 de forma simult\u00e1nea en\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5937645w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\\\/#article\",\"name\":\"\\u00abCarmina y Am\\u00e9n\\u00bb se estrenar\\u00e1 s\\u00f3lo en cines el 30 de abril | El Digital de Asturias\",\"headline\":\"\\u00abCarmina y Am\\u00e9n\\u00bb se estrenar\\u00e1 s\\u00f3lo en cines el 30 de abril\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5937645w.jpg\",\"width\":800,\"height\":506},\"datePublished\":\"2014-02-13T02:33:00+01:00\",\"dateModified\":\"2014-02-13T02:33:00+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\\\/#listItem\",\"name\":\"\\u00abCarmina y Am\\u00e9n\\u00bb se estrenar\\u00e1 s\\u00f3lo en cines el 30 de abril\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\\\/#listItem\",\"position\":3,\"name\":\"\\u00abCarmina y Am\\u00e9n\\u00bb se estrenar\\u00e1 s\\u00f3lo en cines el 30 de abril\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\\\/\",\"name\":\"\\u00abCarmina y Am\\u00e9n\\u00bb se estrenar\\u00e1 s\\u00f3lo en cines el 30 de abril | El Digital de Asturias\",\"description\":\"Madrid, 12 feb (EFE).- \\\"Carmina y Am\\u00e9n\\\", la segunda entrega de las aventuras de Carmina Barrios, dirigida por su hijo Paco Le\\u00f3n, se estrenar\\u00e1 en cines el pr\\u00f3ximo 30 abril, un mes despu\\u00e9s de su presentaci\\u00f3n oficial en el Festival de M\\u00e1laga. A diferencia de \\\"Carmina o revienta\\\", que se estren\\u00f3 de forma simult\\u00e1nea en\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5937645w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\\\/#mainImage\",\"width\":800,\"height\":506},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\\\/#mainImage\"},\"datePublished\":\"2014-02-13T02:33:00+01:00\",\"dateModified\":\"2014-02-13T02:33:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>\u00abCarmina y Am\u00e9n\u00bb se estrenar\u00e1 s\u00f3lo en cines el 30 de abril | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"\u00abCarmina y Am\u00e9n\u00bb se estrenar\u00e1 s\u00f3lo en cines el 30 de abril | El Digital de Asturias","description":"Madrid, 12 feb (EFE).- \"Carmina y Am\u00e9n\", la segunda entrega de las aventuras de Carmina Barrios, dirigida por su hijo Paco Le\u00f3n, se estrenar\u00e1 en cines el pr\u00f3ximo 30 abril, un mes despu\u00e9s de su presentaci\u00f3n oficial en el Festival de M\u00e1laga. A diferencia de \"Carmina o revienta\", que se estren\u00f3 de forma simult\u00e1nea en","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/#article","name":"\u00abCarmina y Am\u00e9n\u00bb se estrenar\u00e1 s\u00f3lo en cines el 30 de abril | El Digital de Asturias","headline":"\u00abCarmina y Am\u00e9n\u00bb se estrenar\u00e1 s\u00f3lo en cines el 30 de abril","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5937645w.jpg","width":800,"height":506},"datePublished":"2014-02-13T02:33:00+01:00","dateModified":"2014-02-13T02:33:00+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/#listItem","name":"\u00abCarmina y Am\u00e9n\u00bb se estrenar\u00e1 s\u00f3lo en cines el 30 de abril"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/#listItem","position":3,"name":"\u00abCarmina y Am\u00e9n\u00bb se estrenar\u00e1 s\u00f3lo en cines el 30 de abril","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/","name":"\u00abCarmina y Am\u00e9n\u00bb se estrenar\u00e1 s\u00f3lo en cines el 30 de abril | El Digital de Asturias","description":"Madrid, 12 feb (EFE).- \"Carmina y Am\u00e9n\", la segunda entrega de las aventuras de Carmina Barrios, dirigida por su hijo Paco Le\u00f3n, se estrenar\u00e1 en cines el pr\u00f3ximo 30 abril, un mes despu\u00e9s de su presentaci\u00f3n oficial en el Festival de M\u00e1laga. A diferencia de \"Carmina o revienta\", que se estren\u00f3 de forma simult\u00e1nea en","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5937645w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/#mainImage","width":800,"height":506},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/#mainImage"},"datePublished":"2014-02-13T02:33:00+01:00","dateModified":"2014-02-13T02:33:00+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"\u00abCarmina y Am\u00e9n\u00bb se estrenar\u00e1 s\u00f3lo en cines el 30 de abril | El Digital de Asturias","og:description":"Madrid, 12 feb (EFE).- &quot;Carmina y Am\u00e9n&quot;, la segunda entrega de las aventuras de Carmina Barrios, dirigida por su hijo Paco Le\u00f3n, se estrenar\u00e1 en cines el pr\u00f3ximo 30 abril, un mes despu\u00e9s de su presentaci\u00f3n oficial en el Festival de M\u00e1laga. A diferencia de &quot;Carmina o revienta&quot;, que se estren\u00f3 de forma simult\u00e1nea en","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5937645w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5937645w.jpg","og:image:width":800,"og:image:height":506,"article:published_time":"2014-02-13T03:33:00+00:00","article:modified_time":"2014-02-13T03:33:00+00:00","twitter:card":"summary_large_image","twitter:title":"\u00abCarmina y Am\u00e9n\u00bb se estrenar\u00e1 s\u00f3lo en cines el 30 de abril | El Digital de Asturias","twitter:description":"Madrid, 12 feb (EFE).- &quot;Carmina y Am\u00e9n&quot;, la segunda entrega de las aventuras de Carmina Barrios, dirigida por su hijo Paco Le\u00f3n, se estrenar\u00e1 en cines el pr\u00f3ximo 30 abril, un mes despu\u00e9s de su presentaci\u00f3n oficial en el Festival de M\u00e1laga. A diferencia de &quot;Carmina o revienta&quot;, que se estren\u00f3 de forma simult\u00e1nea en","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5937645w.jpg"},"aioseo_meta_data":{"post_id":"3910","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 11:08:04","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:50:29","updated":"2026-05-15 11:08:04"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/\" title=\"\u00abCarmina y Am\u00e9n\u00bb se estrenar\u00e1 s\u00f3lo en cines el 30 de abril\">\u00abCarmina y Am\u00e9n\u00bb se estrenar\u00e1 s\u00f3lo en cines el 30 de abril<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"\u00abCarmina y Am\u00e9n\u00bb se estrenar\u00e1 s\u00f3lo en cines el 30 de abril","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/carmina-y-amen-se-estrenara-solo-en-cines-el-30-de-abril\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=3910"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3910\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/3911"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=3910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=3910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=3910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}