{"id":39091,"date":"2015-06-09T03:23:16","date_gmt":"2015-06-09T01:53:16","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=39091"},"modified":"2015-06-09T03:23:16","modified_gmt":"2015-06-09T01:53:16","slug":"retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/","title":{"rendered":"Retrasos de hasta una hora en El Prat por la huelga de controladores"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-39092\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/aeropuerto-360x239.jpg\" alt=\"aeropuerto\" width=\"360\" height=\"239\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/aeropuerto-360x239.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/aeropuerto-650x431.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/aeropuerto-768x510.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/aeropuerto-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/aeropuerto-450x299.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/aeropuerto-696x462.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/aeropuerto-633x420.jpg 633w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/aeropuerto-84x55.jpg 84w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/aeropuerto.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Los vuelos del Aeropuerto de Barcelona-El Prat est\u00e1n registrando retrasos de hasta una hora tanto en las salidas como en las llegadas debido a la huelga que los controladores a\u00e9reos han realizado entre las 10 y las 12 horas.<\/p>\n<p>Seg\u00fan consta en la web de Aena, algunos de los vuelos programados para esta franja horaria han sufrido retrasos, como un avi\u00f3n en direcci\u00f3n a Mil\u00e1n que ha despegado con una hora y diez minutos de retrasos o uno en direcci\u00f3n a Fuerteventura con 50 minutos de demora.<\/p>\n<p>Los problemas tambi\u00e9n han afectado a los vuelos de llegada como un avi\u00f3n procedente de Palma de Mallorca con 36 minutos de retraso y otro procedente de Roma con 40 minutos.<\/p>\n<p>Adem\u00e1s de estos retrasos, ha habido un vuelo cancelado, un avi\u00f3n de Vueling en direcci\u00f3n a Par\u00eds.<\/p>\n<p>A pesar de estos retrasos, la mayor\u00eda de los vuelos que han operado entre las 10 y las 12 del mediod\u00eda han despegado y aterrizado con puntualidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los vuelos del Aeropuerto de Barcelona-El Prat est\u00e1n registrando retrasos de hasta una hora tanto en las salidas como en las llegadas debido a la huelga que los controladores a\u00e9reos han realizado entre las 10 y las 12 horas. Seg\u00fan consta en la web de Aena, algunos de los vuelos programados para esta franja horaria<\/p>\n","protected":false},"author":1,"featured_media":39092,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-39091","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los vuelos del Aeropuerto de Barcelona-El Prat est\u00e1n registrando retrasos de hasta una hora tanto en las salidas como en las llegadas debido a la huelga que los controladores a\u00e9reos han realizado entre las 10 y las 12 horas. Seg\u00fan consta en la web de Aena, algunos de los vuelos programados para esta franja horaria\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Retrasos de hasta una hora en El Prat por la huelga de controladores | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Los vuelos del Aeropuerto de Barcelona-El Prat est\u00e1n registrando retrasos de hasta una hora tanto en las salidas como en las llegadas debido a la huelga que los controladores a\u00e9reos han realizado entre las 10 y las 12 horas. Seg\u00fan consta en la web de Aena, algunos de los vuelos programados para esta franja horaria\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/aeropuerto.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/aeropuerto.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-06-09T01:53:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-06-09T01:53:16+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Retrasos de hasta una hora en El Prat por la huelga de controladores | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los vuelos del Aeropuerto de Barcelona-El Prat est\u00e1n registrando retrasos de hasta una hora tanto en las salidas como en las llegadas debido a la huelga que los controladores a\u00e9reos han realizado entre las 10 y las 12 horas. Seg\u00fan consta en la web de Aena, algunos de los vuelos programados para esta franja horaria\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/aeropuerto.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\\\/#article\",\"name\":\"Retrasos de hasta una hora en El Prat por la huelga de controladores | El Digital de Asturias\",\"headline\":\"Retrasos de hasta una hora en El Prat por la huelga de controladores\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/aeropuerto.jpg\",\"width\":800,\"height\":531},\"datePublished\":\"2015-06-09T03:23:16+02:00\",\"dateModified\":\"2015-06-09T03:23:16+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\\\/#listItem\",\"name\":\"Retrasos de hasta una hora en El Prat por la huelga de controladores\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\\\/#listItem\",\"position\":3,\"name\":\"Retrasos de hasta una hora en El Prat por la huelga de controladores\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\\\/\",\"name\":\"Retrasos de hasta una hora en El Prat por la huelga de controladores | El Digital de Asturias\",\"description\":\"Los vuelos del Aeropuerto de Barcelona-El Prat est\\u00e1n registrando retrasos de hasta una hora tanto en las salidas como en las llegadas debido a la huelga que los controladores a\\u00e9reos han realizado entre las 10 y las 12 horas. Seg\\u00fan consta en la web de Aena, algunos de los vuelos programados para esta franja horaria\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/aeropuerto.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\\\/#mainImage\",\"width\":800,\"height\":531},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\\\/#mainImage\"},\"datePublished\":\"2015-06-09T03:23:16+02:00\",\"dateModified\":\"2015-06-09T03:23:16+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Retrasos de hasta una hora en El Prat por la huelga de controladores | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Retrasos de hasta una hora en El Prat por la huelga de controladores | El Digital de Asturias","description":"Los vuelos del Aeropuerto de Barcelona-El Prat est\u00e1n registrando retrasos de hasta una hora tanto en las salidas como en las llegadas debido a la huelga que los controladores a\u00e9reos han realizado entre las 10 y las 12 horas. Seg\u00fan consta en la web de Aena, algunos de los vuelos programados para esta franja horaria","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/#article","name":"Retrasos de hasta una hora en El Prat por la huelga de controladores | El Digital de Asturias","headline":"Retrasos de hasta una hora en El Prat por la huelga de controladores","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/aeropuerto.jpg","width":800,"height":531},"datePublished":"2015-06-09T03:23:16+02:00","dateModified":"2015-06-09T03:23:16+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/#listItem","name":"Retrasos de hasta una hora en El Prat por la huelga de controladores"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/#listItem","position":3,"name":"Retrasos de hasta una hora en El Prat por la huelga de controladores","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/","name":"Retrasos de hasta una hora en El Prat por la huelga de controladores | El Digital de Asturias","description":"Los vuelos del Aeropuerto de Barcelona-El Prat est\u00e1n registrando retrasos de hasta una hora tanto en las salidas como en las llegadas debido a la huelga que los controladores a\u00e9reos han realizado entre las 10 y las 12 horas. Seg\u00fan consta en la web de Aena, algunos de los vuelos programados para esta franja horaria","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/aeropuerto.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/#mainImage","width":800,"height":531},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/#mainImage"},"datePublished":"2015-06-09T03:23:16+02:00","dateModified":"2015-06-09T03:23:16+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Retrasos de hasta una hora en El Prat por la huelga de controladores | El Digital de Asturias","og:description":"Los vuelos del Aeropuerto de Barcelona-El Prat est\u00e1n registrando retrasos de hasta una hora tanto en las salidas como en las llegadas debido a la huelga que los controladores a\u00e9reos han realizado entre las 10 y las 12 horas. Seg\u00fan consta en la web de Aena, algunos de los vuelos programados para esta franja horaria","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/aeropuerto.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/aeropuerto.jpg","og:image:width":800,"og:image:height":531,"article:published_time":"2015-06-09T01:53:16+00:00","article:modified_time":"2015-06-09T01:53:16+00:00","twitter:card":"summary_large_image","twitter:title":"Retrasos de hasta una hora en El Prat por la huelga de controladores | El Digital de Asturias","twitter:description":"Los vuelos del Aeropuerto de Barcelona-El Prat est\u00e1n registrando retrasos de hasta una hora tanto en las salidas como en las llegadas debido a la huelga que los controladores a\u00e9reos han realizado entre las 10 y las 12 horas. Seg\u00fan consta en la web de Aena, algunos de los vuelos programados para esta franja horaria","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/aeropuerto.jpg"},"aioseo_meta_data":{"post_id":"39091","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 19:26:01","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 02:45:40","updated":"2026-05-20 19:26:01"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/\" title=\"Retrasos de hasta una hora en El Prat por la huelga de controladores\">Retrasos de hasta una hora en El Prat por la huelga de controladores<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Retrasos de hasta una hora en El Prat por la huelga de controladores","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/retrasos-de-hasta-una-hora-en-el-prat-por-la-huelga-de-controladores\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/39091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=39091"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/39091\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/39092"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=39091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=39091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=39091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}