{"id":39082,"date":"2015-06-09T03:18:36","date_gmt":"2015-06-09T01:48:36","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=39082"},"modified":"2015-06-09T03:18:36","modified_gmt":"2015-06-09T01:48:36","slug":"el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/","title":{"rendered":"El impacto econ\u00f3mico del turismo de reuniones en Madrid crece en un 7,4%"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-39083\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/fotonoticia_20150608121532_800-360x226.jpg\" alt=\"fotonoticia_20150608121532_800\" width=\"360\" height=\"226\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/fotonoticia_20150608121532_800-360x226.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/fotonoticia_20150608121532_800-650x408.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/fotonoticia_20150608121532_800-768x482.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/fotonoticia_20150608121532_800-150x94.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/fotonoticia_20150608121532_800-450x282.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/fotonoticia_20150608121532_800-696x437.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/fotonoticia_20150608121532_800-669x420.jpg 669w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/fotonoticia_20150608121532_800-269x170.jpg 269w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/fotonoticia_20150608121532_800-480x300.jpg 480w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/fotonoticia_20150608121532_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El turismo de reuniones en la capital gener\u00f3 816 millones de euros en 2014, un 7,4 por ciento m\u00e1s que en 2013, seg\u00fan un informe elaborado por Madison Market Research, difundido por el Ayuntamiento de Madrid.<\/p>\n<p>El incremento de los encuentros internacionales (+3,2%) y de los asistentes extranjeros (+18,4%), que son los que mayor gasto diario realizan en la ciudad, han favorecido estos resultados.<\/p>\n<p>El gasto en restauraci\u00f3n (47,3%) y las compras (18,8%) supuso m\u00e1s de la mitad del total del consumo realizado por los profesionales asistentes a las 12.455 reuniones que alberg\u00f3 la ciudad el a\u00f1o pasado.<\/p>\n<p>De estos encuentros, 2.266 fueron congresos, 2.585 convenciones y 7.604 jornadas. Los sectores qu\u00edmico y farmac\u00e9utico, m\u00e9dico y el de la docencia y la investigaci\u00f3n fueron los m\u00e1s representados.<\/p>\n<p>M\u00c1S PARTICIPANTES.<\/p>\n<p>A pesar de que se ha producido un ligero descenso en el n\u00famero de encuentros respecto a 2013, Madrid recibi\u00f3 en 2014 un mayor n\u00famero de asistentes, alcanz\u00e1ndose los 1.210.000 participantes (+12,7%).<\/p>\n<p>Estos delegados generaron 2,3 millones de pernoctaciones en los hoteles madrile\u00f1os. Tambi\u00e9n se increment\u00f3 la duraci\u00f3n media de la visita a la capital, que se sit\u00fao en 2,97 d\u00edas, prolong\u00e1ndose as\u00ed la estancia de los delegados en Madrid respecto a 2013.<\/p>\n<p>Adem\u00e1s, en 2014 y seg\u00fan el \u00faltimo ranking de la Internacional Congress and Convention Association (ICCA), la capital se consolid\u00f3 como el tercer destino del mundo.<\/p>\n<p>Seg\u00fan el Ayuntamiento de Madrid, el \u00c1rea de Turismo de la empresa municipal Madrid Destino, a trav\u00e9s del Madrid Convention Bureau (MCB), que es responsable de la estrategia promocional de Madrid como destino de turismo de reuniones, ha sido un \u00abelemento clave\u00bb en el \u00ab\u00e9xito\u00bb de la capital como sede de encuentros profesionales.<\/p>\n<p>Las reuniones captadas directamente por Madrid Convention Bureau en 2014, con el apoyo de sus casi 200 empresas asociadas, fueron 53 y generaron m\u00e1s de 65 millones de euros a la ciudad de Madrid, una cifra que supone el 13,2 por ciento del impacto econ\u00f3mico total del turismo de reuniones en la capital ese a\u00f1o.<\/p>\n<p>En este sentido, el Consistorio ha destacado que en uno de cada dos euros de impacto econ\u00f3mico generados por los congresos celebrados en Madrid ha mediado la actuaci\u00f3n del MCB, lo que ha supuesto unos ingresos de 135 millones de euros para la ciudad.<\/p>\n<p>VALORACI\u00d3N POSITIVA<\/p>\n<p>Los organizadores de reuniones valoran muy positivamente la ciudad de Madrid como sede de encuentros profesionales, as\u00ed como el alto nivel de sus infraestructuras y servicios y la recomendar\u00edan para la celebraci\u00f3n de nuevos eventos, se\u00f1alan desde el Ayuntamiento.<\/p>\n<p>En las encuestas realizadas a organizadores de congresos y convenciones, tanto nacionales como internacionales, Madrid recibe una puntuaci\u00f3n de 7,9 puntos sobre 10 como ciudad de celebraci\u00f3n de la reuni\u00f3n, mientras que le otorgan 8,1 puntos sobre 10 como ciudad a recomendar como destino de negocios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El turismo de reuniones en la capital gener\u00f3 816 millones de euros en 2014, un 7,4 por ciento m\u00e1s que en 2013, seg\u00fan un informe elaborado por Madison Market Research, difundido por el Ayuntamiento de Madrid. El incremento de los encuentros internacionales (+3,2%) y de los asistentes extranjeros (+18,4%), que son los que mayor gasto<\/p>\n","protected":false},"author":1,"featured_media":39083,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-39082","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"El turismo de reuniones en la capital gener\u00f3 816 millones de euros en 2014, un 7,4 por ciento m\u00e1s que en 2013, seg\u00fan un informe elaborado por Madison Market Research, difundido por el Ayuntamiento de Madrid. El incremento de los encuentros internacionales (+3,2%) y de los asistentes extranjeros (+18,4%), que son los que mayor gasto\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El impacto econ\u00f3mico del turismo de reuniones en Madrid crece en un 7,4% | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"El turismo de reuniones en la capital gener\u00f3 816 millones de euros en 2014, un 7,4 por ciento m\u00e1s que en 2013, seg\u00fan un informe elaborado por Madison Market Research, difundido por el Ayuntamiento de Madrid. El incremento de los encuentros internacionales (+3,2%) y de los asistentes extranjeros (+18,4%), que son los que mayor gasto\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/fotonoticia_20150608121532_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/fotonoticia_20150608121532_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"502\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-06-09T01:48:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-06-09T01:48:36+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El impacto econ\u00f3mico del turismo de reuniones en Madrid crece en un 7,4% | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El turismo de reuniones en la capital gener\u00f3 816 millones de euros en 2014, un 7,4 por ciento m\u00e1s que en 2013, seg\u00fan un informe elaborado por Madison Market Research, difundido por el Ayuntamiento de Madrid. El incremento de los encuentros internacionales (+3,2%) y de los asistentes extranjeros (+18,4%), que son los que mayor gasto\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/fotonoticia_20150608121532_800.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\\\/#article\",\"name\":\"El impacto econ\\u00f3mico del turismo de reuniones en Madrid crece en un 7,4% | El Digital de Asturias\",\"headline\":\"El impacto econ\\u00f3mico del turismo de reuniones en Madrid crece en un 7,4%\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/fotonoticia_20150608121532_800.jpg\",\"width\":800,\"height\":502},\"datePublished\":\"2015-06-09T03:18:36+02:00\",\"dateModified\":\"2015-06-09T03:18:36+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\\\/#listItem\",\"name\":\"El impacto econ\\u00f3mico del turismo de reuniones en Madrid crece en un 7,4%\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\\\/#listItem\",\"position\":3,\"name\":\"El impacto econ\\u00f3mico del turismo de reuniones en Madrid crece en un 7,4%\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\\\/\",\"name\":\"El impacto econ\\u00f3mico del turismo de reuniones en Madrid crece en un 7,4% | El Digital de Asturias\",\"description\":\"El turismo de reuniones en la capital gener\\u00f3 816 millones de euros en 2014, un 7,4 por ciento m\\u00e1s que en 2013, seg\\u00fan un informe elaborado por Madison Market Research, difundido por el Ayuntamiento de Madrid. El incremento de los encuentros internacionales (+3,2%) y de los asistentes extranjeros (+18,4%), que son los que mayor gasto\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/fotonoticia_20150608121532_800.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\\\/#mainImage\",\"width\":800,\"height\":502},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\\\/#mainImage\"},\"datePublished\":\"2015-06-09T03:18:36+02:00\",\"dateModified\":\"2015-06-09T03:18:36+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El impacto econ\u00f3mico del turismo de reuniones en Madrid crece en un 7,4% | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El impacto econ\u00f3mico del turismo de reuniones en Madrid crece en un 7,4% | El Digital de Asturias","description":"El turismo de reuniones en la capital gener\u00f3 816 millones de euros en 2014, un 7,4 por ciento m\u00e1s que en 2013, seg\u00fan un informe elaborado por Madison Market Research, difundido por el Ayuntamiento de Madrid. El incremento de los encuentros internacionales (+3,2%) y de los asistentes extranjeros (+18,4%), que son los que mayor gasto","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/#article","name":"El impacto econ\u00f3mico del turismo de reuniones en Madrid crece en un 7,4% | El Digital de Asturias","headline":"El impacto econ\u00f3mico del turismo de reuniones en Madrid crece en un 7,4%","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/fotonoticia_20150608121532_800.jpg","width":800,"height":502},"datePublished":"2015-06-09T03:18:36+02:00","dateModified":"2015-06-09T03:18:36+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/#listItem","name":"El impacto econ\u00f3mico del turismo de reuniones en Madrid crece en un 7,4%"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/#listItem","position":3,"name":"El impacto econ\u00f3mico del turismo de reuniones en Madrid crece en un 7,4%","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/","name":"El impacto econ\u00f3mico del turismo de reuniones en Madrid crece en un 7,4% | El Digital de Asturias","description":"El turismo de reuniones en la capital gener\u00f3 816 millones de euros en 2014, un 7,4 por ciento m\u00e1s que en 2013, seg\u00fan un informe elaborado por Madison Market Research, difundido por el Ayuntamiento de Madrid. El incremento de los encuentros internacionales (+3,2%) y de los asistentes extranjeros (+18,4%), que son los que mayor gasto","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/fotonoticia_20150608121532_800.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/#mainImage","width":800,"height":502},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/#mainImage"},"datePublished":"2015-06-09T03:18:36+02:00","dateModified":"2015-06-09T03:18:36+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"El impacto econ\u00f3mico del turismo de reuniones en Madrid crece en un 7,4% | El Digital de Asturias","og:description":"El turismo de reuniones en la capital gener\u00f3 816 millones de euros en 2014, un 7,4 por ciento m\u00e1s que en 2013, seg\u00fan un informe elaborado por Madison Market Research, difundido por el Ayuntamiento de Madrid. El incremento de los encuentros internacionales (+3,2%) y de los asistentes extranjeros (+18,4%), que son los que mayor gasto","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/fotonoticia_20150608121532_800.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/fotonoticia_20150608121532_800.jpg","og:image:width":800,"og:image:height":502,"article:published_time":"2015-06-09T01:48:36+00:00","article:modified_time":"2015-06-09T01:48:36+00:00","twitter:card":"summary_large_image","twitter:title":"El impacto econ\u00f3mico del turismo de reuniones en Madrid crece en un 7,4% | El Digital de Asturias","twitter:description":"El turismo de reuniones en la capital gener\u00f3 816 millones de euros en 2014, un 7,4 por ciento m\u00e1s que en 2013, seg\u00fan un informe elaborado por Madison Market Research, difundido por el Ayuntamiento de Madrid. El incremento de los encuentros internacionales (+3,2%) y de los asistentes extranjeros (+18,4%), que son los que mayor gasto","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/06\/fotonoticia_20150608121532_800.jpg"},"aioseo_meta_data":{"post_id":"39082","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 19:25:56","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 02:45:40","updated":"2026-05-20 19:25:56"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/\" title=\"El impacto econ\u00f3mico del turismo de reuniones en Madrid crece en un 7,4%\">El impacto econ\u00f3mico del turismo de reuniones en Madrid crece en un 7,4%<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"El impacto econ\u00f3mico del turismo de reuniones en Madrid crece en un 7,4%","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-impacto-economico-del-turismo-de-reuniones-en-madrid-crece-en-un-74\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/39082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=39082"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/39082\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/39083"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=39082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=39082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=39082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}