{"id":3852,"date":"2014-02-13T01:56:52","date_gmt":"2014-02-13T02:56:52","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=3852"},"modified":"2014-02-13T01:56:52","modified_gmt":"2014-02-13T02:56:52","slug":"jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/","title":{"rendered":"Jornada de alto nivel con Rodr\u00edguez, De la Renta y Marc by Marc Jacobs"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3853\" alt=\"5934721w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934721w-360x236.jpg\" width=\"360\" height=\"236\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934721w-360x236.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934721w-650x427.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934721w-768x504.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934721w-150x98.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934721w-450x295.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934721w-696x457.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934721w-741x486.jpg 741w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934721w-640x420.jpg 640w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934721w-84x55.jpg 84w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934721w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Nueva York, 12 feb (EFE).- Dos de los ilustres miembros de la primera plana de los dise\u00f1adores latinos en Nueva York, \u00d3scar de la Renta y Narciso Rodr\u00edguez, dieron hoy sendas lecciones de elegancia en la Semana de la Moda, compartiendo cartel con un Marc by Marc Jacobs desenfadado entre el rictus comunista y la hero\u00edna del manga.<\/p>\n<p>Rodr\u00edguez, de origen cubano, volvi\u00f3 a desglosar la complejidad de la sencillez en uno de los desfiles m\u00e1s limpios vistos esta Semana de la Moda.<\/p>\n<p>Si bien acostumbra a beber de fuentes arquitect\u00f3nicas, quien vistiera a Michelle Obama o Carolyn Bessette hoy puso las miras en una escultora, la inglesa Lynn Chadwick (no en vano, con formaci\u00f3n de delineante), de quien tom\u00f3 prestadas \u00abespecialmente las figuras en movimiento y sus formas femeninas\u00bb, explica en una entrevista con Efe.<\/p>\n<p>Heredados los juegos volum\u00e9tricos de esta artista, Rodr\u00edguez invierte la capacidad de Chadwick para crear una ligereza con materiales pesados para llenar sus ligeros tejidos de contenido met\u00e1lico, con efectos de titanio, bronce y platino, que distorsionan la figura naturalmente curva de la mujer.<\/p>\n<p>\u00abHay muchos materiales ligeros que crean estructuras o cortes inclinados. Han sido esculpidos con un patronaje nuevo, m\u00e1s suave que se transforma en algo fluido y esbelto\u00bb, asegura el dise\u00f1ador, quien define esta fr\u00e1gil rigidez como \u00abvol\u00famenes modernos y limpios\u00bb.<\/p>\n<p>Los tonos elegidos por Rodr\u00edguez evitan en todo momento el chillido. \u00c9l es el maestro de la discreci\u00f3n, aun cuando elige el rojo, el rosa, el color acero, el gris y el oliva. Una paleta que crea la sensaci\u00f3n de que fluye bajo unas hermosas chaquetas de lana, de seda o incluso de vis\u00f3n.<\/p>\n<p>Por su parte, el dominicano \u00d3scar de la Renta, quintaesencia de la belleza de lo conservador, no decepcion\u00f3, sino todo lo contrario, con una profusi\u00f3n de bordados y elegant\u00edsimos trajes de chaqueta con raya diplom\u00e1tica para el d\u00eda y una noche suntuosa, convirtiendo su pasarela en una espectacular puesta de largo.<\/p>\n<p>Su inicio fue sobrio, inspirado por esas mujeres que en los a\u00f1os cuarenta empezaron a robar la masculinidad a sus galanes en el Hollywood dorado. Quiz\u00e1 una Rossalind Russell, quiz\u00e1 una Katharine Hepburn que han decidido llevar ellas los pantalones y con mucha m\u00e1s elegancia que los hombres.<\/p>\n<p>Jers\u00e9is de cuello cisne protagonizados por calurosas lanas, faldas de tubo rematadas con festivos volantes, broches enjoyados a la altura de la garganta y pantalones de elefante dan paso al color estrella de la colecci\u00f3n, el azul cobalto, y al tejido que, digan lo que digan, m\u00e1s calienta: la piel.<\/p>\n<p>Abrigos elegantemente ajedrezados, chaquetas de lana milim\u00e9tricamente deslavazada, blancos y negros. La osad\u00eda de \u00d3scar de la Renta para resultar cl\u00e1sico y minimal no tiene l\u00edmites. Pero de repente, en la tupida selva de bordados, se vislumbra un pez\u00f3n furtivo, una sensualidad que reclama su lugar en una colecci\u00f3n con sabor veterano.<\/p>\n<p>Las chaquetas jaspeadas ya hab\u00edan hecho las veces de interruptor de escotes may\u00fasculos, las faldas globo se un\u00edan con la sutileza de un maestro del susurro y, en uno de los modelos m\u00e1s acertados, De la Renta hace crecer en un print de cuadros blancos y negros un jard\u00edn de flores granates bordadas.<\/p>\n<p>El dominicano, en cambio, entiende todav\u00eda mejor la noche, y al caer el sol convierte la pasarela en una ceremonia sin premios. En el simple placer de celebrar su fort\u00edsimo m\u00fasculo para la sofisticaci\u00f3n y el abolengo, o de hacer realidad el sue\u00f1o de toda mujer por ser princesa capaz de combinar lunares, palabras de honor y vestido de cola.<\/p>\n<p>La jornada la complet\u00f3 el desfile de Marc By Marc Jacobs, la l\u00ednea m\u00e1s urbana con el nombre del dise\u00f1ador que acaba de terminar su contrato con Louis Vuitton para prestar m\u00e1s atenci\u00f3n a su propia marca y que convoc\u00f3 a personalidades como Sofia Coppola.<\/p>\n<p>Su colecci\u00f3n oto\u00f1o\/invierno apost\u00f3 por una mujer severa, con un tono castrense (y un poco castradora) transnacional: desde el rictus comunista a la sobriedad jud\u00eda ortodoxa, pasando por la hero\u00edna manga con kimono y print de vi\u00f1eta de c\u00f3mic.<\/p>\n<p>El factor com\u00fan con el que Jacobs conecta paradas tan distintas en un mismo viaje a la autoridad es el cintur\u00f3n ancho, con una suerte de billetera por hebilla, como si ese ej\u00e9rcito de modelos tuviera lista las \u00f3rdenes de detenci\u00f3n, como si fueran, con sus calcetines almohadillados al estilo \u00abskater\u00bb, la polic\u00eda de la moda.<\/p>\n<p>El rojo y el negro inicial queda roto de golpe con un plateado gal\u00e1ctico. Los lemas como \u00abrevolution\u00bb o \u00abbunny hop\u00bb parecen describir los propios vestidos, y los cuellos de tortuga ahogan a esa mujer dominante pero asexuada.<\/p>\n<p>Vaqueros parcheados, faldas y camisetas pl\u00e1sticas, aparatosas botas blancas con cordones y velcro se combinan con solapas vueltas de terciopelo azul y, finalmente, quiz\u00e1 el elemento m\u00e1s discordante y arriesgado de toda la colecci\u00f3n: el lazo superlativo, que aparece en la cintura como hermosos cintur\u00f3n de castidad o en el cuelo, como remate a una estola con una pajarita estranguladora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nueva York, 12 feb (EFE).- Dos de los ilustres miembros de la primera plana de los dise\u00f1adores latinos en Nueva York, \u00d3scar de la Renta y Narciso Rodr\u00edguez, dieron hoy sendas lecciones de elegancia en la Semana de la Moda, compartiendo cartel con un Marc by Marc Jacobs desenfadado entre el rictus comunista y la<\/p>\n","protected":false},"author":1,"featured_media":3853,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-3852","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Nueva York, 12 feb (EFE).- Dos de los ilustres miembros de la primera plana de los dise\u00f1adores latinos en Nueva York, \u00d3scar de la Renta y Narciso Rodr\u00edguez, dieron hoy sendas lecciones de elegancia en la Semana de la Moda, compartiendo cartel con un Marc by Marc Jacobs desenfadado entre el rictus comunista y la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Jornada de alto nivel con Rodr\u00edguez, De la Renta y Marc by Marc Jacobs | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Nueva York, 12 feb (EFE).- Dos de los ilustres miembros de la primera plana de los dise\u00f1adores latinos en Nueva York, \u00d3scar de la Renta y Narciso Rodr\u00edguez, dieron hoy sendas lecciones de elegancia en la Semana de la Moda, compartiendo cartel con un Marc by Marc Jacobs desenfadado entre el rictus comunista y la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934721w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934721w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-13T02:56:52+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-13T02:56:52+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Jornada de alto nivel con Rodr\u00edguez, De la Renta y Marc by Marc Jacobs | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Nueva York, 12 feb (EFE).- Dos de los ilustres miembros de la primera plana de los dise\u00f1adores latinos en Nueva York, \u00d3scar de la Renta y Narciso Rodr\u00edguez, dieron hoy sendas lecciones de elegancia en la Semana de la Moda, compartiendo cartel con un Marc by Marc Jacobs desenfadado entre el rictus comunista y la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934721w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\\\/#article\",\"name\":\"Jornada de alto nivel con Rodr\\u00edguez, De la Renta y Marc by Marc Jacobs | El Digital de Asturias\",\"headline\":\"Jornada de alto nivel con Rodr\\u00edguez, De la Renta y Marc by Marc Jacobs\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5934721w.jpg\",\"width\":800,\"height\":525},\"datePublished\":\"2014-02-13T01:56:52+01:00\",\"dateModified\":\"2014-02-13T01:56:52+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\\\/#listItem\",\"name\":\"Jornada de alto nivel con Rodr\\u00edguez, De la Renta y Marc by Marc Jacobs\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\\\/#listItem\",\"position\":3,\"name\":\"Jornada de alto nivel con Rodr\\u00edguez, De la Renta y Marc by Marc Jacobs\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\\\/\",\"name\":\"Jornada de alto nivel con Rodr\\u00edguez, De la Renta y Marc by Marc Jacobs | El Digital de Asturias\",\"description\":\"Nueva York, 12 feb (EFE).- Dos de los ilustres miembros de la primera plana de los dise\\u00f1adores latinos en Nueva York, \\u00d3scar de la Renta y Narciso Rodr\\u00edguez, dieron hoy sendas lecciones de elegancia en la Semana de la Moda, compartiendo cartel con un Marc by Marc Jacobs desenfadado entre el rictus comunista y la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5934721w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\\\/#mainImage\",\"width\":800,\"height\":525},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\\\/#mainImage\"},\"datePublished\":\"2014-02-13T01:56:52+01:00\",\"dateModified\":\"2014-02-13T01:56:52+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Jornada de alto nivel con Rodr\u00edguez, De la Renta y Marc by Marc Jacobs | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Jornada de alto nivel con Rodr\u00edguez, De la Renta y Marc by Marc Jacobs | El Digital de Asturias","description":"Nueva York, 12 feb (EFE).- Dos de los ilustres miembros de la primera plana de los dise\u00f1adores latinos en Nueva York, \u00d3scar de la Renta y Narciso Rodr\u00edguez, dieron hoy sendas lecciones de elegancia en la Semana de la Moda, compartiendo cartel con un Marc by Marc Jacobs desenfadado entre el rictus comunista y la","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/#article","name":"Jornada de alto nivel con Rodr\u00edguez, De la Renta y Marc by Marc Jacobs | El Digital de Asturias","headline":"Jornada de alto nivel con Rodr\u00edguez, De la Renta y Marc by Marc Jacobs","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934721w.jpg","width":800,"height":525},"datePublished":"2014-02-13T01:56:52+01:00","dateModified":"2014-02-13T01:56:52+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/#listItem","name":"Jornada de alto nivel con Rodr\u00edguez, De la Renta y Marc by Marc Jacobs"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/#listItem","position":3,"name":"Jornada de alto nivel con Rodr\u00edguez, De la Renta y Marc by Marc Jacobs","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/","name":"Jornada de alto nivel con Rodr\u00edguez, De la Renta y Marc by Marc Jacobs | El Digital de Asturias","description":"Nueva York, 12 feb (EFE).- Dos de los ilustres miembros de la primera plana de los dise\u00f1adores latinos en Nueva York, \u00d3scar de la Renta y Narciso Rodr\u00edguez, dieron hoy sendas lecciones de elegancia en la Semana de la Moda, compartiendo cartel con un Marc by Marc Jacobs desenfadado entre el rictus comunista y la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934721w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/#mainImage","width":800,"height":525},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/#mainImage"},"datePublished":"2014-02-13T01:56:52+01:00","dateModified":"2014-02-13T01:56:52+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Jornada de alto nivel con Rodr\u00edguez, De la Renta y Marc by Marc Jacobs | El Digital de Asturias","og:description":"Nueva York, 12 feb (EFE).- Dos de los ilustres miembros de la primera plana de los dise\u00f1adores latinos en Nueva York, \u00d3scar de la Renta y Narciso Rodr\u00edguez, dieron hoy sendas lecciones de elegancia en la Semana de la Moda, compartiendo cartel con un Marc by Marc Jacobs desenfadado entre el rictus comunista y la","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934721w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934721w.jpg","og:image:width":800,"og:image:height":525,"article:published_time":"2014-02-13T02:56:52+00:00","article:modified_time":"2014-02-13T02:56:52+00:00","twitter:card":"summary_large_image","twitter:title":"Jornada de alto nivel con Rodr\u00edguez, De la Renta y Marc by Marc Jacobs | El Digital de Asturias","twitter:description":"Nueva York, 12 feb (EFE).- Dos de los ilustres miembros de la primera plana de los dise\u00f1adores latinos en Nueva York, \u00d3scar de la Renta y Narciso Rodr\u00edguez, dieron hoy sendas lecciones de elegancia en la Semana de la Moda, compartiendo cartel con un Marc by Marc Jacobs desenfadado entre el rictus comunista y la","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934721w.jpg"},"aioseo_meta_data":{"post_id":"3852","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 10:59:12","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:49:52","updated":"2026-05-15 10:59:12"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/\" title=\"Jornada de alto nivel con Rodr\u00edguez, De la Renta y Marc by Marc Jacobs\">Jornada de alto nivel con Rodr\u00edguez, De la Renta y Marc by Marc Jacobs<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Jornada de alto nivel con Rodr\u00edguez, De la Renta y Marc by Marc Jacobs","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/jornada-de-alto-nivel-con-rodriguez-de-la-renta-y-marc-by-marc-jacobs\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=3852"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3852\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/3853"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=3852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=3852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=3852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}