{"id":3849,"date":"2014-02-13T01:55:14","date_gmt":"2014-02-13T02:55:14","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=3849"},"modified":"2014-02-13T01:58:08","modified_gmt":"2014-02-13T02:58:08","slug":"hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/","title":{"rendered":"Hallan un biomarcador que predice la supervivencia en pacientes con c\u00e1ncer renal"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3850\" alt=\"5935374w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5935374w-360x259.jpg\" width=\"360\" height=\"259\" \/>Barcelona, 12 feb (EFE).- Investigadores del Vall d&#8217;Hebron Institut de Recerca (VHIR) han identificado por primera vez un nuevo biomarcador, el &#8216;pSTAT-3 Ser727&#8217;, presente en los tumores de c\u00e1ncer renal de c\u00e9lula clara, uno de los m\u00e1s frecuentes y agresivos, que predice la supervivencia de los pacientes.<\/p>\n<p>La investigaci\u00f3n, llevada a cabo por el grupo de Fisiolog\u00eda Renal del CIBBIM-Nanomedicina en el VHIR y el Servicio de Urolog\u00eda y Anatom\u00eda Patol\u00f3gica del Hospital Vall d&#8217;Hebron, se publica hoy en la revista \u00abCancer Research\u00bb, y, seg\u00fan los investigadores, supone un cambio de paradigma en el tratamiento de los pacientes.<\/p>\n<p>\u00abEl tumor aparentemente m\u00e1s benigno puede llegar a ser tan grave como los m\u00e1s invasivos si los niveles del biomarcador son altos\u00bb, ha explicado Anna Meseguer, responsable de la investigaci\u00f3n, que ha analizado una muestra de 98 pacientes con c\u00e1ncer renal atendidos en el Hospital Vall d&#8217;Hebron, con m\u00e1s de 5 a\u00f1os de seguimiento cl\u00ednico.<\/p>\n<p>A partir de la presencia del biomarcador en una muestra tumoral, los investigadores han comprobado que \u00abtumores aparentemente similares pueden comportarse de forma muy diferente y determinar la supervivencia de los pacientes, que puede oscilar entre 17 y m\u00e1s de 70 meses\u00bb, seg\u00fan la doctora Meseguer.<\/p>\n<p>El c\u00e1ncer renal de c\u00e9lula clara (ccRCC) es el tipo m\u00e1s agresivo y frecuente de todas las formas de c\u00e1ncer renal y se caracteriza por la falta de s\u00edntomas o anomal\u00edas bioqu\u00edmicas para detectarlo.<\/p>\n<p>Actualmente no existen m\u00e9todos de diagn\u00f3stico y pron\u00f3stico y, por ello, frecuentemente se descubre por sorpresa, seg\u00fan los especialistas.<\/p>\n<p>\u00abCerca de un 30 % de los pacientes con ccRCC se diagnostican demasiado tarde, generalmente de forma incidental cuando se someten a otra prueba de imagen para el estudio de otros s\u00edntomas\u00bb, ha explicado el doctor Enric Trilla, m\u00e9dico adjunto del Servicio de Urolog\u00eda del Hospital Vall d&#8217;Hebron.<\/p>\n<p>\u00abEn estos casos -ha lamentado- suele ser demasiado tarde porque ya han desarrollado met\u00e1stasis y la tasa de mortalidad es del 95 %\u00bb.<\/p>\n<p>El m\u00e9dico ha advertido de que \u00abun tercio de los pacientes con tumores de ccRCC localizados que se tratan con nefrectom\u00eda (extirpaci\u00f3n del ri\u00f1\u00f3n) tambi\u00e9n desarrollan met\u00e1stasis en los meses posteriores a la cirug\u00eda\u00bb.<\/p>\n<p>El diagn\u00f3stico y la monitorizaci\u00f3n del ccRCC requieren continuas y caras pruebas de imagen que no permiten hacer un diagn\u00f3stico precoz de la enfermedad ni predecir c\u00f3mo evolucionar\u00e1 el tumor.<\/p>\n<p>Por eso, los m\u00e9dicos no disponen de marcadores para recomendar de forma fiable el mejor tratamiento, ya sea nefrectom\u00eda, total o parcial, u otros tratamientos.<\/p>\n<p>Con el descubrimiento del biomarcador &#8216;pSTAT-3 Ser727&#8217;, que ya se ha protegido con una patente europea (PTC), los investigadores quieren desarrollar un sistema para introducirlo de forma rutinaria.<\/p>\n<p>\u00abSu uso en la pr\u00e1ctica cl\u00ednica ayudar\u00eda mucho a estratificar mejor a los pacientes y a hacer un seguimiento y tratamiento m\u00e1s preciso en funci\u00f3n de los niveles del marcador\u00bb, ha dicho Trilla.<\/p>\n<p>Con este nuevo marcador se podr\u00eda, por ejemplo, evitar la nefrectom\u00eda en pacientes que presentan tumores peque\u00f1os, inferiores a 4 cent\u00edmetros de di\u00e1metro, si se determina que son de buen pron\u00f3stico, ya que dependiendo de las condiciones del paciente, como la edad avanzada, los problemas cardiovasculares y la diabetes, la extirpaci\u00f3n del tumor es un riesgo m\u00e1s alto que la posibilidad de met\u00e1stasis o crecimiento del tumor.<\/p>\n<p>Los investigadores est\u00e1n ahora en fase de valoraci\u00f3n de una patente europea, validando la pSTAT-3 Ser727 como marcador de supervivencia en una segunda muestra de 125 pacientes con ccRCC y 5 a\u00f1os de seguimiento, y desarrollando una aplicaci\u00f3n inform\u00e1tica que cuantifique autom\u00e1ticamente el biomarcador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Barcelona, 12 feb (EFE).- Investigadores del Vall d&#8217;Hebron Institut de Recerca (VHIR) han identificado por primera vez un nuevo biomarcador, el &#8216;pSTAT-3 Ser727&#8217;, presente en los tumores de c\u00e1ncer renal de c\u00e9lula clara, uno de los m\u00e1s frecuentes y agresivos, que predice la supervivencia de los pacientes. La investigaci\u00f3n, llevada a cabo por el grupo<\/p>\n","protected":false},"author":1,"featured_media":3850,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-3849","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Barcelona, 12 feb (EFE).- Investigadores del Vall d&#039;Hebron Institut de Recerca (VHIR) han identificado por primera vez un nuevo biomarcador, el &#039;pSTAT-3 Ser727&#039;, presente en los tumores de c\u00e1ncer renal de c\u00e9lula clara, uno de los m\u00e1s frecuentes y agresivos, que predice la supervivencia de los pacientes. La investigaci\u00f3n, llevada a cabo por el grupo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Hallan un biomarcador que predice la supervivencia en pacientes con c\u00e1ncer renal | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Barcelona, 12 feb (EFE).- Investigadores del Vall d&#039;Hebron Institut de Recerca (VHIR) han identificado por primera vez un nuevo biomarcador, el &#039;pSTAT-3 Ser727&#039;, presente en los tumores de c\u00e1ncer renal de c\u00e9lula clara, uno de los m\u00e1s frecuentes y agresivos, que predice la supervivencia de los pacientes. La investigaci\u00f3n, llevada a cabo por el grupo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5935374w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5935374w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"577\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-13T02:55:14+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-13T02:58:08+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Hallan un biomarcador que predice la supervivencia en pacientes con c\u00e1ncer renal | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Barcelona, 12 feb (EFE).- Investigadores del Vall d&#039;Hebron Institut de Recerca (VHIR) han identificado por primera vez un nuevo biomarcador, el &#039;pSTAT-3 Ser727&#039;, presente en los tumores de c\u00e1ncer renal de c\u00e9lula clara, uno de los m\u00e1s frecuentes y agresivos, que predice la supervivencia de los pacientes. La investigaci\u00f3n, llevada a cabo por el grupo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5935374w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\\\/#article\",\"name\":\"Hallan un biomarcador que predice la supervivencia en pacientes con c\\u00e1ncer renal | El Digital de Asturias\",\"headline\":\"Hallan un biomarcador que predice la supervivencia en pacientes con c\\u00e1ncer renal\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5935374w.jpg\",\"width\":800,\"height\":577},\"datePublished\":\"2014-02-13T01:55:14+01:00\",\"dateModified\":\"2014-02-13T01:58:08+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\\\/#listItem\",\"name\":\"Hallan un biomarcador que predice la supervivencia en pacientes con c\\u00e1ncer renal\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\\\/#listItem\",\"position\":3,\"name\":\"Hallan un biomarcador que predice la supervivencia en pacientes con c\\u00e1ncer renal\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\\\/\",\"name\":\"Hallan un biomarcador que predice la supervivencia en pacientes con c\\u00e1ncer renal | El Digital de Asturias\",\"description\":\"Barcelona, 12 feb (EFE).- Investigadores del Vall d'Hebron Institut de Recerca (VHIR) han identificado por primera vez un nuevo biomarcador, el 'pSTAT-3 Ser727', presente en los tumores de c\\u00e1ncer renal de c\\u00e9lula clara, uno de los m\\u00e1s frecuentes y agresivos, que predice la supervivencia de los pacientes. La investigaci\\u00f3n, llevada a cabo por el grupo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5935374w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\\\/#mainImage\",\"width\":800,\"height\":577},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\\\/#mainImage\"},\"datePublished\":\"2014-02-13T01:55:14+01:00\",\"dateModified\":\"2014-02-13T01:58:08+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Hallan un biomarcador que predice la supervivencia en pacientes con c\u00e1ncer renal | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Hallan un biomarcador que predice la supervivencia en pacientes con c\u00e1ncer renal | El Digital de Asturias","description":"Barcelona, 12 feb (EFE).- Investigadores del Vall d'Hebron Institut de Recerca (VHIR) han identificado por primera vez un nuevo biomarcador, el 'pSTAT-3 Ser727', presente en los tumores de c\u00e1ncer renal de c\u00e9lula clara, uno de los m\u00e1s frecuentes y agresivos, que predice la supervivencia de los pacientes. La investigaci\u00f3n, llevada a cabo por el grupo","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/#article","name":"Hallan un biomarcador que predice la supervivencia en pacientes con c\u00e1ncer renal | El Digital de Asturias","headline":"Hallan un biomarcador que predice la supervivencia en pacientes con c\u00e1ncer renal","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5935374w.jpg","width":800,"height":577},"datePublished":"2014-02-13T01:55:14+01:00","dateModified":"2014-02-13T01:58:08+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/#listItem","name":"Hallan un biomarcador que predice la supervivencia en pacientes con c\u00e1ncer renal"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/#listItem","position":3,"name":"Hallan un biomarcador que predice la supervivencia en pacientes con c\u00e1ncer renal","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/","name":"Hallan un biomarcador que predice la supervivencia en pacientes con c\u00e1ncer renal | El Digital de Asturias","description":"Barcelona, 12 feb (EFE).- Investigadores del Vall d'Hebron Institut de Recerca (VHIR) han identificado por primera vez un nuevo biomarcador, el 'pSTAT-3 Ser727', presente en los tumores de c\u00e1ncer renal de c\u00e9lula clara, uno de los m\u00e1s frecuentes y agresivos, que predice la supervivencia de los pacientes. La investigaci\u00f3n, llevada a cabo por el grupo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5935374w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/#mainImage","width":800,"height":577},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/#mainImage"},"datePublished":"2014-02-13T01:55:14+01:00","dateModified":"2014-02-13T01:58:08+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Hallan un biomarcador que predice la supervivencia en pacientes con c\u00e1ncer renal | El Digital de Asturias","og:description":"Barcelona, 12 feb (EFE).- Investigadores del Vall d'Hebron Institut de Recerca (VHIR) han identificado por primera vez un nuevo biomarcador, el 'pSTAT-3 Ser727', presente en los tumores de c\u00e1ncer renal de c\u00e9lula clara, uno de los m\u00e1s frecuentes y agresivos, que predice la supervivencia de los pacientes. La investigaci\u00f3n, llevada a cabo por el grupo","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5935374w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5935374w.jpg","og:image:width":800,"og:image:height":577,"article:published_time":"2014-02-13T02:55:14+00:00","article:modified_time":"2014-02-13T02:58:08+00:00","twitter:card":"summary_large_image","twitter:title":"Hallan un biomarcador que predice la supervivencia en pacientes con c\u00e1ncer renal | El Digital de Asturias","twitter:description":"Barcelona, 12 feb (EFE).- Investigadores del Vall d'Hebron Institut de Recerca (VHIR) han identificado por primera vez un nuevo biomarcador, el 'pSTAT-3 Ser727', presente en los tumores de c\u00e1ncer renal de c\u00e9lula clara, uno de los m\u00e1s frecuentes y agresivos, que predice la supervivencia de los pacientes. La investigaci\u00f3n, llevada a cabo por el grupo","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5935374w.jpg"},"aioseo_meta_data":{"post_id":"3849","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 10:59:09","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:49:52","updated":"2026-05-15 10:59:09"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/\" title=\"Hallan un biomarcador que predice la supervivencia en pacientes con c\u00e1ncer renal\">Hallan un biomarcador que predice la supervivencia en pacientes con c\u00e1ncer renal<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Hallan un biomarcador que predice la supervivencia en pacientes con c\u00e1ncer renal","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/hallan-un-biomarcador-que-predice-la-supervivencia-en-pacientes-con-cancer-renal\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=3849"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3849\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/3850"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=3849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=3849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=3849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}