{"id":38266,"date":"2015-05-11T10:25:24","date_gmt":"2015-05-11T08:55:24","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=38266"},"modified":"2015-05-11T10:25:24","modified_gmt":"2015-05-11T08:55:24","slug":"cuanto-gastan-los-espanoles-en-sus-vacaciones","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/","title":{"rendered":"\u00bfCu\u00e1nto gastan los espa\u00f1oles en sus vacaciones?"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-38267\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/05\/cuanto-gastan-los-espanoles-en-sus-vacaciones-680x284-360x150.jpg\" alt=\"cuanto-gastan-los-espanoles-en-sus-vacaciones-680x284\" width=\"360\" height=\"150\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/05\/cuanto-gastan-los-espanoles-en-sus-vacaciones-680x284-360x150.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/05\/cuanto-gastan-los-espanoles-en-sus-vacaciones-680x284-650x271.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/05\/cuanto-gastan-los-espanoles-en-sus-vacaciones-680x284-150x63.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/05\/cuanto-gastan-los-espanoles-en-sus-vacaciones-680x284-450x188.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/05\/cuanto-gastan-los-espanoles-en-sus-vacaciones-680x284.jpg 680w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Gracias a TripAdvisor se han desvelado interesantes datos acerca de las costumbres de los viajeros espa\u00f1oles, algo que viene a ser de gran relevancia ahora que nos acercamos al verano. Y aunque puede que saber cu\u00e1nto dinero se gastan los espa\u00f1oles no afecte mucho a las vacaciones que estamos planificando, s\u00ed nos ayudar\u00e1 a guiarnos para saber si estamos en la media o si nos estamos quedando cortos.<\/p>\n<p>Lo cierto es que los resultados son poco determinantes, con porcentajes que est\u00e1n demasiado repartidos entre los distintos rangos de presupuesto. El mayor porcentaje, con poca distancia respecto a los dem\u00e1s, es un 15% y est\u00e1 concentrado en un presupuesto vacacional de entre 1001 y 1500 euros. El segundo mayor porcentaje es un 14% y est\u00e1 englobado en el presupuesto de entre 501 y 800 euros. Como tercera posici\u00f3n, curiosamente, est\u00e1 el grupo de personas que gastan m\u00e1s de 3000 euros en las vacaciones, con un 13%.<\/p>\n<p>La bajada es progresiva y tambi\u00e9n apreciamos que con un 11% coinciden los rangos de entre 801 y 1000 euros y de 201 a 500 euros. En el final de la tabla destaca el presupuesto inferior a los 100 euros, que solo obtiene, de forma bastante l\u00f3gica, una proporci\u00f3n del 1%. Esto es muy determinante a la hora de entender los h\u00e1bitos de consumo de los espa\u00f1oles en vacaciones.<\/p>\n<p>Si valoramos los cambios de presupuesto respecto al a\u00f1o pasado, lo m\u00e1s destacado es que un 61% de los espa\u00f1oles pretende mantener exactamente el mismo nivel de gasto que asumi\u00f3 en las vacaciones del pasado a\u00f1o. Solo un 21% se ha planteado gastar m\u00e1s dinero, aunque las cifras no difieren mucho de las que se registraron en a\u00f1os anteriores. Otro dato interesante que ha aportado TripAdvisor es que el 90% de los espa\u00f1oles tiene intenci\u00f3n de viajar en este verano de 2015, lo que s\u00ed se trata de una buena estad\u00edstica en comparaci\u00f3n a las registradas en otros periodos.<\/p>\n<p>Espa\u00f1a sigue siendo un destino ideal para los propios espa\u00f1oles, que cada vez encuentran un mayor atractivo en quedarse en el pa\u00eds en vez de salir al extranjero para disfrutar de grandes experiencias. La variedad del turismo espa\u00f1ol ha ayudado a que los principales destinos se vean potenciados, fomentando las reservas en complejos de playa, pero mejorando incluso los viajes de interior. Los turistas del extranjero tambi\u00e9n se est\u00e1n viendo arrastrados por nuestro pa\u00eds en una clara demostraci\u00f3n de c\u00f3mo Espa\u00f1a est\u00e1 recuper\u00e1ndose de manera muy s\u00f3lida gracias a las \u00faltimas novedades de las que est\u00e1n disfrutando sus destinos m\u00e1s populares.<\/p>\n<p>V\u00eda: TripAdvisor<\/p>\n<p>Foto: cascalheira<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gracias a TripAdvisor se han desvelado interesantes datos acerca de las costumbres de los viajeros espa\u00f1oles, algo que viene a ser de gran relevancia ahora que nos acercamos al verano. Y aunque puede que saber cu\u00e1nto dinero se gastan los espa\u00f1oles no afecte mucho a las vacaciones que estamos planificando, s\u00ed nos ayudar\u00e1 a guiarnos<\/p>\n","protected":false},"author":1,"featured_media":38267,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-38266","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Gracias a TripAdvisor se han desvelado interesantes datos acerca de las costumbres de los viajeros espa\u00f1oles, algo que viene a ser de gran relevancia ahora que nos acercamos al verano. Y aunque puede que saber cu\u00e1nto dinero se gastan los espa\u00f1oles no afecte mucho a las vacaciones que estamos planificando, s\u00ed nos ayudar\u00e1 a guiarnos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00bfCu\u00e1nto gastan los espa\u00f1oles en sus vacaciones? | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Gracias a TripAdvisor se han desvelado interesantes datos acerca de las costumbres de los viajeros espa\u00f1oles, algo que viene a ser de gran relevancia ahora que nos acercamos al verano. Y aunque puede que saber cu\u00e1nto dinero se gastan los espa\u00f1oles no afecte mucho a las vacaciones que estamos planificando, s\u00ed nos ayudar\u00e1 a guiarnos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/05\/cuanto-gastan-los-espanoles-en-sus-vacaciones-680x284.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/05\/cuanto-gastan-los-espanoles-en-sus-vacaciones-680x284.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t\t<meta property=\"og:image:height\" content=\"284\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-05-11T08:55:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-05-11T08:55:24+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00bfCu\u00e1nto gastan los espa\u00f1oles en sus vacaciones? | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Gracias a TripAdvisor se han desvelado interesantes datos acerca de las costumbres de los viajeros espa\u00f1oles, algo que viene a ser de gran relevancia ahora que nos acercamos al verano. Y aunque puede que saber cu\u00e1nto dinero se gastan los espa\u00f1oles no afecte mucho a las vacaciones que estamos planificando, s\u00ed nos ayudar\u00e1 a guiarnos\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/05\/cuanto-gastan-los-espanoles-en-sus-vacaciones-680x284.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cuanto-gastan-los-espanoles-en-sus-vacaciones\\\/#article\",\"name\":\"\\u00bfCu\\u00e1nto gastan los espa\\u00f1oles en sus vacaciones? | El Digital de Asturias\",\"headline\":\"\\u00bfCu\\u00e1nto gastan los espa\\u00f1oles en sus vacaciones?\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/cuanto-gastan-los-espanoles-en-sus-vacaciones-680x284.jpg\",\"width\":680,\"height\":284},\"datePublished\":\"2015-05-11T10:25:24+02:00\",\"dateModified\":\"2015-05-11T10:25:24+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cuanto-gastan-los-espanoles-en-sus-vacaciones\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cuanto-gastan-los-espanoles-en-sus-vacaciones\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cuanto-gastan-los-espanoles-en-sus-vacaciones\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cuanto-gastan-los-espanoles-en-sus-vacaciones\\\/#listItem\",\"name\":\"\\u00bfCu\\u00e1nto gastan los espa\\u00f1oles en sus vacaciones?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cuanto-gastan-los-espanoles-en-sus-vacaciones\\\/#listItem\",\"position\":3,\"name\":\"\\u00bfCu\\u00e1nto gastan los espa\\u00f1oles en sus vacaciones?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cuanto-gastan-los-espanoles-en-sus-vacaciones\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cuanto-gastan-los-espanoles-en-sus-vacaciones\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cuanto-gastan-los-espanoles-en-sus-vacaciones\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cuanto-gastan-los-espanoles-en-sus-vacaciones\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cuanto-gastan-los-espanoles-en-sus-vacaciones\\\/\",\"name\":\"\\u00bfCu\\u00e1nto gastan los espa\\u00f1oles en sus vacaciones? | El Digital de Asturias\",\"description\":\"Gracias a TripAdvisor se han desvelado interesantes datos acerca de las costumbres de los viajeros espa\\u00f1oles, algo que viene a ser de gran relevancia ahora que nos acercamos al verano. Y aunque puede que saber cu\\u00e1nto dinero se gastan los espa\\u00f1oles no afecte mucho a las vacaciones que estamos planificando, s\\u00ed nos ayudar\\u00e1 a guiarnos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cuanto-gastan-los-espanoles-en-sus-vacaciones\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/cuanto-gastan-los-espanoles-en-sus-vacaciones-680x284.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cuanto-gastan-los-espanoles-en-sus-vacaciones\\\/#mainImage\",\"width\":680,\"height\":284},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cuanto-gastan-los-espanoles-en-sus-vacaciones\\\/#mainImage\"},\"datePublished\":\"2015-05-11T10:25:24+02:00\",\"dateModified\":\"2015-05-11T10:25:24+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>\u00bfCu\u00e1nto gastan los espa\u00f1oles en sus vacaciones? | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"\u00bfCu\u00e1nto gastan los espa\u00f1oles en sus vacaciones? | El Digital de Asturias","description":"Gracias a TripAdvisor se han desvelado interesantes datos acerca de las costumbres de los viajeros espa\u00f1oles, algo que viene a ser de gran relevancia ahora que nos acercamos al verano. Y aunque puede que saber cu\u00e1nto dinero se gastan los espa\u00f1oles no afecte mucho a las vacaciones que estamos planificando, s\u00ed nos ayudar\u00e1 a guiarnos","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/#article","name":"\u00bfCu\u00e1nto gastan los espa\u00f1oles en sus vacaciones? | El Digital de Asturias","headline":"\u00bfCu\u00e1nto gastan los espa\u00f1oles en sus vacaciones?","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/05\/cuanto-gastan-los-espanoles-en-sus-vacaciones-680x284.jpg","width":680,"height":284},"datePublished":"2015-05-11T10:25:24+02:00","dateModified":"2015-05-11T10:25:24+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/#listItem","name":"\u00bfCu\u00e1nto gastan los espa\u00f1oles en sus vacaciones?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/#listItem","position":3,"name":"\u00bfCu\u00e1nto gastan los espa\u00f1oles en sus vacaciones?","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/","name":"\u00bfCu\u00e1nto gastan los espa\u00f1oles en sus vacaciones? | El Digital de Asturias","description":"Gracias a TripAdvisor se han desvelado interesantes datos acerca de las costumbres de los viajeros espa\u00f1oles, algo que viene a ser de gran relevancia ahora que nos acercamos al verano. Y aunque puede que saber cu\u00e1nto dinero se gastan los espa\u00f1oles no afecte mucho a las vacaciones que estamos planificando, s\u00ed nos ayudar\u00e1 a guiarnos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/05\/cuanto-gastan-los-espanoles-en-sus-vacaciones-680x284.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/#mainImage","width":680,"height":284},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/#mainImage"},"datePublished":"2015-05-11T10:25:24+02:00","dateModified":"2015-05-11T10:25:24+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"\u00bfCu\u00e1nto gastan los espa\u00f1oles en sus vacaciones? | El Digital de Asturias","og:description":"Gracias a TripAdvisor se han desvelado interesantes datos acerca de las costumbres de los viajeros espa\u00f1oles, algo que viene a ser de gran relevancia ahora que nos acercamos al verano. Y aunque puede que saber cu\u00e1nto dinero se gastan los espa\u00f1oles no afecte mucho a las vacaciones que estamos planificando, s\u00ed nos ayudar\u00e1 a guiarnos","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/05\/cuanto-gastan-los-espanoles-en-sus-vacaciones-680x284.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/05\/cuanto-gastan-los-espanoles-en-sus-vacaciones-680x284.jpg","og:image:width":680,"og:image:height":284,"article:published_time":"2015-05-11T08:55:24+00:00","article:modified_time":"2015-05-11T08:55:24+00:00","twitter:card":"summary_large_image","twitter:title":"\u00bfCu\u00e1nto gastan los espa\u00f1oles en sus vacaciones? | El Digital de Asturias","twitter:description":"Gracias a TripAdvisor se han desvelado interesantes datos acerca de las costumbres de los viajeros espa\u00f1oles, algo que viene a ser de gran relevancia ahora que nos acercamos al verano. Y aunque puede que saber cu\u00e1nto dinero se gastan los espa\u00f1oles no afecte mucho a las vacaciones que estamos planificando, s\u00ed nos ayudar\u00e1 a guiarnos","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/05\/cuanto-gastan-los-espanoles-en-sus-vacaciones-680x284.jpg"},"aioseo_meta_data":{"post_id":"38266","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 17:45:01","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 02:55:56","updated":"2026-05-20 17:45:01"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/\" title=\"\u00bfCu\u00e1nto gastan los espa\u00f1oles en sus vacaciones?\">\u00bfCu\u00e1nto gastan los espa\u00f1oles en sus vacaciones?<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"\u00bfCu\u00e1nto gastan los espa\u00f1oles en sus vacaciones?","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/cuanto-gastan-los-espanoles-en-sus-vacaciones\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/38266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=38266"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/38266\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/38267"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=38266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=38266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=38266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}