{"id":3825,"date":"2014-02-13T01:44:00","date_gmt":"2014-02-13T02:44:00","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=3825"},"modified":"2014-02-13T01:44:00","modified_gmt":"2014-02-13T02:44:00","slug":"michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/","title":{"rendered":"Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3826\" alt=\"5934521w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934521w-360x239.jpg\" width=\"360\" height=\"239\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934521w-360x239.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934521w-650x432.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934521w-768x511.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934521w-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934521w-450x299.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934521w-696x463.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934521w-632x420.jpg 632w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934521w-84x55.jpg 84w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934521w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Washington, 12 feb (EFE).- La primera dama de Estados Unidos, Michelle Obama, volvi\u00f3 a confiar en una de sus dise\u00f1adoras favoritas, la venezolano-estadounidense Carolina Herrera, para la cena de Estado del presidente franc\u00e9s, Fran\u00e7ois Hollande, inform\u00f3 la Casa Blanca.<\/p>\n<p>Del modelo destaca el gran vuelo de la falda, larga hasta los pies, y en un tono que la dise\u00f1adora ha bautizado como \u00abazul libertad\u00bb, un a\u00f1il claro.<\/p>\n<p>La parte de arriba, una elegante transparencia con encaje negro de manga tres cuartos, cubre los hombros, una tendencia que ya sigui\u00f3 la primera dama con el modelo escogido para otra gran cita: el discurso sobre el Estado de la Uni\u00f3n en el Capitolio el pasado 28 de enero.<\/p>\n<p>Esta es la primera vez que Michelle, que puso de moda los vestidos sin mangas con su llegada a la Casa Blanca, elige un modelo de este tipo para una cena de Estado.<\/p>\n<p>En ocasiones anteriores opt\u00f3 por lucir sus envidiados hombros torneados con modelos de un s\u00f3lo tirante o con escote palabra de honor.<\/p>\n<p>La primera dama es fiel a Carolina Herrera, una de sus dise\u00f1adoras predilectas. Ya luci\u00f3 creaciones suyas en un evento en Nueva York el pasado oto\u00f1o, as\u00ed como durante su viaje a Alemania el pasado junio.<\/p>\n<p>La dise\u00f1adora nacida en Caracas (Venezuela) visit\u00f3 en el pasado a otras primeras damas, como Laura Bush y Jacqueline Kennedy Onassis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Washington, 12 feb (EFE).- La primera dama de Estados Unidos, Michelle Obama, volvi\u00f3 a confiar en una de sus dise\u00f1adoras favoritas, la venezolano-estadounidense Carolina Herrera, para la cena de Estado del presidente franc\u00e9s, Fran\u00e7ois Hollande, inform\u00f3 la Casa Blanca. Del modelo destaca el gran vuelo de la falda, larga hasta los pies, y en un<\/p>\n","protected":false},"author":1,"featured_media":3826,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-3825","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Washington, 12 feb (EFE).- La primera dama de Estados Unidos, Michelle Obama, volvi\u00f3 a confiar en una de sus dise\u00f1adoras favoritas, la venezolano-estadounidense Carolina Herrera, para la cena de Estado del presidente franc\u00e9s, Fran\u00e7ois Hollande, inform\u00f3 la Casa Blanca. Del modelo destaca el gran vuelo de la falda, larga hasta los pies, y en un\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Washington, 12 feb (EFE).- La primera dama de Estados Unidos, Michelle Obama, volvi\u00f3 a confiar en una de sus dise\u00f1adoras favoritas, la venezolano-estadounidense Carolina Herrera, para la cena de Estado del presidente franc\u00e9s, Fran\u00e7ois Hollande, inform\u00f3 la Casa Blanca. Del modelo destaca el gran vuelo de la falda, larga hasta los pies, y en un\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934521w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934521w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"532\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-13T02:44:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-13T02:44:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Washington, 12 feb (EFE).- La primera dama de Estados Unidos, Michelle Obama, volvi\u00f3 a confiar en una de sus dise\u00f1adoras favoritas, la venezolano-estadounidense Carolina Herrera, para la cena de Estado del presidente franc\u00e9s, Fran\u00e7ois Hollande, inform\u00f3 la Casa Blanca. Del modelo destaca el gran vuelo de la falda, larga hasta los pies, y en un\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934521w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\\\/#article\",\"name\":\"Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande | El Digital de Asturias\",\"headline\":\"Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5934521w.jpg\",\"width\":800,\"height\":532},\"datePublished\":\"2014-02-13T01:44:00+01:00\",\"dateModified\":\"2014-02-13T01:44:00+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\\\/#listItem\",\"name\":\"Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\\\/#listItem\",\"position\":3,\"name\":\"Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\\\/\",\"name\":\"Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande | El Digital de Asturias\",\"description\":\"Washington, 12 feb (EFE).- La primera dama de Estados Unidos, Michelle Obama, volvi\\u00f3 a confiar en una de sus dise\\u00f1adoras favoritas, la venezolano-estadounidense Carolina Herrera, para la cena de Estado del presidente franc\\u00e9s, Fran\\u00e7ois Hollande, inform\\u00f3 la Casa Blanca. Del modelo destaca el gran vuelo de la falda, larga hasta los pies, y en un\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5934521w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\\\/#mainImage\",\"width\":800,\"height\":532},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\\\/#mainImage\"},\"datePublished\":\"2014-02-13T01:44:00+01:00\",\"dateModified\":\"2014-02-13T01:44:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande | El Digital de Asturias","description":"Washington, 12 feb (EFE).- La primera dama de Estados Unidos, Michelle Obama, volvi\u00f3 a confiar en una de sus dise\u00f1adoras favoritas, la venezolano-estadounidense Carolina Herrera, para la cena de Estado del presidente franc\u00e9s, Fran\u00e7ois Hollande, inform\u00f3 la Casa Blanca. Del modelo destaca el gran vuelo de la falda, larga hasta los pies, y en un","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/#article","name":"Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande | El Digital de Asturias","headline":"Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934521w.jpg","width":800,"height":532},"datePublished":"2014-02-13T01:44:00+01:00","dateModified":"2014-02-13T01:44:00+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/#listItem","name":"Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/#listItem","position":3,"name":"Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/","name":"Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande | El Digital de Asturias","description":"Washington, 12 feb (EFE).- La primera dama de Estados Unidos, Michelle Obama, volvi\u00f3 a confiar en una de sus dise\u00f1adoras favoritas, la venezolano-estadounidense Carolina Herrera, para la cena de Estado del presidente franc\u00e9s, Fran\u00e7ois Hollande, inform\u00f3 la Casa Blanca. Del modelo destaca el gran vuelo de la falda, larga hasta los pies, y en un","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934521w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/#mainImage","width":800,"height":532},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/#mainImage"},"datePublished":"2014-02-13T01:44:00+01:00","dateModified":"2014-02-13T01:44:00+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande | El Digital de Asturias","og:description":"Washington, 12 feb (EFE).- La primera dama de Estados Unidos, Michelle Obama, volvi\u00f3 a confiar en una de sus dise\u00f1adoras favoritas, la venezolano-estadounidense Carolina Herrera, para la cena de Estado del presidente franc\u00e9s, Fran\u00e7ois Hollande, inform\u00f3 la Casa Blanca. Del modelo destaca el gran vuelo de la falda, larga hasta los pies, y en un","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934521w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934521w.jpg","og:image:width":800,"og:image:height":532,"article:published_time":"2014-02-13T02:44:00+00:00","article:modified_time":"2014-02-13T02:44:00+00:00","twitter:card":"summary_large_image","twitter:title":"Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande | El Digital de Asturias","twitter:description":"Washington, 12 feb (EFE).- La primera dama de Estados Unidos, Michelle Obama, volvi\u00f3 a confiar en una de sus dise\u00f1adoras favoritas, la venezolano-estadounidense Carolina Herrera, para la cena de Estado del presidente franc\u00e9s, Fran\u00e7ois Hollande, inform\u00f3 la Casa Blanca. Del modelo destaca el gran vuelo de la falda, larga hasta los pies, y en un","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5934521w.jpg"},"aioseo_meta_data":{"post_id":"3825","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 10:55:53","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:49:50","updated":"2026-05-15 10:55:53"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/\" title=\"Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande\">Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Michelle Obama vuelve a confiar en Carolina Herrera para la cena con Hollande","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/michelle-obama-vuelve-a-confiar-en-carolina-herrera-para-la-cena-con-hollande\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=3825"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3825\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/3826"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=3825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=3825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=3825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}