{"id":3756,"date":"2014-02-11T23:48:15","date_gmt":"2014-02-12T00:48:15","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=3756"},"modified":"2014-02-11T23:48:15","modified_gmt":"2014-02-12T00:48:15","slug":"bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/","title":{"rendered":"Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3757\" alt=\"5932357w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5932357w-360x239.jpg\" width=\"360\" height=\"239\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5932357w-360x239.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5932357w-650x432.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5932357w-768x511.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5932357w-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5932357w-450x299.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5932357w-696x463.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5932357w-632x420.jpg 632w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5932357w-84x55.jpg 84w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5932357w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Barcelona, 11 feb (EFE).- Bryan Ferry, Estopa, Nacho Vegas y The Stranglers son algunos de los 30 artistas que actuar\u00e1n en el 25 Festival de Guitarra de Barcelona, que empezar\u00e1 el pr\u00f3ximo 20 de febrero y que este a\u00f1o ampl\u00eda su presupuesto y n\u00famero de entradas puestas a la venta.<\/p>\n<p>Con 840.000 euros de presupuesto y m\u00e1s de 50.000 entradas a la venta, el festival se convierte, seg\u00fan sus organizadores, la promotora The Project -que dirigen Tito Ramoneda y Joan Rosell\u00f3-, en la \u00abmejor y m\u00e1s atractiva edici\u00f3n de su historia\u00bb, caracterizada por las yuxtaposici\u00f3n de conciertos de gran formato, tanto de artistas internacionales como locales, junto a conciertos m\u00e1s minimalistas.<\/p>\n<p>La guitarra como elemento transmisor y la recuperaci\u00f3n de grupos y artistas hist\u00f3ricos siguen siendo, como en el a\u00f1o anterior, el eje que vertebra la programaci\u00f3n de este a\u00f1o.<\/p>\n<p>Habr\u00e1 propuestas como la de la banda brit\u00e1nica Fanfarlo, de la que David Bowie se ha declarado fan absoluto y que abrir\u00e1n el festival el 20 de febrero.<\/p>\n<p>O el cantante brit\u00e1nico Neil Halstead, que interpretar\u00e1 el disco \u00abThe Velvet Underground &amp; Nico\u00bb -15 de marzo-, y los legendarios The Stranglers -1 de abril-, que este a\u00f1o celebran su 40 aniversario.<\/p>\n<p>Son algunos de los conciertos que traspasan las fronteras del g\u00e9nero y tienen la guitarra como elemento transmisor, con la finalidad de acercarse a un p\u00fablico joven, urbano y moderno.<\/p>\n<p>Dentro de este nivel tambi\u00e9n se inscriben actuaciones como la del nigeriano Femi Kuti &amp; The Positive Force -24 de abril-, el concierto de Loquillo -8 de mayo-, o del cantautor gijon\u00e9s Nacho Vegas y su nuevo \u00e1lbum, \u00abResituaci\u00f3n\u00bb -22 de mayo-.<\/p>\n<p>El Festival de Guitarra tambi\u00e9n ha querido resaltar el trabajo de tres sellos catalanes de las escena independiente catalana como Primavera Sound, Bankrobber y Music Bus.<\/p>\n<p>Por otro lado, el festival recuperar\u00e1 grupos hist\u00f3ricos o artistas con una larga trayectoria como es el caso de la cantante Luz -20 de marzo-; cuatro conciertos del d\u00fao Estopa, que presentan un nuevo espect\u00e1culo ac\u00fastico con direcci\u00f3n esc\u00e9nica de Andreu Bonafuente -del 10 al 13 de abril-; o un concierto del ex Sopa de Cabra Gerard Quintana -21 de marzo-.<\/p>\n<p>La banda hispano-brit\u00e1nica Crystal Fighters -15 de mayo-; el exvocalista de Roxy Music Bryan Ferry, que cerrar\u00e1 el festival el 5 de julio-; Rosario -5 de marzo-; Los Secretos -28 de marzo-; Coque Malla -29 de marzo-; la antigua cantante de Esclarecidos, Cristina Lliso -8 de abril-; Jorge Drexler -10 de abril-; Micah P. Hinson -4 de mayo-; Sanjosex -9 de mayo- o Andr\u00e9s Calamaro -20 de mayo- ser\u00e1n otras de las propuestas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Barcelona, 11 feb (EFE).- Bryan Ferry, Estopa, Nacho Vegas y The Stranglers son algunos de los 30 artistas que actuar\u00e1n en el 25 Festival de Guitarra de Barcelona, que empezar\u00e1 el pr\u00f3ximo 20 de febrero y que este a\u00f1o ampl\u00eda su presupuesto y n\u00famero de entradas puestas a la venta. Con 840.000 euros de presupuesto<\/p>\n","protected":false},"author":1,"featured_media":3757,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-3756","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Barcelona, 11 feb (EFE).- Bryan Ferry, Estopa, Nacho Vegas y The Stranglers son algunos de los 30 artistas que actuar\u00e1n en el 25 Festival de Guitarra de Barcelona, que empezar\u00e1 el pr\u00f3ximo 20 de febrero y que este a\u00f1o ampl\u00eda su presupuesto y n\u00famero de entradas puestas a la venta. Con 840.000 euros de presupuesto\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Barcelona, 11 feb (EFE).- Bryan Ferry, Estopa, Nacho Vegas y The Stranglers son algunos de los 30 artistas que actuar\u00e1n en el 25 Festival de Guitarra de Barcelona, que empezar\u00e1 el pr\u00f3ximo 20 de febrero y que este a\u00f1o ampl\u00eda su presupuesto y n\u00famero de entradas puestas a la venta. Con 840.000 euros de presupuesto\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5932357w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5932357w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"532\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-12T00:48:15+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-12T00:48:15+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Barcelona, 11 feb (EFE).- Bryan Ferry, Estopa, Nacho Vegas y The Stranglers son algunos de los 30 artistas que actuar\u00e1n en el 25 Festival de Guitarra de Barcelona, que empezar\u00e1 el pr\u00f3ximo 20 de febrero y que este a\u00f1o ampl\u00eda su presupuesto y n\u00famero de entradas puestas a la venta. Con 840.000 euros de presupuesto\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5932357w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\\\/#article\",\"name\":\"Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona | El Digital de Asturias\",\"headline\":\"Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5932357w.jpg\",\"width\":800,\"height\":532},\"datePublished\":\"2014-02-11T23:48:15+01:00\",\"dateModified\":\"2014-02-11T23:48:15+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\\\/#listItem\",\"name\":\"Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\\\/#listItem\",\"position\":3,\"name\":\"Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\\\/\",\"name\":\"Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona | El Digital de Asturias\",\"description\":\"Barcelona, 11 feb (EFE).- Bryan Ferry, Estopa, Nacho Vegas y The Stranglers son algunos de los 30 artistas que actuar\\u00e1n en el 25 Festival de Guitarra de Barcelona, que empezar\\u00e1 el pr\\u00f3ximo 20 de febrero y que este a\\u00f1o ampl\\u00eda su presupuesto y n\\u00famero de entradas puestas a la venta. Con 840.000 euros de presupuesto\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5932357w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\\\/#mainImage\",\"width\":800,\"height\":532},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\\\/#mainImage\"},\"datePublished\":\"2014-02-11T23:48:15+01:00\",\"dateModified\":\"2014-02-11T23:48:15+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona | El Digital de Asturias","description":"Barcelona, 11 feb (EFE).- Bryan Ferry, Estopa, Nacho Vegas y The Stranglers son algunos de los 30 artistas que actuar\u00e1n en el 25 Festival de Guitarra de Barcelona, que empezar\u00e1 el pr\u00f3ximo 20 de febrero y que este a\u00f1o ampl\u00eda su presupuesto y n\u00famero de entradas puestas a la venta. Con 840.000 euros de presupuesto","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/#article","name":"Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona | El Digital de Asturias","headline":"Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5932357w.jpg","width":800,"height":532},"datePublished":"2014-02-11T23:48:15+01:00","dateModified":"2014-02-11T23:48:15+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/#listItem","name":"Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/#listItem","position":3,"name":"Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/","name":"Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona | El Digital de Asturias","description":"Barcelona, 11 feb (EFE).- Bryan Ferry, Estopa, Nacho Vegas y The Stranglers son algunos de los 30 artistas que actuar\u00e1n en el 25 Festival de Guitarra de Barcelona, que empezar\u00e1 el pr\u00f3ximo 20 de febrero y que este a\u00f1o ampl\u00eda su presupuesto y n\u00famero de entradas puestas a la venta. Con 840.000 euros de presupuesto","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5932357w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/#mainImage","width":800,"height":532},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/#mainImage"},"datePublished":"2014-02-11T23:48:15+01:00","dateModified":"2014-02-11T23:48:15+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona | El Digital de Asturias","og:description":"Barcelona, 11 feb (EFE).- Bryan Ferry, Estopa, Nacho Vegas y The Stranglers son algunos de los 30 artistas que actuar\u00e1n en el 25 Festival de Guitarra de Barcelona, que empezar\u00e1 el pr\u00f3ximo 20 de febrero y que este a\u00f1o ampl\u00eda su presupuesto y n\u00famero de entradas puestas a la venta. Con 840.000 euros de presupuesto","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5932357w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5932357w.jpg","og:image:width":800,"og:image:height":532,"article:published_time":"2014-02-12T00:48:15+00:00","article:modified_time":"2014-02-12T00:48:15+00:00","twitter:card":"summary_large_image","twitter:title":"Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona | El Digital de Asturias","twitter:description":"Barcelona, 11 feb (EFE).- Bryan Ferry, Estopa, Nacho Vegas y The Stranglers son algunos de los 30 artistas que actuar\u00e1n en el 25 Festival de Guitarra de Barcelona, que empezar\u00e1 el pr\u00f3ximo 20 de febrero y que este a\u00f1o ampl\u00eda su presupuesto y n\u00famero de entradas puestas a la venta. Con 840.000 euros de presupuesto","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5932357w.jpg"},"aioseo_meta_data":{"post_id":"3756","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 10:48:13","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:49:46","updated":"2026-05-15 10:48:13"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/\" title=\"Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona\">Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Bryan Ferry, Estopa o The Stranglers, en el 25 Festival Guitarra de Barcelona","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/bryan-ferry-estopa-o-the-stranglers-en-el-25-festival-guitarra-de-barcelona\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=3756"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3756\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/3757"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=3756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=3756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=3756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}