{"id":37259,"date":"2015-01-29T20:03:01","date_gmt":"2015-01-29T22:03:01","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=37259"},"modified":"2015-01-29T20:03:01","modified_gmt":"2015-01-29T22:03:01","slug":"africa-se-revela-como-un-enclave-turistico","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/","title":{"rendered":"\u00c1frica se revela como un enclave tur\u00edstico"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-37260\" alt=\"10168062w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10168062w-360x229.jpg\" width=\"360\" height=\"229\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10168062w-360x229.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10168062w-650x414.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10168062w-768x489.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10168062w-150x95.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10168062w-450x286.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10168062w-696x443.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10168062w-660x420.jpg 660w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10168062w-269x170.jpg 269w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10168062w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Madrid, 29 ene (EFE).- El continente africano muestra su potencial tur\u00edstico a trav\u00e9s de pa\u00edses como Gambia, Etiop\u00eda, Ghana, Sud\u00e1n y Togo en la 35 edici\u00f3n de la Feria Internacional del Turismo (FITUR) que se celebra anualmente en Madrid.<\/p>\n<p>\u00c1frica se revela como un nuevo destino tur\u00edstico para el gran p\u00fablico, la naturaleza, el clima y la amabilidad de sus gentes se postulan como el gran atractivo para elegir este destino en fechas vacacionales.<\/p>\n<p>El director del Consejo de Turismo de Gambia, Bakary K. Jammeh, consider\u00f3 que el turismo \u00abno solo contribuye al desarrollo del pa\u00eds, sino que tambi\u00e9n es un medio para combatir al fantasma de la pobreza.\u00bb<\/p>\n<p>Jammeh a\u00f1adi\u00f3 que el turismo es la segunda actividad del Producto Interior Bruto (PIB) despu\u00e9s de la agricultura.<\/p>\n<p>El turismo promueve puestos de trabajo indirectos. \u00abSon muchos los gambianos que viven gracias a las m\u00faltiples actividades que se desarrollan a consecuencia del turismo\u00bb, a\u00f1adi\u00f3 el alto cargo.<\/p>\n<p>El director del Consejo de Turismo consider\u00f3 que Gambia tiene \u00abuna de las poblaciones m\u00e1s amigables del mundo, siempre dando la bienvenida con una sonrisa.\u00bb<\/p>\n<p>Jammeh a\u00f1adi\u00f3 que las playas de Gambia \u00abpueden encontrarse entre las m\u00e1s bellas del mundo\u00bb.<\/p>\n<p>Asimismo, dijo que su pa\u00eds es \u00abseguro, la gente puede moverse con tranquilidad a cualquier hora del d\u00eda.\u00bb<\/p>\n<p>Fitur cuenta con un 12 por ciento m\u00e1s expositores que en 2014, y aproximadamente un 2 por ciento se debe al aumento de participaci\u00f3n africana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 29 ene (EFE).- El continente africano muestra su potencial tur\u00edstico a trav\u00e9s de pa\u00edses como Gambia, Etiop\u00eda, Ghana, Sud\u00e1n y Togo en la 35 edici\u00f3n de la Feria Internacional del Turismo (FITUR) que se celebra anualmente en Madrid. \u00c1frica se revela como un nuevo destino tur\u00edstico para el gran p\u00fablico, la naturaleza, el clima<\/p>\n","protected":false},"author":1,"featured_media":37260,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-37259","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 29 ene (EFE).- El continente africano muestra su potencial tur\u00edstico a trav\u00e9s de pa\u00edses como Gambia, Etiop\u00eda, Ghana, Sud\u00e1n y Togo en la 35 edici\u00f3n de la Feria Internacional del Turismo (FITUR) que se celebra anualmente en Madrid. \u00c1frica se revela como un nuevo destino tur\u00edstico para el gran p\u00fablico, la naturaleza, el clima\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00c1frica se revela como un enclave tur\u00edstico | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 29 ene (EFE).- El continente africano muestra su potencial tur\u00edstico a trav\u00e9s de pa\u00edses como Gambia, Etiop\u00eda, Ghana, Sud\u00e1n y Togo en la 35 edici\u00f3n de la Feria Internacional del Turismo (FITUR) que se celebra anualmente en Madrid. \u00c1frica se revela como un nuevo destino tur\u00edstico para el gran p\u00fablico, la naturaleza, el clima\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10168062w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10168062w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"509\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-01-29T22:03:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-01-29T22:03:01+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00c1frica se revela como un enclave tur\u00edstico | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 29 ene (EFE).- El continente africano muestra su potencial tur\u00edstico a trav\u00e9s de pa\u00edses como Gambia, Etiop\u00eda, Ghana, Sud\u00e1n y Togo en la 35 edici\u00f3n de la Feria Internacional del Turismo (FITUR) que se celebra anualmente en Madrid. \u00c1frica se revela como un nuevo destino tur\u00edstico para el gran p\u00fablico, la naturaleza, el clima\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10168062w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/africa-se-revela-como-un-enclave-turistico\\\/#article\",\"name\":\"\\u00c1frica se revela como un enclave tur\\u00edstico | El Digital de Asturias\",\"headline\":\"\\u00c1frica se revela como un enclave tur\\u00edstico\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/10168062w.jpg\",\"width\":800,\"height\":509},\"datePublished\":\"2015-01-29T20:03:01+01:00\",\"dateModified\":\"2015-01-29T20:03:01+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/africa-se-revela-como-un-enclave-turistico\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/africa-se-revela-como-un-enclave-turistico\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/africa-se-revela-como-un-enclave-turistico\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/africa-se-revela-como-un-enclave-turistico\\\/#listItem\",\"name\":\"\\u00c1frica se revela como un enclave tur\\u00edstico\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/africa-se-revela-como-un-enclave-turistico\\\/#listItem\",\"position\":3,\"name\":\"\\u00c1frica se revela como un enclave tur\\u00edstico\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/africa-se-revela-como-un-enclave-turistico\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/africa-se-revela-como-un-enclave-turistico\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/africa-se-revela-como-un-enclave-turistico\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/africa-se-revela-como-un-enclave-turistico\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/africa-se-revela-como-un-enclave-turistico\\\/\",\"name\":\"\\u00c1frica se revela como un enclave tur\\u00edstico | El Digital de Asturias\",\"description\":\"Madrid, 29 ene (EFE).- El continente africano muestra su potencial tur\\u00edstico a trav\\u00e9s de pa\\u00edses como Gambia, Etiop\\u00eda, Ghana, Sud\\u00e1n y Togo en la 35 edici\\u00f3n de la Feria Internacional del Turismo (FITUR) que se celebra anualmente en Madrid. \\u00c1frica se revela como un nuevo destino tur\\u00edstico para el gran p\\u00fablico, la naturaleza, el clima\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/africa-se-revela-como-un-enclave-turistico\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/10168062w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/africa-se-revela-como-un-enclave-turistico\\\/#mainImage\",\"width\":800,\"height\":509},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/africa-se-revela-como-un-enclave-turistico\\\/#mainImage\"},\"datePublished\":\"2015-01-29T20:03:01+01:00\",\"dateModified\":\"2015-01-29T20:03:01+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>\u00c1frica se revela como un enclave tur\u00edstico | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"\u00c1frica se revela como un enclave tur\u00edstico | El Digital de Asturias","description":"Madrid, 29 ene (EFE).- El continente africano muestra su potencial tur\u00edstico a trav\u00e9s de pa\u00edses como Gambia, Etiop\u00eda, Ghana, Sud\u00e1n y Togo en la 35 edici\u00f3n de la Feria Internacional del Turismo (FITUR) que se celebra anualmente en Madrid. \u00c1frica se revela como un nuevo destino tur\u00edstico para el gran p\u00fablico, la naturaleza, el clima","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/#article","name":"\u00c1frica se revela como un enclave tur\u00edstico | El Digital de Asturias","headline":"\u00c1frica se revela como un enclave tur\u00edstico","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10168062w.jpg","width":800,"height":509},"datePublished":"2015-01-29T20:03:01+01:00","dateModified":"2015-01-29T20:03:01+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/#listItem","name":"\u00c1frica se revela como un enclave tur\u00edstico"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/#listItem","position":3,"name":"\u00c1frica se revela como un enclave tur\u00edstico","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/","name":"\u00c1frica se revela como un enclave tur\u00edstico | El Digital de Asturias","description":"Madrid, 29 ene (EFE).- El continente africano muestra su potencial tur\u00edstico a trav\u00e9s de pa\u00edses como Gambia, Etiop\u00eda, Ghana, Sud\u00e1n y Togo en la 35 edici\u00f3n de la Feria Internacional del Turismo (FITUR) que se celebra anualmente en Madrid. \u00c1frica se revela como un nuevo destino tur\u00edstico para el gran p\u00fablico, la naturaleza, el clima","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10168062w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/#mainImage","width":800,"height":509},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/#mainImage"},"datePublished":"2015-01-29T20:03:01+01:00","dateModified":"2015-01-29T20:03:01+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"\u00c1frica se revela como un enclave tur\u00edstico | El Digital de Asturias","og:description":"Madrid, 29 ene (EFE).- El continente africano muestra su potencial tur\u00edstico a trav\u00e9s de pa\u00edses como Gambia, Etiop\u00eda, Ghana, Sud\u00e1n y Togo en la 35 edici\u00f3n de la Feria Internacional del Turismo (FITUR) que se celebra anualmente en Madrid. \u00c1frica se revela como un nuevo destino tur\u00edstico para el gran p\u00fablico, la naturaleza, el clima","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10168062w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10168062w.jpg","og:image:width":800,"og:image:height":509,"article:published_time":"2015-01-29T22:03:01+00:00","article:modified_time":"2015-01-29T22:03:01+00:00","twitter:card":"summary_large_image","twitter:title":"\u00c1frica se revela como un enclave tur\u00edstico | El Digital de Asturias","twitter:description":"Madrid, 29 ene (EFE).- El continente africano muestra su potencial tur\u00edstico a trav\u00e9s de pa\u00edses como Gambia, Etiop\u00eda, Ghana, Sud\u00e1n y Togo en la 35 edici\u00f3n de la Feria Internacional del Turismo (FITUR) que se celebra anualmente en Madrid. \u00c1frica se revela como un nuevo destino tur\u00edstico para el gran p\u00fablico, la naturaleza, el clima","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10168062w.jpg"},"aioseo_meta_data":{"post_id":"37259","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 15:44:06","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 03:07:43","updated":"2026-05-20 15:44:06"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/\" title=\"\u00c1frica se revela como un enclave tur\u00edstico\">\u00c1frica se revela como un enclave tur\u00edstico<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"\u00c1frica se revela como un enclave tur\u00edstico","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/africa-se-revela-como-un-enclave-turistico\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/37259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=37259"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/37259\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/37260"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=37259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=37259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=37259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}