{"id":3715,"date":"2014-02-11T18:49:57","date_gmt":"2014-02-11T19:49:57","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=3715"},"modified":"2014-02-11T18:49:57","modified_gmt":"2014-02-11T19:49:57","slug":"el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/","title":{"rendered":"El corto de Esteban Crespo, nominado a los \u00d3scar, se proyecta ma\u00f1ana en la ONU"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3716\" alt=\"5931411w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5931411w-360x235.jpg\" width=\"360\" height=\"235\" \/>Ciudad Real, 11 feb (EFE).- El cortometraje del espa\u00f1ol Esteban Crespo \u00abAquel no era yo\u00bb, que ha sido uno de los cinco cortos nominados para optar a los \u00d3scar en la categor\u00eda de mejor cortometraje, se proyectar\u00e1 ma\u00f1ana, d\u00eda 12, en la sede de las Naciones Unidas en Nueva York.<\/p>\n<p>La proyecci\u00f3n del corto coincide con la celebraci\u00f3n del D\u00eda Mundial contra la Utilizaci\u00f3n de Ni\u00f1os Soldado, seg\u00fan ha explicado hoy el productor de la cinta, el ciudadreale\u00f1o Jos\u00e9 Luis Matas-Negrete, en un comunicado remitido a Efe.<\/p>\n<p>La Misi\u00f3n Permanente de Espa\u00f1a en la ONU y el Representante Especial del Secretario General para la cuesti\u00f3n de los Ni\u00f1os y los Conflictos Armados han organizado esta proyecci\u00f3n, tras la cual habr\u00e1 un coloquio acerca de la cinta y los retos para la erradicaci\u00f3n del reclutamiento y uso de ni\u00f1os en conflictos armados.<\/p>\n<p>En el coloquio participar\u00e1n el representante permanente de Espa\u00f1a en Naciones Unidas, el embajador Rom\u00e1n Oyarzun Marchesi; el representante especial del secretario para la cuesti\u00f3n de los Ni\u00f1os y los Conflictos Armados, Leila Zerrougui; el director de cine Esteban Crespo y el actor Gustavo Salmer\u00f3n.<\/p>\n<p>Tambi\u00e9n estar\u00e1n el vicepresidente asociado de la organizaci\u00f3n Save the Children, Gregg Ramm y el representante de DYES (Desarrollo y Educaci\u00f3n Solidaria) y de la Fundaci\u00f3n El Compromiso, Chema Caballero.<\/p>\n<p>La proyecci\u00f3n del cortometraje espa\u00f1ol se producir\u00e1 semanas antes de optar al \u00d3scar en la categor\u00eda de mejor cortometraje, al que tambi\u00e9n concurren como nominados \u00abAvant Que De Tout Perdre\u00bb, de Xavier Legrand; \u00abHelium\u00bb, de Anders Walter; \u00abPit\u00e4\u00e4k\u00f6 Mun Kaikki Hoitaa?\u00bb, de Selma Vilhunen, y \u00abThe Voorman Problem\u00bb, de Mark Gill.<\/p>\n<p>\u00abAquel no era yo\u00bb relata la situaci\u00f3n en la que viven m\u00e1s de 250.000 ni\u00f1os que son utilizados como soldados para participar activamente en conflictos armados, al tiempo que se centra en contar c\u00f3mo es la participaci\u00f3n de los cooperantes internacionales que tratan de prestarles ayuda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciudad Real, 11 feb (EFE).- El cortometraje del espa\u00f1ol Esteban Crespo \u00abAquel no era yo\u00bb, que ha sido uno de los cinco cortos nominados para optar a los \u00d3scar en la categor\u00eda de mejor cortometraje, se proyectar\u00e1 ma\u00f1ana, d\u00eda 12, en la sede de las Naciones Unidas en Nueva York. La proyecci\u00f3n del corto coincide<\/p>\n","protected":false},"author":1,"featured_media":3716,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-3715","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ciudad Real, 11 feb (EFE).- El cortometraje del espa\u00f1ol Esteban Crespo &quot;Aquel no era yo&quot;, que ha sido uno de los cinco cortos nominados para optar a los \u00d3scar en la categor\u00eda de mejor cortometraje, se proyectar\u00e1 ma\u00f1ana, d\u00eda 12, en la sede de las Naciones Unidas en Nueva York. La proyecci\u00f3n del corto coincide\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El corto de Esteban Crespo, nominado a los \u00d3scar, se proyecta ma\u00f1ana en la ONU | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Ciudad Real, 11 feb (EFE).- El cortometraje del espa\u00f1ol Esteban Crespo &quot;Aquel no era yo&quot;, que ha sido uno de los cinco cortos nominados para optar a los \u00d3scar en la categor\u00eda de mejor cortometraje, se proyectar\u00e1 ma\u00f1ana, d\u00eda 12, en la sede de las Naciones Unidas en Nueva York. La proyecci\u00f3n del corto coincide\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5931411w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5931411w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"524\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-11T19:49:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-11T19:49:57+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El corto de Esteban Crespo, nominado a los \u00d3scar, se proyecta ma\u00f1ana en la ONU | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ciudad Real, 11 feb (EFE).- El cortometraje del espa\u00f1ol Esteban Crespo &quot;Aquel no era yo&quot;, que ha sido uno de los cinco cortos nominados para optar a los \u00d3scar en la categor\u00eda de mejor cortometraje, se proyectar\u00e1 ma\u00f1ana, d\u00eda 12, en la sede de las Naciones Unidas en Nueva York. La proyecci\u00f3n del corto coincide\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5931411w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\\\/#article\",\"name\":\"El corto de Esteban Crespo, nominado a los \\u00d3scar, se proyecta ma\\u00f1ana en la ONU | El Digital de Asturias\",\"headline\":\"El corto de Esteban Crespo, nominado a los \\u00d3scar, se proyecta ma\\u00f1ana en la ONU\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5931411w.jpg\",\"width\":800,\"height\":524},\"datePublished\":\"2014-02-11T18:49:57+01:00\",\"dateModified\":\"2014-02-11T18:49:57+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\\\/#listItem\",\"name\":\"El corto de Esteban Crespo, nominado a los \\u00d3scar, se proyecta ma\\u00f1ana en la ONU\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\\\/#listItem\",\"position\":3,\"name\":\"El corto de Esteban Crespo, nominado a los \\u00d3scar, se proyecta ma\\u00f1ana en la ONU\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\\\/\",\"name\":\"El corto de Esteban Crespo, nominado a los \\u00d3scar, se proyecta ma\\u00f1ana en la ONU | El Digital de Asturias\",\"description\":\"Ciudad Real, 11 feb (EFE).- El cortometraje del espa\\u00f1ol Esteban Crespo \\\"Aquel no era yo\\\", que ha sido uno de los cinco cortos nominados para optar a los \\u00d3scar en la categor\\u00eda de mejor cortometraje, se proyectar\\u00e1 ma\\u00f1ana, d\\u00eda 12, en la sede de las Naciones Unidas en Nueva York. La proyecci\\u00f3n del corto coincide\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5931411w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\\\/#mainImage\",\"width\":800,\"height\":524},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\\\/#mainImage\"},\"datePublished\":\"2014-02-11T18:49:57+01:00\",\"dateModified\":\"2014-02-11T18:49:57+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El corto de Esteban Crespo, nominado a los \u00d3scar, se proyecta ma\u00f1ana en la ONU | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El corto de Esteban Crespo, nominado a los \u00d3scar, se proyecta ma\u00f1ana en la ONU | El Digital de Asturias","description":"Ciudad Real, 11 feb (EFE).- El cortometraje del espa\u00f1ol Esteban Crespo \"Aquel no era yo\", que ha sido uno de los cinco cortos nominados para optar a los \u00d3scar en la categor\u00eda de mejor cortometraje, se proyectar\u00e1 ma\u00f1ana, d\u00eda 12, en la sede de las Naciones Unidas en Nueva York. La proyecci\u00f3n del corto coincide","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/#article","name":"El corto de Esteban Crespo, nominado a los \u00d3scar, se proyecta ma\u00f1ana en la ONU | El Digital de Asturias","headline":"El corto de Esteban Crespo, nominado a los \u00d3scar, se proyecta ma\u00f1ana en la ONU","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5931411w.jpg","width":800,"height":524},"datePublished":"2014-02-11T18:49:57+01:00","dateModified":"2014-02-11T18:49:57+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/#listItem","name":"El corto de Esteban Crespo, nominado a los \u00d3scar, se proyecta ma\u00f1ana en la ONU"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/#listItem","position":3,"name":"El corto de Esteban Crespo, nominado a los \u00d3scar, se proyecta ma\u00f1ana en la ONU","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/","name":"El corto de Esteban Crespo, nominado a los \u00d3scar, se proyecta ma\u00f1ana en la ONU | El Digital de Asturias","description":"Ciudad Real, 11 feb (EFE).- El cortometraje del espa\u00f1ol Esteban Crespo \"Aquel no era yo\", que ha sido uno de los cinco cortos nominados para optar a los \u00d3scar en la categor\u00eda de mejor cortometraje, se proyectar\u00e1 ma\u00f1ana, d\u00eda 12, en la sede de las Naciones Unidas en Nueva York. La proyecci\u00f3n del corto coincide","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5931411w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/#mainImage","width":800,"height":524},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/#mainImage"},"datePublished":"2014-02-11T18:49:57+01:00","dateModified":"2014-02-11T18:49:57+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"El corto de Esteban Crespo, nominado a los \u00d3scar, se proyecta ma\u00f1ana en la ONU | El Digital de Asturias","og:description":"Ciudad Real, 11 feb (EFE).- El cortometraje del espa\u00f1ol Esteban Crespo &quot;Aquel no era yo&quot;, que ha sido uno de los cinco cortos nominados para optar a los \u00d3scar en la categor\u00eda de mejor cortometraje, se proyectar\u00e1 ma\u00f1ana, d\u00eda 12, en la sede de las Naciones Unidas en Nueva York. La proyecci\u00f3n del corto coincide","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5931411w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5931411w.jpg","og:image:width":800,"og:image:height":524,"article:published_time":"2014-02-11T19:49:57+00:00","article:modified_time":"2014-02-11T19:49:57+00:00","twitter:card":"summary_large_image","twitter:title":"El corto de Esteban Crespo, nominado a los \u00d3scar, se proyecta ma\u00f1ana en la ONU | El Digital de Asturias","twitter:description":"Ciudad Real, 11 feb (EFE).- El cortometraje del espa\u00f1ol Esteban Crespo &quot;Aquel no era yo&quot;, que ha sido uno de los cinco cortos nominados para optar a los \u00d3scar en la categor\u00eda de mejor cortometraje, se proyectar\u00e1 ma\u00f1ana, d\u00eda 12, en la sede de las Naciones Unidas en Nueva York. La proyecci\u00f3n del corto coincide","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5931411w.jpg"},"aioseo_meta_data":{"post_id":"3715","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 10:41:25","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:49:44","updated":"2026-05-15 10:41:25"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/\" title=\"El corto de Esteban Crespo, nominado a los \u00d3scar, se proyecta ma\u00f1ana en la ONU\">El corto de Esteban Crespo, nominado a los \u00d3scar, se proyecta ma\u00f1ana en la ONU<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"El corto de Esteban Crespo, nominado a los \u00d3scar, se proyecta ma\u00f1ana en la ONU","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-corto-de-esteban-crespo-nominado-a-los-oscar-se-proyecta-manana-en-la-onu\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=3715"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3715\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/3716"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=3715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=3715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=3715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}