{"id":36966,"date":"2015-01-28T00:41:38","date_gmt":"2015-01-28T02:41:38","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=36966"},"modified":"2015-01-28T00:41:38","modified_gmt":"2015-01-28T02:41:38","slug":"cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/","title":{"rendered":"Cultura, naturaleza y gastronom\u00eda, reclamos de las comunidades en Fitur"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-36967\" alt=\"10158991w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10158991w-360x251.jpg\" width=\"360\" height=\"251\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10158991w-360x251.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10158991w-650x453.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10158991w-768x536.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10158991w-150x105.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10158991w-450x314.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10158991w-100x70.jpg 100w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10158991w-696x485.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10158991w-602x420.jpg 602w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10158991w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Madrid, 26 ene (EFE).- Las comunidades aut\u00f3nomas acudir\u00e1n a la XXXV edici\u00f3n de la Feria Internacional de Turismo (Fitur), que ma\u00f1ana inaugurar\u00e1n los Reyes, con pabellones austeros, como en a\u00f1o anteriores, y que ponen el foco en la naturaleza, la gastronom\u00eda y la cultura.<\/p>\n<p>Andaluc\u00eda, l\u00edder en turismo nacional, centrar\u00e1 su oferta en las experiencias de naturaleza, mar y urbanas, con una de las mayores inversiones (1.030.000 euros), similar a la de la pasada edici\u00f3n y un 35 % menor respecto al 2012.<\/p>\n<p>Contar\u00e1 con un expositor de 5.300 metros cuadrados, reutilizable en otras ferias, y aprovechar\u00e1 el tir\u00f3n del rodaje de Juego de Tronos -exhibir\u00e1 el \u00abTrono de hierro\u00bb- o de la Isla M\u00ednima, as\u00ed como de la apertura del Centre Pompidou o la colecci\u00f3n del Museo Ruso en M\u00e1laga.<\/p>\n<p>La Comunidad Valenciana ha destinado alrededor de 600.000 euros a un pabell\u00f3n inspirado en el Mediterr\u00e1neo que ocupar\u00e1 una superficie total de 1.609 metros cuadrados, un 4 % m\u00e1s que en la pasada edici\u00f3n, tambi\u00e9n reutilizable.<\/p>\n<p>La cocinera Susi D\u00edaz ser\u00e1 embajadora gastron\u00f3mica de la comunidad en una edici\u00f3n en la que el aeropuerto de Castell\u00f3n, que ya puede recibir vuelos comerciales, estar\u00e1 sobre la mesa de negociaci\u00f3n con compa\u00f1\u00edas a\u00e9reas y operadores tur\u00edsticos.<\/p>\n<p>Baleares ha dispuesto dos pantallas gigantes que mostrar\u00e1n im\u00e1genes promocionales y que ser\u00e1n la principal decoraci\u00f3n de un espacio que en esta ocasi\u00f3n cuenta con 560,5 metros cuadrados.<\/p>\n<p>Para consolidar la recuperaci\u00f3n del turismo nacional, Canarias invertir\u00e1 en Fitur m\u00e1s de 545.000 euros, repartidos en un expositor de 1.427 metros cuadrados, aunque ha reducido el presupuesto para la feria en 300.000 euros.<\/p>\n<p>Como en 2014, el stand estar\u00e1 decorado con una cubierta de madera equipada con 54 ca\u00f1ones LED y grandes pantallas con im\u00e1genes atractivas del archipi\u00e9lago.<\/p>\n<p>El pabell\u00f3n de Arag\u00f3n tiene 406 metros cuadrados divididos en dos plantas y su presupuesto ronda los 78.000 euros. Una gran cesta de mimbre mostrar\u00e1 los valores tur\u00edsticos y las experiencias que se pueden vivir all\u00ed. Entre ellas, un espacio dedicado a Goya y otro de enoturismo sobre las cuatro rutas del vino aragonesas.<\/p>\n<p>El principal atractivo de Asturias en Fitur es el propio expositor, de 600 metros cuadrados, cuya decoraci\u00f3n pretende reflejar el paisaje asturiano con recreaciones de la costa y de la monta\u00f1a a trav\u00e9s de un mural vertical de musgo. Una l\u00e1mpara colgante de 400 botellas de sidra ser\u00e1 uno de los reclamos gastron\u00f3micos.<\/p>\n<p>Cantabria contar\u00e1 con un pabell\u00f3n de 500 metros cuadrados con varias pantallas gigantes en el que se mostrar\u00e1n la futura telecabina de Cab\u00e1rceno, el telef\u00e9rico de Vega de Pas o el Centro Bot\u00edn, junto a otras referencias tur\u00edsticas habituales como los Picos de Europa y las Cuevas de Altamira.<\/p>\n<p>Castilla-La Mancha destinar\u00e1 156.000 euros a su stand, protagonizado por Don Quijote y Santa Teresa de Jes\u00fas con motivo del cuarto centenario de la publicaci\u00f3n de la segunda parte de la obra de Cervantes y del quinto centenario del nacimiento de la religiosa.<\/p>\n<p>Tambi\u00e9n se recordar\u00e1 a Santa Teresa en el espacio que ofrece Castilla y Le\u00f3n en el que se apuesta por la internacionalizaci\u00f3n a trav\u00e9s de dos expositores: uno institucional con m\u00e1s de 1.500 metros cuadrados y otro de car\u00e1cter comercial.<\/p>\n<p>Extremadura realzar\u00e1 su gastronom\u00eda en apoyo a C\u00e1ceres, Capital Cultural Gastron\u00f3mica 2015. A diferencia del resto de autonom\u00edas, la Junta ha incrementado su presupuesto para Fitur en un 40 % hasta los 560.000 euros.<\/p>\n<p>Un gran botafumeiro virtual ser\u00e1 el reclamo de Galicia, que contar\u00e1 con 967 metros cuadrados, un espacio similar al de 2014 y donde participa por primera vez el Cl\u00faster de Turismo, que servir\u00e1 \u00abde plataforma\u00bb y punto de encuentro entre empresarios y profesionales del sector.<\/p>\n<p>El expositor vasco tiene 700 metros cuadrados divididos en grandes \u00abkutxas\u00bb de madera con iconograf\u00eda vasca; el exterior, con fotos en blanco y negro, contrastar\u00e1 con un interior colorista.<\/p>\n<p>Navarra acude a Fitur con la campa\u00f1a \u00abD\u00e9jate abrazar\u00bb y aspira a presentarse como \u00abun interesante destino cinematogr\u00e1fico\u00bb, pero tambi\u00e9n invita a recorrer el valle de Baztan de la mano de la escritora Dolores Redondo.<\/p>\n<p>En el caso de Murcia, un gran sol de cuatro metros de di\u00e1metro, visible desde cualquier \u00e1ngulo y que proyectar\u00e1 im\u00e1genes del Mar Menor, ser\u00e1 el eje principal de un stand de 373 metros que cuesta 200.000 euros.<\/p>\n<p>Madrid ha optado por el f\u00fatbol como atractivo tur\u00edstico, dado que considera que Real Madrid y Atl\u00e9tico de Madrid se han convertido en \u00ablos mejores embajadores de la ciudad\u00bb.<\/p>\n<p>La Rioja quiere consolidar su imagen como un destino tur\u00edstico experiencial, con la gastronom\u00eda y el enoturismo como puntos fuertes, a los que suma este a\u00f1o el yacimiento celtib\u00e9rico de Contrebia Leucade y la ermita de San Felices.<\/p>\n<p>Repetir\u00e1 con el mismo expositor que el a\u00f1o pasado, inspirado en una barrica y con el que gan\u00f3 el premio Fitur 2014 al mejor stand en la categor\u00eda de instituciones y comunidades aut\u00f3nomas.<\/p>\n<p>La mayor parte de las autonom\u00edas estar\u00e1n representadas por sus presidentes, a excepci\u00f3n del Pa\u00eds Vasco y de Catalu\u00f1a, que llevar\u00e1 su propuesta \u00abCatalu\u00f1a es tu casa\u00bb que pretende \u00abreflejar la generosidad, el esp\u00edritu de acogida y el respeto por la diversidad, de Catalu\u00f1a y de su gente\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 26 ene (EFE).- Las comunidades aut\u00f3nomas acudir\u00e1n a la XXXV edici\u00f3n de la Feria Internacional de Turismo (Fitur), que ma\u00f1ana inaugurar\u00e1n los Reyes, con pabellones austeros, como en a\u00f1o anteriores, y que ponen el foco en la naturaleza, la gastronom\u00eda y la cultura. Andaluc\u00eda, l\u00edder en turismo nacional, centrar\u00e1 su oferta en las experiencias<\/p>\n","protected":false},"author":1,"featured_media":36967,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-36966","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 26 ene (EFE).- Las comunidades aut\u00f3nomas acudir\u00e1n a la XXXV edici\u00f3n de la Feria Internacional de Turismo (Fitur), que ma\u00f1ana inaugurar\u00e1n los Reyes, con pabellones austeros, como en a\u00f1o anteriores, y que ponen el foco en la naturaleza, la gastronom\u00eda y la cultura. Andaluc\u00eda, l\u00edder en turismo nacional, centrar\u00e1 su oferta en las experiencias\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Cultura, naturaleza y gastronom\u00eda, reclamos de las comunidades en Fitur | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 26 ene (EFE).- Las comunidades aut\u00f3nomas acudir\u00e1n a la XXXV edici\u00f3n de la Feria Internacional de Turismo (Fitur), que ma\u00f1ana inaugurar\u00e1n los Reyes, con pabellones austeros, como en a\u00f1o anteriores, y que ponen el foco en la naturaleza, la gastronom\u00eda y la cultura. Andaluc\u00eda, l\u00edder en turismo nacional, centrar\u00e1 su oferta en las experiencias\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10158991w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10158991w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"558\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-01-28T02:41:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-01-28T02:41:38+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Cultura, naturaleza y gastronom\u00eda, reclamos de las comunidades en Fitur | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 26 ene (EFE).- Las comunidades aut\u00f3nomas acudir\u00e1n a la XXXV edici\u00f3n de la Feria Internacional de Turismo (Fitur), que ma\u00f1ana inaugurar\u00e1n los Reyes, con pabellones austeros, como en a\u00f1o anteriores, y que ponen el foco en la naturaleza, la gastronom\u00eda y la cultura. Andaluc\u00eda, l\u00edder en turismo nacional, centrar\u00e1 su oferta en las experiencias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10158991w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\\\/#article\",\"name\":\"Cultura, naturaleza y gastronom\\u00eda, reclamos de las comunidades en Fitur | El Digital de Asturias\",\"headline\":\"Cultura, naturaleza y gastronom\\u00eda, reclamos de las comunidades en Fitur\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/10158991w.jpg\",\"width\":800,\"height\":558},\"datePublished\":\"2015-01-28T00:41:38+01:00\",\"dateModified\":\"2015-01-28T00:41:38+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\\\/#listItem\",\"name\":\"Cultura, naturaleza y gastronom\\u00eda, reclamos de las comunidades en Fitur\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\\\/#listItem\",\"position\":3,\"name\":\"Cultura, naturaleza y gastronom\\u00eda, reclamos de las comunidades en Fitur\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\\\/\",\"name\":\"Cultura, naturaleza y gastronom\\u00eda, reclamos de las comunidades en Fitur | El Digital de Asturias\",\"description\":\"Madrid, 26 ene (EFE).- Las comunidades aut\\u00f3nomas acudir\\u00e1n a la XXXV edici\\u00f3n de la Feria Internacional de Turismo (Fitur), que ma\\u00f1ana inaugurar\\u00e1n los Reyes, con pabellones austeros, como en a\\u00f1o anteriores, y que ponen el foco en la naturaleza, la gastronom\\u00eda y la cultura. Andaluc\\u00eda, l\\u00edder en turismo nacional, centrar\\u00e1 su oferta en las experiencias\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/10158991w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\\\/#mainImage\",\"width\":800,\"height\":558},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\\\/#mainImage\"},\"datePublished\":\"2015-01-28T00:41:38+01:00\",\"dateModified\":\"2015-01-28T00:41:38+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Cultura, naturaleza y gastronom\u00eda, reclamos de las comunidades en Fitur | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Cultura, naturaleza y gastronom\u00eda, reclamos de las comunidades en Fitur | El Digital de Asturias","description":"Madrid, 26 ene (EFE).- Las comunidades aut\u00f3nomas acudir\u00e1n a la XXXV edici\u00f3n de la Feria Internacional de Turismo (Fitur), que ma\u00f1ana inaugurar\u00e1n los Reyes, con pabellones austeros, como en a\u00f1o anteriores, y que ponen el foco en la naturaleza, la gastronom\u00eda y la cultura. Andaluc\u00eda, l\u00edder en turismo nacional, centrar\u00e1 su oferta en las experiencias","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/#article","name":"Cultura, naturaleza y gastronom\u00eda, reclamos de las comunidades en Fitur | El Digital de Asturias","headline":"Cultura, naturaleza y gastronom\u00eda, reclamos de las comunidades en Fitur","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10158991w.jpg","width":800,"height":558},"datePublished":"2015-01-28T00:41:38+01:00","dateModified":"2015-01-28T00:41:38+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/#listItem","name":"Cultura, naturaleza y gastronom\u00eda, reclamos de las comunidades en Fitur"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/#listItem","position":3,"name":"Cultura, naturaleza y gastronom\u00eda, reclamos de las comunidades en Fitur","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/","name":"Cultura, naturaleza y gastronom\u00eda, reclamos de las comunidades en Fitur | El Digital de Asturias","description":"Madrid, 26 ene (EFE).- Las comunidades aut\u00f3nomas acudir\u00e1n a la XXXV edici\u00f3n de la Feria Internacional de Turismo (Fitur), que ma\u00f1ana inaugurar\u00e1n los Reyes, con pabellones austeros, como en a\u00f1o anteriores, y que ponen el foco en la naturaleza, la gastronom\u00eda y la cultura. Andaluc\u00eda, l\u00edder en turismo nacional, centrar\u00e1 su oferta en las experiencias","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10158991w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/#mainImage","width":800,"height":558},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/#mainImage"},"datePublished":"2015-01-28T00:41:38+01:00","dateModified":"2015-01-28T00:41:38+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Cultura, naturaleza y gastronom\u00eda, reclamos de las comunidades en Fitur | El Digital de Asturias","og:description":"Madrid, 26 ene (EFE).- Las comunidades aut\u00f3nomas acudir\u00e1n a la XXXV edici\u00f3n de la Feria Internacional de Turismo (Fitur), que ma\u00f1ana inaugurar\u00e1n los Reyes, con pabellones austeros, como en a\u00f1o anteriores, y que ponen el foco en la naturaleza, la gastronom\u00eda y la cultura. Andaluc\u00eda, l\u00edder en turismo nacional, centrar\u00e1 su oferta en las experiencias","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10158991w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10158991w.jpg","og:image:width":800,"og:image:height":558,"article:published_time":"2015-01-28T02:41:38+00:00","article:modified_time":"2015-01-28T02:41:38+00:00","twitter:card":"summary_large_image","twitter:title":"Cultura, naturaleza y gastronom\u00eda, reclamos de las comunidades en Fitur | El Digital de Asturias","twitter:description":"Madrid, 26 ene (EFE).- Las comunidades aut\u00f3nomas acudir\u00e1n a la XXXV edici\u00f3n de la Feria Internacional de Turismo (Fitur), que ma\u00f1ana inaugurar\u00e1n los Reyes, con pabellones austeros, como en a\u00f1o anteriores, y que ponen el foco en la naturaleza, la gastronom\u00eda y la cultura. Andaluc\u00eda, l\u00edder en turismo nacional, centrar\u00e1 su oferta en las experiencias","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2015\/01\/10158991w.jpg"},"aioseo_meta_data":{"post_id":"36966","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 15:08:01","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 03:11:43","updated":"2026-05-20 15:08:01"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/\" title=\"Cultura, naturaleza y gastronom\u00eda, reclamos de las comunidades en Fitur\">Cultura, naturaleza y gastronom\u00eda, reclamos de las comunidades en Fitur<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"Cultura, naturaleza y gastronom\u00eda, reclamos de las comunidades en Fitur","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/cultura-naturaleza-y-gastronomia-reclamos-de-las-comunidades-en-fitur\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/36966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=36966"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/36966\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/36967"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=36966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=36966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=36966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}