{"id":3669,"date":"2014-02-10T23:08:36","date_gmt":"2014-02-11T00:08:36","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=3669"},"modified":"2014-02-10T23:08:36","modified_gmt":"2014-02-11T00:08:36","slug":"bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/","title":{"rendered":"Bardem: \u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\u00bb"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3670\" alt=\"5930055w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5930055w-360x277.jpg\" width=\"360\" height=\"277\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5930055w-360x277.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5930055w-650x501.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5930055w-768x591.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5930055w-150x116.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5930055w-450x347.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5930055w-696x536.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5930055w-545x420.jpg 545w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5930055w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Madrid, 10 feb (EFE).- Javier Bardem se siente \u00abmuy orgulloso\u00bb de pertenecer a una Academia de Cine y a un oficio \u00abdonde la gente defiende su industria\u00bb, ha asegurado hoy el actor, un d\u00eda despu\u00e9s de la gala de los Premios Goya, marcada por la ausencia del ministro de Educaci\u00f3n, Cultura y Deporte, Jos\u00e9 Ignacio Wert.<\/p>\n<p>\u00abAyer se dijo todo, tambi\u00e9n ha respondido el ministro y me parece estupendo; la cosa est\u00e1 m\u00e1s que hablada, lo importante es que haya un debate y una conciencia de donde est\u00e1 cada uno\u00bb, se\u00f1al\u00f3 el actor a Efe antes de participar en la presentaci\u00f3n de su documental sobre el Sahara en un acto de la Academia de Cine.<\/p>\n<p>El protagonista de \u00abNo es pa\u00eds para viejos\u00bb o \u00abMar adentro\u00bb adopt\u00f3 ayer, durante la gala de los Goya, una postura reivindicativa y cr\u00edtica, al calificar de \u00abchuler\u00eda\u00bb la ausencia de Wert, al que llam\u00f3 \u00abministro de anticultura\u00bb.<\/p>\n<p>Hoy, prefiri\u00f3 centrarse en la parte estrictamente cinematogr\u00e1fica: \u00abante todo se celebr\u00f3 eso, gente con talento que hace grandes pel\u00edculas, como la triunfadora de David Trueba (\u00abVivir es f\u00e1cil con los ojos cerrados\u00bb que es una hermos\u00edsima pel\u00edcula\u00bb, subray\u00f3.<\/p>\n<p>El documental \u00abHijos de las Nubes\u00bb, que hoy se estrena en abierto en Paramount Channel y que gan\u00f3 el a\u00f1o pasado el goya al mejor documental, sigue siendo casi como un hijo para el actor dos a\u00f1os despu\u00e9s de su estreno.<\/p>\n<p>Junto con su director, \u00c1lvaro Longoria, lo ha paseado por medio mundo, lo ha llevado a la ONU o al Parlamento Europeo y la semana que viene lo estrenar\u00e1n, por fin, en cines de Francia, un pa\u00eds clave en el conflicto y un momento importante para ambos, ya que tienen previsto reunirse con parlamentarios franceses y con la ministra de Justicia de ese pa\u00eds, Michelle Alliot-Marie.<\/p>\n<p>\u00abPar\u00eds es una plaza importante y ha costado conseguirla. Ha habido un boicot absoluto, siempre que se ha propuesto ha habido muchas manos negras que lo han tirado abajo porque tienen derecho veto en ONU\u00bb, ha asegurado.<\/p>\n<p>\u00abPero por fin hemos conseguido una puerta de entrada y ah\u00ed estaremos con el martillo\u00bb.<\/p>\n<p>Bardem expresa, ante todo, un sentido de la responsabilidad con el problema del Sahara occidental.<\/p>\n<p>\u00abSi te has responsabilizado con un tema, con una historia con un peso dram\u00e1tico, que implica a muchos jugadores, tienes que estar a la altura\u00bb, dijo, satisfecho de haber podido plantear sus preguntas de ciudadano concienciado en las m\u00e1s altas esferas diplom\u00e1ticas.<\/p>\n<p>\u00abEsa gente que toma decisiones se siente por un lado muy frustrada, y avergonzada en algunos casos de no poder hacer m\u00e1s, y tambi\u00e9n indefensa porque hay un techo que no pueden superar\u00bb, ha asegurado.<\/p>\n<p>De su viaje al Sahara en 2008, cuando empez\u00f3 toda su implicaci\u00f3n en este conflicto, asegura tener muchas im\u00e1genes grabadas en la cabeza.<\/p>\n<p>\u00abSe me qued\u00f3 grabada la llegada al campamento, el largo recorrido en esos 4&#215;4 por esas carreteras imposibles, y llegar al desierto, a la mitad de la nada, el desierto m\u00e1s cruel que hay, de piedra, nada de romanticismo, y ah\u00ed en medio unas casas de adobe y unos se\u00f1ores muy contentos celebrando nuestra llegada por lo que significaba: un poco de atenci\u00f3n\u00bb, recuerda.<\/p>\n<p>\u00abEl mundo est\u00e1 lleno de cosas que denunciar, cada vez m\u00e1s\u00bb, admite. \u00abPero la experiencia directa con las cosas a uno le cambia el chip, y aquella experiencia fue impactante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 10 feb (EFE).- Javier Bardem se siente \u00abmuy orgulloso\u00bb de pertenecer a una Academia de Cine y a un oficio \u00abdonde la gente defiende su industria\u00bb, ha asegurado hoy el actor, un d\u00eda despu\u00e9s de la gala de los Premios Goya, marcada por la ausencia del ministro de Educaci\u00f3n, Cultura y Deporte, Jos\u00e9 Ignacio<\/p>\n","protected":false},"author":1,"featured_media":3670,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-3669","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 10 feb (EFE).- Javier Bardem se siente &quot;muy orgulloso&quot; de pertenecer a una Academia de Cine y a un oficio &quot;donde la gente defiende su industria&quot;, ha asegurado hoy el actor, un d\u00eda despu\u00e9s de la gala de los Premios Goya, marcada por la ausencia del ministro de Educaci\u00f3n, Cultura y Deporte, Jos\u00e9 Ignacio\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Bardem: \u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\u00bb | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 10 feb (EFE).- Javier Bardem se siente &quot;muy orgulloso&quot; de pertenecer a una Academia de Cine y a un oficio &quot;donde la gente defiende su industria&quot;, ha asegurado hoy el actor, un d\u00eda despu\u00e9s de la gala de los Premios Goya, marcada por la ausencia del ministro de Educaci\u00f3n, Cultura y Deporte, Jos\u00e9 Ignacio\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5930055w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5930055w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"616\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-11T00:08:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-11T00:08:36+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Bardem: \u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\u00bb | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 10 feb (EFE).- Javier Bardem se siente &quot;muy orgulloso&quot; de pertenecer a una Academia de Cine y a un oficio &quot;donde la gente defiende su industria&quot;, ha asegurado hoy el actor, un d\u00eda despu\u00e9s de la gala de los Premios Goya, marcada por la ausencia del ministro de Educaci\u00f3n, Cultura y Deporte, Jos\u00e9 Ignacio\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5930055w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\\\/#article\",\"name\":\"Bardem: \\u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\\u00bb | El Digital de Asturias\",\"headline\":\"Bardem: \\u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5930055w.jpg\",\"width\":800,\"height\":616},\"datePublished\":\"2014-02-10T23:08:36+01:00\",\"dateModified\":\"2014-02-10T23:08:36+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\\\/#listItem\",\"name\":\"Bardem: \\u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\\\/#listItem\",\"position\":3,\"name\":\"Bardem: \\u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\\\/\",\"name\":\"Bardem: \\u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\\u00bb | El Digital de Asturias\",\"description\":\"Madrid, 10 feb (EFE).- Javier Bardem se siente \\\"muy orgulloso\\\" de pertenecer a una Academia de Cine y a un oficio \\\"donde la gente defiende su industria\\\", ha asegurado hoy el actor, un d\\u00eda despu\\u00e9s de la gala de los Premios Goya, marcada por la ausencia del ministro de Educaci\\u00f3n, Cultura y Deporte, Jos\\u00e9 Ignacio\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5930055w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\\\/#mainImage\",\"width\":800,\"height\":616},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\\\/#mainImage\"},\"datePublished\":\"2014-02-10T23:08:36+01:00\",\"dateModified\":\"2014-02-10T23:08:36+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Bardem: \u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\u00bb | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Bardem: \u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\u00bb | El Digital de Asturias","description":"Madrid, 10 feb (EFE).- Javier Bardem se siente \"muy orgulloso\" de pertenecer a una Academia de Cine y a un oficio \"donde la gente defiende su industria\", ha asegurado hoy el actor, un d\u00eda despu\u00e9s de la gala de los Premios Goya, marcada por la ausencia del ministro de Educaci\u00f3n, Cultura y Deporte, Jos\u00e9 Ignacio","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/#article","name":"Bardem: \u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\u00bb | El Digital de Asturias","headline":"Bardem: \u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\u00bb","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5930055w.jpg","width":800,"height":616},"datePublished":"2014-02-10T23:08:36+01:00","dateModified":"2014-02-10T23:08:36+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/#listItem","name":"Bardem: \u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/#listItem","position":3,"name":"Bardem: \u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/","name":"Bardem: \u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\u00bb | El Digital de Asturias","description":"Madrid, 10 feb (EFE).- Javier Bardem se siente \"muy orgulloso\" de pertenecer a una Academia de Cine y a un oficio \"donde la gente defiende su industria\", ha asegurado hoy el actor, un d\u00eda despu\u00e9s de la gala de los Premios Goya, marcada por la ausencia del ministro de Educaci\u00f3n, Cultura y Deporte, Jos\u00e9 Ignacio","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5930055w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/#mainImage","width":800,"height":616},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/#mainImage"},"datePublished":"2014-02-10T23:08:36+01:00","dateModified":"2014-02-10T23:08:36+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Bardem: \u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\u00bb | El Digital de Asturias","og:description":"Madrid, 10 feb (EFE).- Javier Bardem se siente &quot;muy orgulloso&quot; de pertenecer a una Academia de Cine y a un oficio &quot;donde la gente defiende su industria&quot;, ha asegurado hoy el actor, un d\u00eda despu\u00e9s de la gala de los Premios Goya, marcada por la ausencia del ministro de Educaci\u00f3n, Cultura y Deporte, Jos\u00e9 Ignacio","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5930055w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5930055w.jpg","og:image:width":800,"og:image:height":616,"article:published_time":"2014-02-11T00:08:36+00:00","article:modified_time":"2014-02-11T00:08:36+00:00","twitter:card":"summary_large_image","twitter:title":"Bardem: \u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\u00bb | El Digital de Asturias","twitter:description":"Madrid, 10 feb (EFE).- Javier Bardem se siente &quot;muy orgulloso&quot; de pertenecer a una Academia de Cine y a un oficio &quot;donde la gente defiende su industria&quot;, ha asegurado hoy el actor, un d\u00eda despu\u00e9s de la gala de los Premios Goya, marcada por la ausencia del ministro de Educaci\u00f3n, Cultura y Deporte, Jos\u00e9 Ignacio","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5930055w.jpg"},"aioseo_meta_data":{"post_id":"3669","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 10:35:03","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:48:57","updated":"2026-05-15 10:35:03"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/\" title=\"Bardem: \u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\u00bb\">Bardem: \u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\u00bb<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Bardem: \u00abEstoy muy orgulloso de pertenecer a un oficio que defiende lo suyo\u00bb","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/bardem-estoy-muy-orgulloso-de-pertenecer-a-un-oficio-que-defiende-lo-suyo\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=3669"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3669\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/3670"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=3669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=3669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=3669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}