{"id":3630,"date":"2014-02-10T20:03:37","date_gmt":"2014-02-10T21:03:37","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=3630"},"modified":"2014-02-10T20:03:37","modified_gmt":"2014-02-10T21:03:37","slug":"cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/","title":{"rendered":"Cannes adelanta la entrega de los premios de la 67 edici\u00f3n por los comicios europeos"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3631\" alt=\"5928615w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5928615w-360x248.jpg\" width=\"360\" height=\"248\" \/>Par\u00eds, 10 feb (EFE).- La 67 edici\u00f3n del Festival de Cannes, que tendr\u00e1 lugar entre los pr\u00f3ximos 14 y 25 de mayo, entregar\u00e1 los premios la v\u00edspera de la clausura con motivo de las elecciones europeas, inform\u00f3 hoy la organizaci\u00f3n.<\/p>\n<p>Los comicios europeos se celebrar\u00e1n el pr\u00f3ximo 25 de mayo y esa es la raz\u00f3n que ha llevado a los organizadores a adelantar la ceremonia, que tradicionalmente tiene lugar el \u00faltimo d\u00eda del certamen.<\/p>\n<p>Este adelanto supone un recorte en los d\u00edas de competici\u00f3n, ya que la \u00faltima pel\u00edcula de la secci\u00f3n oficial se proyectar\u00e1 el viernes 23.<\/p>\n<p>El palmar\u00e9s se dar\u00e1 a conocer el s\u00e1bado 24 de mayo en la habitual gala en el Gran Teatro Lumi\u00e8re, y el domingo 25 solo est\u00e1 previsto una nueva proyecci\u00f3n de la pel\u00edcula que se alce con la Palma de Oro, que el a\u00f1o pasado fue a parar a \u00abLa vie d&#8217;Ad\u00e8le\u00bb (\u00abLa vida de Ad\u00e8le\u00bb), dirigida por el tunecino Abdellatif Kechiche.<\/p>\n<p>El anuncio de los ganadores de la secci\u00f3n \u00abUna cierta mirada\u00bb, la segunda en importancia de Cannes y que acoge las pel\u00edculas m\u00e1s innovadoras y atrevidas de cineastas habitualmente menos conocidos o noveles, se realizar\u00e1 el viernes 23 de mayo, al igual que los de la Cinefundaci\u00f3n, que busca descubrir nuevos talentos, tambi\u00e9n un d\u00eda antes de lo habitual.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par\u00eds, 10 feb (EFE).- La 67 edici\u00f3n del Festival de Cannes, que tendr\u00e1 lugar entre los pr\u00f3ximos 14 y 25 de mayo, entregar\u00e1 los premios la v\u00edspera de la clausura con motivo de las elecciones europeas, inform\u00f3 hoy la organizaci\u00f3n. Los comicios europeos se celebrar\u00e1n el pr\u00f3ximo 25 de mayo y esa es la raz\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":3631,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-3630","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Par\u00eds, 10 feb (EFE).- La 67 edici\u00f3n del Festival de Cannes, que tendr\u00e1 lugar entre los pr\u00f3ximos 14 y 25 de mayo, entregar\u00e1 los premios la v\u00edspera de la clausura con motivo de las elecciones europeas, inform\u00f3 hoy la organizaci\u00f3n. Los comicios europeos se celebrar\u00e1n el pr\u00f3ximo 25 de mayo y esa es la raz\u00f3n\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Cannes adelanta la entrega de los premios de la 67 edici\u00f3n por los comicios europeos | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Par\u00eds, 10 feb (EFE).- La 67 edici\u00f3n del Festival de Cannes, que tendr\u00e1 lugar entre los pr\u00f3ximos 14 y 25 de mayo, entregar\u00e1 los premios la v\u00edspera de la clausura con motivo de las elecciones europeas, inform\u00f3 hoy la organizaci\u00f3n. Los comicios europeos se celebrar\u00e1n el pr\u00f3ximo 25 de mayo y esa es la raz\u00f3n\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5928615w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5928615w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"553\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-10T21:03:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-10T21:03:37+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Cannes adelanta la entrega de los premios de la 67 edici\u00f3n por los comicios europeos | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Par\u00eds, 10 feb (EFE).- La 67 edici\u00f3n del Festival de Cannes, que tendr\u00e1 lugar entre los pr\u00f3ximos 14 y 25 de mayo, entregar\u00e1 los premios la v\u00edspera de la clausura con motivo de las elecciones europeas, inform\u00f3 hoy la organizaci\u00f3n. Los comicios europeos se celebrar\u00e1n el pr\u00f3ximo 25 de mayo y esa es la raz\u00f3n\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5928615w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\\\/#article\",\"name\":\"Cannes adelanta la entrega de los premios de la 67 edici\\u00f3n por los comicios europeos | El Digital de Asturias\",\"headline\":\"Cannes adelanta la entrega de los premios de la 67 edici\\u00f3n por los comicios europeos\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5928615w.jpg\",\"width\":800,\"height\":553},\"datePublished\":\"2014-02-10T20:03:37+01:00\",\"dateModified\":\"2014-02-10T20:03:37+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\\\/#listItem\",\"name\":\"Cannes adelanta la entrega de los premios de la 67 edici\\u00f3n por los comicios europeos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\\\/#listItem\",\"position\":3,\"name\":\"Cannes adelanta la entrega de los premios de la 67 edici\\u00f3n por los comicios europeos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\\\/\",\"name\":\"Cannes adelanta la entrega de los premios de la 67 edici\\u00f3n por los comicios europeos | El Digital de Asturias\",\"description\":\"Par\\u00eds, 10 feb (EFE).- La 67 edici\\u00f3n del Festival de Cannes, que tendr\\u00e1 lugar entre los pr\\u00f3ximos 14 y 25 de mayo, entregar\\u00e1 los premios la v\\u00edspera de la clausura con motivo de las elecciones europeas, inform\\u00f3 hoy la organizaci\\u00f3n. Los comicios europeos se celebrar\\u00e1n el pr\\u00f3ximo 25 de mayo y esa es la raz\\u00f3n\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5928615w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\\\/#mainImage\",\"width\":800,\"height\":553},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\\\/#mainImage\"},\"datePublished\":\"2014-02-10T20:03:37+01:00\",\"dateModified\":\"2014-02-10T20:03:37+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Cannes adelanta la entrega de los premios de la 67 edici\u00f3n por los comicios europeos | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Cannes adelanta la entrega de los premios de la 67 edici\u00f3n por los comicios europeos | El Digital de Asturias","description":"Par\u00eds, 10 feb (EFE).- La 67 edici\u00f3n del Festival de Cannes, que tendr\u00e1 lugar entre los pr\u00f3ximos 14 y 25 de mayo, entregar\u00e1 los premios la v\u00edspera de la clausura con motivo de las elecciones europeas, inform\u00f3 hoy la organizaci\u00f3n. Los comicios europeos se celebrar\u00e1n el pr\u00f3ximo 25 de mayo y esa es la raz\u00f3n","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/#article","name":"Cannes adelanta la entrega de los premios de la 67 edici\u00f3n por los comicios europeos | El Digital de Asturias","headline":"Cannes adelanta la entrega de los premios de la 67 edici\u00f3n por los comicios europeos","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5928615w.jpg","width":800,"height":553},"datePublished":"2014-02-10T20:03:37+01:00","dateModified":"2014-02-10T20:03:37+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/#listItem","name":"Cannes adelanta la entrega de los premios de la 67 edici\u00f3n por los comicios europeos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/#listItem","position":3,"name":"Cannes adelanta la entrega de los premios de la 67 edici\u00f3n por los comicios europeos","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/","name":"Cannes adelanta la entrega de los premios de la 67 edici\u00f3n por los comicios europeos | El Digital de Asturias","description":"Par\u00eds, 10 feb (EFE).- La 67 edici\u00f3n del Festival de Cannes, que tendr\u00e1 lugar entre los pr\u00f3ximos 14 y 25 de mayo, entregar\u00e1 los premios la v\u00edspera de la clausura con motivo de las elecciones europeas, inform\u00f3 hoy la organizaci\u00f3n. Los comicios europeos se celebrar\u00e1n el pr\u00f3ximo 25 de mayo y esa es la raz\u00f3n","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5928615w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/#mainImage","width":800,"height":553},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/#mainImage"},"datePublished":"2014-02-10T20:03:37+01:00","dateModified":"2014-02-10T20:03:37+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Cannes adelanta la entrega de los premios de la 67 edici\u00f3n por los comicios europeos | El Digital de Asturias","og:description":"Par\u00eds, 10 feb (EFE).- La 67 edici\u00f3n del Festival de Cannes, que tendr\u00e1 lugar entre los pr\u00f3ximos 14 y 25 de mayo, entregar\u00e1 los premios la v\u00edspera de la clausura con motivo de las elecciones europeas, inform\u00f3 hoy la organizaci\u00f3n. Los comicios europeos se celebrar\u00e1n el pr\u00f3ximo 25 de mayo y esa es la raz\u00f3n","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5928615w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5928615w.jpg","og:image:width":800,"og:image:height":553,"article:published_time":"2014-02-10T21:03:37+00:00","article:modified_time":"2014-02-10T21:03:37+00:00","twitter:card":"summary_large_image","twitter:title":"Cannes adelanta la entrega de los premios de la 67 edici\u00f3n por los comicios europeos | El Digital de Asturias","twitter:description":"Par\u00eds, 10 feb (EFE).- La 67 edici\u00f3n del Festival de Cannes, que tendr\u00e1 lugar entre los pr\u00f3ximos 14 y 25 de mayo, entregar\u00e1 los premios la v\u00edspera de la clausura con motivo de las elecciones europeas, inform\u00f3 hoy la organizaci\u00f3n. Los comicios europeos se celebrar\u00e1n el pr\u00f3ximo 25 de mayo y esa es la raz\u00f3n","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5928615w.jpg"},"aioseo_meta_data":{"post_id":"3630","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 10:30:55","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:48:55","updated":"2026-05-15 10:30:55"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/\" title=\"Cannes adelanta la entrega de los premios de la 67 edici\u00f3n por los comicios europeos\">Cannes adelanta la entrega de los premios de la 67 edici\u00f3n por los comicios europeos<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Cannes adelanta la entrega de los premios de la 67 edici\u00f3n por los comicios europeos","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/cannes-adelanta-la-entrega-de-los-premios-de-la-67-edicion-por-los-comicios-europeos\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=3630"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/3631"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=3630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=3630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=3630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}