{"id":3584,"date":"2014-02-10T19:36:22","date_gmt":"2014-02-10T20:36:22","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=3584"},"modified":"2014-02-10T19:36:22","modified_gmt":"2014-02-10T20:36:22","slug":"fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/","title":{"rendered":"Fallece el director dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por \u00abEl fest\u00edn de Babette\u00bb"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3585\" alt=\"5927638w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5927638w-360x247.jpg\" width=\"360\" height=\"247\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5927638w-360x247.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5927638w-650x446.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5927638w-768x527.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5927638w-150x103.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5927638w-450x309.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5927638w-100x70.jpg 100w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5927638w-218x150.jpg 218w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5927638w-696x478.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5927638w-612x420.jpg 612w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5927638w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Copenhague, 10 feb (EFE).- El director de cine dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por \u00abBabettes G\u00e6stebud\u00bb (El fest\u00edn de Babette), ha fallecido a los 95 a\u00f1os, inform\u00f3 hoy su familia.<\/p>\n<p>Axel fue el primer cinemat\u00f3grafo dan\u00e9s en ganar el \u00d3scar a la mejor pel\u00edcula de habla no inglesa, gracias a su adaptaci\u00f3n de la novela del mismo nombre de la escritora Isak Dinesen.<\/p>\n<p>Nacido en Aarhus (Dinamarca) en 1918, Axel creci\u00f3 en Par\u00eds, donde su padre ten\u00eda una f\u00e1brica de muebles, y luego regres\u00f3 a su pa\u00eds de origen para formarse como actor en el Teatro Real.<\/p>\n<p>Tras trabajar como actor en Francia y realizar varias obras de teatro para la televisi\u00f3n p\u00fablica danesa, debut\u00f3 como director de cine en 1955 con el drama social \u00abAltid ballade\u00bb (Siempre jaleo).<\/p>\n<p>Fue la primera de la veintena de obras que conforman su filmograf\u00eda, clausurada con \u00abLeila\u00bb (2001).<\/p>\n<p>Su mayor \u00e9xito le vino con \u00abBabettes g\u00e6stebud\u00bb (El fest\u00edn de Babette), de la que present\u00f3 su primer proyecto en 1973, pero no pudo rodar hasta una d\u00e9cada despu\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Copenhague, 10 feb (EFE).- El director de cine dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por \u00abBabettes G\u00e6stebud\u00bb (El fest\u00edn de Babette), ha fallecido a los 95 a\u00f1os, inform\u00f3 hoy su familia. Axel fue el primer cinemat\u00f3grafo dan\u00e9s en ganar el \u00d3scar a la mejor pel\u00edcula de habla no inglesa, gracias a su adaptaci\u00f3n de la<\/p>\n","protected":false},"author":1,"featured_media":3585,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-3584","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Copenhague, 10 feb (EFE).- El director de cine dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por &quot;Babettes G\u00e6stebud&quot; (El fest\u00edn de Babette), ha fallecido a los 95 a\u00f1os, inform\u00f3 hoy su familia. Axel fue el primer cinemat\u00f3grafo dan\u00e9s en ganar el \u00d3scar a la mejor pel\u00edcula de habla no inglesa, gracias a su adaptaci\u00f3n de la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Fallece el director dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por \u00abEl fest\u00edn de Babette\u00bb | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Copenhague, 10 feb (EFE).- El director de cine dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por &quot;Babettes G\u00e6stebud&quot; (El fest\u00edn de Babette), ha fallecido a los 95 a\u00f1os, inform\u00f3 hoy su familia. Axel fue el primer cinemat\u00f3grafo dan\u00e9s en ganar el \u00d3scar a la mejor pel\u00edcula de habla no inglesa, gracias a su adaptaci\u00f3n de la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5927638w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5927638w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-10T20:36:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-10T20:36:22+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Fallece el director dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por \u00abEl fest\u00edn de Babette\u00bb | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Copenhague, 10 feb (EFE).- El director de cine dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por &quot;Babettes G\u00e6stebud&quot; (El fest\u00edn de Babette), ha fallecido a los 95 a\u00f1os, inform\u00f3 hoy su familia. Axel fue el primer cinemat\u00f3grafo dan\u00e9s en ganar el \u00d3scar a la mejor pel\u00edcula de habla no inglesa, gracias a su adaptaci\u00f3n de la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5927638w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\\\/#article\",\"name\":\"Fallece el director dan\\u00e9s Gabriel Axel, \\u00d3scar en 1988 por \\u00abEl fest\\u00edn de Babette\\u00bb | El Digital de Asturias\",\"headline\":\"Fallece el director dan\\u00e9s Gabriel Axel, \\u00d3scar en 1988 por \\u00abEl fest\\u00edn de Babette\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5927638w.jpg\",\"width\":800,\"height\":549},\"datePublished\":\"2014-02-10T19:36:22+01:00\",\"dateModified\":\"2014-02-10T19:36:22+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\\\/#listItem\",\"name\":\"Fallece el director dan\\u00e9s Gabriel Axel, \\u00d3scar en 1988 por \\u00abEl fest\\u00edn de Babette\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\\\/#listItem\",\"position\":3,\"name\":\"Fallece el director dan\\u00e9s Gabriel Axel, \\u00d3scar en 1988 por \\u00abEl fest\\u00edn de Babette\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\\\/\",\"name\":\"Fallece el director dan\\u00e9s Gabriel Axel, \\u00d3scar en 1988 por \\u00abEl fest\\u00edn de Babette\\u00bb | El Digital de Asturias\",\"description\":\"Copenhague, 10 feb (EFE).- El director de cine dan\\u00e9s Gabriel Axel, \\u00d3scar en 1988 por \\\"Babettes G\\u00e6stebud\\\" (El fest\\u00edn de Babette), ha fallecido a los 95 a\\u00f1os, inform\\u00f3 hoy su familia. Axel fue el primer cinemat\\u00f3grafo dan\\u00e9s en ganar el \\u00d3scar a la mejor pel\\u00edcula de habla no inglesa, gracias a su adaptaci\\u00f3n de la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5927638w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\\\/#mainImage\",\"width\":800,\"height\":549},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\\\/#mainImage\"},\"datePublished\":\"2014-02-10T19:36:22+01:00\",\"dateModified\":\"2014-02-10T19:36:22+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Fallece el director dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por \u00abEl fest\u00edn de Babette\u00bb | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Fallece el director dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por \u00abEl fest\u00edn de Babette\u00bb | El Digital de Asturias","description":"Copenhague, 10 feb (EFE).- El director de cine dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por \"Babettes G\u00e6stebud\" (El fest\u00edn de Babette), ha fallecido a los 95 a\u00f1os, inform\u00f3 hoy su familia. Axel fue el primer cinemat\u00f3grafo dan\u00e9s en ganar el \u00d3scar a la mejor pel\u00edcula de habla no inglesa, gracias a su adaptaci\u00f3n de la","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/#article","name":"Fallece el director dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por \u00abEl fest\u00edn de Babette\u00bb | El Digital de Asturias","headline":"Fallece el director dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por \u00abEl fest\u00edn de Babette\u00bb","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5927638w.jpg","width":800,"height":549},"datePublished":"2014-02-10T19:36:22+01:00","dateModified":"2014-02-10T19:36:22+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/#listItem","name":"Fallece el director dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por \u00abEl fest\u00edn de Babette\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/#listItem","position":3,"name":"Fallece el director dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por \u00abEl fest\u00edn de Babette\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/","name":"Fallece el director dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por \u00abEl fest\u00edn de Babette\u00bb | El Digital de Asturias","description":"Copenhague, 10 feb (EFE).- El director de cine dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por \"Babettes G\u00e6stebud\" (El fest\u00edn de Babette), ha fallecido a los 95 a\u00f1os, inform\u00f3 hoy su familia. Axel fue el primer cinemat\u00f3grafo dan\u00e9s en ganar el \u00d3scar a la mejor pel\u00edcula de habla no inglesa, gracias a su adaptaci\u00f3n de la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5927638w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/#mainImage","width":800,"height":549},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/#mainImage"},"datePublished":"2014-02-10T19:36:22+01:00","dateModified":"2014-02-10T19:36:22+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Fallece el director dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por \u00abEl fest\u00edn de Babette\u00bb | El Digital de Asturias","og:description":"Copenhague, 10 feb (EFE).- El director de cine dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por &quot;Babettes G\u00e6stebud&quot; (El fest\u00edn de Babette), ha fallecido a los 95 a\u00f1os, inform\u00f3 hoy su familia. Axel fue el primer cinemat\u00f3grafo dan\u00e9s en ganar el \u00d3scar a la mejor pel\u00edcula de habla no inglesa, gracias a su adaptaci\u00f3n de la","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5927638w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5927638w.jpg","og:image:width":800,"og:image:height":549,"article:published_time":"2014-02-10T20:36:22+00:00","article:modified_time":"2014-02-10T20:36:22+00:00","twitter:card":"summary_large_image","twitter:title":"Fallece el director dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por \u00abEl fest\u00edn de Babette\u00bb | El Digital de Asturias","twitter:description":"Copenhague, 10 feb (EFE).- El director de cine dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por &quot;Babettes G\u00e6stebud&quot; (El fest\u00edn de Babette), ha fallecido a los 95 a\u00f1os, inform\u00f3 hoy su familia. Axel fue el primer cinemat\u00f3grafo dan\u00e9s en ganar el \u00d3scar a la mejor pel\u00edcula de habla no inglesa, gracias a su adaptaci\u00f3n de la","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5927638w.jpg"},"aioseo_meta_data":{"post_id":"3584","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 10:25:20","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:48:51","updated":"2026-05-15 10:25:20"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/\" title=\"Fallece el director dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por \u00abEl fest\u00edn de Babette\u00bb\">Fallece el director dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por \u00abEl fest\u00edn de Babette\u00bb<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Fallece el director dan\u00e9s Gabriel Axel, \u00d3scar en 1988 por \u00abEl fest\u00edn de Babette\u00bb","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/fallece-el-director-danes-gabriel-axel-oscar-en-1988-por-el-festin-de-babette\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=3584"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3584\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/3585"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=3584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=3584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=3584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}