{"id":3543,"date":"2014-02-10T01:02:20","date_gmt":"2014-02-10T02:02:20","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=3543"},"modified":"2014-02-10T01:02:20","modified_gmt":"2014-02-10T02:02:20","slug":"amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/","title":{"rendered":"\u00abAmor\u00bb, de Michael Haneke, Goya a la mejor pel\u00edcula europea"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3544\" alt=\"5926580w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5926580w-360x225.jpg\" width=\"360\" height=\"225\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5926580w-360x225.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5926580w-650x407.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5926580w-768x481.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5926580w-150x94.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5926580w-450x282.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5926580w-696x436.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5926580w-671x420.jpg 671w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5926580w-279x173.jpg 279w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5926580w-480x300.jpg 480w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5926580w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Madrid, 9 feb (EFE).- \u00abAmor\u00bb, la tremenda historia de Michael Haneke que conquist\u00f3 Cannes, el \u00d3scar y el Globo de Oro, se ha hecho hoy con el Goya al mejor filme europeo, cerrando un ciclo que la convierte, con m\u00e1s de medio centenar de galardones, en el filme m\u00e1s premiado del realizador austr\u00edaco.<\/p>\n<p>Haneke ha conseguido el Goya frente a tres trabajos de altura: \u00abLa caza\u00bb, del dan\u00e9s Thomas Vinterberg; \u00abLa gran belleza\u00bb, del italiano Paolo Sorrentino, y \u00abLa vida de Adele\u00bb, del francotunecino Abdllatif Kechiche.<\/p>\n<p>Un premio que ha recogido el actor Ram\u00f3n Aguirre, que tuvo un peque\u00f1o papel en la pel\u00edcula austr\u00edaca, de manos de Aitana S\u00e1nchez Gij\u00f3n y del presidente del Festival de Cannes, Thierry Fremaux.<\/p>\n<p>Aunque presentada por primera vez en el Festival de Cannes de 2012 y ganadora de la mayor\u00eda de los premios por los que compiti\u00f3 en 2013, ha competido en la 28 edici\u00f3n de los Goya por su tard\u00edo estreno en Espa\u00f1a.<\/p>\n<p>Con una historia tan realista como tierna y dura, la de la decadencia de dos seres humanos, Haneke ha construido una historia que ha provocado tanta adoraci\u00f3n como pavor por la cruda manera en la que se han enfrentado a los \u00faltimos meses de vida de una pareja de ancianos.<\/p>\n<p>Emmanuelle Riva y Jean-Louis Trintignant fueron la perfecta pareja protagonista para esta historia, en la que muestran sin un atisbo de pudor ni condescendencia la crueldad de una situaci\u00f3n que puede tornarse en el mayor acto de amor de un ser humano.<\/p>\n<p>Una pel\u00edcula que mantiene el estilo narrativo seco y directo de Haneke pero que al mismo tiempo muestra una ternura y una esperanza poco habituales en el cine del autor de pel\u00edculas como \u00abFunny Games\u00bb, \u00abCach\u00e9\u00bb, \u00abLa pianista\u00bb o \u00abLa cinta blanca\u00bb.<\/p>\n<p>Y que ha ganado ahora el Goya del cine espa\u00f1ol en un enfrentamiento en el que ha tenido a tres oponentes de gran calidad.<\/p>\n<p>\u00abLa gran belleza\u00bb y \u00abLa caza\u00bb tratar\u00e1n este a\u00f1o de hacerse con el \u00d3scar que el a\u00f1o pasado gan\u00f3 \u00abAmor\u00bb, y en ambos casos precedidas de un paso por Cannes que les report\u00f3 buenas cr\u00edticas y el premio de mejor interpretaci\u00f3n masculina en el caso del filme dan\u00e9s, que fue para Mads Mikkelsen.<\/p>\n<p>El filme italiano, por su parte, ha ganado ya el Globo de Oro a la mejor producci\u00f3n extranjera, y la cuarta en discordia, \u00abLa vida de Adele\u00bb, tambi\u00e9n comenz\u00f3 su exitosa andadura en Cannes, donde gan\u00f3 la Palma de Oro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 9 feb (EFE).- \u00abAmor\u00bb, la tremenda historia de Michael Haneke que conquist\u00f3 Cannes, el \u00d3scar y el Globo de Oro, se ha hecho hoy con el Goya al mejor filme europeo, cerrando un ciclo que la convierte, con m\u00e1s de medio centenar de galardones, en el filme m\u00e1s premiado del realizador austr\u00edaco. Haneke ha<\/p>\n","protected":false},"author":1,"featured_media":3544,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-3543","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 9 feb (EFE).- &quot;Amor&quot;, la tremenda historia de Michael Haneke que conquist\u00f3 Cannes, el \u00d3scar y el Globo de Oro, se ha hecho hoy con el Goya al mejor filme europeo, cerrando un ciclo que la convierte, con m\u00e1s de medio centenar de galardones, en el filme m\u00e1s premiado del realizador austr\u00edaco. Haneke ha\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00abAmor\u00bb, de Michael Haneke, Goya a la mejor pel\u00edcula europea | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 9 feb (EFE).- &quot;Amor&quot;, la tremenda historia de Michael Haneke que conquist\u00f3 Cannes, el \u00d3scar y el Globo de Oro, se ha hecho hoy con el Goya al mejor filme europeo, cerrando un ciclo que la convierte, con m\u00e1s de medio centenar de galardones, en el filme m\u00e1s premiado del realizador austr\u00edaco. Haneke ha\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5926580w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5926580w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"501\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-10T02:02:20+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-10T02:02:20+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00abAmor\u00bb, de Michael Haneke, Goya a la mejor pel\u00edcula europea | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 9 feb (EFE).- &quot;Amor&quot;, la tremenda historia de Michael Haneke que conquist\u00f3 Cannes, el \u00d3scar y el Globo de Oro, se ha hecho hoy con el Goya al mejor filme europeo, cerrando un ciclo que la convierte, con m\u00e1s de medio centenar de galardones, en el filme m\u00e1s premiado del realizador austr\u00edaco. Haneke ha\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5926580w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\\\/#article\",\"name\":\"\\u00abAmor\\u00bb, de Michael Haneke, Goya a la mejor pel\\u00edcula europea | El Digital de Asturias\",\"headline\":\"\\u00abAmor\\u00bb, de Michael Haneke, Goya a la mejor pel\\u00edcula europea\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5926580w.jpg\",\"width\":800,\"height\":501},\"datePublished\":\"2014-02-10T01:02:20+01:00\",\"dateModified\":\"2014-02-10T01:02:20+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\\\/#listItem\",\"name\":\"\\u00abAmor\\u00bb, de Michael Haneke, Goya a la mejor pel\\u00edcula europea\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\\\/#listItem\",\"position\":3,\"name\":\"\\u00abAmor\\u00bb, de Michael Haneke, Goya a la mejor pel\\u00edcula europea\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\\\/\",\"name\":\"\\u00abAmor\\u00bb, de Michael Haneke, Goya a la mejor pel\\u00edcula europea | El Digital de Asturias\",\"description\":\"Madrid, 9 feb (EFE).- \\\"Amor\\\", la tremenda historia de Michael Haneke que conquist\\u00f3 Cannes, el \\u00d3scar y el Globo de Oro, se ha hecho hoy con el Goya al mejor filme europeo, cerrando un ciclo que la convierte, con m\\u00e1s de medio centenar de galardones, en el filme m\\u00e1s premiado del realizador austr\\u00edaco. Haneke ha\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5926580w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\\\/#mainImage\",\"width\":800,\"height\":501},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\\\/#mainImage\"},\"datePublished\":\"2014-02-10T01:02:20+01:00\",\"dateModified\":\"2014-02-10T01:02:20+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>\u00abAmor\u00bb, de Michael Haneke, Goya a la mejor pel\u00edcula europea | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"\u00abAmor\u00bb, de Michael Haneke, Goya a la mejor pel\u00edcula europea | El Digital de Asturias","description":"Madrid, 9 feb (EFE).- \"Amor\", la tremenda historia de Michael Haneke que conquist\u00f3 Cannes, el \u00d3scar y el Globo de Oro, se ha hecho hoy con el Goya al mejor filme europeo, cerrando un ciclo que la convierte, con m\u00e1s de medio centenar de galardones, en el filme m\u00e1s premiado del realizador austr\u00edaco. Haneke ha","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/#article","name":"\u00abAmor\u00bb, de Michael Haneke, Goya a la mejor pel\u00edcula europea | El Digital de Asturias","headline":"\u00abAmor\u00bb, de Michael Haneke, Goya a la mejor pel\u00edcula europea","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5926580w.jpg","width":800,"height":501},"datePublished":"2014-02-10T01:02:20+01:00","dateModified":"2014-02-10T01:02:20+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/#listItem","name":"\u00abAmor\u00bb, de Michael Haneke, Goya a la mejor pel\u00edcula europea"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/#listItem","position":3,"name":"\u00abAmor\u00bb, de Michael Haneke, Goya a la mejor pel\u00edcula europea","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/","name":"\u00abAmor\u00bb, de Michael Haneke, Goya a la mejor pel\u00edcula europea | El Digital de Asturias","description":"Madrid, 9 feb (EFE).- \"Amor\", la tremenda historia de Michael Haneke que conquist\u00f3 Cannes, el \u00d3scar y el Globo de Oro, se ha hecho hoy con el Goya al mejor filme europeo, cerrando un ciclo que la convierte, con m\u00e1s de medio centenar de galardones, en el filme m\u00e1s premiado del realizador austr\u00edaco. Haneke ha","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5926580w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/#mainImage","width":800,"height":501},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/#mainImage"},"datePublished":"2014-02-10T01:02:20+01:00","dateModified":"2014-02-10T01:02:20+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"\u00abAmor\u00bb, de Michael Haneke, Goya a la mejor pel\u00edcula europea | El Digital de Asturias","og:description":"Madrid, 9 feb (EFE).- &quot;Amor&quot;, la tremenda historia de Michael Haneke que conquist\u00f3 Cannes, el \u00d3scar y el Globo de Oro, se ha hecho hoy con el Goya al mejor filme europeo, cerrando un ciclo que la convierte, con m\u00e1s de medio centenar de galardones, en el filme m\u00e1s premiado del realizador austr\u00edaco. Haneke ha","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5926580w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5926580w.jpg","og:image:width":800,"og:image:height":501,"article:published_time":"2014-02-10T02:02:20+00:00","article:modified_time":"2014-02-10T02:02:20+00:00","twitter:card":"summary_large_image","twitter:title":"\u00abAmor\u00bb, de Michael Haneke, Goya a la mejor pel\u00edcula europea | El Digital de Asturias","twitter:description":"Madrid, 9 feb (EFE).- &quot;Amor&quot;, la tremenda historia de Michael Haneke que conquist\u00f3 Cannes, el \u00d3scar y el Globo de Oro, se ha hecho hoy con el Goya al mejor filme europeo, cerrando un ciclo que la convierte, con m\u00e1s de medio centenar de galardones, en el filme m\u00e1s premiado del realizador austr\u00edaco. Haneke ha","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5926580w.jpg"},"aioseo_meta_data":{"post_id":"3543","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 10:15:13","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:48:33","updated":"2026-05-15 10:15:13"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/\" title=\"\u00abAmor\u00bb, de Michael Haneke, Goya a la mejor pel\u00edcula europea\">\u00abAmor\u00bb, de Michael Haneke, Goya a la mejor pel\u00edcula europea<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"\u00abAmor\u00bb, de Michael Haneke, Goya a la mejor pel\u00edcula europea","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/amor-de-michael-haneke-goya-a-la-mejor-pelicula-europea\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=3543"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3543\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/3544"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=3543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=3543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=3543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}