{"id":3501,"date":"2014-02-09T18:32:50","date_gmt":"2014-02-09T19:32:50","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=3501"},"modified":"2014-02-09T18:32:50","modified_gmt":"2014-02-09T19:32:50","slug":"el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/","title":{"rendered":"El miedo argentino y el fanatismo alem\u00e1n, en un inquietante domingo de Berlinale"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3502\" alt=\"5925845w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5925845w-360x261.jpg\" width=\"360\" height=\"261\" \/>Berl\u00edn, 9 feb (EFE).- Argentina entr\u00f3 en competici\u00f3n en la Berlinale con \u00abHistoria del miedo\u00bb, un film centrado en el p\u00e1nico a lo externo dirigido por Benjamin Naishtat, compartiendo jornada con un v\u00eda crucis alem\u00e1n sobre el fanatismo cat\u00f3lico en nuestros d\u00edas.<\/p>\n<p>El debutante Naishtat y el alem\u00e1n Dietrich Br\u00fcggemann, como representante del cine anfitri\u00f3n a concurso, dieron como resultado un domingo inquietante, poblado de los fantasmas internos, propios o adquiridos, generados en sociedades avanzadas.<\/p>\n<p>\u00abLa historia del miedo\u00bb plasma el terror \u00abal otro\u00bb, desde la perspectiva de un barrio privado de las inmediaciones de Buenos Aires, donde cualquier persona, comportamiento o mero gesto ajeno al c\u00edrculo habitual se percibe como una agresi\u00f3n.<\/p>\n<p>\u00abKreuzweg\u00bb (V\u00eda crucis) es la historia de una muchacha de 14 a\u00f1os cuya madre sigue estrictamente el dogma de la Hermandad de P\u00edo XII, mientras el padre calla, mezclado con la adoraci\u00f3n adolescente de la chica hacia el cura de la escuela, que le inculca el precepto del sacrificio extremo como norma de vida.<\/p>\n<p>\u00abPartimos de un fanatismo religioso que algunos creer\u00e1n propio de n\u00facleos isl\u00e1micos, pero que convive en sociedades consideradas perfectas, como la nuestra, donde la religi\u00f3n act\u00faa en complicidad con una violencia sutil emanada de la familia\u00bb, indic\u00f3 Br\u00fcggemann.<\/p>\n<p>Ni el filme argentino ni el alem\u00e1n promet\u00edan un domingo de colorines, pero, tras la sobredosis de estrellato exhibida el s\u00e1bado por George Clooney y su \u00abThe Monuments Men\u00bb en la Berlinale, le vino bien el regreso a la reflexi\u00f3n.<\/p>\n<p>\u00abHistoria del miedo\u00bb incide en lo que su director, nacido en Buenos Aires en 1986, califica como un \u00abproblema muy argentino\u00bb, aunque extendido a buena parte del resto de Am\u00e9rica Latina: blindarse tras las vallas en barrios cerrados, en un intento vano por protegerse de los pavores que en realidad se llevan dentro.<\/p>\n<p>\u00abLos argentinos sufrimos especialmente de un mal llamado miedo al otro. Se refleja en la profusi\u00f3n de barrios cerrados, con los que la clase adinerada trata de protegerse del exterior\u00bb, indic\u00f3 a Efe Naishtat, ante su estreno en la alfombra roja de la Berlinale.<\/p>\n<p>El suyo es un filme de corte experimental y planos cortos, poblado de personajes \u00abaprisionados en una especie de miedo que ni ellos mismos saben a qu\u00e9 se orienta\u00bb y generador del p\u00e1nico ante \u00abcualquier presencia de quienes no pertenecen a su c\u00edrculo\u00bb.<\/p>\n<p>Naishtat trata de \u00abdecodificar la realidad argentina\u00bb, a trav\u00e9s de una pel\u00edcula que toma la apariencia de un &#8216;thriller&#8217;, aunque, como advierte su director, no es una pel\u00edcula de ese g\u00e9nero.<\/p>\n<p>Un helic\u00f3ptero sobrevolando el barrio y sus aleda\u00f1os es el arranque del filme, que luego recala en un grupo de habitantes que de saborear un asado y beber vino tinto pasan al p\u00e1nico colectivo porque se cort\u00f3 la electricidad -\u00ablo que ocurre constantemente en Buenos Aires, solo que ellos lo perciben como algo ajeno a su condici\u00f3n social\u00bb, apunt\u00f3 Naishtat.<\/p>\n<p>Su pel\u00edcula incide en la tem\u00e1tica de novelas como \u00abLa viudas de los jueves\u00bb, de su compatriota Claudia Pi\u00f1eiro, tambi\u00e9n llevada al cine, o de la pel\u00edcula \u00abLa zona\u00bb, del uruguayo Rodrigo Pl\u00e1.<\/p>\n<p>\u00abHistoria del miedo\u00bb lleg\u00f3 a la Berlinale arropada por la subvenci\u00f3n al gui\u00f3n del World Cinema Fund, el fondo de la Berlinale a los j\u00f3venes cineastas, y fue la primera de las dos cintas argentinas a competici\u00f3n en esta edici\u00f3n del festival, muy volcado a las cinematograf\u00edas de Am\u00e9rica Latina.<\/p>\n<p>El pr\u00f3ximo mi\u00e9rcoles se proyectar\u00e1 \u00abLa tercera orilla\u00bb, de la tambi\u00e9n argentina Celina Murga, quien regresa a la Berlinale despu\u00e9s de haber exhibido en 2012, el documental \u00abEscuela normal\u00bb.<\/p>\n<p>A concurso acudir\u00e1n, asimismo, \u00abPraia do Futuro\u00bb, del brasile\u00f1o Karim A\u00efnouz, mientras que la peruana Claudia Llosa, Oso de Oro en 2009 con \u00abLa teta asustada\u00bb, compite con \u00abAloft\u00bb, rodada en ingl\u00e9s y entre hielos polares.<\/p>\n<p>Son cuatro representantes de Am\u00e9rica Latina, el mismo n\u00famero de los cineastas alemanes incluidos en la secci\u00f3n a competici\u00f3n, entre el total de 20 aspirantes a los Osos.<\/p>\n<p>Gemma Casadevall<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 9 feb (EFE).- Argentina entr\u00f3 en competici\u00f3n en la Berlinale con \u00abHistoria del miedo\u00bb, un film centrado en el p\u00e1nico a lo externo dirigido por Benjamin Naishtat, compartiendo jornada con un v\u00eda crucis alem\u00e1n sobre el fanatismo cat\u00f3lico en nuestros d\u00edas. El debutante Naishtat y el alem\u00e1n Dietrich Br\u00fcggemann, como representante del cine anfitri\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":3502,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-3501","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 9 feb (EFE).- Argentina entr\u00f3 en competici\u00f3n en la Berlinale con &quot;Historia del miedo&quot;, un film centrado en el p\u00e1nico a lo externo dirigido por Benjamin Naishtat, compartiendo jornada con un v\u00eda crucis alem\u00e1n sobre el fanatismo cat\u00f3lico en nuestros d\u00edas. El debutante Naishtat y el alem\u00e1n Dietrich Br\u00fcggemann, como representante del cine anfitri\u00f3n\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El miedo argentino y el fanatismo alem\u00e1n, en un inquietante domingo de Berlinale | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 9 feb (EFE).- Argentina entr\u00f3 en competici\u00f3n en la Berlinale con &quot;Historia del miedo&quot;, un film centrado en el p\u00e1nico a lo externo dirigido por Benjamin Naishtat, compartiendo jornada con un v\u00eda crucis alem\u00e1n sobre el fanatismo cat\u00f3lico en nuestros d\u00edas. El debutante Naishtat y el alem\u00e1n Dietrich Br\u00fcggemann, como representante del cine anfitri\u00f3n\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5925845w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5925845w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"582\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-09T19:32:50+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-09T19:32:50+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El miedo argentino y el fanatismo alem\u00e1n, en un inquietante domingo de Berlinale | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 9 feb (EFE).- Argentina entr\u00f3 en competici\u00f3n en la Berlinale con &quot;Historia del miedo&quot;, un film centrado en el p\u00e1nico a lo externo dirigido por Benjamin Naishtat, compartiendo jornada con un v\u00eda crucis alem\u00e1n sobre el fanatismo cat\u00f3lico en nuestros d\u00edas. El debutante Naishtat y el alem\u00e1n Dietrich Br\u00fcggemann, como representante del cine anfitri\u00f3n\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5925845w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\\\/#article\",\"name\":\"El miedo argentino y el fanatismo alem\\u00e1n, en un inquietante domingo de Berlinale | El Digital de Asturias\",\"headline\":\"El miedo argentino y el fanatismo alem\\u00e1n, en un inquietante domingo de Berlinale\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5925845w.jpg\",\"width\":800,\"height\":582},\"datePublished\":\"2014-02-09T18:32:50+01:00\",\"dateModified\":\"2014-02-09T18:32:50+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\\\/#listItem\",\"name\":\"El miedo argentino y el fanatismo alem\\u00e1n, en un inquietante domingo de Berlinale\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\\\/#listItem\",\"position\":3,\"name\":\"El miedo argentino y el fanatismo alem\\u00e1n, en un inquietante domingo de Berlinale\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\\\/\",\"name\":\"El miedo argentino y el fanatismo alem\\u00e1n, en un inquietante domingo de Berlinale | El Digital de Asturias\",\"description\":\"Berl\\u00edn, 9 feb (EFE).- Argentina entr\\u00f3 en competici\\u00f3n en la Berlinale con \\\"Historia del miedo\\\", un film centrado en el p\\u00e1nico a lo externo dirigido por Benjamin Naishtat, compartiendo jornada con un v\\u00eda crucis alem\\u00e1n sobre el fanatismo cat\\u00f3lico en nuestros d\\u00edas. El debutante Naishtat y el alem\\u00e1n Dietrich Br\\u00fcggemann, como representante del cine anfitri\\u00f3n\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5925845w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\\\/#mainImage\",\"width\":800,\"height\":582},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\\\/#mainImage\"},\"datePublished\":\"2014-02-09T18:32:50+01:00\",\"dateModified\":\"2014-02-09T18:32:50+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El miedo argentino y el fanatismo alem\u00e1n, en un inquietante domingo de Berlinale | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El miedo argentino y el fanatismo alem\u00e1n, en un inquietante domingo de Berlinale | El Digital de Asturias","description":"Berl\u00edn, 9 feb (EFE).- Argentina entr\u00f3 en competici\u00f3n en la Berlinale con \"Historia del miedo\", un film centrado en el p\u00e1nico a lo externo dirigido por Benjamin Naishtat, compartiendo jornada con un v\u00eda crucis alem\u00e1n sobre el fanatismo cat\u00f3lico en nuestros d\u00edas. El debutante Naishtat y el alem\u00e1n Dietrich Br\u00fcggemann, como representante del cine anfitri\u00f3n","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/#article","name":"El miedo argentino y el fanatismo alem\u00e1n, en un inquietante domingo de Berlinale | El Digital de Asturias","headline":"El miedo argentino y el fanatismo alem\u00e1n, en un inquietante domingo de Berlinale","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5925845w.jpg","width":800,"height":582},"datePublished":"2014-02-09T18:32:50+01:00","dateModified":"2014-02-09T18:32:50+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/#listItem","name":"El miedo argentino y el fanatismo alem\u00e1n, en un inquietante domingo de Berlinale"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/#listItem","position":3,"name":"El miedo argentino y el fanatismo alem\u00e1n, en un inquietante domingo de Berlinale","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/","name":"El miedo argentino y el fanatismo alem\u00e1n, en un inquietante domingo de Berlinale | El Digital de Asturias","description":"Berl\u00edn, 9 feb (EFE).- Argentina entr\u00f3 en competici\u00f3n en la Berlinale con \"Historia del miedo\", un film centrado en el p\u00e1nico a lo externo dirigido por Benjamin Naishtat, compartiendo jornada con un v\u00eda crucis alem\u00e1n sobre el fanatismo cat\u00f3lico en nuestros d\u00edas. El debutante Naishtat y el alem\u00e1n Dietrich Br\u00fcggemann, como representante del cine anfitri\u00f3n","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5925845w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/#mainImage","width":800,"height":582},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/#mainImage"},"datePublished":"2014-02-09T18:32:50+01:00","dateModified":"2014-02-09T18:32:50+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"El miedo argentino y el fanatismo alem\u00e1n, en un inquietante domingo de Berlinale | El Digital de Asturias","og:description":"Berl\u00edn, 9 feb (EFE).- Argentina entr\u00f3 en competici\u00f3n en la Berlinale con &quot;Historia del miedo&quot;, un film centrado en el p\u00e1nico a lo externo dirigido por Benjamin Naishtat, compartiendo jornada con un v\u00eda crucis alem\u00e1n sobre el fanatismo cat\u00f3lico en nuestros d\u00edas. El debutante Naishtat y el alem\u00e1n Dietrich Br\u00fcggemann, como representante del cine anfitri\u00f3n","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5925845w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5925845w.jpg","og:image:width":800,"og:image:height":582,"article:published_time":"2014-02-09T19:32:50+00:00","article:modified_time":"2014-02-09T19:32:50+00:00","twitter:card":"summary_large_image","twitter:title":"El miedo argentino y el fanatismo alem\u00e1n, en un inquietante domingo de Berlinale | El Digital de Asturias","twitter:description":"Berl\u00edn, 9 feb (EFE).- Argentina entr\u00f3 en competici\u00f3n en la Berlinale con &quot;Historia del miedo&quot;, un film centrado en el p\u00e1nico a lo externo dirigido por Benjamin Naishtat, compartiendo jornada con un v\u00eda crucis alem\u00e1n sobre el fanatismo cat\u00f3lico en nuestros d\u00edas. El debutante Naishtat y el alem\u00e1n Dietrich Br\u00fcggemann, como representante del cine anfitri\u00f3n","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5925845w.jpg"},"aioseo_meta_data":{"post_id":"3501","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 10:11:09","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:48:31","updated":"2026-05-15 10:11:09"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/\" title=\"El miedo argentino y el fanatismo alem\u00e1n, en un inquietante domingo de Berlinale\">El miedo argentino y el fanatismo alem\u00e1n, en un inquietante domingo de Berlinale<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"El miedo argentino y el fanatismo alem\u00e1n, en un inquietante domingo de Berlinale","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-miedo-argentino-y-el-fanatismo-aleman-en-un-inquietante-domingo-de-berlinale\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=3501"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3501\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/3502"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=3501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=3501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=3501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}