{"id":3474,"date":"2014-02-09T08:29:50","date_gmt":"2014-02-09T09:29:50","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=3474"},"modified":"2014-02-09T08:29:50","modified_gmt":"2014-02-09T09:29:50","slug":"el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/","title":{"rendered":"El cine espa\u00f1ol celebra hoy la 28 edici\u00f3n de los Premios Goya"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3475\" alt=\"5924939w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5924939w-360x228.jpg\" width=\"360\" height=\"228\" \/>Madrid, 9 feb (EFE).- El cine espa\u00f1ol se vestir\u00e1 hoy de largo para premiar lo mejor de 2013. \u00abLa Gran Familia Espa\u00f1ola\u00bb, de Daniel S\u00e1nchez Ar\u00e9valo, es, con once nominaciones, la favorita de esta edici\u00f3n, la n\u00famero 28, en la que tambi\u00e9n despunta \u00abLa herida\u00bb, de Fernando Franco.<\/p>\n<p>David Trueba y su optimista historia sesentera sobre el profesor que ense\u00f1a ingl\u00e9s con las canciones de los Beatles, \u00abVivir es f\u00e1cil con los ojos cerrados\u00bb, la oscura e inquietante \u00abCan\u00edbal\u00bb, de Manuel Mart\u00edn Cuenca, y el drama familiar de Gracia Querejeta \u00ab15 a\u00f1os y un d\u00eda\u00bb tambi\u00e9n tienen opciones de coronarse como la mejor pel\u00edcula.<\/p>\n<p>La gala, que dirigir\u00e1 y presentar\u00e1 Manel Fuentes y tendr\u00e1 lugar en el Hotel Auditorium de Madrid, no contar\u00e1 con la presencia del ministro de Cultura, Jos\u00e9 Ignacio Wert, que el pasado jueves adujo problemas de agenda: una reuni\u00f3n en Londres, el lunes, con el secretario de Estado brit\u00e1nico de Empresas e Innovaci\u00f3n, responsable de Universidades, Vince Cable.<\/p>\n<p>El anuncio fue recibido con indignaci\u00f3n por actores y directores que vieron un nuevo gesto de \u00abdesprecio\u00bb al sector, uno m\u00e1s de los m\u00faltiples desencuentros que han mantenido desde que fue designado en el cargo, el m\u00e1s reciente en los Premios Forqu\u00e9, el pasado mes de enero, cuando fue el ministro abucheado en su discurso.<\/p>\n<p>Uno de los momentos m\u00e1s emocionantes de la gala de esta noche ser\u00e1, previsiblemente, cuando se abra el sobre con el nombre del mejor actor.<\/p>\n<p>Puede ser la hora, por fin, de Javier C\u00e1mara, despu\u00e9s de seis nominaciones sin premio, o de Antonio de la Torre, uno de los actores m\u00e1s s\u00f3lidos del cine actual, que se llevar\u00eda su primer Goya protagonista por \u00abCan\u00edbal\u00bb.<\/p>\n<p>Sin olvidar las opciones de Tito Valverde, el abuelo de \u00ab15 a\u00f1os y un d\u00eda\u00bb, y de Eduard Fern\u00e1ndez, que ya se impuso a todos ellos en los Premios Forqu\u00e9, que concede EGEDA, por ese canalla acorralado de \u00abTodas las mujeres\u00bb.<\/p>\n<p>En cuanto a las mujeres, el duelo principal estar\u00e1 entre Inma Cuesta, que ha recibido espl\u00e9ndidas cr\u00edticas por la revelaci\u00f3n de su vena c\u00f3mica en \u00ab3 bodas de m\u00e1s\u00bb, y Marian \u00c1lvarez, que se llev\u00f3 la Concha de Plata en San Sebasti\u00e1n por \u00abLa herida\u00bb.<\/p>\n<p>Las otras candidatas tambi\u00e9n pisan fuerte: Aura Garrido, con su segunda nominaci\u00f3n por \u00abStockholm\u00bb, y Nora Navas, la mujer desconcertada de \u00abTodos queremos lo mejor para ella\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 9 feb (EFE).- El cine espa\u00f1ol se vestir\u00e1 hoy de largo para premiar lo mejor de 2013. \u00abLa Gran Familia Espa\u00f1ola\u00bb, de Daniel S\u00e1nchez Ar\u00e9valo, es, con once nominaciones, la favorita de esta edici\u00f3n, la n\u00famero 28, en la que tambi\u00e9n despunta \u00abLa herida\u00bb, de Fernando Franco. David Trueba y su optimista historia sesentera<\/p>\n","protected":false},"author":1,"featured_media":3475,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-3474","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 9 feb (EFE).- El cine espa\u00f1ol se vestir\u00e1 hoy de largo para premiar lo mejor de 2013. &quot;La Gran Familia Espa\u00f1ola&quot;, de Daniel S\u00e1nchez Ar\u00e9valo, es, con once nominaciones, la favorita de esta edici\u00f3n, la n\u00famero 28, en la que tambi\u00e9n despunta &quot;La herida&quot;, de Fernando Franco. David Trueba y su optimista historia sesentera\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El cine espa\u00f1ol celebra hoy la 28 edici\u00f3n de los Premios Goya | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 9 feb (EFE).- El cine espa\u00f1ol se vestir\u00e1 hoy de largo para premiar lo mejor de 2013. &quot;La Gran Familia Espa\u00f1ola&quot;, de Daniel S\u00e1nchez Ar\u00e9valo, es, con once nominaciones, la favorita de esta edici\u00f3n, la n\u00famero 28, en la que tambi\u00e9n despunta &quot;La herida&quot;, de Fernando Franco. David Trueba y su optimista historia sesentera\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5924939w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5924939w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"508\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-09T09:29:50+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-09T09:29:50+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El cine espa\u00f1ol celebra hoy la 28 edici\u00f3n de los Premios Goya | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 9 feb (EFE).- El cine espa\u00f1ol se vestir\u00e1 hoy de largo para premiar lo mejor de 2013. &quot;La Gran Familia Espa\u00f1ola&quot;, de Daniel S\u00e1nchez Ar\u00e9valo, es, con once nominaciones, la favorita de esta edici\u00f3n, la n\u00famero 28, en la que tambi\u00e9n despunta &quot;La herida&quot;, de Fernando Franco. David Trueba y su optimista historia sesentera\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5924939w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\\\/#article\",\"name\":\"El cine espa\\u00f1ol celebra hoy la 28 edici\\u00f3n de los Premios Goya | El Digital de Asturias\",\"headline\":\"El cine espa\\u00f1ol celebra hoy la 28 edici\\u00f3n de los Premios Goya\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5924939w.jpg\",\"width\":800,\"height\":508},\"datePublished\":\"2014-02-09T08:29:50+01:00\",\"dateModified\":\"2014-02-09T08:29:50+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\\\/#listItem\",\"name\":\"El cine espa\\u00f1ol celebra hoy la 28 edici\\u00f3n de los Premios Goya\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\\\/#listItem\",\"position\":3,\"name\":\"El cine espa\\u00f1ol celebra hoy la 28 edici\\u00f3n de los Premios Goya\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\\\/\",\"name\":\"El cine espa\\u00f1ol celebra hoy la 28 edici\\u00f3n de los Premios Goya | El Digital de Asturias\",\"description\":\"Madrid, 9 feb (EFE).- El cine espa\\u00f1ol se vestir\\u00e1 hoy de largo para premiar lo mejor de 2013. \\\"La Gran Familia Espa\\u00f1ola\\\", de Daniel S\\u00e1nchez Ar\\u00e9valo, es, con once nominaciones, la favorita de esta edici\\u00f3n, la n\\u00famero 28, en la que tambi\\u00e9n despunta \\\"La herida\\\", de Fernando Franco. David Trueba y su optimista historia sesentera\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5924939w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\\\/#mainImage\",\"width\":800,\"height\":508},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\\\/#mainImage\"},\"datePublished\":\"2014-02-09T08:29:50+01:00\",\"dateModified\":\"2014-02-09T08:29:50+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El cine espa\u00f1ol celebra hoy la 28 edici\u00f3n de los Premios Goya | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El cine espa\u00f1ol celebra hoy la 28 edici\u00f3n de los Premios Goya | El Digital de Asturias","description":"Madrid, 9 feb (EFE).- El cine espa\u00f1ol se vestir\u00e1 hoy de largo para premiar lo mejor de 2013. \"La Gran Familia Espa\u00f1ola\", de Daniel S\u00e1nchez Ar\u00e9valo, es, con once nominaciones, la favorita de esta edici\u00f3n, la n\u00famero 28, en la que tambi\u00e9n despunta \"La herida\", de Fernando Franco. David Trueba y su optimista historia sesentera","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/#article","name":"El cine espa\u00f1ol celebra hoy la 28 edici\u00f3n de los Premios Goya | El Digital de Asturias","headline":"El cine espa\u00f1ol celebra hoy la 28 edici\u00f3n de los Premios Goya","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5924939w.jpg","width":800,"height":508},"datePublished":"2014-02-09T08:29:50+01:00","dateModified":"2014-02-09T08:29:50+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/#listItem","name":"El cine espa\u00f1ol celebra hoy la 28 edici\u00f3n de los Premios Goya"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/#listItem","position":3,"name":"El cine espa\u00f1ol celebra hoy la 28 edici\u00f3n de los Premios Goya","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/","name":"El cine espa\u00f1ol celebra hoy la 28 edici\u00f3n de los Premios Goya | El Digital de Asturias","description":"Madrid, 9 feb (EFE).- El cine espa\u00f1ol se vestir\u00e1 hoy de largo para premiar lo mejor de 2013. \"La Gran Familia Espa\u00f1ola\", de Daniel S\u00e1nchez Ar\u00e9valo, es, con once nominaciones, la favorita de esta edici\u00f3n, la n\u00famero 28, en la que tambi\u00e9n despunta \"La herida\", de Fernando Franco. David Trueba y su optimista historia sesentera","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5924939w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/#mainImage","width":800,"height":508},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/#mainImage"},"datePublished":"2014-02-09T08:29:50+01:00","dateModified":"2014-02-09T08:29:50+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"El cine espa\u00f1ol celebra hoy la 28 edici\u00f3n de los Premios Goya | El Digital de Asturias","og:description":"Madrid, 9 feb (EFE).- El cine espa\u00f1ol se vestir\u00e1 hoy de largo para premiar lo mejor de 2013. &quot;La Gran Familia Espa\u00f1ola&quot;, de Daniel S\u00e1nchez Ar\u00e9valo, es, con once nominaciones, la favorita de esta edici\u00f3n, la n\u00famero 28, en la que tambi\u00e9n despunta &quot;La herida&quot;, de Fernando Franco. David Trueba y su optimista historia sesentera","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5924939w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5924939w.jpg","og:image:width":800,"og:image:height":508,"article:published_time":"2014-02-09T09:29:50+00:00","article:modified_time":"2014-02-09T09:29:50+00:00","twitter:card":"summary_large_image","twitter:title":"El cine espa\u00f1ol celebra hoy la 28 edici\u00f3n de los Premios Goya | El Digital de Asturias","twitter:description":"Madrid, 9 feb (EFE).- El cine espa\u00f1ol se vestir\u00e1 hoy de largo para premiar lo mejor de 2013. &quot;La Gran Familia Espa\u00f1ola&quot;, de Daniel S\u00e1nchez Ar\u00e9valo, es, con once nominaciones, la favorita de esta edici\u00f3n, la n\u00famero 28, en la que tambi\u00e9n despunta &quot;La herida&quot;, de Fernando Franco. David Trueba y su optimista historia sesentera","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5924939w.jpg"},"aioseo_meta_data":{"post_id":"3474","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 10:06:15","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:48:29","updated":"2026-05-15 10:06:15"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/\" title=\"El cine espa\u00f1ol celebra hoy la 28 edici\u00f3n de los Premios Goya\">El cine espa\u00f1ol celebra hoy la 28 edici\u00f3n de los Premios Goya<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"El cine espa\u00f1ol celebra hoy la 28 edici\u00f3n de los Premios Goya","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-cine-espanol-celebra-hoy-la-28-edicion-de-los-premios-goya\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=3474"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3474\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/3475"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=3474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=3474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=3474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}