{"id":33441,"date":"2014-12-11T15:57:07","date_gmt":"2014-12-11T17:57:07","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=33441"},"modified":"2014-12-11T15:57:07","modified_gmt":"2014-12-11T17:57:07","slug":"iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/","title":{"rendered":"Iberia e Iberia Express abrir\u00e1n 13 nuevas rutas en el programa de verano 2015"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-33442\" alt=\"8155513w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/12\/8155513w-360x239.jpg\" width=\"360\" height=\"239\" \/>Madrid, 11 dic (EFE).- Iberia y su filial de bajo coste Iberia Express abrir\u00e1n trece nuevas rutas y elevar\u00e1n frecuencias en veinticuatro de las existentes dentro de su programa verano 2015, ha informado hoy el grupo a\u00e9reo en un comunicado.<\/p>\n<p>As\u00ed, el grupo ofrecer\u00e1 vuelos directos desde Madrid a Florencia, N\u00e1poles, Palermo, Catania y Verona en Italia; a M\u00e1nchester y Edimburgo en el Reino Unido; a Hamburgo en Alemania; a Funchal en Madeira (Portugal); y a Budapest en Hungr\u00eda.<\/p>\n<p>Tambi\u00e9n se inaugurar\u00e1n las rutas directas Asturias-Tenerife, Madrid-Par\u00eds\/Charles de Gaulle y Madrid-Londres\/Gatwick.<\/p>\n<p>En paralelo, el grupo Iberia programar\u00e1 65 frecuencias adicionales en 24 rutas ya consolidadas, entre ellas M\u00e9xico y Nueva York en el largo radio, y Par\u00eds-Orly, Lisboa, Tel Aviv, Venecia, Dubl\u00edn, Praga, Berl\u00edn, Stuttgart, Asturias, Canarias, Baleares y Galicia, entre otras, en el corto y medio.<\/p>\n<p>Para el presidente ejecutivo de Iberia, Luis Gallego, este despliegue de nuevas rutas y frecuencias confirma \u00abla efectividad de la reducci\u00f3n de la base de costes de Iberia y la calidad del nuevo producto y los nuevos servicios que ofrecemos a nuestros clientes.\u00bb<\/p>\n<p>\u00abCon el programa de verano 2015, Iberia Express se consolida a\u00fan m\u00e1s como compa\u00f1\u00eda de referencia en Madrid, para conectar la capital con nuevos y atractivos mercados\u00bb, a\u00f1ade el presidente de la l\u00ednea de bajo coste, Fernando Candela.<\/p>\n<p>En el comunicado, Iberia destaca que estas novedades se suman a los ocho destinos inaugurados en 2014 -Montevideo, Santo Domingo, Estambul, Atenas, \u00c1msterdam, Estocolmo, Hannover y Stuttgart-, as\u00ed como a la mejora de oferta en mercados como Panam\u00e1 o Santiago de Chile; y a las habituales rutas estacionales que se recuperan como San Petersburgo, Ibiza, Dubrovnik y Zagreb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 11 dic (EFE).- Iberia y su filial de bajo coste Iberia Express abrir\u00e1n trece nuevas rutas y elevar\u00e1n frecuencias en veinticuatro de las existentes dentro de su programa verano 2015, ha informado hoy el grupo a\u00e9reo en un comunicado. As\u00ed, el grupo ofrecer\u00e1 vuelos directos desde Madrid a Florencia, N\u00e1poles, Palermo, Catania y Verona<\/p>\n","protected":false},"author":1,"featured_media":33442,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-33441","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 11 dic (EFE).- Iberia y su filial de bajo coste Iberia Express abrir\u00e1n trece nuevas rutas y elevar\u00e1n frecuencias en veinticuatro de las existentes dentro de su programa verano 2015, ha informado hoy el grupo a\u00e9reo en un comunicado. As\u00ed, el grupo ofrecer\u00e1 vuelos directos desde Madrid a Florencia, N\u00e1poles, Palermo, Catania y Verona\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Iberia e Iberia Express abrir\u00e1n 13 nuevas rutas en el programa de verano 2015 | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 11 dic (EFE).- Iberia y su filial de bajo coste Iberia Express abrir\u00e1n trece nuevas rutas y elevar\u00e1n frecuencias en veinticuatro de las existentes dentro de su programa verano 2015, ha informado hoy el grupo a\u00e9reo en un comunicado. As\u00ed, el grupo ofrecer\u00e1 vuelos directos desde Madrid a Florencia, N\u00e1poles, Palermo, Catania y Verona\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/12\/8155513w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/12\/8155513w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-12-11T17:57:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-12-11T17:57:07+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Iberia e Iberia Express abrir\u00e1n 13 nuevas rutas en el programa de verano 2015 | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 11 dic (EFE).- Iberia y su filial de bajo coste Iberia Express abrir\u00e1n trece nuevas rutas y elevar\u00e1n frecuencias en veinticuatro de las existentes dentro de su programa verano 2015, ha informado hoy el grupo a\u00e9reo en un comunicado. As\u00ed, el grupo ofrecer\u00e1 vuelos directos desde Madrid a Florencia, N\u00e1poles, Palermo, Catania y Verona\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/12\/8155513w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\\\/#article\",\"name\":\"Iberia e Iberia Express abrir\\u00e1n 13 nuevas rutas en el programa de verano 2015 | El Digital de Asturias\",\"headline\":\"Iberia e Iberia Express abrir\\u00e1n 13 nuevas rutas en el programa de verano 2015\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/8155513w.jpg\",\"width\":800,\"height\":533},\"datePublished\":\"2014-12-11T15:57:07+01:00\",\"dateModified\":\"2014-12-11T15:57:07+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\\\/#listItem\",\"name\":\"Iberia e Iberia Express abrir\\u00e1n 13 nuevas rutas en el programa de verano 2015\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\\\/#listItem\",\"position\":3,\"name\":\"Iberia e Iberia Express abrir\\u00e1n 13 nuevas rutas en el programa de verano 2015\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\\\/\",\"name\":\"Iberia e Iberia Express abrir\\u00e1n 13 nuevas rutas en el programa de verano 2015 | El Digital de Asturias\",\"description\":\"Madrid, 11 dic (EFE).- Iberia y su filial de bajo coste Iberia Express abrir\\u00e1n trece nuevas rutas y elevar\\u00e1n frecuencias en veinticuatro de las existentes dentro de su programa verano 2015, ha informado hoy el grupo a\\u00e9reo en un comunicado. As\\u00ed, el grupo ofrecer\\u00e1 vuelos directos desde Madrid a Florencia, N\\u00e1poles, Palermo, Catania y Verona\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/8155513w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\\\/#mainImage\",\"width\":800,\"height\":533},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\\\/#mainImage\"},\"datePublished\":\"2014-12-11T15:57:07+01:00\",\"dateModified\":\"2014-12-11T15:57:07+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Iberia e Iberia Express abrir\u00e1n 13 nuevas rutas en el programa de verano 2015 | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Iberia e Iberia Express abrir\u00e1n 13 nuevas rutas en el programa de verano 2015 | El Digital de Asturias","description":"Madrid, 11 dic (EFE).- Iberia y su filial de bajo coste Iberia Express abrir\u00e1n trece nuevas rutas y elevar\u00e1n frecuencias en veinticuatro de las existentes dentro de su programa verano 2015, ha informado hoy el grupo a\u00e9reo en un comunicado. As\u00ed, el grupo ofrecer\u00e1 vuelos directos desde Madrid a Florencia, N\u00e1poles, Palermo, Catania y Verona","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/#article","name":"Iberia e Iberia Express abrir\u00e1n 13 nuevas rutas en el programa de verano 2015 | El Digital de Asturias","headline":"Iberia e Iberia Express abrir\u00e1n 13 nuevas rutas en el programa de verano 2015","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/12\/8155513w.jpg","width":800,"height":533},"datePublished":"2014-12-11T15:57:07+01:00","dateModified":"2014-12-11T15:57:07+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/#listItem","name":"Iberia e Iberia Express abrir\u00e1n 13 nuevas rutas en el programa de verano 2015"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/#listItem","position":3,"name":"Iberia e Iberia Express abrir\u00e1n 13 nuevas rutas en el programa de verano 2015","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/","name":"Iberia e Iberia Express abrir\u00e1n 13 nuevas rutas en el programa de verano 2015 | El Digital de Asturias","description":"Madrid, 11 dic (EFE).- Iberia y su filial de bajo coste Iberia Express abrir\u00e1n trece nuevas rutas y elevar\u00e1n frecuencias en veinticuatro de las existentes dentro de su programa verano 2015, ha informado hoy el grupo a\u00e9reo en un comunicado. As\u00ed, el grupo ofrecer\u00e1 vuelos directos desde Madrid a Florencia, N\u00e1poles, Palermo, Catania y Verona","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/12\/8155513w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/#mainImage","width":800,"height":533},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/#mainImage"},"datePublished":"2014-12-11T15:57:07+01:00","dateModified":"2014-12-11T15:57:07+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Iberia e Iberia Express abrir\u00e1n 13 nuevas rutas en el programa de verano 2015 | El Digital de Asturias","og:description":"Madrid, 11 dic (EFE).- Iberia y su filial de bajo coste Iberia Express abrir\u00e1n trece nuevas rutas y elevar\u00e1n frecuencias en veinticuatro de las existentes dentro de su programa verano 2015, ha informado hoy el grupo a\u00e9reo en un comunicado. As\u00ed, el grupo ofrecer\u00e1 vuelos directos desde Madrid a Florencia, N\u00e1poles, Palermo, Catania y Verona","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/12\/8155513w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/12\/8155513w.jpg","og:image:width":800,"og:image:height":533,"article:published_time":"2014-12-11T17:57:07+00:00","article:modified_time":"2014-12-11T17:57:07+00:00","twitter:card":"summary_large_image","twitter:title":"Iberia e Iberia Express abrir\u00e1n 13 nuevas rutas en el programa de verano 2015 | El Digital de Asturias","twitter:description":"Madrid, 11 dic (EFE).- Iberia y su filial de bajo coste Iberia Express abrir\u00e1n trece nuevas rutas y elevar\u00e1n frecuencias en veinticuatro de las existentes dentro de su programa verano 2015, ha informado hoy el grupo a\u00e9reo en un comunicado. As\u00ed, el grupo ofrecer\u00e1 vuelos directos desde Madrid a Florencia, N\u00e1poles, Palermo, Catania y Verona","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/12\/8155513w.jpg"},"aioseo_meta_data":{"post_id":"33441","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 07:34:37","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 03:17:54","updated":"2026-05-20 07:34:37"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/\" title=\"Iberia e Iberia Express abrir\u00e1n 13 nuevas rutas en el programa de verano 2015\">Iberia e Iberia Express abrir\u00e1n 13 nuevas rutas en el programa de verano 2015<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"Iberia e Iberia Express abrir\u00e1n 13 nuevas rutas en el programa de verano 2015","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-e-iberia-express-abriran-13-nuevas-rutas-en-el-programa-de-verano-2015\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/33441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=33441"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/33441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/33442"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=33441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=33441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=33441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}