{"id":3286,"date":"2014-02-07T20:00:20","date_gmt":"2014-02-07T21:00:20","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=3286"},"modified":"2014-02-07T20:00:20","modified_gmt":"2014-02-07T21:00:20","slug":"sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/","title":{"rendered":"Sorkin revela que Hoffman dijo que si mor\u00eda de sobredosis salvar\u00eda diez vidas"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3287\" alt=\"5919968w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5919968w-360x220.jpg\" width=\"360\" height=\"220\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5919968w-360x220.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5919968w-650x397.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5919968w-768x469.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5919968w-150x92.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5919968w-450x275.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5919968w-696x425.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5919968w-687x420.jpg 687w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5919968w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Washington, 7 feb (EFE).- Aaron Sorkin, creador de las series \u00abEl ala oeste de la Casa Blanca\u00bb y \u00abThe Newsroom\u00bb, revela que el fallecido actor Philip Seymour Hoffman le dijo una vez en una conversaci\u00f3n privada que si uno de los dos mor\u00eda de sobredosis, probablemente se salvar\u00edan diez vidas.<\/p>\n<p>\u00abQuer\u00eda decir que nuestras muertes ser\u00edan noticia y que eso probablemente asustar\u00eda a alguien limpio\u00bb, explica Sorkin en un obituario que escribe en la revista \u00abTime\u00bb a Hoffman, con quien compart\u00eda dos cosas: \u00abser padres de ni\u00f1os peque\u00f1os y estar en terapia por adicci\u00f3n a las drogas\u00bb.<\/p>\n<p>En los descansos de \u00abLa guerra de Charlie Wilson\u00bb, en la que trabajaron juntos, Sorkin y Hoffman comentaban su relaci\u00f3n con las drogas y la evoluci\u00f3n de su adicci\u00f3n, seg\u00fan relata el guionista.<\/p>\n<p>Hoffman muri\u00f3 de forma repentina el pasado fin de semana en su apartamento del West Village de Nueva York, donde la polic\u00eda encontr\u00f3 50 papelinas de hero\u00edna y varias jeringuillas.<\/p>\n<p>Su p\u00e9rdida ha sacudido a EE.UU. y a los cin\u00e9filos de todo el mundo y, como \u00e9l predijo, ha puesto rostro al alarmante resurgir de la hero\u00edna en este pa\u00eds, que es ahora una alternativa barata y accesible a los analg\u00e9sicos con receta derivados del opio a los que son adictos miles de estadounidenses.<\/p>\n<p>\u00abSi uno de los dos muere de sobredosis, probablemente diez personas que estaban a punto, no lo har\u00e1n\u00bb, fueron las palabras exactas de Hoffman en su conversaci\u00f3n con Sorkin.<\/p>\n<p>El guionista pide en su obituario que se deje de decir que Hoffman \u00abmuri\u00f3 de sobredosis\u00bb.<\/p>\n<p>\u00abHoffman no muri\u00f3 de una sobredosis de hero\u00edna. Muri\u00f3 a causa de la hero\u00edna. Deber\u00edamos dejar de sugerir que si solo se hubiera inyectado la cantidad adecuada todo habr\u00eda ido bien\u00bb, afirma.<\/p>\n<p>Y a\u00f1ade: \u00abNo muri\u00f3 en una fiesta loca ni tampoco estaba deprimido. Muri\u00f3 porque era un adicto cada uno de los d\u00edas de la semana\u00bb.<\/p>\n<p>\u00abSum\u00e9mos al legado que nos ha dejado con sus personajes las vidas de las diez personas que iban a morir y ya no morir\u00e1n\u00bb, concluye.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Washington, 7 feb (EFE).- Aaron Sorkin, creador de las series \u00abEl ala oeste de la Casa Blanca\u00bb y \u00abThe Newsroom\u00bb, revela que el fallecido actor Philip Seymour Hoffman le dijo una vez en una conversaci\u00f3n privada que si uno de los dos mor\u00eda de sobredosis, probablemente se salvar\u00edan diez vidas. \u00abQuer\u00eda decir que nuestras muertes<\/p>\n","protected":false},"author":1,"featured_media":3287,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-3286","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Washington, 7 feb (EFE).- Aaron Sorkin, creador de las series &quot;El ala oeste de la Casa Blanca&quot; y &quot;The Newsroom&quot;, revela que el fallecido actor Philip Seymour Hoffman le dijo una vez en una conversaci\u00f3n privada que si uno de los dos mor\u00eda de sobredosis, probablemente se salvar\u00edan diez vidas. &quot;Quer\u00eda decir que nuestras muertes\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sorkin revela que Hoffman dijo que si mor\u00eda de sobredosis salvar\u00eda diez vidas | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Washington, 7 feb (EFE).- Aaron Sorkin, creador de las series &quot;El ala oeste de la Casa Blanca&quot; y &quot;The Newsroom&quot;, revela que el fallecido actor Philip Seymour Hoffman le dijo una vez en una conversaci\u00f3n privada que si uno de los dos mor\u00eda de sobredosis, probablemente se salvar\u00edan diez vidas. &quot;Quer\u00eda decir que nuestras muertes\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5919968w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5919968w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"489\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-07T21:00:20+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-07T21:00:20+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sorkin revela que Hoffman dijo que si mor\u00eda de sobredosis salvar\u00eda diez vidas | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Washington, 7 feb (EFE).- Aaron Sorkin, creador de las series &quot;El ala oeste de la Casa Blanca&quot; y &quot;The Newsroom&quot;, revela que el fallecido actor Philip Seymour Hoffman le dijo una vez en una conversaci\u00f3n privada que si uno de los dos mor\u00eda de sobredosis, probablemente se salvar\u00edan diez vidas. &quot;Quer\u00eda decir que nuestras muertes\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5919968w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\\\/#article\",\"name\":\"Sorkin revela que Hoffman dijo que si mor\\u00eda de sobredosis salvar\\u00eda diez vidas | El Digital de Asturias\",\"headline\":\"Sorkin revela que Hoffman dijo que si mor\\u00eda de sobredosis salvar\\u00eda diez vidas\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5919968w.jpg\",\"width\":800,\"height\":489},\"datePublished\":\"2014-02-07T20:00:20+01:00\",\"dateModified\":\"2014-02-07T20:00:20+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\\\/#listItem\",\"name\":\"Sorkin revela que Hoffman dijo que si mor\\u00eda de sobredosis salvar\\u00eda diez vidas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\\\/#listItem\",\"position\":3,\"name\":\"Sorkin revela que Hoffman dijo que si mor\\u00eda de sobredosis salvar\\u00eda diez vidas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\\\/\",\"name\":\"Sorkin revela que Hoffman dijo que si mor\\u00eda de sobredosis salvar\\u00eda diez vidas | El Digital de Asturias\",\"description\":\"Washington, 7 feb (EFE).- Aaron Sorkin, creador de las series \\\"El ala oeste de la Casa Blanca\\\" y \\\"The Newsroom\\\", revela que el fallecido actor Philip Seymour Hoffman le dijo una vez en una conversaci\\u00f3n privada que si uno de los dos mor\\u00eda de sobredosis, probablemente se salvar\\u00edan diez vidas. \\\"Quer\\u00eda decir que nuestras muertes\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5919968w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\\\/#mainImage\",\"width\":800,\"height\":489},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\\\/#mainImage\"},\"datePublished\":\"2014-02-07T20:00:20+01:00\",\"dateModified\":\"2014-02-07T20:00:20+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Sorkin revela que Hoffman dijo que si mor\u00eda de sobredosis salvar\u00eda diez vidas | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Sorkin revela que Hoffman dijo que si mor\u00eda de sobredosis salvar\u00eda diez vidas | El Digital de Asturias","description":"Washington, 7 feb (EFE).- Aaron Sorkin, creador de las series \"El ala oeste de la Casa Blanca\" y \"The Newsroom\", revela que el fallecido actor Philip Seymour Hoffman le dijo una vez en una conversaci\u00f3n privada que si uno de los dos mor\u00eda de sobredosis, probablemente se salvar\u00edan diez vidas. \"Quer\u00eda decir que nuestras muertes","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/#article","name":"Sorkin revela que Hoffman dijo que si mor\u00eda de sobredosis salvar\u00eda diez vidas | El Digital de Asturias","headline":"Sorkin revela que Hoffman dijo que si mor\u00eda de sobredosis salvar\u00eda diez vidas","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5919968w.jpg","width":800,"height":489},"datePublished":"2014-02-07T20:00:20+01:00","dateModified":"2014-02-07T20:00:20+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/#listItem","name":"Sorkin revela que Hoffman dijo que si mor\u00eda de sobredosis salvar\u00eda diez vidas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/#listItem","position":3,"name":"Sorkin revela que Hoffman dijo que si mor\u00eda de sobredosis salvar\u00eda diez vidas","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/","name":"Sorkin revela que Hoffman dijo que si mor\u00eda de sobredosis salvar\u00eda diez vidas | El Digital de Asturias","description":"Washington, 7 feb (EFE).- Aaron Sorkin, creador de las series \"El ala oeste de la Casa Blanca\" y \"The Newsroom\", revela que el fallecido actor Philip Seymour Hoffman le dijo una vez en una conversaci\u00f3n privada que si uno de los dos mor\u00eda de sobredosis, probablemente se salvar\u00edan diez vidas. \"Quer\u00eda decir que nuestras muertes","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5919968w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/#mainImage","width":800,"height":489},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/#mainImage"},"datePublished":"2014-02-07T20:00:20+01:00","dateModified":"2014-02-07T20:00:20+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Sorkin revela que Hoffman dijo que si mor\u00eda de sobredosis salvar\u00eda diez vidas | El Digital de Asturias","og:description":"Washington, 7 feb (EFE).- Aaron Sorkin, creador de las series &quot;El ala oeste de la Casa Blanca&quot; y &quot;The Newsroom&quot;, revela que el fallecido actor Philip Seymour Hoffman le dijo una vez en una conversaci\u00f3n privada que si uno de los dos mor\u00eda de sobredosis, probablemente se salvar\u00edan diez vidas. &quot;Quer\u00eda decir que nuestras muertes","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5919968w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5919968w.jpg","og:image:width":800,"og:image:height":489,"article:published_time":"2014-02-07T21:00:20+00:00","article:modified_time":"2014-02-07T21:00:20+00:00","twitter:card":"summary_large_image","twitter:title":"Sorkin revela que Hoffman dijo que si mor\u00eda de sobredosis salvar\u00eda diez vidas | El Digital de Asturias","twitter:description":"Washington, 7 feb (EFE).- Aaron Sorkin, creador de las series &quot;El ala oeste de la Casa Blanca&quot; y &quot;The Newsroom&quot;, revela que el fallecido actor Philip Seymour Hoffman le dijo una vez en una conversaci\u00f3n privada que si uno de los dos mor\u00eda de sobredosis, probablemente se salvar\u00edan diez vidas. &quot;Quer\u00eda decir que nuestras muertes","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5919968w.jpg"},"aioseo_meta_data":{"post_id":"3286","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 09:41:57","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:47:46","updated":"2026-05-15 09:41:57"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/\" title=\"Sorkin revela que Hoffman dijo que si mor\u00eda de sobredosis salvar\u00eda diez vidas\">Sorkin revela que Hoffman dijo que si mor\u00eda de sobredosis salvar\u00eda diez vidas<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Sorkin revela que Hoffman dijo que si mor\u00eda de sobredosis salvar\u00eda diez vidas","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/sorkin-revela-que-hoffman-dijo-que-si-moria-de-sobredosis-salvaria-diez-vidas\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=3286"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3286\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/3287"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=3286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=3286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=3286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}