{"id":32502,"date":"2014-12-02T18:11:43","date_gmt":"2014-12-02T20:11:43","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=32502"},"modified":"2014-12-02T18:11:43","modified_gmt":"2014-12-02T20:11:43","slug":"toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/","title":{"rendered":"Toyota ofrecer\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-32503\" alt=\"7772703w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/12\/7772703w-360x233.jpg\" width=\"360\" height=\"233\" \/>Madrid, 2 dic (EFE).- Toyota Motor Corporation (TMC) ha anunciado hoy que comenzar\u00e1 a comercializar en 2015 en Jap\u00f3n un conjunto de nuevas tecnolog\u00edas de seguridad activa y de ayuda, que paulatinamente ir\u00e1n extendi\u00e9ndose por Norteam\u00e9rica y Europa hasta finales de 2017.<\/p>\n<p>Para prevenir o mitigar colisiones en un amplio intervalo de velocidades comercializar\u00e1 dos paquetes \u00abToyota Safety Sense\u00bb: el C para veh\u00edculos compactos y el &#8216;P&#8217; para tama\u00f1o medio y alta gama.<\/p>\n<p>Emplean un radar l\u00e1ser (el paquete C) o de ondas milim\u00e9tricas (el P) y una c\u00e1mara para analizar la conducci\u00f3n y los veh\u00edculos que preceden al Toyota.<\/p>\n<p>El paquete C integra varias de las tecnolog\u00edas de seguridad activa ya existentes en el fabricante japon\u00e9s como el Sistema pre-colisi\u00f3n -Pre-Collision System (PCS)- que ayuda a evitar o mitigar colisiones; el Aviso de cambio involuntario de carril -Lane Departure Alert (LDA)- que alerta cuando el veh\u00edculo abandona su carril involuntariamente; y las Luces largas autom\u00e1ticas -Automatic High Beam (AHB)- que aportan una mayor visibilidad por la noche.<\/p>\n<p>Por su parte, el paquete P, adem\u00e1s de incorporar las tres tecnolog\u00edas de seguridad activa incluidas en el C, incluye una funci\u00f3n de detecci\u00f3n de peatones en el Sistema pre-colisi\u00f3n y ofrece un control de crucero con radar.<\/p>\n<p>Mediante el radar y la c\u00e1mara se detecta a personas y veh\u00edculos y se advierte al conductor mediante un aviso sonoro y visual. Si el conductor no para el veh\u00edculo a tiempo, el sistema frena de forma autom\u00e1tica el veh\u00edculo.<\/p>\n<p>La activaci\u00f3n autom\u00e1tica de los frenos funciona a velocidades relativas de entre 10 y 80 kil\u00f3metros\/hora y puede reducir la velocidad unos 30 km\/h.<\/p>\n<p>Para evitar colisiones con veh\u00edculos, el PCS del paquete P se activa desde 10 km\/h y hasta la velocidad punta del veh\u00edculo, y reduce la velocidad en unos 40 km\/h.<\/p>\n<p>A partir de 2015, algunos de los nuevos modelos de Toyota ser\u00e1n compatibles con sistemas avanzados de cooperaci\u00f3n veh\u00edculo-infraestructura, que utilizan una frecuencia inal\u00e1mbrica reservada a los Sistemas de Transporte Inteligentes -Intelligent Transport Systems (ITS)-.<\/p>\n<p>Esta compatibilidad se ofrecer\u00e1 como opci\u00f3n para el paquete P, que estar\u00e1 disponible en 2015 en algunos modelos vendidos en Jap\u00f3n.<\/p>\n<p>Estos sistemas utilizar\u00e1n la frecuencia espec\u00edfica de los ITS, de 760 MegaHerzios, para la comunicaci\u00f3n entre la v\u00eda y el veh\u00edculo y entre unos autom\u00f3viles y otros, para as\u00ed recopilar informaci\u00f3n que no se pueda obtener mediante los sensores del veh\u00edculo.<\/p>\n<p>Toyota desarrolla interfaces compatibles con ITS en colaboraci\u00f3n con ministerios y agencias gubernamentales, as\u00ed como empresas privadas, con el objetivo de comercializarlas tan pronto como sea factible.<\/p>\n<p>Tambi\u00e9n en 2015 Toyota montar\u00e1 en algunos modelos el nuevo sistema de luces de carretera adaptables de LED -LED Array Adaptive High-Beam System- que ofrecen una mayor amplitud de iluminaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 2 dic (EFE).- Toyota Motor Corporation (TMC) ha anunciado hoy que comenzar\u00e1 a comercializar en 2015 en Jap\u00f3n un conjunto de nuevas tecnolog\u00edas de seguridad activa y de ayuda, que paulatinamente ir\u00e1n extendi\u00e9ndose por Norteam\u00e9rica y Europa hasta finales de 2017. Para prevenir o mitigar colisiones en un amplio intervalo de velocidades comercializar\u00e1 dos<\/p>\n","protected":false},"author":1,"featured_media":32503,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-32502","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 2 dic (EFE).- Toyota Motor Corporation (TMC) ha anunciado hoy que comenzar\u00e1 a comercializar en 2015 en Jap\u00f3n un conjunto de nuevas tecnolog\u00edas de seguridad activa y de ayuda, que paulatinamente ir\u00e1n extendi\u00e9ndose por Norteam\u00e9rica y Europa hasta finales de 2017. Para prevenir o mitigar colisiones en un amplio intervalo de velocidades comercializar\u00e1 dos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Toyota ofrecer\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 2 dic (EFE).- Toyota Motor Corporation (TMC) ha anunciado hoy que comenzar\u00e1 a comercializar en 2015 en Jap\u00f3n un conjunto de nuevas tecnolog\u00edas de seguridad activa y de ayuda, que paulatinamente ir\u00e1n extendi\u00e9ndose por Norteam\u00e9rica y Europa hasta finales de 2017. Para prevenir o mitigar colisiones en un amplio intervalo de velocidades comercializar\u00e1 dos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/12\/7772703w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/12\/7772703w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"519\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-12-02T20:11:43+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-12-02T20:11:43+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Toyota ofrecer\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 2 dic (EFE).- Toyota Motor Corporation (TMC) ha anunciado hoy que comenzar\u00e1 a comercializar en 2015 en Jap\u00f3n un conjunto de nuevas tecnolog\u00edas de seguridad activa y de ayuda, que paulatinamente ir\u00e1n extendi\u00e9ndose por Norteam\u00e9rica y Europa hasta finales de 2017. Para prevenir o mitigar colisiones en un amplio intervalo de velocidades comercializar\u00e1 dos\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/12\/7772703w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\\\/#article\",\"name\":\"Toyota ofrecer\\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda | El Digital de Asturias\",\"headline\":\"Toyota ofrecer\\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/7772703w.jpg\",\"width\":800,\"height\":519},\"datePublished\":\"2014-12-02T18:11:43+01:00\",\"dateModified\":\"2014-12-02T18:11:43+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\\\/#listItem\",\"name\":\"Toyota ofrecer\\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\\\/#listItem\",\"position\":3,\"name\":\"Toyota ofrecer\\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\\\/\",\"name\":\"Toyota ofrecer\\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda | El Digital de Asturias\",\"description\":\"Madrid, 2 dic (EFE).- Toyota Motor Corporation (TMC) ha anunciado hoy que comenzar\\u00e1 a comercializar en 2015 en Jap\\u00f3n un conjunto de nuevas tecnolog\\u00edas de seguridad activa y de ayuda, que paulatinamente ir\\u00e1n extendi\\u00e9ndose por Norteam\\u00e9rica y Europa hasta finales de 2017. Para prevenir o mitigar colisiones en un amplio intervalo de velocidades comercializar\\u00e1 dos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/7772703w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\\\/#mainImage\",\"width\":800,\"height\":519},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\\\/#mainImage\"},\"datePublished\":\"2014-12-02T18:11:43+01:00\",\"dateModified\":\"2014-12-02T18:11:43+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Toyota ofrecer\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Toyota ofrecer\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda | El Digital de Asturias","description":"Madrid, 2 dic (EFE).- Toyota Motor Corporation (TMC) ha anunciado hoy que comenzar\u00e1 a comercializar en 2015 en Jap\u00f3n un conjunto de nuevas tecnolog\u00edas de seguridad activa y de ayuda, que paulatinamente ir\u00e1n extendi\u00e9ndose por Norteam\u00e9rica y Europa hasta finales de 2017. Para prevenir o mitigar colisiones en un amplio intervalo de velocidades comercializar\u00e1 dos","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/#article","name":"Toyota ofrecer\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda | El Digital de Asturias","headline":"Toyota ofrecer\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/12\/7772703w.jpg","width":800,"height":519},"datePublished":"2014-12-02T18:11:43+01:00","dateModified":"2014-12-02T18:11:43+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/#listItem","name":"Toyota ofrecer\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/#listItem","position":3,"name":"Toyota ofrecer\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/","name":"Toyota ofrecer\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda | El Digital de Asturias","description":"Madrid, 2 dic (EFE).- Toyota Motor Corporation (TMC) ha anunciado hoy que comenzar\u00e1 a comercializar en 2015 en Jap\u00f3n un conjunto de nuevas tecnolog\u00edas de seguridad activa y de ayuda, que paulatinamente ir\u00e1n extendi\u00e9ndose por Norteam\u00e9rica y Europa hasta finales de 2017. Para prevenir o mitigar colisiones en un amplio intervalo de velocidades comercializar\u00e1 dos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/12\/7772703w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/#mainImage","width":800,"height":519},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/#mainImage"},"datePublished":"2014-12-02T18:11:43+01:00","dateModified":"2014-12-02T18:11:43+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Toyota ofrecer\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda | El Digital de Asturias","og:description":"Madrid, 2 dic (EFE).- Toyota Motor Corporation (TMC) ha anunciado hoy que comenzar\u00e1 a comercializar en 2015 en Jap\u00f3n un conjunto de nuevas tecnolog\u00edas de seguridad activa y de ayuda, que paulatinamente ir\u00e1n extendi\u00e9ndose por Norteam\u00e9rica y Europa hasta finales de 2017. Para prevenir o mitigar colisiones en un amplio intervalo de velocidades comercializar\u00e1 dos","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/12\/7772703w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/12\/7772703w.jpg","og:image:width":800,"og:image:height":519,"article:published_time":"2014-12-02T20:11:43+00:00","article:modified_time":"2014-12-02T20:11:43+00:00","twitter:card":"summary_large_image","twitter:title":"Toyota ofrecer\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda | El Digital de Asturias","twitter:description":"Madrid, 2 dic (EFE).- Toyota Motor Corporation (TMC) ha anunciado hoy que comenzar\u00e1 a comercializar en 2015 en Jap\u00f3n un conjunto de nuevas tecnolog\u00edas de seguridad activa y de ayuda, que paulatinamente ir\u00e1n extendi\u00e9ndose por Norteam\u00e9rica y Europa hasta finales de 2017. Para prevenir o mitigar colisiones en un amplio intervalo de velocidades comercializar\u00e1 dos","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/12\/7772703w.jpg"},"aioseo_meta_data":{"post_id":"32502","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-20 05:31:24","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 04:10:45","updated":"2026-05-20 05:31:24"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/\" title=\"Toyota ofrecer\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda\">Toyota ofrecer\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"Toyota ofrecer\u00e1 a partir de 2015 nuevos sistemas de seguridad y de ayuda","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/toyota-ofrecera-a-partir-de-2015-nuevos-sistemas-de-seguridad-y-de-ayuda\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/32502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=32502"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/32502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/32503"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=32502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=32502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=32502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}