{"id":3248,"date":"2014-02-06T21:38:44","date_gmt":"2014-02-06T22:38:44","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=3248"},"modified":"2014-02-06T21:38:44","modified_gmt":"2014-02-06T22:38:44","slug":"fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/","title":{"rendered":"Fito &#038; Fitipaldis publicar\u00e1n en marzo un disco en directo"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3249\" alt=\"5918389w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5918389w-360x239.jpg\" width=\"360\" height=\"239\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5918389w-360x239.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5918389w-650x432.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5918389w-768x511.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5918389w-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5918389w-450x299.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5918389w-696x463.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5918389w-632x420.jpg 632w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5918389w-84x55.jpg 84w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5918389w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Madrid, 6 feb (EFE).- Fito &amp; Fitipaldis publicar\u00e1n un disco doble en directo el pr\u00f3ximo 4 de marzo que, bajo el t\u00edtulo \u00abEn directo desde el Teatro Arriaga\u00bb y acompa\u00f1ado de un DVD, permitir\u00e1 revivir los dos conciertos que ofreci\u00f3 esta banda en ese c\u00e9lebre recinto bilba\u00edno como culminaci\u00f3n de su gira de teatros.<\/p>\n<p>\u00abHay momentos en la vida en los que uno se permite ciertos lujos\u00bb, ha escrito Fito Cabrales en el anuncio oficial en su p\u00e1gina web. \u00abEra una idea sencilla: salir a tocar simplemente por el placer de hacer m\u00fasica; el momento era el adecuado, sin ning\u00fan tipo de presi\u00f3n, sin disco nuevo, sin promoci\u00f3n\u00bb, recuerda el m\u00fasico vizca\u00edno.<\/p>\n<p>Junto a los Fitipaldis (Carlos Raya, Javier Alzola, Joserra Senperena, Daniel Griffin y Alejandro \u00abBoli\u00bb Climent), esta gira obtuvo un gran \u00e9xito de convocatoria y se cerr\u00f3 de forma \u00abemotiva y muy especial\u00bb con las dos citas mencionadas, de car\u00e1cter solidario, \u00aben casa y en uno de los teatros so\u00f1ados por cualquier m\u00fasico\u00bb, subraya el texto.<\/p>\n<p>\u00abEn directo desde el Teatro Arriaga\u00bb permitir\u00e1 disfrutar de las mejores canciones del repertorio de la banda con arreglos nuevos, como los de su \u00e9xito \u00abSoldadito marinero\u00bb, que toma sones de \u00abtaberna irlandesa\u00bb, seg\u00fan dijo el cantante y compositor a Efe al inicio del tour.<\/p>\n<p>Ya en aquella entrevista, en agosto de 2012, Cabrales, que no publica material in\u00e9dito desde \u00abAntes de que cuente diez\u00bb, en 2009, afirm\u00f3 que \u00abhabr\u00e1 un disco (de estudio) cuando est\u00e9 emocionado con las canciones y las quiera grabar\u00bb.<\/p>\n<p>Su nuevo disco grabado en vivo, que incluye temas como \u00abPor la boca vive el pez\u00bb, \u00abMe equivocar\u00eda otra vez\u00bb o \u00abLa casa por el tejado\u00bb, tambi\u00e9n estar\u00e1 disponible en un formato especial y limitado que incluye 3 vinilos, 2 CDs, un DVD y su versi\u00f3n digital.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 6 feb (EFE).- Fito &amp; Fitipaldis publicar\u00e1n un disco doble en directo el pr\u00f3ximo 4 de marzo que, bajo el t\u00edtulo \u00abEn directo desde el Teatro Arriaga\u00bb y acompa\u00f1ado de un DVD, permitir\u00e1 revivir los dos conciertos que ofreci\u00f3 esta banda en ese c\u00e9lebre recinto bilba\u00edno como culminaci\u00f3n de su gira de teatros. \u00abHay<\/p>\n","protected":false},"author":1,"featured_media":3249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-3248","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 6 feb (EFE).- Fito &amp; Fitipaldis publicar\u00e1n un disco doble en directo el pr\u00f3ximo 4 de marzo que, bajo el t\u00edtulo &quot;En directo desde el Teatro Arriaga&quot; y acompa\u00f1ado de un DVD, permitir\u00e1 revivir los dos conciertos que ofreci\u00f3 esta banda en ese c\u00e9lebre recinto bilba\u00edno como culminaci\u00f3n de su gira de teatros. &quot;Hay\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Fito &amp; Fitipaldis publicar\u00e1n en marzo un disco en directo | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 6 feb (EFE).- Fito &amp; Fitipaldis publicar\u00e1n un disco doble en directo el pr\u00f3ximo 4 de marzo que, bajo el t\u00edtulo &quot;En directo desde el Teatro Arriaga&quot; y acompa\u00f1ado de un DVD, permitir\u00e1 revivir los dos conciertos que ofreci\u00f3 esta banda en ese c\u00e9lebre recinto bilba\u00edno como culminaci\u00f3n de su gira de teatros. &quot;Hay\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5918389w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5918389w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"532\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-06T22:38:44+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-06T22:38:44+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Fito &amp; Fitipaldis publicar\u00e1n en marzo un disco en directo | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 6 feb (EFE).- Fito &amp; Fitipaldis publicar\u00e1n un disco doble en directo el pr\u00f3ximo 4 de marzo que, bajo el t\u00edtulo &quot;En directo desde el Teatro Arriaga&quot; y acompa\u00f1ado de un DVD, permitir\u00e1 revivir los dos conciertos que ofreci\u00f3 esta banda en ese c\u00e9lebre recinto bilba\u00edno como culminaci\u00f3n de su gira de teatros. &quot;Hay\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5918389w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\\\/#article\",\"name\":\"Fito & Fitipaldis publicar\\u00e1n en marzo un disco en directo | El Digital de Asturias\",\"headline\":\"Fito &#038; Fitipaldis publicar\\u00e1n en marzo un disco en directo\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5918389w.jpg\",\"width\":800,\"height\":532},\"datePublished\":\"2014-02-06T21:38:44+01:00\",\"dateModified\":\"2014-02-06T21:38:44+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\\\/#listItem\",\"name\":\"Fito &#038; Fitipaldis publicar\\u00e1n en marzo un disco en directo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\\\/#listItem\",\"position\":3,\"name\":\"Fito &#038; Fitipaldis publicar\\u00e1n en marzo un disco en directo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\\\/\",\"name\":\"Fito & Fitipaldis publicar\\u00e1n en marzo un disco en directo | El Digital de Asturias\",\"description\":\"Madrid, 6 feb (EFE).- Fito & Fitipaldis publicar\\u00e1n un disco doble en directo el pr\\u00f3ximo 4 de marzo que, bajo el t\\u00edtulo \\\"En directo desde el Teatro Arriaga\\\" y acompa\\u00f1ado de un DVD, permitir\\u00e1 revivir los dos conciertos que ofreci\\u00f3 esta banda en ese c\\u00e9lebre recinto bilba\\u00edno como culminaci\\u00f3n de su gira de teatros. \\\"Hay\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5918389w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\\\/#mainImage\",\"width\":800,\"height\":532},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\\\/#mainImage\"},\"datePublished\":\"2014-02-06T21:38:44+01:00\",\"dateModified\":\"2014-02-06T21:38:44+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Fito &amp; Fitipaldis publicar\u00e1n en marzo un disco en directo | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Fito & Fitipaldis publicar\u00e1n en marzo un disco en directo | El Digital de Asturias","description":"Madrid, 6 feb (EFE).- Fito & Fitipaldis publicar\u00e1n un disco doble en directo el pr\u00f3ximo 4 de marzo que, bajo el t\u00edtulo \"En directo desde el Teatro Arriaga\" y acompa\u00f1ado de un DVD, permitir\u00e1 revivir los dos conciertos que ofreci\u00f3 esta banda en ese c\u00e9lebre recinto bilba\u00edno como culminaci\u00f3n de su gira de teatros. \"Hay","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/#article","name":"Fito & Fitipaldis publicar\u00e1n en marzo un disco en directo | El Digital de Asturias","headline":"Fito &#038; Fitipaldis publicar\u00e1n en marzo un disco en directo","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5918389w.jpg","width":800,"height":532},"datePublished":"2014-02-06T21:38:44+01:00","dateModified":"2014-02-06T21:38:44+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/#listItem","name":"Fito &#038; Fitipaldis publicar\u00e1n en marzo un disco en directo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/#listItem","position":3,"name":"Fito &#038; Fitipaldis publicar\u00e1n en marzo un disco en directo","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/","name":"Fito & Fitipaldis publicar\u00e1n en marzo un disco en directo | El Digital de Asturias","description":"Madrid, 6 feb (EFE).- Fito & Fitipaldis publicar\u00e1n un disco doble en directo el pr\u00f3ximo 4 de marzo que, bajo el t\u00edtulo \"En directo desde el Teatro Arriaga\" y acompa\u00f1ado de un DVD, permitir\u00e1 revivir los dos conciertos que ofreci\u00f3 esta banda en ese c\u00e9lebre recinto bilba\u00edno como culminaci\u00f3n de su gira de teatros. \"Hay","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5918389w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/#mainImage","width":800,"height":532},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/#mainImage"},"datePublished":"2014-02-06T21:38:44+01:00","dateModified":"2014-02-06T21:38:44+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Fito &amp; Fitipaldis publicar\u00e1n en marzo un disco en directo | El Digital de Asturias","og:description":"Madrid, 6 feb (EFE).- Fito &amp; Fitipaldis publicar\u00e1n un disco doble en directo el pr\u00f3ximo 4 de marzo que, bajo el t\u00edtulo &quot;En directo desde el Teatro Arriaga&quot; y acompa\u00f1ado de un DVD, permitir\u00e1 revivir los dos conciertos que ofreci\u00f3 esta banda en ese c\u00e9lebre recinto bilba\u00edno como culminaci\u00f3n de su gira de teatros. &quot;Hay","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5918389w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5918389w.jpg","og:image:width":800,"og:image:height":532,"article:published_time":"2014-02-06T22:38:44+00:00","article:modified_time":"2014-02-06T22:38:44+00:00","twitter:card":"summary_large_image","twitter:title":"Fito &amp; Fitipaldis publicar\u00e1n en marzo un disco en directo | El Digital de Asturias","twitter:description":"Madrid, 6 feb (EFE).- Fito &amp; Fitipaldis publicar\u00e1n un disco doble en directo el pr\u00f3ximo 4 de marzo que, bajo el t\u00edtulo &quot;En directo desde el Teatro Arriaga&quot; y acompa\u00f1ado de un DVD, permitir\u00e1 revivir los dos conciertos que ofreci\u00f3 esta banda en ese c\u00e9lebre recinto bilba\u00edno como culminaci\u00f3n de su gira de teatros. &quot;Hay","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5918389w.jpg"},"aioseo_meta_data":{"post_id":"3248","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 09:37:19","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:47:44","updated":"2026-05-15 09:37:19"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/\" title=\"Fito &amp; Fitipaldis publicar\u00e1n en marzo un disco en directo\">Fito &amp; Fitipaldis publicar\u00e1n en marzo un disco en directo<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Fito &#038; Fitipaldis publicar\u00e1n en marzo un disco en directo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/fito-fitipaldis-publicaran-en-marzo-un-disco-en-directo\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=3248"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3248\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/3249"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=3248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=3248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=3248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}