{"id":3136,"date":"2014-02-06T15:08:17","date_gmt":"2014-02-06T16:08:17","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=3136"},"modified":"2014-02-06T15:08:17","modified_gmt":"2014-02-06T16:08:17","slug":"ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/","title":{"rendered":"Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3137\" alt=\"5915631w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5915631w-360x244.jpg\" width=\"360\" height=\"244\" \/>Nueva York, 6 feb (EFE).- La diva alemana Ute Lemper act\u00faa ma\u00f1ana en Barcelona para cantar poemas de amor del chileno Pablo Neruda, pieza central de un at\u00edpico tr\u00edptico latinoamericano que comenz\u00f3 con Astor Piazzola y que cerrar\u00e1 con su pr\u00f3ximo proyecto: un disco basado en textos de Paulo Coelho.<\/p>\n<p>Lemper, que se hizo famosa reivindicando y redescubriendo la \u00e9poca de la Rep\u00fablica de Weimar que los nazis ocultaron a Alemania, sigue su viaje geogr\u00e1fico y decide empezar su disco \u00abForever: The Love Poems of Pablo Neruda\u00bb homenajeando a la \u00abchanson\u00bb de Jacques Brel y Edith Piaf en \u00abLa nuit dans l&#8217;ile\u00bb.<\/p>\n<p>\u00abNeruda era un ciudadano del mundo, igual que yo\u00bb, explica Lemper a Efe en una entrevista en su apartamento en Nueva York, con las maletas hechas para poder brillar ma\u00f1ana en el Palau de la M\u00fasica con su voz, siempre intensa, siempre teatral y siempre pol\u00edglota. Esta vez cantar\u00e1 en espa\u00f1ol, en franc\u00e9s y en ingl\u00e9s.<\/p>\n<p>Lemper, la que fuera una de las m\u00e1s inolvidables Sally Bowles de \u00abCabaret\u00bb sobre las tablas de un teatro y que acaba de cerrar su \u00ab\u00daltimo tango en Berl\u00edn\u00bb sobre las tablas de Broadway, se confiesa ahora enamorada de Latinoam\u00e9rica.<\/p>\n<p>Su primer amor fue Piazzola y \u00e9l, a su manera, la empuj\u00f3 a los brazos del exiliado Neruda. \u00abEs una de las pocas personas que combinan un mensaje y una misi\u00f3n como pol\u00edtico y como artista\u00bb, explica, aunque finalmente se dedicara a su lado m\u00e1s rom\u00e1ntico. \u00abMe daba miedo banalizar su mensaje con la m\u00fasica. Los poemas de amor era m\u00e1s ligeros\u00bb, se justifica.<\/p>\n<p>Despu\u00e9s de una carrera de sobra consagrada, Lemper se permiti\u00f3 este capricho. Ella misma reconoce orgullosa que ha pagado el disco y no espera recuperar la inversi\u00f3n. Un experimento similar al que hizo con Charles Bukowsky, pero esta vez m\u00e1s centrada en la poes\u00eda.<\/p>\n<p>\u00abNo quer\u00eda que fuera nada espec\u00edfico, sino que fuera po\u00e9tico, experimental\u00bb, asegura quien ha contado para este proyecto con la colaboraci\u00f3n del bandeonero argentino Marcelo Nisinman.<\/p>\n<p>\u00abMadrigal escrito en Invierno\u00bb, \u00abSiempre\u00bb, \u00abAusencia\u00bb u \u00abOda con un lamento\u00bb le permiten viajar por el alma del autor de \u00ab20 poemas de amor y una canci\u00f3n desesperada\u00bb, quien para Lemper marca una gran diferencia entre escribir de amor y ser rom\u00e1ntico.<\/p>\n<p>\u00abNeruda no es rom\u00e1ntico, es dial\u00e9ctico. Si hay momentos de romanticismo quedan destrozados por la imposibilidad de mantener eternamente ese romanticismo, de abrazar ese momento de felicidad. Creo que Neruda era salvaje en su alma, posesivo, obsesivo&#8230; a veces sufr\u00eda por el hecho de que era adicto a las mujeres y que ellas eran m\u00e1s poderosas\u00bb, resume.<\/p>\n<p>Por eso, sus canciones a veces suenan \u00abcomo un himno, vehemente y extrovertido. Luego pueden ser introvertidas, de sentimientos rotos\u00bb, explica.<\/p>\n<p>Su siguiente amor latino ser\u00e1 brasile\u00f1o. Ya est\u00e1 trabajando en un nuevo disco \u00abmuy filos\u00f3fico, nada pol\u00edtico y muy espiritual\u00bb que adaptar\u00e1 musicalmente el \u00faltimo libro de Paulo Coelho, \u00abEl manuscrito encontrado en Accra\u00bb.<\/p>\n<p>\u00abLo le\u00ed el verano pasado mientras estaba de gira por Australia. Estaba desconcentrada y algo triste por distintas razones y fue para m\u00ed como una Biblia. Un biblia de la paz interior que hablaba de amor, p\u00e9rdida, \u00e9xito, belleza, movimiento&#8230; Estoy convirtiendo cada cap\u00edtulo en una poes\u00eda que ser\u00e1 una canci\u00f3n. He hablado con \u00e9l y me dijo que le gustaba mi m\u00fasica, as\u00ed que nos veremos a lo largo de este mes\u00bb, revela.<\/p>\n<p>Y as\u00ed, desde Accra, Lemper confirma su relaci\u00f3n de inspiraci\u00f3n con lo pret\u00e9rito, siempre encontrando respuestas en el pasado. \u00abCreo que ahora ya no hay tanta posibilidad de comprometerse con la realidad, aunque haya muchos problemas. Todo se ha comercializado\u00bb, concluye.<\/p>\n<p>Mateo Sancho Cardiel<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nueva York, 6 feb (EFE).- La diva alemana Ute Lemper act\u00faa ma\u00f1ana en Barcelona para cantar poemas de amor del chileno Pablo Neruda, pieza central de un at\u00edpico tr\u00edptico latinoamericano que comenz\u00f3 con Astor Piazzola y que cerrar\u00e1 con su pr\u00f3ximo proyecto: un disco basado en textos de Paulo Coelho. Lemper, que se hizo famosa<\/p>\n","protected":false},"author":1,"featured_media":3137,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-3136","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Nueva York, 6 feb (EFE).- La diva alemana Ute Lemper act\u00faa ma\u00f1ana en Barcelona para cantar poemas de amor del chileno Pablo Neruda, pieza central de un at\u00edpico tr\u00edptico latinoamericano que comenz\u00f3 con Astor Piazzola y que cerrar\u00e1 con su pr\u00f3ximo proyecto: un disco basado en textos de Paulo Coelho. Lemper, que se hizo famosa\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Nueva York, 6 feb (EFE).- La diva alemana Ute Lemper act\u00faa ma\u00f1ana en Barcelona para cantar poemas de amor del chileno Pablo Neruda, pieza central de un at\u00edpico tr\u00edptico latinoamericano que comenz\u00f3 con Astor Piazzola y que cerrar\u00e1 con su pr\u00f3ximo proyecto: un disco basado en textos de Paulo Coelho. Lemper, que se hizo famosa\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5915631w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5915631w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"544\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-06T16:08:17+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-06T16:08:17+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Nueva York, 6 feb (EFE).- La diva alemana Ute Lemper act\u00faa ma\u00f1ana en Barcelona para cantar poemas de amor del chileno Pablo Neruda, pieza central de un at\u00edpico tr\u00edptico latinoamericano que comenz\u00f3 con Astor Piazzola y que cerrar\u00e1 con su pr\u00f3ximo proyecto: un disco basado en textos de Paulo Coelho. Lemper, que se hizo famosa\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5915631w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\\\/#article\",\"name\":\"Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho | El Digital de Asturias\",\"headline\":\"Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5915631w.jpg\",\"width\":800,\"height\":544},\"datePublished\":\"2014-02-06T15:08:17+01:00\",\"dateModified\":\"2014-02-06T15:08:17+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\\\/#listItem\",\"name\":\"Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\\\/#listItem\",\"position\":3,\"name\":\"Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\\\/\",\"name\":\"Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho | El Digital de Asturias\",\"description\":\"Nueva York, 6 feb (EFE).- La diva alemana Ute Lemper act\\u00faa ma\\u00f1ana en Barcelona para cantar poemas de amor del chileno Pablo Neruda, pieza central de un at\\u00edpico tr\\u00edptico latinoamericano que comenz\\u00f3 con Astor Piazzola y que cerrar\\u00e1 con su pr\\u00f3ximo proyecto: un disco basado en textos de Paulo Coelho. Lemper, que se hizo famosa\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5915631w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\\\/#mainImage\",\"width\":800,\"height\":544},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\\\/#mainImage\"},\"datePublished\":\"2014-02-06T15:08:17+01:00\",\"dateModified\":\"2014-02-06T15:08:17+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho | El Digital de Asturias","description":"Nueva York, 6 feb (EFE).- La diva alemana Ute Lemper act\u00faa ma\u00f1ana en Barcelona para cantar poemas de amor del chileno Pablo Neruda, pieza central de un at\u00edpico tr\u00edptico latinoamericano que comenz\u00f3 con Astor Piazzola y que cerrar\u00e1 con su pr\u00f3ximo proyecto: un disco basado en textos de Paulo Coelho. Lemper, que se hizo famosa","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/#article","name":"Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho | El Digital de Asturias","headline":"Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5915631w.jpg","width":800,"height":544},"datePublished":"2014-02-06T15:08:17+01:00","dateModified":"2014-02-06T15:08:17+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/#listItem","name":"Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/#listItem","position":3,"name":"Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/","name":"Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho | El Digital de Asturias","description":"Nueva York, 6 feb (EFE).- La diva alemana Ute Lemper act\u00faa ma\u00f1ana en Barcelona para cantar poemas de amor del chileno Pablo Neruda, pieza central de un at\u00edpico tr\u00edptico latinoamericano que comenz\u00f3 con Astor Piazzola y que cerrar\u00e1 con su pr\u00f3ximo proyecto: un disco basado en textos de Paulo Coelho. Lemper, que se hizo famosa","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5915631w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/#mainImage","width":800,"height":544},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/#mainImage"},"datePublished":"2014-02-06T15:08:17+01:00","dateModified":"2014-02-06T15:08:17+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho | El Digital de Asturias","og:description":"Nueva York, 6 feb (EFE).- La diva alemana Ute Lemper act\u00faa ma\u00f1ana en Barcelona para cantar poemas de amor del chileno Pablo Neruda, pieza central de un at\u00edpico tr\u00edptico latinoamericano que comenz\u00f3 con Astor Piazzola y que cerrar\u00e1 con su pr\u00f3ximo proyecto: un disco basado en textos de Paulo Coelho. Lemper, que se hizo famosa","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5915631w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5915631w.jpg","og:image:width":800,"og:image:height":544,"article:published_time":"2014-02-06T16:08:17+00:00","article:modified_time":"2014-02-06T16:08:17+00:00","twitter:card":"summary_large_image","twitter:title":"Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho | El Digital de Asturias","twitter:description":"Nueva York, 6 feb (EFE).- La diva alemana Ute Lemper act\u00faa ma\u00f1ana en Barcelona para cantar poemas de amor del chileno Pablo Neruda, pieza central de un at\u00edpico tr\u00edptico latinoamericano que comenz\u00f3 con Astor Piazzola y que cerrar\u00e1 con su pr\u00f3ximo proyecto: un disco basado en textos de Paulo Coelho. Lemper, que se hizo famosa","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5915631w.jpg"},"aioseo_meta_data":{"post_id":"3136","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 09:19:15","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:46:51","updated":"2026-05-15 09:19:15"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/\" title=\"Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho\">Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Ute Lemper para en Barcelona para cantar a Neruda y prepara un disco con Coelho","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/ute-lemper-para-en-barcelona-para-cantar-a-neruda-y-prepara-un-disco-con-coelho\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=3136"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3136\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/3137"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=3136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=3136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=3136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}