{"id":3071,"date":"2014-02-05T22:50:18","date_gmt":"2014-02-05T23:50:18","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=3071"},"modified":"2014-02-05T22:50:18","modified_gmt":"2014-02-05T23:50:18","slug":"skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/","title":{"rendered":"Skinny Puppy reclama a EE.UU. por usar su m\u00fasica en la c\u00e1rcel de Guant\u00e1namo"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-3072\" alt=\"5914451w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5914451w-360x241.jpg\" width=\"360\" height=\"241\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5914451w-360x241.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5914451w-650x436.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5914451w-768x515.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5914451w-150x101.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5914451w-450x302.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5914451w-696x466.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5914451w-627x420.jpg 627w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5914451w-84x55.jpg 84w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5914451w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Washington, 5 feb (EFE).- La banda musical canadiense Skinny Puppy ha reclamado al Departamento de Estado de Estados Unidos 666.000 d\u00f3lares (492.000 euros) en pago de derechos por el supuesto uso de su m\u00fasica en interrogatorios a presos de la Base Naval de Guant\u00e1namo (Cuba).<\/p>\n<p>El grupo ha enviado al gobierno de Estados Unidos una factura con la curiosa cifra por haber recibido informaci\u00f3n por parte de un antiguo guarda de la prisi\u00f3n de que su m\u00fasica, del g\u00e9nero metal industrial con toques de punk electr\u00f3nico, fue utilizada sin permiso en interrogatorios en al menos cuatro ocasiones.<\/p>\n<p>\u00abM\u00fasica original para interrogatorios en la base de Guant\u00e1namo. Alto secreto\u00bb, indica el concepto de facturaci\u00f3n que el cantante de la formaci\u00f3n, Cevin Key, ha enviado al gobierno estadounidense.<\/p>\n<p>Key ha indicado a medios canadienses que no descartan demandar al Departamento de Defensa por el uso de su m\u00fasica para interrogatorios, en los que seg\u00fan organizaciones de derechos humanos se practic\u00f3 la tortura y que ocurrieron en los primeros a\u00f1os de la prisi\u00f3n.<\/p>\n<p>La fuente que revel\u00f3 que la m\u00fasica de Skinny Puppy era utilizada en Guant\u00e1namo est\u00e1 escribiendo un libro y asegura que en el presidio se lleg\u00f3 a someter a los detenidos a entre 6 y 12 horas continuadas de m\u00fasica \u00abdark metal\u00bb a todo volumen para quebrantar su moral.<\/p>\n<p>El l\u00edder de la banda dijo hoy al canal CTV de Canad\u00e1 que desconoc\u00edan que su m\u00fasica se utilizaba \u00abcomo un arma contra alguien\u00bb y se sienten \u00abofendidos\u00bb por el hecho de que se haya usado para \u00abinfligir da\u00f1o\u00bb a personas.<\/p>\n<p>La prisi\u00f3n de la base naval estadounidense de Guant\u00e1namo (Cuba) comenz\u00f3 a operar en 2002 para detener e interrogar con t\u00e9cnicas hoy consideradas tortura a presos de la guerra contra Al Qaeda.<\/p>\n<p>Tras doce a\u00f1os y haber mantenido encarcelados a casi 700 sospechosos, el penal de Guant\u00e1namo sigue operativo, y en \u00e9l permanecen detenidas 155 personas pese a las promesas del presidente estadounidense, Barack Obama, para completar su cierre definitivo.<\/p>\n<p>Del total de internos, la mayor\u00eda tienen el visto bueno para ser transferidos a un tercer pa\u00eds, y unos pocos esperan un juicio que les podr\u00eda acarrear la muerte por planear atentados como los del 11S de 2001 y contra el destructor estadounidense USS Cole en 2000.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Washington, 5 feb (EFE).- La banda musical canadiense Skinny Puppy ha reclamado al Departamento de Estado de Estados Unidos 666.000 d\u00f3lares (492.000 euros) en pago de derechos por el supuesto uso de su m\u00fasica en interrogatorios a presos de la Base Naval de Guant\u00e1namo (Cuba). El grupo ha enviado al gobierno de Estados Unidos una<\/p>\n","protected":false},"author":1,"featured_media":3072,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-3071","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Washington, 5 feb (EFE).- La banda musical canadiense Skinny Puppy ha reclamado al Departamento de Estado de Estados Unidos 666.000 d\u00f3lares (492.000 euros) en pago de derechos por el supuesto uso de su m\u00fasica en interrogatorios a presos de la Base Naval de Guant\u00e1namo (Cuba). El grupo ha enviado al gobierno de Estados Unidos una\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Skinny Puppy reclama a EE.UU. por usar su m\u00fasica en la c\u00e1rcel de Guant\u00e1namo | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Washington, 5 feb (EFE).- La banda musical canadiense Skinny Puppy ha reclamado al Departamento de Estado de Estados Unidos 666.000 d\u00f3lares (492.000 euros) en pago de derechos por el supuesto uso de su m\u00fasica en interrogatorios a presos de la Base Naval de Guant\u00e1namo (Cuba). El grupo ha enviado al gobierno de Estados Unidos una\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5914451w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5914451w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"536\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-05T23:50:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-05T23:50:18+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Skinny Puppy reclama a EE.UU. por usar su m\u00fasica en la c\u00e1rcel de Guant\u00e1namo | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Washington, 5 feb (EFE).- La banda musical canadiense Skinny Puppy ha reclamado al Departamento de Estado de Estados Unidos 666.000 d\u00f3lares (492.000 euros) en pago de derechos por el supuesto uso de su m\u00fasica en interrogatorios a presos de la Base Naval de Guant\u00e1namo (Cuba). El grupo ha enviado al gobierno de Estados Unidos una\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5914451w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\\\/#article\",\"name\":\"Skinny Puppy reclama a EE.UU. por usar su m\\u00fasica en la c\\u00e1rcel de Guant\\u00e1namo | El Digital de Asturias\",\"headline\":\"Skinny Puppy reclama a EE.UU. por usar su m\\u00fasica en la c\\u00e1rcel de Guant\\u00e1namo\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5914451w.jpg\",\"width\":800,\"height\":536},\"datePublished\":\"2014-02-05T22:50:18+01:00\",\"dateModified\":\"2014-02-05T22:50:18+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\\\/#listItem\",\"name\":\"Skinny Puppy reclama a EE.UU. por usar su m\\u00fasica en la c\\u00e1rcel de Guant\\u00e1namo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\\\/#listItem\",\"position\":3,\"name\":\"Skinny Puppy reclama a EE.UU. por usar su m\\u00fasica en la c\\u00e1rcel de Guant\\u00e1namo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\\\/\",\"name\":\"Skinny Puppy reclama a EE.UU. por usar su m\\u00fasica en la c\\u00e1rcel de Guant\\u00e1namo | El Digital de Asturias\",\"description\":\"Washington, 5 feb (EFE).- La banda musical canadiense Skinny Puppy ha reclamado al Departamento de Estado de Estados Unidos 666.000 d\\u00f3lares (492.000 euros) en pago de derechos por el supuesto uso de su m\\u00fasica en interrogatorios a presos de la Base Naval de Guant\\u00e1namo (Cuba). El grupo ha enviado al gobierno de Estados Unidos una\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5914451w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\\\/#mainImage\",\"width\":800,\"height\":536},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\\\/#mainImage\"},\"datePublished\":\"2014-02-05T22:50:18+01:00\",\"dateModified\":\"2014-02-05T22:50:18+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Skinny Puppy reclama a EE.UU. por usar su m\u00fasica en la c\u00e1rcel de Guant\u00e1namo | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Skinny Puppy reclama a EE.UU. por usar su m\u00fasica en la c\u00e1rcel de Guant\u00e1namo | El Digital de Asturias","description":"Washington, 5 feb (EFE).- La banda musical canadiense Skinny Puppy ha reclamado al Departamento de Estado de Estados Unidos 666.000 d\u00f3lares (492.000 euros) en pago de derechos por el supuesto uso de su m\u00fasica en interrogatorios a presos de la Base Naval de Guant\u00e1namo (Cuba). El grupo ha enviado al gobierno de Estados Unidos una","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/#article","name":"Skinny Puppy reclama a EE.UU. por usar su m\u00fasica en la c\u00e1rcel de Guant\u00e1namo | El Digital de Asturias","headline":"Skinny Puppy reclama a EE.UU. por usar su m\u00fasica en la c\u00e1rcel de Guant\u00e1namo","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5914451w.jpg","width":800,"height":536},"datePublished":"2014-02-05T22:50:18+01:00","dateModified":"2014-02-05T22:50:18+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/#listItem","name":"Skinny Puppy reclama a EE.UU. por usar su m\u00fasica en la c\u00e1rcel de Guant\u00e1namo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/#listItem","position":3,"name":"Skinny Puppy reclama a EE.UU. por usar su m\u00fasica en la c\u00e1rcel de Guant\u00e1namo","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/","name":"Skinny Puppy reclama a EE.UU. por usar su m\u00fasica en la c\u00e1rcel de Guant\u00e1namo | El Digital de Asturias","description":"Washington, 5 feb (EFE).- La banda musical canadiense Skinny Puppy ha reclamado al Departamento de Estado de Estados Unidos 666.000 d\u00f3lares (492.000 euros) en pago de derechos por el supuesto uso de su m\u00fasica en interrogatorios a presos de la Base Naval de Guant\u00e1namo (Cuba). El grupo ha enviado al gobierno de Estados Unidos una","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5914451w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/#mainImage","width":800,"height":536},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/#mainImage"},"datePublished":"2014-02-05T22:50:18+01:00","dateModified":"2014-02-05T22:50:18+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Skinny Puppy reclama a EE.UU. por usar su m\u00fasica en la c\u00e1rcel de Guant\u00e1namo | El Digital de Asturias","og:description":"Washington, 5 feb (EFE).- La banda musical canadiense Skinny Puppy ha reclamado al Departamento de Estado de Estados Unidos 666.000 d\u00f3lares (492.000 euros) en pago de derechos por el supuesto uso de su m\u00fasica en interrogatorios a presos de la Base Naval de Guant\u00e1namo (Cuba). El grupo ha enviado al gobierno de Estados Unidos una","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5914451w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5914451w.jpg","og:image:width":800,"og:image:height":536,"article:published_time":"2014-02-05T23:50:18+00:00","article:modified_time":"2014-02-05T23:50:18+00:00","twitter:card":"summary_large_image","twitter:title":"Skinny Puppy reclama a EE.UU. por usar su m\u00fasica en la c\u00e1rcel de Guant\u00e1namo | El Digital de Asturias","twitter:description":"Washington, 5 feb (EFE).- La banda musical canadiense Skinny Puppy ha reclamado al Departamento de Estado de Estados Unidos 666.000 d\u00f3lares (492.000 euros) en pago de derechos por el supuesto uso de su m\u00fasica en interrogatorios a presos de la Base Naval de Guant\u00e1namo (Cuba). El grupo ha enviado al gobierno de Estados Unidos una","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5914451w.jpg"},"aioseo_meta_data":{"post_id":"3071","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 09:11:33","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:46:30","updated":"2026-05-15 09:11:33"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/\" title=\"Skinny Puppy reclama a EE.UU. por usar su m\u00fasica en la c\u00e1rcel de Guant\u00e1namo\">Skinny Puppy reclama a EE.UU. por usar su m\u00fasica en la c\u00e1rcel de Guant\u00e1namo<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Skinny Puppy reclama a EE.UU. por usar su m\u00fasica en la c\u00e1rcel de Guant\u00e1namo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/skinny-puppy-reclama-a-ee-uu-por-usar-su-musica-en-la-carcel-de-guantanamo\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=3071"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/3071\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/3072"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=3071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=3071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=3071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}