{"id":2971,"date":"2014-02-05T17:50:18","date_gmt":"2014-02-05T18:50:18","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=2971"},"modified":"2014-02-05T17:50:18","modified_gmt":"2014-02-05T18:50:18","slug":"arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/","title":{"rendered":"Arte y ciencia: dos mundos conectados por el bi\u00f3logo pintor Fernando Bol\u00edvar"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-2972\" alt=\"5911567w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5911567w-360x241.jpg\" width=\"360\" height=\"241\" \/>Granada, 5 feb (EFE).- Demostrar que arte y ciencia est\u00e1n m\u00e1s conectados de lo que parece es uno de los objetivos de una muestra que acoge desde esta semana la Facultad de Ciencias de Granada, que se adentra en el extra\u00f1o gabinete de un profesor universitario capaz de combinar su faceta como bi\u00f3logo con de la catedr\u00e1tico de Pintura.<\/p>\n<p>\u00abArte y Ciencia. El extra\u00f1o Gabinete del Prof. Bol\u00edvar-Galiano\u00bb es el t\u00edtulo de esta particular propuesta expositiva, que recoger\u00e1 hasta el 7 de marzo una densa y completa colecci\u00f3n de peque\u00f1as \u00abcuriosidades y maravillas\u00bb.<\/p>\n<p>Fernando Bol\u00edvar, bi\u00f3logo y catedr\u00e1tico de Pintura de la Universidad de Granada, ha explicado a Efe que con esta muestra pretende recuperar la tradici\u00f3n \u00abhuman\u00edstica\u00bb de mezclar en un mismo \u00e1mbito distintas disciplinas como los viajes, la zoolog\u00eda, la bot\u00e1nica, la ciencia, la restauraci\u00f3n o las bellas artes.<\/p>\n<p>\u00abEs una forma de darle valor a este tipo de actividad. Mostrar el trabajo de m\u00e1s de 30 a\u00f1os\u00bb, ha explicado Bol\u00edvar, que combina en la muestra pintura figurativa y abstracta, a trav\u00e9s de t\u00e9cnicas no convencionales como la pintura con algas.<\/p>\n<p>Bol\u00edvar, que dirige proyectos nacionales coordinados de qu\u00edmica, arte y microbiolog\u00eda, hizo no en vano su tesis doctoral sobre algas de la Alhambra bajo la direcci\u00f3n del catedr\u00e1tico de esta especialidad, Pedro S\u00e1nchez Castillo, del Departamento de Bot\u00e1nica.<\/p>\n<p>Precisamente, en colaboraci\u00f3n con este experto, la exposici\u00f3n recoge por primera vez \u00abcuadros vivos\u00bb, que consiguen que se mantengan los colores con algas que usan como medio de cultivo la propia obra art\u00edstica.<\/p>\n<p>La exposici\u00f3n, que dif\u00edcilmente podr\u00e1 dejar indiferente a su visitante, re\u00fane tambi\u00e9n un grupo de cuadros que pueden ser contemplados con el uso de una gafas en tres dimensiones.<\/p>\n<p>Pero m\u00e1s all\u00e1 de las varias decenas de los coloristas \u00f3leos y acr\u00edlicos que aglutina, tambi\u00e9n se exhiben infinidad de objetos recopilados a lo largo de d\u00e9cadas por Bol\u00edvar, que pretende crear adem\u00e1s una ambientaci\u00f3n especial.<\/p>\n<p>Entre las esculturas destaca un lince ib\u00e9rico de bronce, homenaje a F\u00e9lix Rodr\u00edguez de la Fuente, un \u00e1guila y un lobo ib\u00e9ricos blancos, ambos de poli\u00e9ster, tallas de madera, resina pl\u00e1stica o arcilla, que se unen a otros materiales como el hierro o la escayola.<\/p>\n<p>Resultan asimismo especialmente llamativas instalaciones como las de un ajedrez \u00abdeluxe\u00bb para f\u00edsicos electr\u00f3nicos, un violonchelo \u00abmatem\u00e1tico\u00bb, peces planos de acuario e incluso una tortuga viva sobre bustos con el caparaz\u00f3n pintado.<\/p>\n<p>La exposici\u00f3n, que cuenta asimismo con varios audiovisuales, se completa con un taller de pintor donde los visitantes pueden ver tanto la creaci\u00f3n de algunas obras a trav\u00e9s de sus materiales o t\u00e9cnicas o como conocer un espacio de este tipo.<\/p>\n<p>Bol\u00edvar, quien llega a sentirse un \u00abextra\u00f1o\u00bb entre sus compa\u00f1eros de Ciencias y tambi\u00e9n lo es entre los de Bellas Artes, ha destacado adem\u00e1s que la muestra, que parte de conceptos art\u00edsticos m\u00e1s cl\u00e1sicos, cuenta asimismo con gui\u00f1os a Eugenio Salvador Dal\u00ed, Marcel Duchamp y al arte contempor\u00e1neo.<\/p>\n<p>Por Roberto Ruiz Oliva<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Granada, 5 feb (EFE).- Demostrar que arte y ciencia est\u00e1n m\u00e1s conectados de lo que parece es uno de los objetivos de una muestra que acoge desde esta semana la Facultad de Ciencias de Granada, que se adentra en el extra\u00f1o gabinete de un profesor universitario capaz de combinar su faceta como bi\u00f3logo con de<\/p>\n","protected":false},"author":1,"featured_media":2972,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-2971","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Granada, 5 feb (EFE).- Demostrar que arte y ciencia est\u00e1n m\u00e1s conectados de lo que parece es uno de los objetivos de una muestra que acoge desde esta semana la Facultad de Ciencias de Granada, que se adentra en el extra\u00f1o gabinete de un profesor universitario capaz de combinar su faceta como bi\u00f3logo con de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Arte y ciencia: dos mundos conectados por el bi\u00f3logo pintor Fernando Bol\u00edvar | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Granada, 5 feb (EFE).- Demostrar que arte y ciencia est\u00e1n m\u00e1s conectados de lo que parece es uno de los objetivos de una muestra que acoge desde esta semana la Facultad de Ciencias de Granada, que se adentra en el extra\u00f1o gabinete de un profesor universitario capaz de combinar su faceta como bi\u00f3logo con de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5911567w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5911567w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"537\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-05T18:50:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-05T18:50:18+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Arte y ciencia: dos mundos conectados por el bi\u00f3logo pintor Fernando Bol\u00edvar | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Granada, 5 feb (EFE).- Demostrar que arte y ciencia est\u00e1n m\u00e1s conectados de lo que parece es uno de los objetivos de una muestra que acoge desde esta semana la Facultad de Ciencias de Granada, que se adentra en el extra\u00f1o gabinete de un profesor universitario capaz de combinar su faceta como bi\u00f3logo con de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5911567w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\\\/#article\",\"name\":\"Arte y ciencia: dos mundos conectados por el bi\\u00f3logo pintor Fernando Bol\\u00edvar | El Digital de Asturias\",\"headline\":\"Arte y ciencia: dos mundos conectados por el bi\\u00f3logo pintor Fernando Bol\\u00edvar\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5911567w.jpg\",\"width\":800,\"height\":537},\"datePublished\":\"2014-02-05T17:50:18+01:00\",\"dateModified\":\"2014-02-05T17:50:18+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\\\/#listItem\",\"name\":\"Arte y ciencia: dos mundos conectados por el bi\\u00f3logo pintor Fernando Bol\\u00edvar\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\\\/#listItem\",\"position\":3,\"name\":\"Arte y ciencia: dos mundos conectados por el bi\\u00f3logo pintor Fernando Bol\\u00edvar\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\\\/\",\"name\":\"Arte y ciencia: dos mundos conectados por el bi\\u00f3logo pintor Fernando Bol\\u00edvar | El Digital de Asturias\",\"description\":\"Granada, 5 feb (EFE).- Demostrar que arte y ciencia est\\u00e1n m\\u00e1s conectados de lo que parece es uno de los objetivos de una muestra que acoge desde esta semana la Facultad de Ciencias de Granada, que se adentra en el extra\\u00f1o gabinete de un profesor universitario capaz de combinar su faceta como bi\\u00f3logo con de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5911567w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\\\/#mainImage\",\"width\":800,\"height\":537},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\\\/#mainImage\"},\"datePublished\":\"2014-02-05T17:50:18+01:00\",\"dateModified\":\"2014-02-05T17:50:18+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Arte y ciencia: dos mundos conectados por el bi\u00f3logo pintor Fernando Bol\u00edvar | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Arte y ciencia: dos mundos conectados por el bi\u00f3logo pintor Fernando Bol\u00edvar | El Digital de Asturias","description":"Granada, 5 feb (EFE).- Demostrar que arte y ciencia est\u00e1n m\u00e1s conectados de lo que parece es uno de los objetivos de una muestra que acoge desde esta semana la Facultad de Ciencias de Granada, que se adentra en el extra\u00f1o gabinete de un profesor universitario capaz de combinar su faceta como bi\u00f3logo con de","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/#article","name":"Arte y ciencia: dos mundos conectados por el bi\u00f3logo pintor Fernando Bol\u00edvar | El Digital de Asturias","headline":"Arte y ciencia: dos mundos conectados por el bi\u00f3logo pintor Fernando Bol\u00edvar","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5911567w.jpg","width":800,"height":537},"datePublished":"2014-02-05T17:50:18+01:00","dateModified":"2014-02-05T17:50:18+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/#listItem","name":"Arte y ciencia: dos mundos conectados por el bi\u00f3logo pintor Fernando Bol\u00edvar"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/#listItem","position":3,"name":"Arte y ciencia: dos mundos conectados por el bi\u00f3logo pintor Fernando Bol\u00edvar","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/","name":"Arte y ciencia: dos mundos conectados por el bi\u00f3logo pintor Fernando Bol\u00edvar | El Digital de Asturias","description":"Granada, 5 feb (EFE).- Demostrar que arte y ciencia est\u00e1n m\u00e1s conectados de lo que parece es uno de los objetivos de una muestra que acoge desde esta semana la Facultad de Ciencias de Granada, que se adentra en el extra\u00f1o gabinete de un profesor universitario capaz de combinar su faceta como bi\u00f3logo con de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5911567w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/#mainImage","width":800,"height":537},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/#mainImage"},"datePublished":"2014-02-05T17:50:18+01:00","dateModified":"2014-02-05T17:50:18+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Arte y ciencia: dos mundos conectados por el bi\u00f3logo pintor Fernando Bol\u00edvar | El Digital de Asturias","og:description":"Granada, 5 feb (EFE).- Demostrar que arte y ciencia est\u00e1n m\u00e1s conectados de lo que parece es uno de los objetivos de una muestra que acoge desde esta semana la Facultad de Ciencias de Granada, que se adentra en el extra\u00f1o gabinete de un profesor universitario capaz de combinar su faceta como bi\u00f3logo con de","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5911567w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5911567w.jpg","og:image:width":800,"og:image:height":537,"article:published_time":"2014-02-05T18:50:18+00:00","article:modified_time":"2014-02-05T18:50:18+00:00","twitter:card":"summary_large_image","twitter:title":"Arte y ciencia: dos mundos conectados por el bi\u00f3logo pintor Fernando Bol\u00edvar | El Digital de Asturias","twitter:description":"Granada, 5 feb (EFE).- Demostrar que arte y ciencia est\u00e1n m\u00e1s conectados de lo que parece es uno de los objetivos de una muestra que acoge desde esta semana la Facultad de Ciencias de Granada, que se adentra en el extra\u00f1o gabinete de un profesor universitario capaz de combinar su faceta como bi\u00f3logo con de","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5911567w.jpg"},"aioseo_meta_data":{"post_id":"2971","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 08:59:07","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:46:24","updated":"2026-05-15 08:59:07"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/\" title=\"Arte y ciencia: dos mundos conectados por el bi\u00f3logo pintor Fernando Bol\u00edvar\">Arte y ciencia: dos mundos conectados por el bi\u00f3logo pintor Fernando Bol\u00edvar<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Arte y ciencia: dos mundos conectados por el bi\u00f3logo pintor Fernando Bol\u00edvar","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/arte-y-ciencia-dos-mundos-conectados-por-el-biologo-pintor-fernando-bolivar\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/2971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=2971"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/2971\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/2972"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=2971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=2971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=2971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}