{"id":29614,"date":"2014-11-04T19:58:26","date_gmt":"2014-11-04T21:58:26","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=29614"},"modified":"2014-11-04T19:58:26","modified_gmt":"2014-11-04T21:58:26","slug":"uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/","title":{"rendered":"Uruguay se promociona en Europa como pa\u00eds bello, abierto y tolerante"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-29615\" alt=\"6979846w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/11\/6979846w-360x239.jpg\" width=\"360\" height=\"239\" \/>Londres, 4 nov (EFE).- Uruguay se presenta este a\u00f1o en la Feria Mundial del Turismo de Londres como un pa\u00eds con m\u00faltiples atractivos naturales y culturales, pero tambi\u00e9n \u00ababierto y tolerante\u00bb, explic\u00f3 hoy a Efe la ministra uruguaya de Turismo, Liliam Kechichi\u00e1n.<\/p>\n<p>Con un expositor que resalta los paisajes aut\u00f3ctonos, el Gobierno uruguayo, que ha \u00abmultiplicado por cuatro\u00bb la inversi\u00f3n en promoci\u00f3n tur\u00edstica en los \u00faltimos a\u00f1os, pretende captar a m\u00e1s turistas europeos para seguir creciendo, se\u00f1al\u00f3 Kechichi\u00e1n.<\/p>\n<p>\u00abEl turista europeo es una de nuestras prioridades\u00bb, declar\u00f3 la ministra del Gobierno de Jos\u00e9 Mujica, quien subray\u00f3 que \u00abla reciente mejora de las conexiones a\u00e9reas\u00bb ofrece mayores posibilidades de expansi\u00f3n.<\/p>\n<p>Seg\u00fan datos oficiales, el principal emisor de turistas a Uruguay es la vecina Argentina, con 1,6 millones anuales, si bien ahora hay un descenso \u00abpor el desincentivo que afrontan los argentinos para salir del pa\u00eds\u00bb, dijo.<\/p>\n<p>El Gobierno uruguayo ha hecho adem\u00e1s \u00abuna campa\u00f1a muy inteligente en el mercado brasilero\u00bb, que ha aumentado en los \u00faltimos seis a\u00f1os de 150.000 visitantes al medio mill\u00f3n actual, con lo que se convierte en el segundo mercado, indic\u00f3 Kechichi\u00e1n.<\/p>\n<p>Chile y Paraguay aportan unos 50.000 turistas anuales cada uno, mientras que los europeos en su conjunto son unos 150.000 y en torno a 90.000 los estadounidenses, que se desplazan cada vez m\u00e1s atra\u00eddos por la combinaci\u00f3n de seguridad y apertura de este pa\u00eds latinoamericano.<\/p>\n<p>A esta nueva imagen de Uruguay, cuyas pol\u00edticas sociales e iniciativas de su presidente han acaparado titulares en todo el mundo, han contribuido la mejora econ\u00f3mica, con un crecimiento del 4 por ciento del producto interior bruto (PIB) previsto para este a\u00f1o, y la promulgaci\u00f3n de leyes progresistas, afirm\u00f3 la ministra.<\/p>\n<p>Uruguay, resalt\u00f3, es hoy el pa\u00eds \u00abm\u00e1s amigable para los gais de Am\u00e9rica Latina\u00bb y uno de los m\u00e1s abiertos y tolerantes del mundo, tras la aprobaci\u00f3n de las leyes del concubinato y del matrimonio igualitario y la regulaci\u00f3n de la marihuana como medio para combatir el tr\u00e1fico de drogas.<\/p>\n<p>Precis\u00f3 que el turismo \u00abdel segmento gay\u00bb ha aumentado de forma destacada -el Gobierno ha formado incluso una mesa espec\u00edfica para desarrollarlo- y el sector privado ofrece una gran variedad de propuestas para este sector.<\/p>\n<p>En cuanto a la pionera regulaci\u00f3n del cannabis, se ha dise\u00f1ado como mecanismo para luchar contra el narcotr\u00e1fico y \u00abde ninguna manera Uruguay potenciar\u00e1 un turismo cann\u00e1bico\u00bb, afirm\u00f3.<\/p>\n<p>\u00abLa ley -destac\u00f3- es espec\u00edficamente para los uruguayos, no tiene nada que ver con el turismo\u00bb.<\/p>\n<p>Tras llegar a un r\u00e9cord de 3 millones de turistas en 2011, Uruguay -con una poblaci\u00f3n de 3,3 millones de personas- cerrar\u00e1 este a\u00f1o con m\u00e1s de 2,8 millones de visitantes, por encima de su objetivo inicial de 2,6, lo que Kichichi\u00e1n considera muy positivo.<\/p>\n<p>A la imagen de apertura, trazabilidad de su carne y la tradicional oferta de playa y lugares hist\u00f3ricos, este pa\u00eds emergente a\u00f1ade ahora el turismo idiom\u00e1tico -quiere atraer a europeos para aprender espa\u00f1ol- y una mejor oferta de naturaleza.<\/p>\n<p>\u00abHemos diversificado la oferta, hemos hecho una consultor\u00eda de turismo n\u00e1utico y fluvial, tenemos un plan de desarrollo importante\u00bb, puntualiz\u00f3.<\/p>\n<p>Uruguay supo hoy que ha sido elegida por la popular gu\u00eda de viajes \u00abLonely Planet\u00bb como uno de los diez destinos m\u00e1s recomendables del mundo para 2015, junto con Per\u00fa, Chile y Brasil entre los latinoamericanos.<\/p>\n<p>Adem\u00e1s, en 2013, junto con Argentina, consigui\u00f3 que el candombe fuera declarado con el tango patrimonio intangible de la humanidad.<\/p>\n<p>A ello se a\u00f1ade una petici\u00f3n a la Organizaci\u00f3n de las Naciones Unidas para la Educaci\u00f3n, la Ciencia y la Cultura (Unesco) para que declare patrimonio industrial del mundo el Frigor\u00edfico Anglo de Fray Bentos, que elabor\u00f3 el \u00abcorned beef\u00bb consumido por los soldados durante la Segunda Guerra Mundial.<\/p>\n<p>\u00abSomos un pa\u00eds amigable, manejable, serio y seguro, donde se respetan las reglas del juego\u00bb, apunt\u00f3 la ministra.<\/p>\n<p>Recalc\u00f3 tambi\u00e9n la calidez de la poblaci\u00f3n: \u00abUruguay es un pa\u00eds de inmigrantes. Siempre hemos recibido a extranjeros&#8230; Todos nosotros somos hijos de alguien que lleg\u00f3 al Uruguay hace cien a\u00f1os, por lo que tenemos una cultura arraigada de recibir bien al de afuera\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Londres, 4 nov (EFE).- Uruguay se presenta este a\u00f1o en la Feria Mundial del Turismo de Londres como un pa\u00eds con m\u00faltiples atractivos naturales y culturales, pero tambi\u00e9n \u00ababierto y tolerante\u00bb, explic\u00f3 hoy a Efe la ministra uruguaya de Turismo, Liliam Kechichi\u00e1n. Con un expositor que resalta los paisajes aut\u00f3ctonos, el Gobierno uruguayo, que ha<\/p>\n","protected":false},"author":1,"featured_media":29615,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-29614","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Londres, 4 nov (EFE).- Uruguay se presenta este a\u00f1o en la Feria Mundial del Turismo de Londres como un pa\u00eds con m\u00faltiples atractivos naturales y culturales, pero tambi\u00e9n &quot;abierto y tolerante&quot;, explic\u00f3 hoy a Efe la ministra uruguaya de Turismo, Liliam Kechichi\u00e1n. Con un expositor que resalta los paisajes aut\u00f3ctonos, el Gobierno uruguayo, que ha\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Uruguay se promociona en Europa como pa\u00eds bello, abierto y tolerante | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Londres, 4 nov (EFE).- Uruguay se presenta este a\u00f1o en la Feria Mundial del Turismo de Londres como un pa\u00eds con m\u00faltiples atractivos naturales y culturales, pero tambi\u00e9n &quot;abierto y tolerante&quot;, explic\u00f3 hoy a Efe la ministra uruguaya de Turismo, Liliam Kechichi\u00e1n. Con un expositor que resalta los paisajes aut\u00f3ctonos, el Gobierno uruguayo, que ha\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/11\/6979846w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/11\/6979846w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-11-04T21:58:26+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-11-04T21:58:26+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Uruguay se promociona en Europa como pa\u00eds bello, abierto y tolerante | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Londres, 4 nov (EFE).- Uruguay se presenta este a\u00f1o en la Feria Mundial del Turismo de Londres como un pa\u00eds con m\u00faltiples atractivos naturales y culturales, pero tambi\u00e9n &quot;abierto y tolerante&quot;, explic\u00f3 hoy a Efe la ministra uruguaya de Turismo, Liliam Kechichi\u00e1n. Con un expositor que resalta los paisajes aut\u00f3ctonos, el Gobierno uruguayo, que ha\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/11\/6979846w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\\\/#article\",\"name\":\"Uruguay se promociona en Europa como pa\\u00eds bello, abierto y tolerante | El Digital de Asturias\",\"headline\":\"Uruguay se promociona en Europa como pa\\u00eds bello, abierto y tolerante\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/6979846w.jpg\",\"width\":800,\"height\":533},\"datePublished\":\"2014-11-04T19:58:26+01:00\",\"dateModified\":\"2014-11-04T19:58:26+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\\\/#listItem\",\"name\":\"Uruguay se promociona en Europa como pa\\u00eds bello, abierto y tolerante\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\\\/#listItem\",\"position\":3,\"name\":\"Uruguay se promociona en Europa como pa\\u00eds bello, abierto y tolerante\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\\\/\",\"name\":\"Uruguay se promociona en Europa como pa\\u00eds bello, abierto y tolerante | El Digital de Asturias\",\"description\":\"Londres, 4 nov (EFE).- Uruguay se presenta este a\\u00f1o en la Feria Mundial del Turismo de Londres como un pa\\u00eds con m\\u00faltiples atractivos naturales y culturales, pero tambi\\u00e9n \\\"abierto y tolerante\\\", explic\\u00f3 hoy a Efe la ministra uruguaya de Turismo, Liliam Kechichi\\u00e1n. Con un expositor que resalta los paisajes aut\\u00f3ctonos, el Gobierno uruguayo, que ha\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/6979846w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\\\/#mainImage\",\"width\":800,\"height\":533},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\\\/#mainImage\"},\"datePublished\":\"2014-11-04T19:58:26+01:00\",\"dateModified\":\"2014-11-04T19:58:26+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Uruguay se promociona en Europa como pa\u00eds bello, abierto y tolerante | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Uruguay se promociona en Europa como pa\u00eds bello, abierto y tolerante | El Digital de Asturias","description":"Londres, 4 nov (EFE).- Uruguay se presenta este a\u00f1o en la Feria Mundial del Turismo de Londres como un pa\u00eds con m\u00faltiples atractivos naturales y culturales, pero tambi\u00e9n \"abierto y tolerante\", explic\u00f3 hoy a Efe la ministra uruguaya de Turismo, Liliam Kechichi\u00e1n. Con un expositor que resalta los paisajes aut\u00f3ctonos, el Gobierno uruguayo, que ha","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/#article","name":"Uruguay se promociona en Europa como pa\u00eds bello, abierto y tolerante | El Digital de Asturias","headline":"Uruguay se promociona en Europa como pa\u00eds bello, abierto y tolerante","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/11\/6979846w.jpg","width":800,"height":533},"datePublished":"2014-11-04T19:58:26+01:00","dateModified":"2014-11-04T19:58:26+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/#listItem","name":"Uruguay se promociona en Europa como pa\u00eds bello, abierto y tolerante"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/#listItem","position":3,"name":"Uruguay se promociona en Europa como pa\u00eds bello, abierto y tolerante","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/","name":"Uruguay se promociona en Europa como pa\u00eds bello, abierto y tolerante | El Digital de Asturias","description":"Londres, 4 nov (EFE).- Uruguay se presenta este a\u00f1o en la Feria Mundial del Turismo de Londres como un pa\u00eds con m\u00faltiples atractivos naturales y culturales, pero tambi\u00e9n \"abierto y tolerante\", explic\u00f3 hoy a Efe la ministra uruguaya de Turismo, Liliam Kechichi\u00e1n. Con un expositor que resalta los paisajes aut\u00f3ctonos, el Gobierno uruguayo, que ha","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/11\/6979846w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/#mainImage","width":800,"height":533},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/#mainImage"},"datePublished":"2014-11-04T19:58:26+01:00","dateModified":"2014-11-04T19:58:26+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Uruguay se promociona en Europa como pa\u00eds bello, abierto y tolerante | El Digital de Asturias","og:description":"Londres, 4 nov (EFE).- Uruguay se presenta este a\u00f1o en la Feria Mundial del Turismo de Londres como un pa\u00eds con m\u00faltiples atractivos naturales y culturales, pero tambi\u00e9n &quot;abierto y tolerante&quot;, explic\u00f3 hoy a Efe la ministra uruguaya de Turismo, Liliam Kechichi\u00e1n. Con un expositor que resalta los paisajes aut\u00f3ctonos, el Gobierno uruguayo, que ha","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/11\/6979846w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/11\/6979846w.jpg","og:image:width":800,"og:image:height":533,"article:published_time":"2014-11-04T21:58:26+00:00","article:modified_time":"2014-11-04T21:58:26+00:00","twitter:card":"summary_large_image","twitter:title":"Uruguay se promociona en Europa como pa\u00eds bello, abierto y tolerante | El Digital de Asturias","twitter:description":"Londres, 4 nov (EFE).- Uruguay se presenta este a\u00f1o en la Feria Mundial del Turismo de Londres como un pa\u00eds con m\u00faltiples atractivos naturales y culturales, pero tambi\u00e9n &quot;abierto y tolerante&quot;, explic\u00f3 hoy a Efe la ministra uruguaya de Turismo, Liliam Kechichi\u00e1n. Con un expositor que resalta los paisajes aut\u00f3ctonos, el Gobierno uruguayo, que ha","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/11\/6979846w.jpg"},"aioseo_meta_data":{"post_id":"29614","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-17 19:26:00","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 04:48:46","updated":"2026-05-17 19:26:00"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/\" title=\"Uruguay se promociona en Europa como pa\u00eds bello, abierto y tolerante\">Uruguay se promociona en Europa como pa\u00eds bello, abierto y tolerante<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"Uruguay se promociona en Europa como pa\u00eds bello, abierto y tolerante","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/uruguay-se-promociona-en-europa-como-pais-bello-abierto-y-tolerante\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/29614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=29614"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/29614\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/29615"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=29614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=29614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=29614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}