{"id":2959,"date":"2014-02-05T17:45:18","date_gmt":"2014-02-05T18:45:18","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=2959"},"modified":"2014-02-05T17:45:18","modified_gmt":"2014-02-05T18:45:18","slug":"la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/","title":{"rendered":"La lucha de C\u00e9sar Ch\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-2960\" alt=\"5910631w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5910631w-360x239.jpg\" width=\"360\" height=\"239\" \/>Washington, 5 feb (EFE).- El actor y director mexicano Diego Luna llev\u00f3 al Congreso de Estados Unidos la pel\u00edcula que ha filmado sobre el l\u00edder sindical C\u00e9sar Ch\u00e1vez y asegur\u00f3 en una entrevista con Efe que espera que la cinta contribuya a que la reforma migratoria que se est\u00e1 debatiendo en el pa\u00eds \u00abllegue pronto a un final feliz\u00bb.<\/p>\n<p>Luna expres\u00f3 su deseo de que la figura de Ch\u00e1vez (1927-1993), fundador del sindicato Asociaci\u00f3n Nacional de Trabajadores del Campo, y su lucha por los derechos de los campesinos sirvan de ejemplo y anim\u00f3 a la comunidad latina de Estados Unidos a \u00abimplicarse\u00bb en la defensa de una nueva ley sobre inmigraci\u00f3n.<\/p>\n<p>Su pel\u00edcula, \u00abC\u00e9sar Ch\u00e1vez: History is made one step at a time\u00bb, tiene a Michael Pe\u00f1a (\u00abEnd of Watch\u00bb) a la cabeza de un reparto en el que tambi\u00e9n figuran Am\u00e9rica Ferrera (\u00abUgly Betty\u00bb), Rosario Dawson (\u00abSin City\u00bb) y John Malkovich.<\/p>\n<p>Varios legisladores, sindicalistas, activistas por los derechos de los inmigrantes y familiares de C\u00e9sar Ch\u00e1vez asistieron hoy a la presentaci\u00f3n de este biograf\u00eda cinematogr\u00e1fica en el Capitolio de Washington, sede de las dos c\u00e1maras del Congreso.<\/p>\n<p>\u00abOjal\u00e1 esto sume para que el debate sobre la reforma migratoria llegue pronto a un final feliz y deje de haber un n\u00famero tan alto de personas viviendo una realidad tan injusta\u00bb, afirm\u00f3 Luna.<\/p>\n<p>Con Estados Unidos inmerso en el debate sobre la reforma migratoria, la cinta, que se estrena el pr\u00f3ximo 28 de marzo, ve la luz \u00aben un momento muy oportuno\u00bb, explic\u00f3 su realizador, que es optimista sobre una eventual aprobaci\u00f3n de la ley.<\/p>\n<p>\u00abNos corresponde a todos ser parte de ese cambio. No nos vamos a sentar y va a suceder. No vamos a leer en los peri\u00f3dicos que un d\u00eda m\u00e1gicamente suceda. Hay que implicarse\u00bb, se\u00f1al\u00f3 el actor de pel\u00edculas como \u00abY tu mam\u00e1 tambi\u00e9n\u00bb o \u00abHarvey Milk\u00bb.<\/p>\n<p>Luna admiti\u00f3 que quiere pensar que historias como la que cuenta su pel\u00edcula \u00abpueden definitivamente motivar el cambio\u00bb.<\/p>\n<p>\u00abCuando ves lo que lograron, cuando ves que una comunidad tan d\u00e9bil, ignorada, logr\u00f3 colapsar a una de las industrias m\u00e1s poderosas de Estados Unidos y en particular California te das cuenta de que s\u00ed es posible. Es un gran ejemplo\u00bb, a\u00f1adi\u00f3.<\/p>\n<p>Seg\u00fan Luna, C\u00e9sar Ch\u00e1vez es un personaje desconocido en la mayor parte de Estados Unidos y, a su juicio, \u00abes indispensable que se sepa qui\u00e9n es y se celebre\u00bb.<\/p>\n<p>En este sentido, la fundaci\u00f3n que lleva el nombre del sindicalista ya ha lanzado una campa\u00f1a para que Estados Unidos tenga una fiesta de \u00e1mbito nacional dedicada a la memoria de Ch\u00e1vez, que ya celebran en algunos estados el 31 de marzo, fecha de su nacimiento.<\/p>\n<p>La pel\u00edcula no abarca la vida completa del fundador del primer sindicato de campesinos de Estados Unidos, sino que se centra s\u00f3lo en diez a\u00f1os y muestra el nacimiento de esta organizaci\u00f3n, en 1962, y el boicot a la venta de uvas y la huelga de recolectores que impuls\u00f3 en 1965.<\/p>\n<p>Aunque la familia del sindicalista ya ha manifestado su conformidad con el contenido de la pel\u00edcula, su director es consciente de que el hecho de narrar una historia reciente y que muchos de las personajes que aparecen en la cinta est\u00e9n vivos conlleva \u00abuna gran responsabilidad\u00bb.<\/p>\n<p>\u00abEs una responsabilidad tremenda, pero no puedes dejar que ese peso te detenga\u00bb, asever\u00f3 Luna, quien espera que la cinta \u00abdespierte un debate y una reflexi\u00f3n y haga que la gente se acerque m\u00e1s a otro tipo de documentos para conocer m\u00e1s a C\u00e9sar Ch\u00e1vez, que sirva para despertar ese inter\u00e9s\u00bb.<\/p>\n<p>La pel\u00edcula llegar\u00e1 a los cines estadounidenses el pr\u00f3ximo 28 de marzo, aunque la pr\u00f3xima semana se estrenar\u00e1 en el Festival de Cine de Berl\u00edn.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Washington, 5 feb (EFE).- El actor y director mexicano Diego Luna llev\u00f3 al Congreso de Estados Unidos la pel\u00edcula que ha filmado sobre el l\u00edder sindical C\u00e9sar Ch\u00e1vez y asegur\u00f3 en una entrevista con Efe que espera que la cinta contribuya a que la reforma migratoria que se est\u00e1 debatiendo en el pa\u00eds \u00abllegue pronto<\/p>\n","protected":false},"author":1,"featured_media":2960,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-2959","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Washington, 5 feb (EFE).- El actor y director mexicano Diego Luna llev\u00f3 al Congreso de Estados Unidos la pel\u00edcula que ha filmado sobre el l\u00edder sindical C\u00e9sar Ch\u00e1vez y asegur\u00f3 en una entrevista con Efe que espera que la cinta contribuya a que la reforma migratoria que se est\u00e1 debatiendo en el pa\u00eds &quot;llegue pronto\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La lucha de C\u00e9sar Ch\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Washington, 5 feb (EFE).- El actor y director mexicano Diego Luna llev\u00f3 al Congreso de Estados Unidos la pel\u00edcula que ha filmado sobre el l\u00edder sindical C\u00e9sar Ch\u00e1vez y asegur\u00f3 en una entrevista con Efe que espera que la cinta contribuya a que la reforma migratoria que se est\u00e1 debatiendo en el pa\u00eds &quot;llegue pronto\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5910631w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5910631w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-05T18:45:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-05T18:45:18+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La lucha de C\u00e9sar Ch\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Washington, 5 feb (EFE).- El actor y director mexicano Diego Luna llev\u00f3 al Congreso de Estados Unidos la pel\u00edcula que ha filmado sobre el l\u00edder sindical C\u00e9sar Ch\u00e1vez y asegur\u00f3 en una entrevista con Efe que espera que la cinta contribuya a que la reforma migratoria que se est\u00e1 debatiendo en el pa\u00eds &quot;llegue pronto\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5910631w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\\\/#article\",\"name\":\"La lucha de C\\u00e9sar Ch\\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna | El Digital de Asturias\",\"headline\":\"La lucha de C\\u00e9sar Ch\\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5910631w.jpg\",\"width\":800,\"height\":533},\"datePublished\":\"2014-02-05T17:45:18+01:00\",\"dateModified\":\"2014-02-05T17:45:18+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\\\/#listItem\",\"name\":\"La lucha de C\\u00e9sar Ch\\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\\\/#listItem\",\"position\":3,\"name\":\"La lucha de C\\u00e9sar Ch\\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\\\/\",\"name\":\"La lucha de C\\u00e9sar Ch\\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna | El Digital de Asturias\",\"description\":\"Washington, 5 feb (EFE).- El actor y director mexicano Diego Luna llev\\u00f3 al Congreso de Estados Unidos la pel\\u00edcula que ha filmado sobre el l\\u00edder sindical C\\u00e9sar Ch\\u00e1vez y asegur\\u00f3 en una entrevista con Efe que espera que la cinta contribuya a que la reforma migratoria que se est\\u00e1 debatiendo en el pa\\u00eds \\\"llegue pronto\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5910631w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\\\/#mainImage\",\"width\":800,\"height\":533},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\\\/#mainImage\"},\"datePublished\":\"2014-02-05T17:45:18+01:00\",\"dateModified\":\"2014-02-05T17:45:18+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La lucha de C\u00e9sar Ch\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"La lucha de C\u00e9sar Ch\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna | El Digital de Asturias","description":"Washington, 5 feb (EFE).- El actor y director mexicano Diego Luna llev\u00f3 al Congreso de Estados Unidos la pel\u00edcula que ha filmado sobre el l\u00edder sindical C\u00e9sar Ch\u00e1vez y asegur\u00f3 en una entrevista con Efe que espera que la cinta contribuya a que la reforma migratoria que se est\u00e1 debatiendo en el pa\u00eds \"llegue pronto","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/#article","name":"La lucha de C\u00e9sar Ch\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna | El Digital de Asturias","headline":"La lucha de C\u00e9sar Ch\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5910631w.jpg","width":800,"height":533},"datePublished":"2014-02-05T17:45:18+01:00","dateModified":"2014-02-05T17:45:18+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/#listItem","name":"La lucha de C\u00e9sar Ch\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/#listItem","position":3,"name":"La lucha de C\u00e9sar Ch\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/","name":"La lucha de C\u00e9sar Ch\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna | El Digital de Asturias","description":"Washington, 5 feb (EFE).- El actor y director mexicano Diego Luna llev\u00f3 al Congreso de Estados Unidos la pel\u00edcula que ha filmado sobre el l\u00edder sindical C\u00e9sar Ch\u00e1vez y asegur\u00f3 en una entrevista con Efe que espera que la cinta contribuya a que la reforma migratoria que se est\u00e1 debatiendo en el pa\u00eds \"llegue pronto","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5910631w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/#mainImage","width":800,"height":533},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/#mainImage"},"datePublished":"2014-02-05T17:45:18+01:00","dateModified":"2014-02-05T17:45:18+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"La lucha de C\u00e9sar Ch\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna | El Digital de Asturias","og:description":"Washington, 5 feb (EFE).- El actor y director mexicano Diego Luna llev\u00f3 al Congreso de Estados Unidos la pel\u00edcula que ha filmado sobre el l\u00edder sindical C\u00e9sar Ch\u00e1vez y asegur\u00f3 en una entrevista con Efe que espera que la cinta contribuya a que la reforma migratoria que se est\u00e1 debatiendo en el pa\u00eds &quot;llegue pronto","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5910631w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5910631w.jpg","og:image:width":800,"og:image:height":533,"article:published_time":"2014-02-05T18:45:18+00:00","article:modified_time":"2014-02-05T18:45:18+00:00","twitter:card":"summary_large_image","twitter:title":"La lucha de C\u00e9sar Ch\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna | El Digital de Asturias","twitter:description":"Washington, 5 feb (EFE).- El actor y director mexicano Diego Luna llev\u00f3 al Congreso de Estados Unidos la pel\u00edcula que ha filmado sobre el l\u00edder sindical C\u00e9sar Ch\u00e1vez y asegur\u00f3 en una entrevista con Efe que espera que la cinta contribuya a que la reforma migratoria que se est\u00e1 debatiendo en el pa\u00eds &quot;llegue pronto","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5910631w.jpg"},"aioseo_meta_data":{"post_id":"2959","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 08:57:04","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:46:23","updated":"2026-05-15 08:57:04"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/\" title=\"La lucha de C\u00e9sar Ch\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna\">La lucha de C\u00e9sar Ch\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"La lucha de C\u00e9sar Ch\u00e1vez llega al Congreso de EE.UU. de la mano de Diego Luna","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-lucha-de-cesar-chavez-llega-al-congreso-de-ee-uu-de-la-mano-de-diego-luna\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/2959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=2959"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/2959\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/2960"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=2959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=2959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=2959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}