{"id":2953,"date":"2014-02-05T02:30:07","date_gmt":"2014-02-05T03:30:07","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=2953"},"modified":"2014-02-05T02:30:07","modified_gmt":"2014-02-05T03:30:07","slug":"la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/","title":{"rendered":"La Oreja de Van Gogh presentar\u00e1 un \u00abconcierto \u00edntimo\u00bb en Panam\u00e1"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-2954\" alt=\"5910441w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5910441w-360x227.jpg\" width=\"360\" height=\"227\" \/>Panam\u00e1, 4 feb (EFE).- El grupo de m\u00fasica pop espa\u00f1ol La Oreja de Van Gogh ofrecer\u00e1 el pr\u00f3ximo 26 de marzo un \u00abconcierto \u00edntimo\u00bb en Panam\u00e1 para presentar su \u00faltima producci\u00f3n discogr\u00e1fica, \u00abPrimera Fila\u00bb, informaron hoy los organizadores.<\/p>\n<p>El espect\u00e1culo se llevar\u00e1 a cabo en la sala de conciertos Latitude 47, en la capital paname\u00f1a, ante un p\u00fablico limitado a 900 personas, seg\u00fan la informaci\u00f3n oficial.<\/p>\n<p>La vocalista Leire Mart\u00ednez, el guitarrista Pablo Benegas, el pianista Xabi San Mart\u00edn, el bajista \u00c1lvaro Fuentes y el bater\u00eda Haritz Garde regresan a Panam\u00e1 tras dos a\u00f1os de ausencia del pa\u00eds centroamericano.<\/p>\n<p>El grupo interpretar\u00e1 canciones de anteriores producciones, pero sobre todo las del nuevo disco, \u00abPrimera Fila\u00bb, que contiene cuatro sencillos in\u00e9ditos y once \u00e9xitos versionados y cuenta con la colaboraci\u00f3n de artistas invitados como Natalia Lafourcade, Samo, Leonel Garc\u00eda y Abel Pintos.<\/p>\n<p>El primer sencillo lanzado al mercado de este disco, \u00abEl primer d\u00eda del resto de mi vida\u00bb, ocupa los primeros puestos de radio en Espa\u00f1a y Latinoam\u00e9rica, seg\u00fan el comunicado de los organizadores.<\/p>\n<p>La banda donostiarra presentar\u00e1 en su concierto paname\u00f1o, entre otras canciones, \u00abLa Playa\u00bb, \u00abRosas\u00bb y \u00abDeseos de cosas imposibles\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Panam\u00e1, 4 feb (EFE).- El grupo de m\u00fasica pop espa\u00f1ol La Oreja de Van Gogh ofrecer\u00e1 el pr\u00f3ximo 26 de marzo un \u00abconcierto \u00edntimo\u00bb en Panam\u00e1 para presentar su \u00faltima producci\u00f3n discogr\u00e1fica, \u00abPrimera Fila\u00bb, informaron hoy los organizadores. El espect\u00e1culo se llevar\u00e1 a cabo en la sala de conciertos Latitude 47, en la capital paname\u00f1a,<\/p>\n","protected":false},"author":1,"featured_media":2954,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-2953","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Panam\u00e1, 4 feb (EFE).- El grupo de m\u00fasica pop espa\u00f1ol La Oreja de Van Gogh ofrecer\u00e1 el pr\u00f3ximo 26 de marzo un &quot;concierto \u00edntimo&quot; en Panam\u00e1 para presentar su \u00faltima producci\u00f3n discogr\u00e1fica, &quot;Primera Fila&quot;, informaron hoy los organizadores. El espect\u00e1culo se llevar\u00e1 a cabo en la sala de conciertos Latitude 47, en la capital paname\u00f1a,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Oreja de Van Gogh presentar\u00e1 un \u00abconcierto \u00edntimo\u00bb en Panam\u00e1 | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Panam\u00e1, 4 feb (EFE).- El grupo de m\u00fasica pop espa\u00f1ol La Oreja de Van Gogh ofrecer\u00e1 el pr\u00f3ximo 26 de marzo un &quot;concierto \u00edntimo&quot; en Panam\u00e1 para presentar su \u00faltima producci\u00f3n discogr\u00e1fica, &quot;Primera Fila&quot;, informaron hoy los organizadores. El espect\u00e1culo se llevar\u00e1 a cabo en la sala de conciertos Latitude 47, en la capital paname\u00f1a,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5910441w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5910441w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-05T03:30:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-05T03:30:07+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Oreja de Van Gogh presentar\u00e1 un \u00abconcierto \u00edntimo\u00bb en Panam\u00e1 | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Panam\u00e1, 4 feb (EFE).- El grupo de m\u00fasica pop espa\u00f1ol La Oreja de Van Gogh ofrecer\u00e1 el pr\u00f3ximo 26 de marzo un &quot;concierto \u00edntimo&quot; en Panam\u00e1 para presentar su \u00faltima producci\u00f3n discogr\u00e1fica, &quot;Primera Fila&quot;, informaron hoy los organizadores. El espect\u00e1culo se llevar\u00e1 a cabo en la sala de conciertos Latitude 47, en la capital paname\u00f1a,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5910441w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\\\/#article\",\"name\":\"La Oreja de Van Gogh presentar\\u00e1 un \\u00abconcierto \\u00edntimo\\u00bb en Panam\\u00e1 | El Digital de Asturias\",\"headline\":\"La Oreja de Van Gogh presentar\\u00e1 un \\u00abconcierto \\u00edntimo\\u00bb en Panam\\u00e1\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5910441w.jpg\",\"width\":800,\"height\":506},\"datePublished\":\"2014-02-05T02:30:07+01:00\",\"dateModified\":\"2014-02-05T02:30:07+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\\\/#listItem\",\"name\":\"La Oreja de Van Gogh presentar\\u00e1 un \\u00abconcierto \\u00edntimo\\u00bb en Panam\\u00e1\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\\\/#listItem\",\"position\":3,\"name\":\"La Oreja de Van Gogh presentar\\u00e1 un \\u00abconcierto \\u00edntimo\\u00bb en Panam\\u00e1\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\\\/\",\"name\":\"La Oreja de Van Gogh presentar\\u00e1 un \\u00abconcierto \\u00edntimo\\u00bb en Panam\\u00e1 | El Digital de Asturias\",\"description\":\"Panam\\u00e1, 4 feb (EFE).- El grupo de m\\u00fasica pop espa\\u00f1ol La Oreja de Van Gogh ofrecer\\u00e1 el pr\\u00f3ximo 26 de marzo un \\\"concierto \\u00edntimo\\\" en Panam\\u00e1 para presentar su \\u00faltima producci\\u00f3n discogr\\u00e1fica, \\\"Primera Fila\\\", informaron hoy los organizadores. El espect\\u00e1culo se llevar\\u00e1 a cabo en la sala de conciertos Latitude 47, en la capital paname\\u00f1a,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5910441w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\\\/#mainImage\",\"width\":800,\"height\":506},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\\\/#mainImage\"},\"datePublished\":\"2014-02-05T02:30:07+01:00\",\"dateModified\":\"2014-02-05T02:30:07+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La Oreja de Van Gogh presentar\u00e1 un \u00abconcierto \u00edntimo\u00bb en Panam\u00e1 | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"La Oreja de Van Gogh presentar\u00e1 un \u00abconcierto \u00edntimo\u00bb en Panam\u00e1 | El Digital de Asturias","description":"Panam\u00e1, 4 feb (EFE).- El grupo de m\u00fasica pop espa\u00f1ol La Oreja de Van Gogh ofrecer\u00e1 el pr\u00f3ximo 26 de marzo un \"concierto \u00edntimo\" en Panam\u00e1 para presentar su \u00faltima producci\u00f3n discogr\u00e1fica, \"Primera Fila\", informaron hoy los organizadores. El espect\u00e1culo se llevar\u00e1 a cabo en la sala de conciertos Latitude 47, en la capital paname\u00f1a,","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/#article","name":"La Oreja de Van Gogh presentar\u00e1 un \u00abconcierto \u00edntimo\u00bb en Panam\u00e1 | El Digital de Asturias","headline":"La Oreja de Van Gogh presentar\u00e1 un \u00abconcierto \u00edntimo\u00bb en Panam\u00e1","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5910441w.jpg","width":800,"height":506},"datePublished":"2014-02-05T02:30:07+01:00","dateModified":"2014-02-05T02:30:07+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/#listItem","name":"La Oreja de Van Gogh presentar\u00e1 un \u00abconcierto \u00edntimo\u00bb en Panam\u00e1"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/#listItem","position":3,"name":"La Oreja de Van Gogh presentar\u00e1 un \u00abconcierto \u00edntimo\u00bb en Panam\u00e1","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/","name":"La Oreja de Van Gogh presentar\u00e1 un \u00abconcierto \u00edntimo\u00bb en Panam\u00e1 | El Digital de Asturias","description":"Panam\u00e1, 4 feb (EFE).- El grupo de m\u00fasica pop espa\u00f1ol La Oreja de Van Gogh ofrecer\u00e1 el pr\u00f3ximo 26 de marzo un \"concierto \u00edntimo\" en Panam\u00e1 para presentar su \u00faltima producci\u00f3n discogr\u00e1fica, \"Primera Fila\", informaron hoy los organizadores. El espect\u00e1culo se llevar\u00e1 a cabo en la sala de conciertos Latitude 47, en la capital paname\u00f1a,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5910441w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/#mainImage","width":800,"height":506},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/#mainImage"},"datePublished":"2014-02-05T02:30:07+01:00","dateModified":"2014-02-05T02:30:07+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"La Oreja de Van Gogh presentar\u00e1 un \u00abconcierto \u00edntimo\u00bb en Panam\u00e1 | El Digital de Asturias","og:description":"Panam\u00e1, 4 feb (EFE).- El grupo de m\u00fasica pop espa\u00f1ol La Oreja de Van Gogh ofrecer\u00e1 el pr\u00f3ximo 26 de marzo un &quot;concierto \u00edntimo&quot; en Panam\u00e1 para presentar su \u00faltima producci\u00f3n discogr\u00e1fica, &quot;Primera Fila&quot;, informaron hoy los organizadores. El espect\u00e1culo se llevar\u00e1 a cabo en la sala de conciertos Latitude 47, en la capital paname\u00f1a,","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5910441w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5910441w.jpg","og:image:width":800,"og:image:height":506,"article:published_time":"2014-02-05T03:30:07+00:00","article:modified_time":"2014-02-05T03:30:07+00:00","twitter:card":"summary_large_image","twitter:title":"La Oreja de Van Gogh presentar\u00e1 un \u00abconcierto \u00edntimo\u00bb en Panam\u00e1 | El Digital de Asturias","twitter:description":"Panam\u00e1, 4 feb (EFE).- El grupo de m\u00fasica pop espa\u00f1ol La Oreja de Van Gogh ofrecer\u00e1 el pr\u00f3ximo 26 de marzo un &quot;concierto \u00edntimo&quot; en Panam\u00e1 para presentar su \u00faltima producci\u00f3n discogr\u00e1fica, &quot;Primera Fila&quot;, informaron hoy los organizadores. El espect\u00e1culo se llevar\u00e1 a cabo en la sala de conciertos Latitude 47, en la capital paname\u00f1a,","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5910441w.jpg"},"aioseo_meta_data":{"post_id":"2953","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 08:55:00","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:46:22","updated":"2026-05-15 08:55:00"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/\" title=\"La Oreja de Van Gogh presentar\u00e1 un \u00abconcierto \u00edntimo\u00bb en Panam\u00e1\">La Oreja de Van Gogh presentar\u00e1 un \u00abconcierto \u00edntimo\u00bb en Panam\u00e1<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"La Oreja de Van Gogh presentar\u00e1 un \u00abconcierto \u00edntimo\u00bb en Panam\u00e1","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-oreja-de-van-gogh-presentara-un-concierto-intimo-en-panama\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/2953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=2953"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/2953\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/2954"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=2953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=2953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=2953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}