{"id":29113,"date":"2014-10-30T15:52:17","date_gmt":"2014-10-30T17:52:17","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=29113"},"modified":"2014-10-30T15:52:17","modified_gmt":"2014-10-30T17:52:17","slug":"el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/","title":{"rendered":"El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\u00e1s"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-29114\" alt=\"6949823w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6949823w-360x239.jpg\" width=\"360\" height=\"239\" \/>Madrid, 30 oct (EFE).- El empleo en las actividades tur\u00edsticas creci\u00f3 un 6,1 % en el tercer trimestre de 2014, hasta casi 2,4 millones de trabajadores, 135.274 m\u00e1s que un a\u00f1o antes, con lo que los ocupados de este sector representan el 13,5 % del total de la econom\u00eda espa\u00f1ola, pero sigue aumentando la tasa de temporalidad.<\/p>\n<p>Las actividades tur\u00edsticas dispon\u00edan en el per\u00edodo de julio a septiembre de m\u00e1s de 2,7 millones de trabajadores en activo (un 4,4 % m\u00e1s), de los que 383.275 fueron parados, lo que supone un ratio del 14 %, 1,4 puntos porcentuales por debajo del 15,4 % del mismo per\u00edodo del a\u00f1o anterior.<\/p>\n<p>El porcentaje de parados sobre activos del sector tur\u00edstico fue as\u00ed inferior en casi 10 puntos al de la econom\u00eda en general, que se situ\u00f3 en el tercer trimestre del a\u00f1o en el 23,7 %, frente al 25,7 % en los mismos meses del ejercicio precedente.<\/p>\n<p>Los desempleados en turismo se redujeron por cuarto trimestre consecutivo, registr\u00e1ndose 20.009 parados menos que un a\u00f1o antes, seg\u00fan se desprende de los datos de la Encuesta de Poblaci\u00f3n Activa (EPA), difundidos hoy por el Ministerio de Industria, Energ\u00eda y Turismo.<\/p>\n<p>El n\u00famero de ocupados en el sector tur\u00edstico aument\u00f3 tanto entre los asalariados como entre los aut\u00f3nomos, con repuntes del 5,5 % y del 8,2 %, respectivamente.<\/p>\n<p>Entre las seis comunidades aut\u00f3nomas con mayor volumen de empleo en las actividades tur\u00edsticas, los ocupados crecieron en cuatro de ellas, destacando Catalu\u00f1a, con un incremento interanual del 12,3 %, seguida de la Comunidad Valenciana (un 10,2 %), Andaluc\u00eda (un 9,1 %) y la de Madrid (un 1,6 %).<\/p>\n<p>En cambio, Baleares y Canarias experimentaron descensos en el n\u00famero de ocupados en turismo del 3,4 % y del 0,7 %, respectivamente, mientras que, en el conjunto del resto de comunidades, el empleo creci\u00f3 un 5,9 %.<\/p>\n<p>La tasa de temporalidad -proporci\u00f3n de asalariados con contrato temporal sobre el total de asalariados- sigui\u00f3 aumentando, hasta alcanzar el 38,2 %, frente al 37,6 % del mismo periodo del a\u00f1o anterior, debido al mayor crecimiento de los asalariados con contrato temporal (un 7,3 %) frente al de los indefinidos (un 4,4 %), cuyo volumen se incrementa por tercer trimestre consecutivo.<\/p>\n<p>El empleo temporal subi\u00f3 en todas las ramas del turismo, salvo en el transporte de viajeros, donde descendi\u00f3 un 7 %, siendo adem\u00e1s el segmento que menos tasa de temporalidad registra, con un 18,8 %. La tasa de temporalidad en el total de la econom\u00eda nacional fue muy inferior a la del turismo, al situarse en el 24,6 %.<\/p>\n<p>Los asalariados con jornada laboral a tiempo parcial en turismo (un 25,2 % del total) aumentaron en el tercer trimestre un 5,2 %, lo que supone un ritmo de crecimiento similar a aquellos contratados a tiempo completo, con un repunte del 5,6 %.<\/p>\n<p>Por ramas de actividad, se produjeron incrementos en todas, destacando los crecimientos registrados en otras actividades tur\u00edsticas (del 8,9 %), en los servicios de comida y bebida (un 6,9 %) y en hosteler\u00eda (un 5,9 %).<\/p>\n<p>En cuanto a los ocupados extranjeros en el sector tur\u00edstico, disminuyeron un 1,1 %, con 4.667 trabajadores menos, con lo que representan un 17,9 % del empleo total en turismo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 30 oct (EFE).- El empleo en las actividades tur\u00edsticas creci\u00f3 un 6,1 % en el tercer trimestre de 2014, hasta casi 2,4 millones de trabajadores, 135.274 m\u00e1s que un a\u00f1o antes, con lo que los ocupados de este sector representan el 13,5 % del total de la econom\u00eda espa\u00f1ola, pero sigue aumentando la tasa<\/p>\n","protected":false},"author":1,"featured_media":29114,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-29113","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 30 oct (EFE).- El empleo en las actividades tur\u00edsticas creci\u00f3 un 6,1 % en el tercer trimestre de 2014, hasta casi 2,4 millones de trabajadores, 135.274 m\u00e1s que un a\u00f1o antes, con lo que los ocupados de este sector representan el 13,5 % del total de la econom\u00eda espa\u00f1ola, pero sigue aumentando la tasa\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\u00e1s | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 30 oct (EFE).- El empleo en las actividades tur\u00edsticas creci\u00f3 un 6,1 % en el tercer trimestre de 2014, hasta casi 2,4 millones de trabajadores, 135.274 m\u00e1s que un a\u00f1o antes, con lo que los ocupados de este sector representan el 13,5 % del total de la econom\u00eda espa\u00f1ola, pero sigue aumentando la tasa\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6949823w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6949823w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-10-30T17:52:17+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-10-30T17:52:17+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\u00e1s | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 30 oct (EFE).- El empleo en las actividades tur\u00edsticas creci\u00f3 un 6,1 % en el tercer trimestre de 2014, hasta casi 2,4 millones de trabajadores, 135.274 m\u00e1s que un a\u00f1o antes, con lo que los ocupados de este sector representan el 13,5 % del total de la econom\u00eda espa\u00f1ola, pero sigue aumentando la tasa\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6949823w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\\\/#article\",\"name\":\"El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\\u00e1s | El Digital de Asturias\",\"headline\":\"El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\\u00e1s\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/6949823w.jpg\",\"width\":800,\"height\":533},\"datePublished\":\"2014-10-30T15:52:17+01:00\",\"dateModified\":\"2014-10-30T15:52:17+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\\\/#listItem\",\"name\":\"El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\\u00e1s\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\\\/#listItem\",\"position\":3,\"name\":\"El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\\u00e1s\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\\\/\",\"name\":\"El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\\u00e1s | El Digital de Asturias\",\"description\":\"Madrid, 30 oct (EFE).- El empleo en las actividades tur\\u00edsticas creci\\u00f3 un 6,1 % en el tercer trimestre de 2014, hasta casi 2,4 millones de trabajadores, 135.274 m\\u00e1s que un a\\u00f1o antes, con lo que los ocupados de este sector representan el 13,5 % del total de la econom\\u00eda espa\\u00f1ola, pero sigue aumentando la tasa\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/6949823w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\\\/#mainImage\",\"width\":800,\"height\":533},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\\\/#mainImage\"},\"datePublished\":\"2014-10-30T15:52:17+01:00\",\"dateModified\":\"2014-10-30T15:52:17+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\u00e1s | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\u00e1s | El Digital de Asturias","description":"Madrid, 30 oct (EFE).- El empleo en las actividades tur\u00edsticas creci\u00f3 un 6,1 % en el tercer trimestre de 2014, hasta casi 2,4 millones de trabajadores, 135.274 m\u00e1s que un a\u00f1o antes, con lo que los ocupados de este sector representan el 13,5 % del total de la econom\u00eda espa\u00f1ola, pero sigue aumentando la tasa","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/#article","name":"El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\u00e1s | El Digital de Asturias","headline":"El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\u00e1s","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6949823w.jpg","width":800,"height":533},"datePublished":"2014-10-30T15:52:17+01:00","dateModified":"2014-10-30T15:52:17+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/#listItem","name":"El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\u00e1s"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/#listItem","position":3,"name":"El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\u00e1s","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/","name":"El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\u00e1s | El Digital de Asturias","description":"Madrid, 30 oct (EFE).- El empleo en las actividades tur\u00edsticas creci\u00f3 un 6,1 % en el tercer trimestre de 2014, hasta casi 2,4 millones de trabajadores, 135.274 m\u00e1s que un a\u00f1o antes, con lo que los ocupados de este sector representan el 13,5 % del total de la econom\u00eda espa\u00f1ola, pero sigue aumentando la tasa","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6949823w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/#mainImage","width":800,"height":533},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/#mainImage"},"datePublished":"2014-10-30T15:52:17+01:00","dateModified":"2014-10-30T15:52:17+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\u00e1s | El Digital de Asturias","og:description":"Madrid, 30 oct (EFE).- El empleo en las actividades tur\u00edsticas creci\u00f3 un 6,1 % en el tercer trimestre de 2014, hasta casi 2,4 millones de trabajadores, 135.274 m\u00e1s que un a\u00f1o antes, con lo que los ocupados de este sector representan el 13,5 % del total de la econom\u00eda espa\u00f1ola, pero sigue aumentando la tasa","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6949823w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6949823w.jpg","og:image:width":800,"og:image:height":533,"article:published_time":"2014-10-30T17:52:17+00:00","article:modified_time":"2014-10-30T17:52:17+00:00","twitter:card":"summary_large_image","twitter:title":"El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\u00e1s | El Digital de Asturias","twitter:description":"Madrid, 30 oct (EFE).- El empleo en las actividades tur\u00edsticas creci\u00f3 un 6,1 % en el tercer trimestre de 2014, hasta casi 2,4 millones de trabajadores, 135.274 m\u00e1s que un a\u00f1o antes, con lo que los ocupados de este sector representan el 13,5 % del total de la econom\u00eda espa\u00f1ola, pero sigue aumentando la tasa","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6949823w.jpg"},"aioseo_meta_data":{"post_id":"29113","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-17 18:20:37","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 04:56:45","updated":"2026-05-17 18:20:37"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/\" title=\"El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\u00e1s\">El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\u00e1s<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"El empleo en turismo sube un 6,1 % hasta septiembre, con 135.274 personas m\u00e1s","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-empleo-en-turismo-sube-un-61-hasta-septiembre-con-135-274-personas-mas\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/29113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=29113"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/29113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/29114"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=29113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=29113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=29113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}