{"id":2898,"date":"2014-02-04T23:16:15","date_gmt":"2014-02-05T00:16:15","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=2898"},"modified":"2014-02-04T23:21:12","modified_gmt":"2014-02-05T00:21:12","slug":"ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/","title":{"rendered":"Ricky Martin lanza una aplicaci\u00f3n para verle en concierto de forma personalizada"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-2899\" alt=\"5909802w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5909802w-360x239.jpg\" width=\"360\" height=\"239\" \/>Miami (EE.UU.), 4 feb (EFE).- Ricky Martin lanz\u00f3 hoy una aplicaci\u00f3n que permitir\u00e1 a los seguidores del cantante puertorrique\u00f1o verle en concierto de forma personalizada a trav\u00e9s de plataformas m\u00f3viles.<\/p>\n<p>\u00abDurante mi reciente gira por Australia, no par\u00e9 de recibir mensajes de personas de todo el mundo que deseaban poder estar en el concierto y ser parte de la gira\u00bb, dijo Martin en un comunicado divulgado hoy por su discogr\u00e1fica, Sony Music.<\/p>\n<p>Por ello, para el lanzamiento de este dispositivo, denominado \u00abRicky Martin Concert 4U\u00bb, la empresa de tecnolog\u00eda 3D-4U aprovech\u00f3 el concierto realizado por el boricua en Australia.<\/p>\n<p>A trav\u00e9s de esta aplicaci\u00f3n, los usuarios pueden controlar qu\u00e9 quieren ver del concierto de Martin, la vista que prefieren y si la desean en dos o tres dimensiones, gracias a una gran cantidad de panor\u00e1micas que se han escogido de las canciones que fueron seleccionadas.<\/p>\n<p>\u00abEs un gran placer y un honor lanzar nuestro primer producto de consumo masivo, en asociaci\u00f3n con una superestrella como Ricky Martin y el gigante visionario de los medios Sony Music Estados Unidos\u00bb, dijo Jay Jayaram, presidente de 3D-4U.<\/p>\n<p>Ricky Martin ha vendido m\u00e1s de 70 millones de copias de sus discos, por los que ha recibido alrededor de 95 discos de platino en m\u00e1s de 20 pa\u00edses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miami (EE.UU.), 4 feb (EFE).- Ricky Martin lanz\u00f3 hoy una aplicaci\u00f3n que permitir\u00e1 a los seguidores del cantante puertorrique\u00f1o verle en concierto de forma personalizada a trav\u00e9s de plataformas m\u00f3viles. \u00abDurante mi reciente gira por Australia, no par\u00e9 de recibir mensajes de personas de todo el mundo que deseaban poder estar en el concierto y<\/p>\n","protected":false},"author":1,"featured_media":2899,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-2898","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Miami (EE.UU.), 4 feb (EFE).- Ricky Martin lanz\u00f3 hoy una aplicaci\u00f3n que permitir\u00e1 a los seguidores del cantante puertorrique\u00f1o verle en concierto de forma personalizada a trav\u00e9s de plataformas m\u00f3viles. &quot;Durante mi reciente gira por Australia, no par\u00e9 de recibir mensajes de personas de todo el mundo que deseaban poder estar en el concierto y\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ricky Martin lanza una aplicaci\u00f3n para verle en concierto de forma personalizada | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Miami (EE.UU.), 4 feb (EFE).- Ricky Martin lanz\u00f3 hoy una aplicaci\u00f3n que permitir\u00e1 a los seguidores del cantante puertorrique\u00f1o verle en concierto de forma personalizada a trav\u00e9s de plataformas m\u00f3viles. &quot;Durante mi reciente gira por Australia, no par\u00e9 de recibir mensajes de personas de todo el mundo que deseaban poder estar en el concierto y\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5909802w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5909802w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-05T00:16:15+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-05T00:21:12+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ricky Martin lanza una aplicaci\u00f3n para verle en concierto de forma personalizada | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Miami (EE.UU.), 4 feb (EFE).- Ricky Martin lanz\u00f3 hoy una aplicaci\u00f3n que permitir\u00e1 a los seguidores del cantante puertorrique\u00f1o verle en concierto de forma personalizada a trav\u00e9s de plataformas m\u00f3viles. &quot;Durante mi reciente gira por Australia, no par\u00e9 de recibir mensajes de personas de todo el mundo que deseaban poder estar en el concierto y\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5909802w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\\\/#article\",\"name\":\"Ricky Martin lanza una aplicaci\\u00f3n para verle en concierto de forma personalizada | El Digital de Asturias\",\"headline\":\"Ricky Martin lanza una aplicaci\\u00f3n para verle en concierto de forma personalizada\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5909802w.jpg\",\"width\":800,\"height\":533},\"datePublished\":\"2014-02-04T23:16:15+01:00\",\"dateModified\":\"2014-02-04T23:21:12+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\\\/#listItem\",\"name\":\"Ricky Martin lanza una aplicaci\\u00f3n para verle en concierto de forma personalizada\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\\\/#listItem\",\"position\":3,\"name\":\"Ricky Martin lanza una aplicaci\\u00f3n para verle en concierto de forma personalizada\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\\\/\",\"name\":\"Ricky Martin lanza una aplicaci\\u00f3n para verle en concierto de forma personalizada | El Digital de Asturias\",\"description\":\"Miami (EE.UU.), 4 feb (EFE).- Ricky Martin lanz\\u00f3 hoy una aplicaci\\u00f3n que permitir\\u00e1 a los seguidores del cantante puertorrique\\u00f1o verle en concierto de forma personalizada a trav\\u00e9s de plataformas m\\u00f3viles. \\\"Durante mi reciente gira por Australia, no par\\u00e9 de recibir mensajes de personas de todo el mundo que deseaban poder estar en el concierto y\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5909802w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\\\/#mainImage\",\"width\":800,\"height\":533},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\\\/#mainImage\"},\"datePublished\":\"2014-02-04T23:16:15+01:00\",\"dateModified\":\"2014-02-04T23:21:12+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Ricky Martin lanza una aplicaci\u00f3n para verle en concierto de forma personalizada | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Ricky Martin lanza una aplicaci\u00f3n para verle en concierto de forma personalizada | El Digital de Asturias","description":"Miami (EE.UU.), 4 feb (EFE).- Ricky Martin lanz\u00f3 hoy una aplicaci\u00f3n que permitir\u00e1 a los seguidores del cantante puertorrique\u00f1o verle en concierto de forma personalizada a trav\u00e9s de plataformas m\u00f3viles. \"Durante mi reciente gira por Australia, no par\u00e9 de recibir mensajes de personas de todo el mundo que deseaban poder estar en el concierto y","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/#article","name":"Ricky Martin lanza una aplicaci\u00f3n para verle en concierto de forma personalizada | El Digital de Asturias","headline":"Ricky Martin lanza una aplicaci\u00f3n para verle en concierto de forma personalizada","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5909802w.jpg","width":800,"height":533},"datePublished":"2014-02-04T23:16:15+01:00","dateModified":"2014-02-04T23:21:12+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/#listItem","name":"Ricky Martin lanza una aplicaci\u00f3n para verle en concierto de forma personalizada"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/#listItem","position":3,"name":"Ricky Martin lanza una aplicaci\u00f3n para verle en concierto de forma personalizada","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/","name":"Ricky Martin lanza una aplicaci\u00f3n para verle en concierto de forma personalizada | El Digital de Asturias","description":"Miami (EE.UU.), 4 feb (EFE).- Ricky Martin lanz\u00f3 hoy una aplicaci\u00f3n que permitir\u00e1 a los seguidores del cantante puertorrique\u00f1o verle en concierto de forma personalizada a trav\u00e9s de plataformas m\u00f3viles. \"Durante mi reciente gira por Australia, no par\u00e9 de recibir mensajes de personas de todo el mundo que deseaban poder estar en el concierto y","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5909802w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/#mainImage","width":800,"height":533},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/#mainImage"},"datePublished":"2014-02-04T23:16:15+01:00","dateModified":"2014-02-04T23:21:12+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Ricky Martin lanza una aplicaci\u00f3n para verle en concierto de forma personalizada | El Digital de Asturias","og:description":"Miami (EE.UU.), 4 feb (EFE).- Ricky Martin lanz\u00f3 hoy una aplicaci\u00f3n que permitir\u00e1 a los seguidores del cantante puertorrique\u00f1o verle en concierto de forma personalizada a trav\u00e9s de plataformas m\u00f3viles. &quot;Durante mi reciente gira por Australia, no par\u00e9 de recibir mensajes de personas de todo el mundo que deseaban poder estar en el concierto y","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5909802w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5909802w.jpg","og:image:width":800,"og:image:height":533,"article:published_time":"2014-02-05T00:16:15+00:00","article:modified_time":"2014-02-05T00:21:12+00:00","twitter:card":"summary_large_image","twitter:title":"Ricky Martin lanza una aplicaci\u00f3n para verle en concierto de forma personalizada | El Digital de Asturias","twitter:description":"Miami (EE.UU.), 4 feb (EFE).- Ricky Martin lanz\u00f3 hoy una aplicaci\u00f3n que permitir\u00e1 a los seguidores del cantante puertorrique\u00f1o verle en concierto de forma personalizada a trav\u00e9s de plataformas m\u00f3viles. &quot;Durante mi reciente gira por Australia, no par\u00e9 de recibir mensajes de personas de todo el mundo que deseaban poder estar en el concierto y","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5909802w.jpg"},"aioseo_meta_data":{"post_id":"2898","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 08:48:28","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:44:58","updated":"2026-05-15 08:48:28"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/\" title=\"Ricky Martin lanza una aplicaci\u00f3n para verle en concierto de forma personalizada\">Ricky Martin lanza una aplicaci\u00f3n para verle en concierto de forma personalizada<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Ricky Martin lanza una aplicaci\u00f3n para verle en concierto de forma personalizada","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/ricky-martin-lanza-una-aplicacion-para-verle-en-concierto-de-forma-personalizada\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/2898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=2898"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/2898\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/2899"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=2898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=2898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=2898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}