{"id":27629,"date":"2014-10-17T19:05:42","date_gmt":"2014-10-17T21:05:42","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=27629"},"modified":"2014-10-17T19:05:42","modified_gmt":"2014-10-17T21:05:42","slug":"patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/","title":{"rendered":"Patagonia se alza como destino tur\u00edstico predilecto en medios internacionales"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-27630\" alt=\"6759323w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6759323w-360x238.jpg\" width=\"360\" height=\"238\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6759323w-360x238.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6759323w-650x430.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6759323w-768x508.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6759323w-150x99.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6759323w-450x298.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6759323w-696x460.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6759323w-635x420.jpg 635w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6759323w-84x55.jpg 84w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6759323w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Santiago de Chile, 17 oct (EFE).- La prensa internacional posiciona a la Patagonia (en el extremo sur de Chile y Argentina) como uno de los principales destinos tur\u00edsticos de Suram\u00e9rica, incluso por encima de Machu Piccchu y las Islas Gal\u00e1pagos, seg\u00fan un estudio publicado hoy en Santiago.<\/p>\n<p>De acuerdo con el informe, elaborado por la Fundaci\u00f3n Imagen de Chile, el sur y el extremo sur del pa\u00eds austral encabezan la lista de los destinos predilectos de los medios internacionales, al concentrar un 51 % de las publicaciones analizadas entre un total de 207 medios extranjeros.<\/p>\n<p>Lugares como la Patagonia, Tierra del Fuego y Chilo\u00e9 son los escogidos por la prensa internacional por \u00absu naturaleza \u00fanica que incluso evoca al para\u00edso\u00bb, destaca el informe.<\/p>\n<p>Asimismo, la publicaci\u00f3n enfatiza la reiterada aparici\u00f3n de adjetivos y conceptos diversos como \u00abaventura\u00bb, \u00abmaravilla\u00bb y \u00abm\u00e1gico\u00bb, al retratar las caracter\u00edsticas que ofrece esa regi\u00f3n como destino atractivo.<\/p>\n<p>Al respeto, la directora Ejecutiva de la Fundaci\u00f3n Imagen de Chile, Myriam G\u00f3mez, se\u00f1al\u00f3 que es \u00abun pa\u00eds privilegiado como destino tur\u00edstico, con gran diversidad, contrastes de climas y tipos de experiencias tur\u00edsticas\u00bb.<\/p>\n<p>Y a\u00f1adi\u00f3 que una imagen potente pone al pa\u00eds \u00aben vitrina para atraer no s\u00f3lo turistas sino inversiones en ese \u00e1mbito\u00bb, por lo que el Gobierno debe \u00abhacer esfuerzos por visibilizar\u00bb esos \u00abatributos\u00bb.<\/p>\n<p>Las publicaciones internacionales no s\u00f3lo se refieren a las bellezas naturales que ofrece el pa\u00eds a sus visitantes, sino que tambi\u00e9n aluden, en muchos casos, a las actividades que se pueden realizar.<\/p>\n<p>As\u00ed, el excursionismo o trekking destaca como la actividad m\u00e1s recurrente en la cobertura period\u00edstica y concentra un 25 % de las publicaciones internacionales, seguido de las cabalgatas (19 %), el esqu\u00ed (13 %) y el rafting (9 %).<\/p>\n<p>El informe, titulado \u00abTurismo Chileno en la prensa internacional\u00bb analiz\u00f3 un total de 207 medios extranjeros, tanto prensa de car\u00e1cter generalista, como publicaciones especializadas en turismo.<\/p>\n<p>En \u00e9l se ratifica la preeminencia de la Patagonia como destino tur\u00edstico predilecto de la prensa internacional, pues aparece en un 27 % de las publicaciones analizadas, mientras el sur chileno suma un 24 % de las mismas.<\/p>\n<p>En el primer lugar, en todo caso, figura la Amazon\u00eda (30 %), en tanto m\u00e1s atr\u00e1s figuran Machu Picchu (15 %), Islas Gal\u00e1pagos (4 %), Titicaca (3 %) y las Cataratas de Iguaz\u00fa (2 %).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santiago de Chile, 17 oct (EFE).- La prensa internacional posiciona a la Patagonia (en el extremo sur de Chile y Argentina) como uno de los principales destinos tur\u00edsticos de Suram\u00e9rica, incluso por encima de Machu Piccchu y las Islas Gal\u00e1pagos, seg\u00fan un estudio publicado hoy en Santiago. De acuerdo con el informe, elaborado por la<\/p>\n","protected":false},"author":1,"featured_media":27630,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-27629","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Santiago de Chile, 17 oct (EFE).- La prensa internacional posiciona a la Patagonia (en el extremo sur de Chile y Argentina) como uno de los principales destinos tur\u00edsticos de Suram\u00e9rica, incluso por encima de Machu Piccchu y las Islas Gal\u00e1pagos, seg\u00fan un estudio publicado hoy en Santiago. De acuerdo con el informe, elaborado por la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Patagonia se alza como destino tur\u00edstico predilecto en medios internacionales | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Santiago de Chile, 17 oct (EFE).- La prensa internacional posiciona a la Patagonia (en el extremo sur de Chile y Argentina) como uno de los principales destinos tur\u00edsticos de Suram\u00e9rica, incluso por encima de Machu Piccchu y las Islas Gal\u00e1pagos, seg\u00fan un estudio publicado hoy en Santiago. De acuerdo con el informe, elaborado por la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6759323w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6759323w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"529\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-10-17T21:05:42+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-10-17T21:05:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Patagonia se alza como destino tur\u00edstico predilecto en medios internacionales | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Santiago de Chile, 17 oct (EFE).- La prensa internacional posiciona a la Patagonia (en el extremo sur de Chile y Argentina) como uno de los principales destinos tur\u00edsticos de Suram\u00e9rica, incluso por encima de Machu Piccchu y las Islas Gal\u00e1pagos, seg\u00fan un estudio publicado hoy en Santiago. De acuerdo con el informe, elaborado por la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6759323w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\\\/#article\",\"name\":\"Patagonia se alza como destino tur\\u00edstico predilecto en medios internacionales | El Digital de Asturias\",\"headline\":\"Patagonia se alza como destino tur\\u00edstico predilecto en medios internacionales\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/6759323w.jpg\",\"width\":800,\"height\":529},\"datePublished\":\"2014-10-17T19:05:42+02:00\",\"dateModified\":\"2014-10-17T19:05:42+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\\\/#listItem\",\"name\":\"Patagonia se alza como destino tur\\u00edstico predilecto en medios internacionales\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\\\/#listItem\",\"position\":3,\"name\":\"Patagonia se alza como destino tur\\u00edstico predilecto en medios internacionales\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\\\/\",\"name\":\"Patagonia se alza como destino tur\\u00edstico predilecto en medios internacionales | El Digital de Asturias\",\"description\":\"Santiago de Chile, 17 oct (EFE).- La prensa internacional posiciona a la Patagonia (en el extremo sur de Chile y Argentina) como uno de los principales destinos tur\\u00edsticos de Suram\\u00e9rica, incluso por encima de Machu Piccchu y las Islas Gal\\u00e1pagos, seg\\u00fan un estudio publicado hoy en Santiago. De acuerdo con el informe, elaborado por la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/6759323w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\\\/#mainImage\",\"width\":800,\"height\":529},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\\\/#mainImage\"},\"datePublished\":\"2014-10-17T19:05:42+02:00\",\"dateModified\":\"2014-10-17T19:05:42+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Patagonia se alza como destino tur\u00edstico predilecto en medios internacionales | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Patagonia se alza como destino tur\u00edstico predilecto en medios internacionales | El Digital de Asturias","description":"Santiago de Chile, 17 oct (EFE).- La prensa internacional posiciona a la Patagonia (en el extremo sur de Chile y Argentina) como uno de los principales destinos tur\u00edsticos de Suram\u00e9rica, incluso por encima de Machu Piccchu y las Islas Gal\u00e1pagos, seg\u00fan un estudio publicado hoy en Santiago. De acuerdo con el informe, elaborado por la","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/#article","name":"Patagonia se alza como destino tur\u00edstico predilecto en medios internacionales | El Digital de Asturias","headline":"Patagonia se alza como destino tur\u00edstico predilecto en medios internacionales","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6759323w.jpg","width":800,"height":529},"datePublished":"2014-10-17T19:05:42+02:00","dateModified":"2014-10-17T19:05:42+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/#listItem","name":"Patagonia se alza como destino tur\u00edstico predilecto en medios internacionales"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/#listItem","position":3,"name":"Patagonia se alza como destino tur\u00edstico predilecto en medios internacionales","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/","name":"Patagonia se alza como destino tur\u00edstico predilecto en medios internacionales | El Digital de Asturias","description":"Santiago de Chile, 17 oct (EFE).- La prensa internacional posiciona a la Patagonia (en el extremo sur de Chile y Argentina) como uno de los principales destinos tur\u00edsticos de Suram\u00e9rica, incluso por encima de Machu Piccchu y las Islas Gal\u00e1pagos, seg\u00fan un estudio publicado hoy en Santiago. De acuerdo con el informe, elaborado por la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6759323w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/#mainImage","width":800,"height":529},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/#mainImage"},"datePublished":"2014-10-17T19:05:42+02:00","dateModified":"2014-10-17T19:05:42+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Patagonia se alza como destino tur\u00edstico predilecto en medios internacionales | El Digital de Asturias","og:description":"Santiago de Chile, 17 oct (EFE).- La prensa internacional posiciona a la Patagonia (en el extremo sur de Chile y Argentina) como uno de los principales destinos tur\u00edsticos de Suram\u00e9rica, incluso por encima de Machu Piccchu y las Islas Gal\u00e1pagos, seg\u00fan un estudio publicado hoy en Santiago. De acuerdo con el informe, elaborado por la","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6759323w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6759323w.jpg","og:image:width":800,"og:image:height":529,"article:published_time":"2014-10-17T21:05:42+00:00","article:modified_time":"2014-10-17T21:05:42+00:00","twitter:card":"summary_large_image","twitter:title":"Patagonia se alza como destino tur\u00edstico predilecto en medios internacionales | El Digital de Asturias","twitter:description":"Santiago de Chile, 17 oct (EFE).- La prensa internacional posiciona a la Patagonia (en el extremo sur de Chile y Argentina) como uno de los principales destinos tur\u00edsticos de Suram\u00e9rica, incluso por encima de Machu Piccchu y las Islas Gal\u00e1pagos, seg\u00fan un estudio publicado hoy en Santiago. De acuerdo con el informe, elaborado por la","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6759323w.jpg"},"aioseo_meta_data":{"post_id":"27629","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-17 15:05:38","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 05:14:52","updated":"2026-05-17 15:05:38"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/\" title=\"Patagonia se alza como destino tur\u00edstico predilecto en medios internacionales\">Patagonia se alza como destino tur\u00edstico predilecto en medios internacionales<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"Patagonia se alza como destino tur\u00edstico predilecto en medios internacionales","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/patagonia-se-alza-como-destino-turistico-predilecto-en-medios-internacionales\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/27629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=27629"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/27629\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/27630"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=27629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=27629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=27629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}