{"id":27605,"date":"2014-10-17T18:36:00","date_gmt":"2014-10-17T20:36:00","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=27605"},"modified":"2014-10-17T18:36:00","modified_gmt":"2014-10-17T20:36:00","slug":"iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/","title":{"rendered":"Iberia Express supera los 8 millones de pasajeros en dos a\u00f1os y medio de actividad"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-27606\" alt=\"6757945w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6757945w-360x224.jpg\" width=\"360\" height=\"224\" \/>Madrid, 17 oct (EFE).- Iberia Express ha superado ocho millones de pasajeros transportados desde el inicio de sus operaciones hace dos a\u00f1os y medio, en marzo de 2012, ha informado hoy la filial de bajo coste de Iberia en un comunicado.<\/p>\n<p>Desde entonces, la aerol\u00ednea ha cubierto 64.000 vuelos en las 31 rutas que ha operado desde su lanzamiento y ha sido \u00abla m\u00e1s puntual de Europa durante el primer semestre del a\u00f1o, con un 95 % de puntualidad media\u00bb.<\/p>\n<p>Durante estos dos a\u00f1os y medio, la compa\u00f1\u00eda ha operado una red compuesta por 18 rutas nacionales y 13 internacionales, ofreciendo vuelos desde Madrid a destinos espa\u00f1oles como Canarias, Galicia, Andaluc\u00eda o Baleares, y extranjeros como Copenhague, Dubl\u00edn, Estocolmo o Amsterdam.<\/p>\n<p>Entre los pa\u00edses europeos a los que Iberia Express ofrece conexiones, destaca Alemania, donde opera ya cinco destinos: Berl\u00edn, Fr\u00e1ncfort, D\u00fcsseldorf y las reci\u00e9n anunciadas Hannover y Stuttgart, lo que refleja su \u00abapuesta por el pa\u00eds germano\u00bb, ha se\u00f1alado la compa\u00f1\u00eda en su nota.<\/p>\n<p>Adem\u00e1s de operar rutas de corto y medio radio en Espa\u00f1a y Europa, Iberia Express aporta tr\u00e1fico directo y alimenta la red de largo radio de su matriz.<\/p>\n<p>La filial de Iberia es miembro de la alianza a\u00e9rea oneworld, que integra a once compa\u00f1\u00edas que ofrecen a sus pasajeros 14.000 vuelos diarios a cerca de 1.000 aeropuertos de 150 pa\u00edses.<\/p>\n<p>La compa\u00f1\u00eda opera en c\u00f3digo compartido con Iberia, LAN Airlines, Air Berlin, Japan Air Lines, American Airlines, Avianca, Finnair, British Airways, Siberia Airlines y Royal Air Maroc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 17 oct (EFE).- Iberia Express ha superado ocho millones de pasajeros transportados desde el inicio de sus operaciones hace dos a\u00f1os y medio, en marzo de 2012, ha informado hoy la filial de bajo coste de Iberia en un comunicado. Desde entonces, la aerol\u00ednea ha cubierto 64.000 vuelos en las 31 rutas que ha<\/p>\n","protected":false},"author":1,"featured_media":27606,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-27605","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 17 oct (EFE).- Iberia Express ha superado ocho millones de pasajeros transportados desde el inicio de sus operaciones hace dos a\u00f1os y medio, en marzo de 2012, ha informado hoy la filial de bajo coste de Iberia en un comunicado. Desde entonces, la aerol\u00ednea ha cubierto 64.000 vuelos en las 31 rutas que ha\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Iberia Express supera los 8 millones de pasajeros en dos a\u00f1os y medio de actividad | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 17 oct (EFE).- Iberia Express ha superado ocho millones de pasajeros transportados desde el inicio de sus operaciones hace dos a\u00f1os y medio, en marzo de 2012, ha informado hoy la filial de bajo coste de Iberia en un comunicado. Desde entonces, la aerol\u00ednea ha cubierto 64.000 vuelos en las 31 rutas que ha\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6757945w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6757945w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"499\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-10-17T20:36:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-10-17T20:36:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Iberia Express supera los 8 millones de pasajeros en dos a\u00f1os y medio de actividad | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 17 oct (EFE).- Iberia Express ha superado ocho millones de pasajeros transportados desde el inicio de sus operaciones hace dos a\u00f1os y medio, en marzo de 2012, ha informado hoy la filial de bajo coste de Iberia en un comunicado. Desde entonces, la aerol\u00ednea ha cubierto 64.000 vuelos en las 31 rutas que ha\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6757945w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\\\/#article\",\"name\":\"Iberia Express supera los 8 millones de pasajeros en dos a\\u00f1os y medio de actividad | El Digital de Asturias\",\"headline\":\"Iberia Express supera los 8 millones de pasajeros en dos a\\u00f1os y medio de actividad\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/6757945w.jpg\",\"width\":800,\"height\":499},\"datePublished\":\"2014-10-17T18:36:00+02:00\",\"dateModified\":\"2014-10-17T18:36:00+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\\\/#listItem\",\"name\":\"Iberia Express supera los 8 millones de pasajeros en dos a\\u00f1os y medio de actividad\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\\\/#listItem\",\"position\":3,\"name\":\"Iberia Express supera los 8 millones de pasajeros en dos a\\u00f1os y medio de actividad\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\\\/\",\"name\":\"Iberia Express supera los 8 millones de pasajeros en dos a\\u00f1os y medio de actividad | El Digital de Asturias\",\"description\":\"Madrid, 17 oct (EFE).- Iberia Express ha superado ocho millones de pasajeros transportados desde el inicio de sus operaciones hace dos a\\u00f1os y medio, en marzo de 2012, ha informado hoy la filial de bajo coste de Iberia en un comunicado. Desde entonces, la aerol\\u00ednea ha cubierto 64.000 vuelos en las 31 rutas que ha\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/6757945w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\\\/#mainImage\",\"width\":800,\"height\":499},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\\\/#mainImage\"},\"datePublished\":\"2014-10-17T18:36:00+02:00\",\"dateModified\":\"2014-10-17T18:36:00+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Iberia Express supera los 8 millones de pasajeros en dos a\u00f1os y medio de actividad | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Iberia Express supera los 8 millones de pasajeros en dos a\u00f1os y medio de actividad | El Digital de Asturias","description":"Madrid, 17 oct (EFE).- Iberia Express ha superado ocho millones de pasajeros transportados desde el inicio de sus operaciones hace dos a\u00f1os y medio, en marzo de 2012, ha informado hoy la filial de bajo coste de Iberia en un comunicado. Desde entonces, la aerol\u00ednea ha cubierto 64.000 vuelos en las 31 rutas que ha","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/#article","name":"Iberia Express supera los 8 millones de pasajeros en dos a\u00f1os y medio de actividad | El Digital de Asturias","headline":"Iberia Express supera los 8 millones de pasajeros en dos a\u00f1os y medio de actividad","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6757945w.jpg","width":800,"height":499},"datePublished":"2014-10-17T18:36:00+02:00","dateModified":"2014-10-17T18:36:00+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/#listItem","name":"Iberia Express supera los 8 millones de pasajeros en dos a\u00f1os y medio de actividad"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/#listItem","position":3,"name":"Iberia Express supera los 8 millones de pasajeros en dos a\u00f1os y medio de actividad","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/","name":"Iberia Express supera los 8 millones de pasajeros en dos a\u00f1os y medio de actividad | El Digital de Asturias","description":"Madrid, 17 oct (EFE).- Iberia Express ha superado ocho millones de pasajeros transportados desde el inicio de sus operaciones hace dos a\u00f1os y medio, en marzo de 2012, ha informado hoy la filial de bajo coste de Iberia en un comunicado. Desde entonces, la aerol\u00ednea ha cubierto 64.000 vuelos en las 31 rutas que ha","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6757945w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/#mainImage","width":800,"height":499},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/#mainImage"},"datePublished":"2014-10-17T18:36:00+02:00","dateModified":"2014-10-17T18:36:00+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Iberia Express supera los 8 millones de pasajeros en dos a\u00f1os y medio de actividad | El Digital de Asturias","og:description":"Madrid, 17 oct (EFE).- Iberia Express ha superado ocho millones de pasajeros transportados desde el inicio de sus operaciones hace dos a\u00f1os y medio, en marzo de 2012, ha informado hoy la filial de bajo coste de Iberia en un comunicado. Desde entonces, la aerol\u00ednea ha cubierto 64.000 vuelos en las 31 rutas que ha","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6757945w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6757945w.jpg","og:image:width":800,"og:image:height":499,"article:published_time":"2014-10-17T20:36:00+00:00","article:modified_time":"2014-10-17T20:36:00+00:00","twitter:card":"summary_large_image","twitter:title":"Iberia Express supera los 8 millones de pasajeros en dos a\u00f1os y medio de actividad | El Digital de Asturias","twitter:description":"Madrid, 17 oct (EFE).- Iberia Express ha superado ocho millones de pasajeros transportados desde el inicio de sus operaciones hace dos a\u00f1os y medio, en marzo de 2012, ha informado hoy la filial de bajo coste de Iberia en un comunicado. Desde entonces, la aerol\u00ednea ha cubierto 64.000 vuelos en las 31 rutas que ha","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6757945w.jpg"},"aioseo_meta_data":{"post_id":"27605","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-17 15:02:19","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 05:15:54","updated":"2026-05-17 15:02:19"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/\" title=\"Iberia Express supera los 8 millones de pasajeros en dos a\u00f1os y medio de actividad\">Iberia Express supera los 8 millones de pasajeros en dos a\u00f1os y medio de actividad<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"Iberia Express supera los 8 millones de pasajeros en dos a\u00f1os y medio de actividad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/iberia-express-supera-los-8-millones-de-pasajeros-en-dos-anos-y-medio-de-actividad\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/27605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=27605"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/27605\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/27606"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=27605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=27605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=27605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}