{"id":27102,"date":"2014-10-12T19:17:33","date_gmt":"2014-10-12T21:17:33","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=27102"},"modified":"2014-10-12T19:17:33","modified_gmt":"2014-10-12T21:17:33","slug":"latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/","title":{"rendered":"Latinoam\u00e9rica, fuente de inspiraci\u00f3n para las pel\u00edculas cl\u00e1sicas de Disney"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-27103\" alt=\"6726877w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6726877w-360x288.jpg\" width=\"360\" height=\"288\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6726877w-360x288.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6726877w-650x521.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6726877w-768x615.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6726877w-150x120.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6726877w-450x361.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6726877w-696x558.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6726877w-524x420.jpg 524w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6726877w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>San Francisco (EE.UU.), 12 oct (EFE).- En 1941, Walt Disney y varios artistas de su estudio hicieron una gira de dos semanas y media por Am\u00e9rica Latina, un viaje pagado por el Gobierno de EE.UU. que les sirvi\u00f3 de inspiraci\u00f3n para crear t\u00edtulos cl\u00e1sicos de la factor\u00eda como \u00abPeter Pan\u00bb y \u00abAlicia en el pa\u00eds de las maravillas\u00bb.<\/p>\n<p>Eran tiempos de la Segunda Guerra Mundial y la administraci\u00f3n del entonces presidente Franklin Roosevelt miraba con recelo la creciente influencia que Alemania y las potencias del Eje ten\u00edan en los pa\u00edses latinoamericanos, por lo que para revertir la situaci\u00f3n decidi\u00f3 enviar a su mejor embajador: el ya entonces mundialmente famoso Walt Disney.<\/p>\n<p>\u00abEl viaje por Latinoam\u00e9rica supuso una renovaci\u00f3n art\u00edstica para Walt Disney\u00bb, explic\u00f3 en una entrevista con Efe Theodore \u00abTed\u00bb Thomas, hijo del animador Frank Thomas, quien trabaj\u00f3 codo con codo con Walt Disney y particip\u00f3 en la expedici\u00f3n a Am\u00e9rica Latina.<\/p>\n<p>Adem\u00e1s, Thomas es el director del documental Walt &amp; El Grupo, que narra los detalles del viaje latinoamericano de Disney y su padre.<\/p>\n<p>Producto directo de la gira fueron dos de los t\u00edtulos menos conocidos del per\u00edodo cl\u00e1sico de Disney, \u00abSaludos Amigos\u00bb (1942) y \u00abLos tres caballeros\u00bb (1944), ambos ambientados en distintos parajes latinoamericanos como la Patagonia, los Andes, R\u00edo de Janeiro o Ciudad de M\u00e9xico y realizados por petici\u00f3n expresa del Gobierno de EE.UU.<\/p>\n<p>Sin embargo, a juicio de Thomas, la importancia de ese viaje para la factor\u00eda Disney va mucho m\u00e1s all\u00e1, y su influencia se extiende a t\u00edtulos tan ic\u00f3nicos como \u00abLa cenicienta\u00bb (1950), \u00abAlicia en el pa\u00eds de las maravillas\u00bb (1951) y \u00abPeter Pan\u00bb (1953).<\/p>\n<p>\u00abEl viaje tuvo un gran impacto sobre el propio Walt y todos los artistas que le acompa\u00f1aron, siendo quiz\u00e1s el m\u00e1s destacado el caso de Mary Blair. Durante el tiempo que pas\u00f3 en Latinoam\u00e9rica, el estilo y la paleta de colores de Blair sufrieron una gran transformaci\u00f3n, adquiriendo muchas influencias de la naturaleza y las culturas latinoamericanas\u00bb, explic\u00f3 Thomas.<\/p>\n<p>Este nuevo estilo adquirido por una de las pocas mujeres animadoras de la m\u00e1xima confianza de Disney la llev\u00f3 a ser la principal responsable del desarrollo gr\u00e1fico de las tres pel\u00edculas citadas anteriormente.<\/p>\n<p>La expedici\u00f3n de los estudios Disney viaj\u00f3 desde EE.UU. en dos grupos, principalmente porque el seguro de vida de Walt Disney le prohib\u00eda viajar con m\u00e1s de siete miembros de su estudio.<\/p>\n<p>Los que viajaban con Disney cogieron el avi\u00f3n el 15 de agosto de 1941 en Miami Beach (Florida), pasaron una noche en Puerto Rico y despu\u00e9s se trasladaron a Brasil, Argentina (donde conocieron a varios gauchos, que despu\u00e9s aparecer\u00edan en \u00abSaludos Amigos\u00bb), Uruguay y Chile.<\/p>\n<p>\u00abWalt y su personal creativo hac\u00edan muchas observaciones de la realidad que luego conservaban para usos posteriores, en ocasiones para usarlas muchos a\u00f1os despu\u00e9s\u00bb, explic\u00f3 Thomas.<\/p>\n<p>Desde Chile, el equipo de Walt Disney cogi\u00f3 un barco en Valpara\u00edso que les llev\u00f3 hasta Nueva York a trav\u00e9s del canal de Panam\u00e1, realizando paradas en Per\u00fa, Ecuador, Colombia y Panam\u00e1.<\/p>\n<p>Cuando el grupo se ape\u00f3 en Colombia, tom\u00f3 una expedici\u00f3n de un d\u00eda para remontar con un barco un r\u00edo de la jungla colombiana.<\/p>\n<p>Seg\u00fan Thomas, las fotograf\u00edas de esa expedici\u00f3n muestran que el barco en el que se mont\u00f3 el grupo es \u00abenormemente parecido\u00bb a los barcos del crucero de la jungla dise\u00f1ados para el primer parque de atracciones Disneyland, inaugurado en Anaheim (California) en 1955.<\/p>\n<p>\u00abTan buena fue la experiencia que Walt Disney se llev\u00f3 de su viaje por Latinoam\u00e9rica en 1941 que \u00e9ste mantuvo la amistad con muchas de las personas que all\u00ed conoci\u00f3 durante el resto de su vida. Cada vez que un conocido de Brasil, Argentina o Chile visitaba Los \u00c1ngeles, Walt Disney lo invitaba a conocer sus estudios\u00bb, concluy\u00f3 el experto en Disney.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Francisco (EE.UU.), 12 oct (EFE).- En 1941, Walt Disney y varios artistas de su estudio hicieron una gira de dos semanas y media por Am\u00e9rica Latina, un viaje pagado por el Gobierno de EE.UU. que les sirvi\u00f3 de inspiraci\u00f3n para crear t\u00edtulos cl\u00e1sicos de la factor\u00eda como \u00abPeter Pan\u00bb y \u00abAlicia en el pa\u00eds<\/p>\n","protected":false},"author":1,"featured_media":27103,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-27102","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"San Francisco (EE.UU.), 12 oct (EFE).- En 1941, Walt Disney y varios artistas de su estudio hicieron una gira de dos semanas y media por Am\u00e9rica Latina, un viaje pagado por el Gobierno de EE.UU. que les sirvi\u00f3 de inspiraci\u00f3n para crear t\u00edtulos cl\u00e1sicos de la factor\u00eda como &quot;Peter Pan&quot; y &quot;Alicia en el pa\u00eds\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Latinoam\u00e9rica, fuente de inspiraci\u00f3n para las pel\u00edculas cl\u00e1sicas de Disney | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"San Francisco (EE.UU.), 12 oct (EFE).- En 1941, Walt Disney y varios artistas de su estudio hicieron una gira de dos semanas y media por Am\u00e9rica Latina, un viaje pagado por el Gobierno de EE.UU. que les sirvi\u00f3 de inspiraci\u00f3n para crear t\u00edtulos cl\u00e1sicos de la factor\u00eda como &quot;Peter Pan&quot; y &quot;Alicia en el pa\u00eds\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6726877w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6726877w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"641\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-10-12T21:17:33+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-10-12T21:17:33+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Latinoam\u00e9rica, fuente de inspiraci\u00f3n para las pel\u00edculas cl\u00e1sicas de Disney | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"San Francisco (EE.UU.), 12 oct (EFE).- En 1941, Walt Disney y varios artistas de su estudio hicieron una gira de dos semanas y media por Am\u00e9rica Latina, un viaje pagado por el Gobierno de EE.UU. que les sirvi\u00f3 de inspiraci\u00f3n para crear t\u00edtulos cl\u00e1sicos de la factor\u00eda como &quot;Peter Pan&quot; y &quot;Alicia en el pa\u00eds\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6726877w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\\\/#article\",\"name\":\"Latinoam\\u00e9rica, fuente de inspiraci\\u00f3n para las pel\\u00edculas cl\\u00e1sicas de Disney | El Digital de Asturias\",\"headline\":\"Latinoam\\u00e9rica, fuente de inspiraci\\u00f3n para las pel\\u00edculas cl\\u00e1sicas de Disney\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/6726877w.jpg\",\"width\":800,\"height\":641},\"datePublished\":\"2014-10-12T19:17:33+02:00\",\"dateModified\":\"2014-10-12T19:17:33+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\\\/#listItem\",\"name\":\"Latinoam\\u00e9rica, fuente de inspiraci\\u00f3n para las pel\\u00edculas cl\\u00e1sicas de Disney\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\\\/#listItem\",\"position\":3,\"name\":\"Latinoam\\u00e9rica, fuente de inspiraci\\u00f3n para las pel\\u00edculas cl\\u00e1sicas de Disney\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\\\/\",\"name\":\"Latinoam\\u00e9rica, fuente de inspiraci\\u00f3n para las pel\\u00edculas cl\\u00e1sicas de Disney | El Digital de Asturias\",\"description\":\"San Francisco (EE.UU.), 12 oct (EFE).- En 1941, Walt Disney y varios artistas de su estudio hicieron una gira de dos semanas y media por Am\\u00e9rica Latina, un viaje pagado por el Gobierno de EE.UU. que les sirvi\\u00f3 de inspiraci\\u00f3n para crear t\\u00edtulos cl\\u00e1sicos de la factor\\u00eda como \\\"Peter Pan\\\" y \\\"Alicia en el pa\\u00eds\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/6726877w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\\\/#mainImage\",\"width\":800,\"height\":641},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\\\/#mainImage\"},\"datePublished\":\"2014-10-12T19:17:33+02:00\",\"dateModified\":\"2014-10-12T19:17:33+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Latinoam\u00e9rica, fuente de inspiraci\u00f3n para las pel\u00edculas cl\u00e1sicas de Disney | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Latinoam\u00e9rica, fuente de inspiraci\u00f3n para las pel\u00edculas cl\u00e1sicas de Disney | El Digital de Asturias","description":"San Francisco (EE.UU.), 12 oct (EFE).- En 1941, Walt Disney y varios artistas de su estudio hicieron una gira de dos semanas y media por Am\u00e9rica Latina, un viaje pagado por el Gobierno de EE.UU. que les sirvi\u00f3 de inspiraci\u00f3n para crear t\u00edtulos cl\u00e1sicos de la factor\u00eda como \"Peter Pan\" y \"Alicia en el pa\u00eds","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/#article","name":"Latinoam\u00e9rica, fuente de inspiraci\u00f3n para las pel\u00edculas cl\u00e1sicas de Disney | El Digital de Asturias","headline":"Latinoam\u00e9rica, fuente de inspiraci\u00f3n para las pel\u00edculas cl\u00e1sicas de Disney","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6726877w.jpg","width":800,"height":641},"datePublished":"2014-10-12T19:17:33+02:00","dateModified":"2014-10-12T19:17:33+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/#listItem","name":"Latinoam\u00e9rica, fuente de inspiraci\u00f3n para las pel\u00edculas cl\u00e1sicas de Disney"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/#listItem","position":3,"name":"Latinoam\u00e9rica, fuente de inspiraci\u00f3n para las pel\u00edculas cl\u00e1sicas de Disney","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/","name":"Latinoam\u00e9rica, fuente de inspiraci\u00f3n para las pel\u00edculas cl\u00e1sicas de Disney | El Digital de Asturias","description":"San Francisco (EE.UU.), 12 oct (EFE).- En 1941, Walt Disney y varios artistas de su estudio hicieron una gira de dos semanas y media por Am\u00e9rica Latina, un viaje pagado por el Gobierno de EE.UU. que les sirvi\u00f3 de inspiraci\u00f3n para crear t\u00edtulos cl\u00e1sicos de la factor\u00eda como \"Peter Pan\" y \"Alicia en el pa\u00eds","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6726877w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/#mainImage","width":800,"height":641},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/#mainImage"},"datePublished":"2014-10-12T19:17:33+02:00","dateModified":"2014-10-12T19:17:33+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Latinoam\u00e9rica, fuente de inspiraci\u00f3n para las pel\u00edculas cl\u00e1sicas de Disney | El Digital de Asturias","og:description":"San Francisco (EE.UU.), 12 oct (EFE).- En 1941, Walt Disney y varios artistas de su estudio hicieron una gira de dos semanas y media por Am\u00e9rica Latina, un viaje pagado por el Gobierno de EE.UU. que les sirvi\u00f3 de inspiraci\u00f3n para crear t\u00edtulos cl\u00e1sicos de la factor\u00eda como &quot;Peter Pan&quot; y &quot;Alicia en el pa\u00eds","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6726877w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6726877w.jpg","og:image:width":800,"og:image:height":641,"article:published_time":"2014-10-12T21:17:33+00:00","article:modified_time":"2014-10-12T21:17:33+00:00","twitter:card":"summary_large_image","twitter:title":"Latinoam\u00e9rica, fuente de inspiraci\u00f3n para las pel\u00edculas cl\u00e1sicas de Disney | El Digital de Asturias","twitter:description":"San Francisco (EE.UU.), 12 oct (EFE).- En 1941, Walt Disney y varios artistas de su estudio hicieron una gira de dos semanas y media por Am\u00e9rica Latina, un viaje pagado por el Gobierno de EE.UU. que les sirvi\u00f3 de inspiraci\u00f3n para crear t\u00edtulos cl\u00e1sicos de la factor\u00eda como &quot;Peter Pan&quot; y &quot;Alicia en el pa\u00eds","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6726877w.jpg"},"aioseo_meta_data":{"post_id":"27102","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-17 14:03:31","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 05:21:40","updated":"2026-05-17 14:03:31"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/\" title=\"Latinoam\u00e9rica, fuente de inspiraci\u00f3n para las pel\u00edculas cl\u00e1sicas de Disney\">Latinoam\u00e9rica, fuente de inspiraci\u00f3n para las pel\u00edculas cl\u00e1sicas de Disney<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"Latinoam\u00e9rica, fuente de inspiraci\u00f3n para las pel\u00edculas cl\u00e1sicas de Disney","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/latinoamerica-fuente-de-inspiracion-para-las-peliculas-clasicas-de-disney\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/27102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=27102"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/27102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/27103"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=27102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=27102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=27102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}