{"id":26960,"date":"2014-10-10T20:13:47","date_gmt":"2014-10-10T22:13:47","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=26960"},"modified":"2014-10-10T20:13:47","modified_gmt":"2014-10-10T22:13:47","slug":"compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/","title":{"rendered":"Compostela acogi\u00f3 216.000 peregrinos desde inicio del a\u00f1o, tantos como en 2013"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-26961\" alt=\"6723257w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6723257w-360x265.jpg\" width=\"360\" height=\"265\" \/>Santiago de Compostela, 10 oct (EFE).- Cerca de 216.000 personas llegaron a Santiago de Compostela por las denominadas rutas jacobeas desde principios de este a\u00f1o, tantos como el total registrado en 2013, seg\u00fan datos de la oficina de peregrinos de la Iglesia cat\u00f3lica, inform\u00f3 hoy la Xunta en un comunicado.<\/p>\n<p>La cifra global de peregrinos, comparado con el mismo per\u00edodo de 2013, supone un aumento de 9,69 %, se\u00f1ala la nota, y apunta que la directora de Turismo de la Xunta, Nava Castro, se congratula de esos resultados.<\/p>\n<p>\u00abEl Camino de Santiago es nuestro icono m\u00e1s universal, nuestro principal producto tur\u00edstico y un eje vertebrador de la cultura europea\u00bb, indic\u00f3 Castro.<\/p>\n<p>Del total de caminantes registrados este a\u00f1o por la citada oficina de la Iglesia cat\u00f3lica, 104.349 proceden de territorio espa\u00f1ol, lo que representa 48,31 % del total.<\/p>\n<p>Los caminantes de otras nacionalidades, un total de 111.651 desde principios de a\u00f1o, representan 51,69 % de los peregrinos, y destacan en primer lugar los procedentes de Italia, Alemania, Portugal, Estados Unidos, Francia, Irlanda, Reino Unido, Holanda, Australia, Corea, Canad\u00e1, Brasil, Polonia, B\u00e9lgica y Dinamarca, seg\u00fan la Xunta.<\/p>\n<p>De los caminantes que acudieron a la oficina del peregrino, 146.656 indicaron haber recorrido el denominado Camino franc\u00e9s, que acapara 68 % del total.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santiago de Compostela, 10 oct (EFE).- Cerca de 216.000 personas llegaron a Santiago de Compostela por las denominadas rutas jacobeas desde principios de este a\u00f1o, tantos como el total registrado en 2013, seg\u00fan datos de la oficina de peregrinos de la Iglesia cat\u00f3lica, inform\u00f3 hoy la Xunta en un comunicado. La cifra global de peregrinos,<\/p>\n","protected":false},"author":1,"featured_media":26961,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-26960","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Santiago de Compostela, 10 oct (EFE).- Cerca de 216.000 personas llegaron a Santiago de Compostela por las denominadas rutas jacobeas desde principios de este a\u00f1o, tantos como el total registrado en 2013, seg\u00fan datos de la oficina de peregrinos de la Iglesia cat\u00f3lica, inform\u00f3 hoy la Xunta en un comunicado. La cifra global de peregrinos,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Compostela acogi\u00f3 216.000 peregrinos desde inicio del a\u00f1o, tantos como en 2013 | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Santiago de Compostela, 10 oct (EFE).- Cerca de 216.000 personas llegaron a Santiago de Compostela por las denominadas rutas jacobeas desde principios de este a\u00f1o, tantos como el total registrado en 2013, seg\u00fan datos de la oficina de peregrinos de la Iglesia cat\u00f3lica, inform\u00f3 hoy la Xunta en un comunicado. La cifra global de peregrinos,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6723257w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6723257w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"590\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-10-10T22:13:47+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-10-10T22:13:47+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Compostela acogi\u00f3 216.000 peregrinos desde inicio del a\u00f1o, tantos como en 2013 | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Santiago de Compostela, 10 oct (EFE).- Cerca de 216.000 personas llegaron a Santiago de Compostela por las denominadas rutas jacobeas desde principios de este a\u00f1o, tantos como el total registrado en 2013, seg\u00fan datos de la oficina de peregrinos de la Iglesia cat\u00f3lica, inform\u00f3 hoy la Xunta en un comunicado. La cifra global de peregrinos,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6723257w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\\\/#article\",\"name\":\"Compostela acogi\\u00f3 216.000 peregrinos desde inicio del a\\u00f1o, tantos como en 2013 | El Digital de Asturias\",\"headline\":\"Compostela acogi\\u00f3 216.000 peregrinos desde inicio del a\\u00f1o, tantos como en 2013\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/6723257w.jpg\",\"width\":800,\"height\":590},\"datePublished\":\"2014-10-10T20:13:47+02:00\",\"dateModified\":\"2014-10-10T20:13:47+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\\\/#listItem\",\"name\":\"Compostela acogi\\u00f3 216.000 peregrinos desde inicio del a\\u00f1o, tantos como en 2013\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\\\/#listItem\",\"position\":3,\"name\":\"Compostela acogi\\u00f3 216.000 peregrinos desde inicio del a\\u00f1o, tantos como en 2013\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\\\/\",\"name\":\"Compostela acogi\\u00f3 216.000 peregrinos desde inicio del a\\u00f1o, tantos como en 2013 | El Digital de Asturias\",\"description\":\"Santiago de Compostela, 10 oct (EFE).- Cerca de 216.000 personas llegaron a Santiago de Compostela por las denominadas rutas jacobeas desde principios de este a\\u00f1o, tantos como el total registrado en 2013, seg\\u00fan datos de la oficina de peregrinos de la Iglesia cat\\u00f3lica, inform\\u00f3 hoy la Xunta en un comunicado. La cifra global de peregrinos,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/6723257w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\\\/#mainImage\",\"width\":800,\"height\":590},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\\\/#mainImage\"},\"datePublished\":\"2014-10-10T20:13:47+02:00\",\"dateModified\":\"2014-10-10T20:13:47+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Compostela acogi\u00f3 216.000 peregrinos desde inicio del a\u00f1o, tantos como en 2013 | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Compostela acogi\u00f3 216.000 peregrinos desde inicio del a\u00f1o, tantos como en 2013 | El Digital de Asturias","description":"Santiago de Compostela, 10 oct (EFE).- Cerca de 216.000 personas llegaron a Santiago de Compostela por las denominadas rutas jacobeas desde principios de este a\u00f1o, tantos como el total registrado en 2013, seg\u00fan datos de la oficina de peregrinos de la Iglesia cat\u00f3lica, inform\u00f3 hoy la Xunta en un comunicado. La cifra global de peregrinos,","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/#article","name":"Compostela acogi\u00f3 216.000 peregrinos desde inicio del a\u00f1o, tantos como en 2013 | El Digital de Asturias","headline":"Compostela acogi\u00f3 216.000 peregrinos desde inicio del a\u00f1o, tantos como en 2013","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6723257w.jpg","width":800,"height":590},"datePublished":"2014-10-10T20:13:47+02:00","dateModified":"2014-10-10T20:13:47+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/#listItem","name":"Compostela acogi\u00f3 216.000 peregrinos desde inicio del a\u00f1o, tantos como en 2013"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/#listItem","position":3,"name":"Compostela acogi\u00f3 216.000 peregrinos desde inicio del a\u00f1o, tantos como en 2013","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/","name":"Compostela acogi\u00f3 216.000 peregrinos desde inicio del a\u00f1o, tantos como en 2013 | El Digital de Asturias","description":"Santiago de Compostela, 10 oct (EFE).- Cerca de 216.000 personas llegaron a Santiago de Compostela por las denominadas rutas jacobeas desde principios de este a\u00f1o, tantos como el total registrado en 2013, seg\u00fan datos de la oficina de peregrinos de la Iglesia cat\u00f3lica, inform\u00f3 hoy la Xunta en un comunicado. La cifra global de peregrinos,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6723257w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/#mainImage","width":800,"height":590},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/#mainImage"},"datePublished":"2014-10-10T20:13:47+02:00","dateModified":"2014-10-10T20:13:47+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Compostela acogi\u00f3 216.000 peregrinos desde inicio del a\u00f1o, tantos como en 2013 | El Digital de Asturias","og:description":"Santiago de Compostela, 10 oct (EFE).- Cerca de 216.000 personas llegaron a Santiago de Compostela por las denominadas rutas jacobeas desde principios de este a\u00f1o, tantos como el total registrado en 2013, seg\u00fan datos de la oficina de peregrinos de la Iglesia cat\u00f3lica, inform\u00f3 hoy la Xunta en un comunicado. La cifra global de peregrinos,","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6723257w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6723257w.jpg","og:image:width":800,"og:image:height":590,"article:published_time":"2014-10-10T22:13:47+00:00","article:modified_time":"2014-10-10T22:13:47+00:00","twitter:card":"summary_large_image","twitter:title":"Compostela acogi\u00f3 216.000 peregrinos desde inicio del a\u00f1o, tantos como en 2013 | El Digital de Asturias","twitter:description":"Santiago de Compostela, 10 oct (EFE).- Cerca de 216.000 personas llegaron a Santiago de Compostela por las denominadas rutas jacobeas desde principios de este a\u00f1o, tantos como el total registrado en 2013, seg\u00fan datos de la oficina de peregrinos de la Iglesia cat\u00f3lica, inform\u00f3 hoy la Xunta en un comunicado. La cifra global de peregrinos,","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/10\/6723257w.jpg"},"aioseo_meta_data":{"post_id":"26960","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-17 13:45:10","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 05:24:23","updated":"2026-05-17 13:45:10"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/\" title=\"Compostela acogi\u00f3 216.000 peregrinos desde inicio del a\u00f1o, tantos como en 2013\">Compostela acogi\u00f3 216.000 peregrinos desde inicio del a\u00f1o, tantos como en 2013<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"Compostela acogi\u00f3 216.000 peregrinos desde inicio del a\u00f1o, tantos como en 2013","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/compostela-acogio-216-000-peregrinos-desde-inicio-del-ano-tantos-como-en-2013\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/26960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=26960"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/26960\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/26961"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=26960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=26960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=26960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}