{"id":2635,"date":"2014-02-02T16:28:32","date_gmt":"2014-02-02T17:28:32","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=2635"},"modified":"2014-02-02T16:28:32","modified_gmt":"2014-02-02T17:28:32","slug":"beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/","title":{"rendered":"Beckham disfruta construyendo piezas de \u00abLego\u00bb y cocinando para su familia"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-2636\" alt=\"5900965w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5900965w-360x247.jpg\" width=\"360\" height=\"247\" \/>Londres, 2 feb (EFE).- El exjugador ingl\u00e9s David Beckham admite que tras su retirada del f\u00fatbol disfruta con las construcciones de las piezas \u00abLego\u00bb y cocinando para su familia en una entrevista publicada hoy por el dominical brit\u00e1nico \u00abThe Sunday Times\u00bb.<\/p>\n<p>El que fuera capit\u00e1n de la selecci\u00f3n de Inglaterra, de 38 a\u00f1os, y militante, entre otros clubes, del Manchester United y el Real Madrid, dijo al citado peri\u00f3dico que no se ve diferente \u00abde cualquier otra persona\u00bb.<\/p>\n<p>Considerado una leyenda viva del f\u00fatbol, multimillonario, y percibido, tambi\u00e9n, como un icono de la moda, Beckham reconoci\u00f3 que encuentra \u00abrelajante\u00bb completar estructuras \u00abLego\u00bb y que cocinar le resulta \u00abterap\u00e9utico\u00bb.<\/p>\n<p>\u00abLo \u00faltimo que he construido fue la Torre de Londres. Fue incre\u00edble. Creo que Lego me ayuda a relajarme\u00bb, dijo el excentrocampista de una estructura que consta de 4.287 piezas y que est\u00e1 recomendada, por el fabricante, para mayores de 16 a\u00f1os.<\/p>\n<p>Beckham dijo que le ocurre lo mismo con cocinar: \u00abLo encuentro muy terap\u00e9utico y con frecuencia cocino por las tardes\u00bb.<\/p>\n<p>\u00abCuando estaba en Italia me encantaba la comida y aprend\u00ed a cocinarla. Por suerte, a los ni\u00f1os tambi\u00e9n les encanta as\u00ed que me resulta f\u00e1cil hacerles algo\u00bb, se\u00f1al\u00f3.<\/p>\n<p>En la entrevista, tambi\u00e9n revel\u00f3 que suele preparar el desayuno a sus hijos y luego les lleva al colegio: \u00abAl \u00fanico al que no acompa\u00f1amos a la puerta es a Brooklyn, que quiere que le dejemos en la otra parte de la carretera porque no es &#8216;cool&#8217; que tu padre te lleve a la escuela\u00bb.<\/p>\n<p>\u00abTambi\u00e9n hago la compra de la comida semanal y, de hecho, siempre lo he hecho. La gente se sorprende pero es f\u00e1cil; s\u00e9 exactamente lo que les gusta a los ni\u00f1os y s\u00e9 exactamente lo que le gusta a Victoria\u00bb, dijo.<\/p>\n<p>Casado con la excantante del ya desaparecido grupo de pop \u00abSpice Girls\u00bb y ahora dise\u00f1adora de moda, Victoria Beckham, y padre de cuatro hijos -tres varones y una ni\u00f1a- en 2013 se mud\u00f3 con su familia a una vivienda valorada en 40 millones de libras (48,7 millones de euros) en el lujoso barrio de Kensington, al oeste de Londres.<\/p>\n<p>Sobre su regreso a la capital brit\u00e1nica, Beckham dijo que le \u00abencanta caminar por los parques de Londres\u00bb as\u00ed como \u00abir a un par de pubs\u00bb de su barrio.<\/p>\n<p>\u00abLa gente all\u00ed me conoce y me resulta f\u00e1cil pasarme a tomar una pinta\u00bb, explic\u00f3.<\/p>\n<p>En 2006, el exjugador del Milan y LA Galaxy revel\u00f3 que sufre de un desorden compulsivo obsesivo: \u00abTengo ese problema. Cuando voy a una habitaci\u00f3n de hotel, antes de poder relajarme, tengo que quitar todos los folletos y libros y ponerlos en un caj\u00f3n. Todo tiene que estar perfecto\u00bb, admiti\u00f3 entonces el jugador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Londres, 2 feb (EFE).- El exjugador ingl\u00e9s David Beckham admite que tras su retirada del f\u00fatbol disfruta con las construcciones de las piezas \u00abLego\u00bb y cocinando para su familia en una entrevista publicada hoy por el dominical brit\u00e1nico \u00abThe Sunday Times\u00bb. El que fuera capit\u00e1n de la selecci\u00f3n de Inglaterra, de 38 a\u00f1os, y militante,<\/p>\n","protected":false},"author":1,"featured_media":2636,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-2635","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Londres, 2 feb (EFE).- El exjugador ingl\u00e9s David Beckham admite que tras su retirada del f\u00fatbol disfruta con las construcciones de las piezas &quot;Lego&quot; y cocinando para su familia en una entrevista publicada hoy por el dominical brit\u00e1nico &quot;The Sunday Times&quot;. El que fuera capit\u00e1n de la selecci\u00f3n de Inglaterra, de 38 a\u00f1os, y militante,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Beckham disfruta construyendo piezas de \u00abLego\u00bb y cocinando para su familia | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Londres, 2 feb (EFE).- El exjugador ingl\u00e9s David Beckham admite que tras su retirada del f\u00fatbol disfruta con las construcciones de las piezas &quot;Lego&quot; y cocinando para su familia en una entrevista publicada hoy por el dominical brit\u00e1nico &quot;The Sunday Times&quot;. El que fuera capit\u00e1n de la selecci\u00f3n de Inglaterra, de 38 a\u00f1os, y militante,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5900965w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5900965w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-02T17:28:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-02T17:28:32+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Beckham disfruta construyendo piezas de \u00abLego\u00bb y cocinando para su familia | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Londres, 2 feb (EFE).- El exjugador ingl\u00e9s David Beckham admite que tras su retirada del f\u00fatbol disfruta con las construcciones de las piezas &quot;Lego&quot; y cocinando para su familia en una entrevista publicada hoy por el dominical brit\u00e1nico &quot;The Sunday Times&quot;. El que fuera capit\u00e1n de la selecci\u00f3n de Inglaterra, de 38 a\u00f1os, y militante,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5900965w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\\\/#article\",\"name\":\"Beckham disfruta construyendo piezas de \\u00abLego\\u00bb y cocinando para su familia | El Digital de Asturias\",\"headline\":\"Beckham disfruta construyendo piezas de \\u00abLego\\u00bb y cocinando para su familia\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5900965w.jpg\",\"width\":800,\"height\":550},\"datePublished\":\"2014-02-02T16:28:32+01:00\",\"dateModified\":\"2014-02-02T16:28:32+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\\\/#listItem\",\"name\":\"Beckham disfruta construyendo piezas de \\u00abLego\\u00bb y cocinando para su familia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\\\/#listItem\",\"position\":3,\"name\":\"Beckham disfruta construyendo piezas de \\u00abLego\\u00bb y cocinando para su familia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\\\/\",\"name\":\"Beckham disfruta construyendo piezas de \\u00abLego\\u00bb y cocinando para su familia | El Digital de Asturias\",\"description\":\"Londres, 2 feb (EFE).- El exjugador ingl\\u00e9s David Beckham admite que tras su retirada del f\\u00fatbol disfruta con las construcciones de las piezas \\\"Lego\\\" y cocinando para su familia en una entrevista publicada hoy por el dominical brit\\u00e1nico \\\"The Sunday Times\\\". El que fuera capit\\u00e1n de la selecci\\u00f3n de Inglaterra, de 38 a\\u00f1os, y militante,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5900965w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\\\/#mainImage\",\"width\":800,\"height\":550},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\\\/#mainImage\"},\"datePublished\":\"2014-02-02T16:28:32+01:00\",\"dateModified\":\"2014-02-02T16:28:32+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Beckham disfruta construyendo piezas de \u00abLego\u00bb y cocinando para su familia | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Beckham disfruta construyendo piezas de \u00abLego\u00bb y cocinando para su familia | El Digital de Asturias","description":"Londres, 2 feb (EFE).- El exjugador ingl\u00e9s David Beckham admite que tras su retirada del f\u00fatbol disfruta con las construcciones de las piezas \"Lego\" y cocinando para su familia en una entrevista publicada hoy por el dominical brit\u00e1nico \"The Sunday Times\". El que fuera capit\u00e1n de la selecci\u00f3n de Inglaterra, de 38 a\u00f1os, y militante,","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/#article","name":"Beckham disfruta construyendo piezas de \u00abLego\u00bb y cocinando para su familia | El Digital de Asturias","headline":"Beckham disfruta construyendo piezas de \u00abLego\u00bb y cocinando para su familia","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5900965w.jpg","width":800,"height":550},"datePublished":"2014-02-02T16:28:32+01:00","dateModified":"2014-02-02T16:28:32+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/#listItem","name":"Beckham disfruta construyendo piezas de \u00abLego\u00bb y cocinando para su familia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/#listItem","position":3,"name":"Beckham disfruta construyendo piezas de \u00abLego\u00bb y cocinando para su familia","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/","name":"Beckham disfruta construyendo piezas de \u00abLego\u00bb y cocinando para su familia | El Digital de Asturias","description":"Londres, 2 feb (EFE).- El exjugador ingl\u00e9s David Beckham admite que tras su retirada del f\u00fatbol disfruta con las construcciones de las piezas \"Lego\" y cocinando para su familia en una entrevista publicada hoy por el dominical brit\u00e1nico \"The Sunday Times\". El que fuera capit\u00e1n de la selecci\u00f3n de Inglaterra, de 38 a\u00f1os, y militante,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5900965w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/#mainImage","width":800,"height":550},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/#mainImage"},"datePublished":"2014-02-02T16:28:32+01:00","dateModified":"2014-02-02T16:28:32+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Beckham disfruta construyendo piezas de \u00abLego\u00bb y cocinando para su familia | El Digital de Asturias","og:description":"Londres, 2 feb (EFE).- El exjugador ingl\u00e9s David Beckham admite que tras su retirada del f\u00fatbol disfruta con las construcciones de las piezas &quot;Lego&quot; y cocinando para su familia en una entrevista publicada hoy por el dominical brit\u00e1nico &quot;The Sunday Times&quot;. El que fuera capit\u00e1n de la selecci\u00f3n de Inglaterra, de 38 a\u00f1os, y militante,","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5900965w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5900965w.jpg","og:image:width":800,"og:image:height":550,"article:published_time":"2014-02-02T17:28:32+00:00","article:modified_time":"2014-02-02T17:28:32+00:00","twitter:card":"summary_large_image","twitter:title":"Beckham disfruta construyendo piezas de \u00abLego\u00bb y cocinando para su familia | El Digital de Asturias","twitter:description":"Londres, 2 feb (EFE).- El exjugador ingl\u00e9s David Beckham admite que tras su retirada del f\u00fatbol disfruta con las construcciones de las piezas &quot;Lego&quot; y cocinando para su familia en una entrevista publicada hoy por el dominical brit\u00e1nico &quot;The Sunday Times&quot;. El que fuera capit\u00e1n de la selecci\u00f3n de Inglaterra, de 38 a\u00f1os, y militante,","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5900965w.jpg"},"aioseo_meta_data":{"post_id":"2635","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 08:16:06","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:44:07","updated":"2026-05-15 08:16:06"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/\" title=\"Beckham disfruta construyendo piezas de \u00abLego\u00bb y cocinando para su familia\">Beckham disfruta construyendo piezas de \u00abLego\u00bb y cocinando para su familia<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Beckham disfruta construyendo piezas de \u00abLego\u00bb y cocinando para su familia","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/beckham-disfruta-construyendo-piezas-de-lego-y-cocinando-para-su-familia\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/2635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=2635"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/2635\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/2636"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=2635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=2635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=2635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}