{"id":2584,"date":"2014-02-01T18:09:52","date_gmt":"2014-02-01T19:09:52","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=2584"},"modified":"2014-02-01T18:09:52","modified_gmt":"2014-02-01T19:09:52","slug":"jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/","title":{"rendered":"Jos\u00e9 Padilha, el hombre tras los 100 millones de d\u00f3lares del nuevo \u00abRobocop\u00bb"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-2585\" alt=\"5899643w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899643w-360x239.jpg\" width=\"360\" height=\"239\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899643w-360x239.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899643w-650x432.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899643w-768x511.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899643w-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899643w-450x299.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899643w-696x463.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899643w-632x420.jpg 632w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899643w-84x55.jpg 84w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899643w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Los \u00c1ngeles (EE.UU.), 1 feb (EFE).- Reclinado sobre un sof\u00e1 se encuentra un hombre afable, cercano y ataviado con una gorra que delata su admiraci\u00f3n por Rafael Nadal. Pasa inadvertido, pero sobre sus hombros recae la responsabilidad de devolver a \u00abRobocop\u00bb al cine. Es Jos\u00e9 Padilha, y no le teme a su juguete de 100 millones de d\u00f3lares.<\/p>\n<p>\u00abNo me asustan las altas expectativas\u00bb, afirm\u00f3 el cineasta brasile\u00f1o en una entrevista con Efe. \u00abMiedo me hubiera dado hacer un &#8216;remake&#8217; de una pel\u00edcula mala. Con &#8216;Robocop&#8217; sent\u00ed felicidad. Se trata de un concepto poderoso y muy inteligente que me inspir\u00f3. Y lo que tratamos en la historia va a ocurrir. Est\u00e1 a la vuelta de la esquina\u00bb, a\u00f1adi\u00f3.<\/p>\n<p>Es el a\u00f1o 2028 y la multinacional OmniCorp domina la tecnolog\u00eda rob\u00f3tica. Fuera de EE.UU., sus \u00abdrones\u00bb (aviones no tripulados) han sido empleados durante a\u00f1os por las Fuerzas Armadas, no as\u00ed dentro de sus propias fronteras. En un nuevo esfuerzo por convencer a los pol\u00edticos, la compa\u00f1\u00eda apuesta por una nueva arma: un agente de la ley mitad hombre, mitad m\u00e1quina.<\/p>\n<p>El elegido es Alex Murphy (Joel Kinnaman), esposo, padre y polic\u00eda que hace frente a la corrupci\u00f3n en Detroit, una misi\u00f3n que le lleva a sufrir un atentado en el que est\u00e1 a punto de perder la vida. OmniCorp ve en \u00e9l la llave para amasar una fortuna procedente de sus accionistas, pero olvida que en la m\u00e1quina reposan resquicios de una persona.<\/p>\n<p>\u00abEl concepto del &#8216;Robocop&#8217; original (1987) es que existe una conexi\u00f3n entre la automatizaci\u00f3n de la violencia y el fascismo, y quer\u00eda traerlo al presente. EE.UU. se fue de Irak porque estaban muriendo sus soldados. Si se hubieran reemplazado por m\u00e1quinas, \u00bfqu\u00e9 habr\u00eda pasado? Un polic\u00eda puede negarse a acatar una orden. Las m\u00e1quinas no. Ese futuro va a ocurrir y plantea un serio dilema moral y \u00e9tico\u00bb, declar\u00f3 el realizador de 45 a\u00f1os.<\/p>\n<p>Padilha se sent\u00f3 con los directivos de MGM para hablar sobre posibles proyectos en com\u00fan. Todo lo que le ofrecieron eran \u00abremakes\u00bb (nuevas versiones) de pel\u00edculas populares. Nada le interesaba, hasta que un d\u00eda, en la sala donde se reun\u00edan, vio un cartel de \u00abRobocop\u00bb, el cl\u00e1sico de Paul Verhoeven. Entonces, lo tuvo claro.<\/p>\n<p>\u00abLes pareci\u00f3 bien, as\u00ed que me reun\u00ed con varios guionistas. Escog\u00ed a uno, se vino a R\u00edo de Janeiro y desarrollamos el gui\u00f3n en mi oficina durante un mes. Me dieron el espacio para hacer la pel\u00edcula que yo quer\u00eda. Y el resultado es bastante similar a lo que imagin\u00e9. Es como la dise\u00f1amos\u00bb, indic\u00f3 Padilha.<\/p>\n<p>El director trabaj\u00f3 con compatriotas que conoce bien, como el director de fotograf\u00eda Lula Carvalho, el montador Daniel Rezende o el compositor Pedro Bromfmam. \u00abEs dif\u00edcil que un gran estudio te d\u00e9 libertad, pero si tienes las ideas claras y luchas por ellas, se puede lograr\u00bb, indic\u00f3.<\/p>\n<p>Padilha rinde homenaje a Verhoeven incluyendo la recordada banda sonora de Basil Poledouris y algunas de las frases m\u00e1s c\u00e9lebres de la original, como \u00abvivo o muerto, t\u00fa vendr\u00e1s conmigo\u00bb, pero ha apostado por una historia global en la que su estilo y forma de entender el cine est\u00e1n muy presentes.<\/p>\n<p>\u00abEso no se puede evitar, al menos en directores que quieren hacer suya la historia. Lees a TS Eliot y sabes inmediatamente que es \u00e9l. Igual que reconoces un cuadro de Picasso o una jugada de Messi. Si hago una pel\u00edcula, es porque la amo y la quiero hacer a mi manera\u00bb, manifest\u00f3.<\/p>\n<p>El director coment\u00f3 tambi\u00e9n que el nivel de violencia -una de las se\u00f1as de la obra original- es el que buscaba, ya que resulta \u00abcoherente con la historia\u00bb. Padilha considera que ha rodado escenas \u00abmuy gr\u00e1ficas\u00bb, y a\u00fan as\u00ed la pel\u00edcula ha obtenido la calificaci\u00f3n de no recomendada para menores de 13 a\u00f1os.<\/p>\n<p>La escena m\u00e1s dura llega cuando el protagonista descubre lo que queda de su propio cuerpo. No cree lo que ve y desea morir. Se pregunta qu\u00e9 le hace humano, y recuerda el amor por su mujer y su hijo.<\/p>\n<p>\u00abDespu\u00e9s, le quitan la voluntad propia e incluso sus emociones. Son nociones impl\u00edcitas en la versi\u00f3n antigua que aqu\u00ed exploramos y desarrollamos\u00bb, explic\u00f3 Padilha, quien dice sentirse privilegiado por contar con un reparto que incluye a Michael Keaton, Gary Oldman y Samuel L. Jackson, entre otros.<\/p>\n<p>El filme se estrena el d\u00eda 12 en EE.UU., pero a Padilha lo que verdaderamente le quita el sue\u00f1o es conocer a Nadal. Est\u00e1 previsto que el tenista espa\u00f1ol acuda este mes al R\u00edo Open de Tenis, y quiere invitarle a ver la pel\u00edcula.<\/p>\n<p>\u00abSoy un fan enorme. Ojal\u00e1 le guste\u00bb, concluy\u00f3.<\/p>\n<p>Antonio Mart\u00edn Guirado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los \u00c1ngeles (EE.UU.), 1 feb (EFE).- Reclinado sobre un sof\u00e1 se encuentra un hombre afable, cercano y ataviado con una gorra que delata su admiraci\u00f3n por Rafael Nadal. Pasa inadvertido, pero sobre sus hombros recae la responsabilidad de devolver a \u00abRobocop\u00bb al cine. Es Jos\u00e9 Padilha, y no le teme a su juguete de 100<\/p>\n","protected":false},"author":1,"featured_media":2585,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-2584","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los \u00c1ngeles (EE.UU.), 1 feb (EFE).- Reclinado sobre un sof\u00e1 se encuentra un hombre afable, cercano y ataviado con una gorra que delata su admiraci\u00f3n por Rafael Nadal. Pasa inadvertido, pero sobre sus hombros recae la responsabilidad de devolver a &quot;Robocop&quot; al cine. Es Jos\u00e9 Padilha, y no le teme a su juguete de 100\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Jos\u00e9 Padilha, el hombre tras los 100 millones de d\u00f3lares del nuevo \u00abRobocop\u00bb | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Los \u00c1ngeles (EE.UU.), 1 feb (EFE).- Reclinado sobre un sof\u00e1 se encuentra un hombre afable, cercano y ataviado con una gorra que delata su admiraci\u00f3n por Rafael Nadal. Pasa inadvertido, pero sobre sus hombros recae la responsabilidad de devolver a &quot;Robocop&quot; al cine. Es Jos\u00e9 Padilha, y no le teme a su juguete de 100\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899643w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899643w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"532\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-01T19:09:52+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-01T19:09:52+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Jos\u00e9 Padilha, el hombre tras los 100 millones de d\u00f3lares del nuevo \u00abRobocop\u00bb | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los \u00c1ngeles (EE.UU.), 1 feb (EFE).- Reclinado sobre un sof\u00e1 se encuentra un hombre afable, cercano y ataviado con una gorra que delata su admiraci\u00f3n por Rafael Nadal. Pasa inadvertido, pero sobre sus hombros recae la responsabilidad de devolver a &quot;Robocop&quot; al cine. Es Jos\u00e9 Padilha, y no le teme a su juguete de 100\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899643w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\\\/#article\",\"name\":\"Jos\\u00e9 Padilha, el hombre tras los 100 millones de d\\u00f3lares del nuevo \\u00abRobocop\\u00bb | El Digital de Asturias\",\"headline\":\"Jos\\u00e9 Padilha, el hombre tras los 100 millones de d\\u00f3lares del nuevo \\u00abRobocop\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5899643w.jpg\",\"width\":800,\"height\":532},\"datePublished\":\"2014-02-01T18:09:52+01:00\",\"dateModified\":\"2014-02-01T18:09:52+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\\\/#listItem\",\"name\":\"Jos\\u00e9 Padilha, el hombre tras los 100 millones de d\\u00f3lares del nuevo \\u00abRobocop\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\\\/#listItem\",\"position\":3,\"name\":\"Jos\\u00e9 Padilha, el hombre tras los 100 millones de d\\u00f3lares del nuevo \\u00abRobocop\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\\\/\",\"name\":\"Jos\\u00e9 Padilha, el hombre tras los 100 millones de d\\u00f3lares del nuevo \\u00abRobocop\\u00bb | El Digital de Asturias\",\"description\":\"Los \\u00c1ngeles (EE.UU.), 1 feb (EFE).- Reclinado sobre un sof\\u00e1 se encuentra un hombre afable, cercano y ataviado con una gorra que delata su admiraci\\u00f3n por Rafael Nadal. Pasa inadvertido, pero sobre sus hombros recae la responsabilidad de devolver a \\\"Robocop\\\" al cine. Es Jos\\u00e9 Padilha, y no le teme a su juguete de 100\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5899643w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\\\/#mainImage\",\"width\":800,\"height\":532},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\\\/#mainImage\"},\"datePublished\":\"2014-02-01T18:09:52+01:00\",\"dateModified\":\"2014-02-01T18:09:52+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Jos\u00e9 Padilha, el hombre tras los 100 millones de d\u00f3lares del nuevo \u00abRobocop\u00bb | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Jos\u00e9 Padilha, el hombre tras los 100 millones de d\u00f3lares del nuevo \u00abRobocop\u00bb | El Digital de Asturias","description":"Los \u00c1ngeles (EE.UU.), 1 feb (EFE).- Reclinado sobre un sof\u00e1 se encuentra un hombre afable, cercano y ataviado con una gorra que delata su admiraci\u00f3n por Rafael Nadal. Pasa inadvertido, pero sobre sus hombros recae la responsabilidad de devolver a \"Robocop\" al cine. Es Jos\u00e9 Padilha, y no le teme a su juguete de 100","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/#article","name":"Jos\u00e9 Padilha, el hombre tras los 100 millones de d\u00f3lares del nuevo \u00abRobocop\u00bb | El Digital de Asturias","headline":"Jos\u00e9 Padilha, el hombre tras los 100 millones de d\u00f3lares del nuevo \u00abRobocop\u00bb","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899643w.jpg","width":800,"height":532},"datePublished":"2014-02-01T18:09:52+01:00","dateModified":"2014-02-01T18:09:52+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/#listItem","name":"Jos\u00e9 Padilha, el hombre tras los 100 millones de d\u00f3lares del nuevo \u00abRobocop\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/#listItem","position":3,"name":"Jos\u00e9 Padilha, el hombre tras los 100 millones de d\u00f3lares del nuevo \u00abRobocop\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/","name":"Jos\u00e9 Padilha, el hombre tras los 100 millones de d\u00f3lares del nuevo \u00abRobocop\u00bb | El Digital de Asturias","description":"Los \u00c1ngeles (EE.UU.), 1 feb (EFE).- Reclinado sobre un sof\u00e1 se encuentra un hombre afable, cercano y ataviado con una gorra que delata su admiraci\u00f3n por Rafael Nadal. Pasa inadvertido, pero sobre sus hombros recae la responsabilidad de devolver a \"Robocop\" al cine. Es Jos\u00e9 Padilha, y no le teme a su juguete de 100","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899643w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/#mainImage","width":800,"height":532},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/#mainImage"},"datePublished":"2014-02-01T18:09:52+01:00","dateModified":"2014-02-01T18:09:52+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Jos\u00e9 Padilha, el hombre tras los 100 millones de d\u00f3lares del nuevo \u00abRobocop\u00bb | El Digital de Asturias","og:description":"Los \u00c1ngeles (EE.UU.), 1 feb (EFE).- Reclinado sobre un sof\u00e1 se encuentra un hombre afable, cercano y ataviado con una gorra que delata su admiraci\u00f3n por Rafael Nadal. Pasa inadvertido, pero sobre sus hombros recae la responsabilidad de devolver a &quot;Robocop&quot; al cine. Es Jos\u00e9 Padilha, y no le teme a su juguete de 100","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899643w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899643w.jpg","og:image:width":800,"og:image:height":532,"article:published_time":"2014-02-01T19:09:52+00:00","article:modified_time":"2014-02-01T19:09:52+00:00","twitter:card":"summary_large_image","twitter:title":"Jos\u00e9 Padilha, el hombre tras los 100 millones de d\u00f3lares del nuevo \u00abRobocop\u00bb | El Digital de Asturias","twitter:description":"Los \u00c1ngeles (EE.UU.), 1 feb (EFE).- Reclinado sobre un sof\u00e1 se encuentra un hombre afable, cercano y ataviado con una gorra que delata su admiraci\u00f3n por Rafael Nadal. Pasa inadvertido, pero sobre sus hombros recae la responsabilidad de devolver a &quot;Robocop&quot; al cine. Es Jos\u00e9 Padilha, y no le teme a su juguete de 100","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899643w.jpg"},"aioseo_meta_data":{"post_id":"2584","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 08:09:01","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:43:45","updated":"2026-05-15 08:09:01"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/\" title=\"Jos\u00e9 Padilha, el hombre tras los 100 millones de d\u00f3lares del nuevo \u00abRobocop\u00bb\">Jos\u00e9 Padilha, el hombre tras los 100 millones de d\u00f3lares del nuevo \u00abRobocop\u00bb<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Jos\u00e9 Padilha, el hombre tras los 100 millones de d\u00f3lares del nuevo \u00abRobocop\u00bb","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/jose-padilha-el-hombre-tras-los-100-millones-de-dolares-del-nuevo-robocop\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/2584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=2584"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/2584\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/2585"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=2584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=2584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=2584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}