{"id":2578,"date":"2014-02-01T17:33:13","date_gmt":"2014-02-01T18:33:13","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=2578"},"modified":"2014-02-01T17:33:13","modified_gmt":"2014-02-01T18:33:13","slug":"ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/","title":{"rendered":"Ken Loach duda de tener fuerzas para dirigir m\u00e1s pel\u00edculas"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-2579\" alt=\"5899445w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899445w-360x228.jpg\" width=\"360\" height=\"228\" \/>Berl\u00edn, 1 feb (EFE).- El director de cine brit\u00e1nico Ken Loach, que ser\u00e1 homenajeado con el Oso de Oro honor\u00edfico este a\u00f1o en la Berlinale, duda a sus 77 a\u00f1os de tener fuerza suficiente para rodar mas pel\u00edculas.<\/p>\n<p>En una entrevista con el diario alem\u00e1n \u00abPotsdamer Neuesten Nachrichten\u00bb, Loach destaca el esfuerzo y la energ\u00eda que exigen las largas jornadas de trabajo.<\/p>\n<p>\u00abNo s\u00e9 si conseguir\u00e9 de nuevo reunir las fuerzas necesarias\u00bb, se\u00f1ala el director, que se encuentra en estos momentos inmerso en su \u00faltima pel\u00edcula, \u00abJimmy&#8217;s Hall\u00bb.<\/p>\n<p>Su extensa y fruct\u00edfera carrera ser\u00e1 galardonada este a\u00f1o por el Festival de Cine Internacional de Berl\u00edn, que comienza el jueves en la capital alemana.<\/p>\n<p>Adem\u00e1s de entregarle el Oso de Oro honor\u00edfico, la Berlinale exhibir\u00e1 una selecci\u00f3n de diez de sus cintas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 1 feb (EFE).- El director de cine brit\u00e1nico Ken Loach, que ser\u00e1 homenajeado con el Oso de Oro honor\u00edfico este a\u00f1o en la Berlinale, duda a sus 77 a\u00f1os de tener fuerza suficiente para rodar mas pel\u00edculas. En una entrevista con el diario alem\u00e1n \u00abPotsdamer Neuesten Nachrichten\u00bb, Loach destaca el esfuerzo y la energ\u00eda<\/p>\n","protected":false},"author":1,"featured_media":2579,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-2578","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 1 feb (EFE).- El director de cine brit\u00e1nico Ken Loach, que ser\u00e1 homenajeado con el Oso de Oro honor\u00edfico este a\u00f1o en la Berlinale, duda a sus 77 a\u00f1os de tener fuerza suficiente para rodar mas pel\u00edculas. En una entrevista con el diario alem\u00e1n \u00abPotsdamer Neuesten Nachrichten\u00bb, Loach destaca el esfuerzo y la energ\u00eda\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ken Loach duda de tener fuerzas para dirigir m\u00e1s pel\u00edculas | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 1 feb (EFE).- El director de cine brit\u00e1nico Ken Loach, que ser\u00e1 homenajeado con el Oso de Oro honor\u00edfico este a\u00f1o en la Berlinale, duda a sus 77 a\u00f1os de tener fuerza suficiente para rodar mas pel\u00edculas. En una entrevista con el diario alem\u00e1n \u00abPotsdamer Neuesten Nachrichten\u00bb, Loach destaca el esfuerzo y la energ\u00eda\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899445w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899445w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"508\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-01T18:33:13+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-02-01T18:33:13+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ken Loach duda de tener fuerzas para dirigir m\u00e1s pel\u00edculas | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 1 feb (EFE).- El director de cine brit\u00e1nico Ken Loach, que ser\u00e1 homenajeado con el Oso de Oro honor\u00edfico este a\u00f1o en la Berlinale, duda a sus 77 a\u00f1os de tener fuerza suficiente para rodar mas pel\u00edculas. En una entrevista con el diario alem\u00e1n \u00abPotsdamer Neuesten Nachrichten\u00bb, Loach destaca el esfuerzo y la energ\u00eda\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899445w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\\\/#article\",\"name\":\"Ken Loach duda de tener fuerzas para dirigir m\\u00e1s pel\\u00edculas | El Digital de Asturias\",\"headline\":\"Ken Loach duda de tener fuerzas para dirigir m\\u00e1s pel\\u00edculas\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5899445w.jpg\",\"width\":800,\"height\":508},\"datePublished\":\"2014-02-01T17:33:13+01:00\",\"dateModified\":\"2014-02-01T17:33:13+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\\\/#listItem\",\"name\":\"Ken Loach duda de tener fuerzas para dirigir m\\u00e1s pel\\u00edculas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\\\/#listItem\",\"position\":3,\"name\":\"Ken Loach duda de tener fuerzas para dirigir m\\u00e1s pel\\u00edculas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\\\/\",\"name\":\"Ken Loach duda de tener fuerzas para dirigir m\\u00e1s pel\\u00edculas | El Digital de Asturias\",\"description\":\"Berl\\u00edn, 1 feb (EFE).- El director de cine brit\\u00e1nico Ken Loach, que ser\\u00e1 homenajeado con el Oso de Oro honor\\u00edfico este a\\u00f1o en la Berlinale, duda a sus 77 a\\u00f1os de tener fuerza suficiente para rodar mas pel\\u00edculas. En una entrevista con el diario alem\\u00e1n \\u00abPotsdamer Neuesten Nachrichten\\u00bb, Loach destaca el esfuerzo y la energ\\u00eda\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/5899445w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\\\/#mainImage\",\"width\":800,\"height\":508},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\\\/#mainImage\"},\"datePublished\":\"2014-02-01T17:33:13+01:00\",\"dateModified\":\"2014-02-01T17:33:13+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Ken Loach duda de tener fuerzas para dirigir m\u00e1s pel\u00edculas | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Ken Loach duda de tener fuerzas para dirigir m\u00e1s pel\u00edculas | El Digital de Asturias","description":"Berl\u00edn, 1 feb (EFE).- El director de cine brit\u00e1nico Ken Loach, que ser\u00e1 homenajeado con el Oso de Oro honor\u00edfico este a\u00f1o en la Berlinale, duda a sus 77 a\u00f1os de tener fuerza suficiente para rodar mas pel\u00edculas. En una entrevista con el diario alem\u00e1n \u00abPotsdamer Neuesten Nachrichten\u00bb, Loach destaca el esfuerzo y la energ\u00eda","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/#article","name":"Ken Loach duda de tener fuerzas para dirigir m\u00e1s pel\u00edculas | El Digital de Asturias","headline":"Ken Loach duda de tener fuerzas para dirigir m\u00e1s pel\u00edculas","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899445w.jpg","width":800,"height":508},"datePublished":"2014-02-01T17:33:13+01:00","dateModified":"2014-02-01T17:33:13+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/#listItem","name":"Ken Loach duda de tener fuerzas para dirigir m\u00e1s pel\u00edculas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/#listItem","position":3,"name":"Ken Loach duda de tener fuerzas para dirigir m\u00e1s pel\u00edculas","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/","name":"Ken Loach duda de tener fuerzas para dirigir m\u00e1s pel\u00edculas | El Digital de Asturias","description":"Berl\u00edn, 1 feb (EFE).- El director de cine brit\u00e1nico Ken Loach, que ser\u00e1 homenajeado con el Oso de Oro honor\u00edfico este a\u00f1o en la Berlinale, duda a sus 77 a\u00f1os de tener fuerza suficiente para rodar mas pel\u00edculas. En una entrevista con el diario alem\u00e1n \u00abPotsdamer Neuesten Nachrichten\u00bb, Loach destaca el esfuerzo y la energ\u00eda","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899445w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/#mainImage","width":800,"height":508},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/#mainImage"},"datePublished":"2014-02-01T17:33:13+01:00","dateModified":"2014-02-01T17:33:13+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Ken Loach duda de tener fuerzas para dirigir m\u00e1s pel\u00edculas | El Digital de Asturias","og:description":"Berl\u00edn, 1 feb (EFE).- El director de cine brit\u00e1nico Ken Loach, que ser\u00e1 homenajeado con el Oso de Oro honor\u00edfico este a\u00f1o en la Berlinale, duda a sus 77 a\u00f1os de tener fuerza suficiente para rodar mas pel\u00edculas. En una entrevista con el diario alem\u00e1n \u00abPotsdamer Neuesten Nachrichten\u00bb, Loach destaca el esfuerzo y la energ\u00eda","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899445w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899445w.jpg","og:image:width":800,"og:image:height":508,"article:published_time":"2014-02-01T18:33:13+00:00","article:modified_time":"2014-02-01T18:33:13+00:00","twitter:card":"summary_large_image","twitter:title":"Ken Loach duda de tener fuerzas para dirigir m\u00e1s pel\u00edculas | El Digital de Asturias","twitter:description":"Berl\u00edn, 1 feb (EFE).- El director de cine brit\u00e1nico Ken Loach, que ser\u00e1 homenajeado con el Oso de Oro honor\u00edfico este a\u00f1o en la Berlinale, duda a sus 77 a\u00f1os de tener fuerza suficiente para rodar mas pel\u00edculas. En una entrevista con el diario alem\u00e1n \u00abPotsdamer Neuesten Nachrichten\u00bb, Loach destaca el esfuerzo y la energ\u00eda","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/02\/5899445w.jpg"},"aioseo_meta_data":{"post_id":"2578","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 08:08:58","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:43:44","updated":"2026-05-15 08:08:58"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/\" title=\"Ken Loach duda de tener fuerzas para dirigir m\u00e1s pel\u00edculas\">Ken Loach duda de tener fuerzas para dirigir m\u00e1s pel\u00edculas<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Ken Loach duda de tener fuerzas para dirigir m\u00e1s pel\u00edculas","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/ken-loach-duda-de-tener-fuerzas-para-dirigir-mas-peliculas\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/2578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=2578"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/2578\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/2579"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=2578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=2578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=2578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}