{"id":25257,"date":"2014-09-23T17:32:17","date_gmt":"2014-09-23T19:32:17","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=25257"},"modified":"2014-09-23T17:32:17","modified_gmt":"2014-09-23T19:32:17","slug":"los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/","title":{"rendered":"Los hoteles andaluces logran un m\u00e1ximo hist\u00f3rico en agosto en pernoctaciones"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-25258\" alt=\"6673579w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/09\/6673579w-360x227.jpg\" width=\"360\" height=\"227\" \/>Sevilla, 23 sep (EFE).- Los establecimientos hoteleros de Andaluc\u00eda registraron cerca de 6,8 millones de pernoctaciones en agosto, lo que supone el m\u00e1ximo hist\u00f3rico en este mes al superar en un 4,5 % al mismo periodo de 2013, que marcaba el tope hasta ahora.<\/p>\n<p>Seg\u00fan los datos hechos p\u00fablicos hoy por el Instituto Nacional de Estad\u00edstica, los hoteles andaluces recibieron en agosto 1,9 millones de viajeros, un 4,7 % m\u00e1s que en el mismo mes del 2013, con incrementos del 3,6 % en los turistas nacionales y del 6,7 % en los extranjeros.<\/p>\n<p>El mercado nacional, primer emisor de viajeros para Andaluc\u00eda, sum\u00f3 cerca de 6,3 millones de viajeros y 16,6 millones de pernoctaciones, lo que supone aumentos del 3,6 % y del 4,3 %, respectivamente.<\/p>\n<p>Por su parte, los 4,5 millones de turistas extranjeros alojados (3,2 %) realizaron 15 millones de estancias (3,5 %).<\/p>\n<p>Tras publicarse estos datos oficiales, el consejero de Turismo y Comercio, Rafael Rodr\u00edguez, ha subrayado que \u00abAndaluc\u00eda muestra la vitalidad de su industria tur\u00edstica, el enorme atractivo de su oferta y la competitividad del conjunto del destino\u00bb, ha informado en un comunicado su departamento.<\/p>\n<p>El empleo en el sector tambi\u00e9n experiment\u00f3 un crecimiento en agosto del 3,7 % y de 40.664 trabajadores en establecimientos hoteleros, y en el periodo enero-agosto subi\u00f3 un 2,3 % y una media de 30.315 personas empleadas.<\/p>\n<p>El crecimiento de pernoctaciones fue generalizado en el conjunto de la comunidad, ya que todas las provincias andaluzas mostraron incrementos de estancias y destacan Sevilla ( 20,2 %), Granada (13 %) y C\u00f3rdoba (9,6 %).<\/p>\n<p>Las que mayor cuota de estancias registraron fueron M\u00e1laga (38,7 %), C\u00e1diz (17,8 %) y Almer\u00eda (14,6 %).<\/p>\n<p>Asimismo, entre enero y agosto los hoteles andaluces sumaron 10,7 millones de viajeros alojados y 31,7 millones de pernoctaciones, lo que supone aumentos en relaci\u00f3n con el mismo periodo del pasado a\u00f1o del 3,4 % y del 3,9 %, respectivamente.<\/p>\n<p>El consejero ha valorado que el destino supera el r\u00e9cord hist\u00f3rico de estancias hoteleras en los ocho primeros meses del ejercicio, que se manten\u00eda desde 2008, \u00absobrepasando as\u00ed los niveles previos a la crisis\u00bb, por lo que ha confiado en que esta tendencia se mantenga durante lo que resta de a\u00f1o.<\/p>\n<p>Andaluc\u00eda present\u00f3 una mejor evoluci\u00f3n en las estancias hoteleras que la media del pa\u00eds, tanto en agosto, con una subida del 4,5 % frente al 2,7 % nacional, como en los ocho primeros meses del a\u00f1o, con un 3,9 % m\u00e1s de pernoctaciones frente al incremento del 2,8 % en el conjunto de comunidades, seg\u00fan el comunicado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sevilla, 23 sep (EFE).- Los establecimientos hoteleros de Andaluc\u00eda registraron cerca de 6,8 millones de pernoctaciones en agosto, lo que supone el m\u00e1ximo hist\u00f3rico en este mes al superar en un 4,5 % al mismo periodo de 2013, que marcaba el tope hasta ahora. Seg\u00fan los datos hechos p\u00fablicos hoy por el Instituto Nacional de<\/p>\n","protected":false},"author":1,"featured_media":25258,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-25257","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-turismo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Sevilla, 23 sep (EFE).- Los establecimientos hoteleros de Andaluc\u00eda registraron cerca de 6,8 millones de pernoctaciones en agosto, lo que supone el m\u00e1ximo hist\u00f3rico en este mes al superar en un 4,5 % al mismo periodo de 2013, que marcaba el tope hasta ahora. Seg\u00fan los datos hechos p\u00fablicos hoy por el Instituto Nacional de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"actualidad turismo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los hoteles andaluces logran un m\u00e1ximo hist\u00f3rico en agosto en pernoctaciones | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Sevilla, 23 sep (EFE).- Los establecimientos hoteleros de Andaluc\u00eda registraron cerca de 6,8 millones de pernoctaciones en agosto, lo que supone el m\u00e1ximo hist\u00f3rico en este mes al superar en un 4,5 % al mismo periodo de 2013, que marcaba el tope hasta ahora. Seg\u00fan los datos hechos p\u00fablicos hoy por el Instituto Nacional de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/09\/6673579w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/09\/6673579w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-09-23T19:32:17+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-09-23T19:32:17+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los hoteles andaluces logran un m\u00e1ximo hist\u00f3rico en agosto en pernoctaciones | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Sevilla, 23 sep (EFE).- Los establecimientos hoteleros de Andaluc\u00eda registraron cerca de 6,8 millones de pernoctaciones en agosto, lo que supone el m\u00e1ximo hist\u00f3rico en este mes al superar en un 4,5 % al mismo periodo de 2013, que marcaba el tope hasta ahora. Seg\u00fan los datos hechos p\u00fablicos hoy por el Instituto Nacional de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/09\/6673579w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\\\/#article\",\"name\":\"Los hoteles andaluces logran un m\\u00e1ximo hist\\u00f3rico en agosto en pernoctaciones | El Digital de Asturias\",\"headline\":\"Los hoteles andaluces logran un m\\u00e1ximo hist\\u00f3rico en agosto en pernoctaciones\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/6673579w.jpg\",\"width\":800,\"height\":506},\"datePublished\":\"2014-09-23T17:32:17+02:00\",\"dateModified\":\"2014-09-23T17:32:17+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\\\/#webpage\"},\"articleSection\":\"Actualidad Turismo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Turismo\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\\\/#listItem\",\"name\":\"Los hoteles andaluces logran un m\\u00e1ximo hist\\u00f3rico en agosto en pernoctaciones\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\\\/#listItem\",\"position\":3,\"name\":\"Los hoteles andaluces logran un m\\u00e1ximo hist\\u00f3rico en agosto en pernoctaciones\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/actualidad-turismo\\\/#listItem\",\"name\":\"Actualidad Turismo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\\\/\",\"name\":\"Los hoteles andaluces logran un m\\u00e1ximo hist\\u00f3rico en agosto en pernoctaciones | El Digital de Asturias\",\"description\":\"Sevilla, 23 sep (EFE).- Los establecimientos hoteleros de Andaluc\\u00eda registraron cerca de 6,8 millones de pernoctaciones en agosto, lo que supone el m\\u00e1ximo hist\\u00f3rico en este mes al superar en un 4,5 % al mismo periodo de 2013, que marcaba el tope hasta ahora. Seg\\u00fan los datos hechos p\\u00fablicos hoy por el Instituto Nacional de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/6673579w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\\\/#mainImage\",\"width\":800,\"height\":506},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\\\/#mainImage\"},\"datePublished\":\"2014-09-23T17:32:17+02:00\",\"dateModified\":\"2014-09-23T17:32:17+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Los hoteles andaluces logran un m\u00e1ximo hist\u00f3rico en agosto en pernoctaciones | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Los hoteles andaluces logran un m\u00e1ximo hist\u00f3rico en agosto en pernoctaciones | El Digital de Asturias","description":"Sevilla, 23 sep (EFE).- Los establecimientos hoteleros de Andaluc\u00eda registraron cerca de 6,8 millones de pernoctaciones en agosto, lo que supone el m\u00e1ximo hist\u00f3rico en este mes al superar en un 4,5 % al mismo periodo de 2013, que marcaba el tope hasta ahora. Seg\u00fan los datos hechos p\u00fablicos hoy por el Instituto Nacional de","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/","robots":"max-image-preview:large","keywords":"actualidad turismo","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/#article","name":"Los hoteles andaluces logran un m\u00e1ximo hist\u00f3rico en agosto en pernoctaciones | El Digital de Asturias","headline":"Los hoteles andaluces logran un m\u00e1ximo hist\u00f3rico en agosto en pernoctaciones","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/09\/6673579w.jpg","width":800,"height":506},"datePublished":"2014-09-23T17:32:17+02:00","dateModified":"2014-09-23T17:32:17+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/#webpage"},"articleSection":"Actualidad Turismo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","position":2,"name":"Actualidad Turismo","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/#listItem","name":"Los hoteles andaluces logran un m\u00e1ximo hist\u00f3rico en agosto en pernoctaciones"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/#listItem","position":3,"name":"Los hoteles andaluces logran un m\u00e1ximo hist\u00f3rico en agosto en pernoctaciones","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/#listItem","name":"Actualidad Turismo"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/","name":"Los hoteles andaluces logran un m\u00e1ximo hist\u00f3rico en agosto en pernoctaciones | El Digital de Asturias","description":"Sevilla, 23 sep (EFE).- Los establecimientos hoteleros de Andaluc\u00eda registraron cerca de 6,8 millones de pernoctaciones en agosto, lo que supone el m\u00e1ximo hist\u00f3rico en este mes al superar en un 4,5 % al mismo periodo de 2013, que marcaba el tope hasta ahora. Seg\u00fan los datos hechos p\u00fablicos hoy por el Instituto Nacional de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/09\/6673579w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/#mainImage","width":800,"height":506},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/#mainImage"},"datePublished":"2014-09-23T17:32:17+02:00","dateModified":"2014-09-23T17:32:17+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Los hoteles andaluces logran un m\u00e1ximo hist\u00f3rico en agosto en pernoctaciones | El Digital de Asturias","og:description":"Sevilla, 23 sep (EFE).- Los establecimientos hoteleros de Andaluc\u00eda registraron cerca de 6,8 millones de pernoctaciones en agosto, lo que supone el m\u00e1ximo hist\u00f3rico en este mes al superar en un 4,5 % al mismo periodo de 2013, que marcaba el tope hasta ahora. Seg\u00fan los datos hechos p\u00fablicos hoy por el Instituto Nacional de","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/09\/6673579w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/09\/6673579w.jpg","og:image:width":800,"og:image:height":506,"article:published_time":"2014-09-23T19:32:17+00:00","article:modified_time":"2014-09-23T19:32:17+00:00","twitter:card":"summary_large_image","twitter:title":"Los hoteles andaluces logran un m\u00e1ximo hist\u00f3rico en agosto en pernoctaciones | El Digital de Asturias","twitter:description":"Sevilla, 23 sep (EFE).- Los establecimientos hoteleros de Andaluc\u00eda registraron cerca de 6,8 millones de pernoctaciones en agosto, lo que supone el m\u00e1ximo hist\u00f3rico en este mes al superar en un 4,5 % al mismo periodo de 2013, que marcaba el tope hasta ahora. Seg\u00fan los datos hechos p\u00fablicos hoy por el Instituto Nacional de","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/09\/6673579w.jpg"},"aioseo_meta_data":{"post_id":"25257","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-17 10:02:59","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 05:48:12","updated":"2026-05-17 10:02:59"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/\" title=\"Actualidad Turismo\">Actualidad Turismo<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/\" title=\"Los hoteles andaluces logran un m\u00e1ximo hist\u00f3rico en agosto en pernoctaciones\">Los hoteles andaluces logran un m\u00e1ximo hist\u00f3rico en agosto en pernoctaciones<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Actualidad Turismo","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/actualidad-turismo\/"},{"label":"Los hoteles andaluces logran un m\u00e1ximo hist\u00f3rico en agosto en pernoctaciones","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/los-hoteles-andaluces-logran-un-maximo-historico-en-agosto-en-pernoctaciones\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/25257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=25257"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/25257\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/25258"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=25257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=25257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=25257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}