{"id":2493,"date":"2014-01-31T17:13:09","date_gmt":"2014-01-31T18:13:09","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=2493"},"modified":"2014-01-31T17:13:09","modified_gmt":"2014-01-31T18:13:09","slug":"pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/","title":{"rendered":"Pilar Bardem, presidenta de Aisge afirma que \u00abhay 364 noches al a\u00f1o sin alfombra roja\u00bb"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-2494\" alt=\"5896188w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5896188w-360x241.jpg\" width=\"360\" height=\"241\" \/>Madrid, 31 ene (EFE).- La presidenta de Aisge, Pilar Bardem, ha mostrado su preocupaci\u00f3n por el \u00edndice de precariedad que sufren los actores espa\u00f1oles, que apunta a que el 72,9 por ciento de ellos no pueden vivir exclusivamente de su trabajo, y por la alt\u00edsima tasa de desempleo que sufren: el 65 % no lo logra m\u00e1s de tres meses al a\u00f1o.<\/p>\n<p>\u00abHay 364 noches al a\u00f1o sin alfombra roja\u00bb, ha dicho la veterana actriz, presidenta de la sociedad de gesti\u00f3n de derechos de autor en la presentaci\u00f3n de las principales conclusiones del informe, realizado por la Fundaci\u00f3n Aisge sobre la situaci\u00f3n sociolaboral de actores y bailarines de Espa\u00f1a, sobre 1.201 encuestas realizadas en 2012.<\/p>\n<p>Bardem hizo notar que las cifras del informe son \u00abrigurosas y elocuentes\u00bb y reclam\u00f3 \u00aba la sociedad en general\u00bb, y tambi\u00e9n a las administraciones p\u00fablicas, que \u00abcomprendan mejor las singularidades de un oficio hermos\u00edsimo, pero no exento ni un solo d\u00eda de grandes dificultades\u00bb.<\/p>\n<p>La presidenta record\u00f3 que, siempre a principios de a\u00f1o, los actores celebran un mont\u00f3n de eventos en los que diversos colectivos premian su trabajo: los premios Forqu\u00e9, los Asecan de Andaluc\u00eda, los Gaud\u00ed, las medallas del CEC, los Goya y ahora -destac\u00f3 Bardem- los nuevos premios Feroz, \u00abinstaurados con saludable af\u00e1n transgresor y a los que les deseamos longevidad\u00bb.<\/p>\n<p>\u00abTodo ello es muy saludable: convertimos al cine en protagonista, promocionamos las mejores obras de cada temporada y reconocemos el trabajo de los compa\u00f1eros y compa\u00f1eras m\u00e1s inspirados. Pero este diagn\u00f3stico -advierte- sirve para recordarnos la realidad cotidiana: la de esas 364 noches al a\u00f1o en las que no desfilamos por la alfombra roja\u00bb.<\/p>\n<p>En su opini\u00f3n, \u00abconviene\u00bb que esa realidad la conozca todo el mundo, desde los compa\u00f1eros a la opini\u00f3n p\u00fablica y, \u00abpor supuesto -a\u00f1ade-, todas esas administraciones en las que los pol\u00edticos pueden confundir, por falta de informaci\u00f3n (o, en el caso del ministro Montoro, por mala fe), el glamur de una gala con los supuestos privilegios de una profesi\u00f3n que pasa por momentos delicados\u00bb.<\/p>\n<p>La ganadora de un Goya por \u00abNadie hablar\u00e1 de nosotras cuando hayamos muerto\u00bb ha insistido en la gravedad que refleja el informe: 7 de cada 10 actores no pueden vivir solo de este trabajo, y m\u00e1s de la mitad de ellos obtienen unos ingresos mensuales por debajo del salario m\u00ednimo interprofesional.<\/p>\n<p>Asimismo, ha destacado que la encuesta, realizada entre 729 actores, 356 actores de voz (dobladores) y 117 bailarines, demuestra c\u00f3mo \u00ablas incertidumbres propias\u00bb del oficio interpretativo \u00abse han agravado sensiblemente\u00bb con la crisis econ\u00f3mica, y los actores tienen \u00abmenos oportunidades\u00bb de trabajar. Cuando lo logran, suele ser \u00aben peores condiciones\u00bb que en a\u00f1os precedentes.<\/p>\n<p>\u00abPoco podemos aportar frente a unos n\u00fameros tan llamativos: las cifras hablan por s\u00ed solas\u00bb, ha resumido la presidenta de la entidad de gesti\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 31 ene (EFE).- La presidenta de Aisge, Pilar Bardem, ha mostrado su preocupaci\u00f3n por el \u00edndice de precariedad que sufren los actores espa\u00f1oles, que apunta a que el 72,9 por ciento de ellos no pueden vivir exclusivamente de su trabajo, y por la alt\u00edsima tasa de desempleo que sufren: el 65 % no lo<\/p>\n","protected":false},"author":1,"featured_media":2494,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-2493","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 31 ene (EFE).- La presidenta de Aisge, Pilar Bardem, ha mostrado su preocupaci\u00f3n por el \u00edndice de precariedad que sufren los actores espa\u00f1oles, que apunta a que el 72,9 por ciento de ellos no pueden vivir exclusivamente de su trabajo, y por la alt\u00edsima tasa de desempleo que sufren: el 65 % no lo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pilar Bardem, presidenta de Aisge afirma que \u00abhay 364 noches al a\u00f1o sin alfombra roja\u00bb | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 31 ene (EFE).- La presidenta de Aisge, Pilar Bardem, ha mostrado su preocupaci\u00f3n por el \u00edndice de precariedad que sufren los actores espa\u00f1oles, que apunta a que el 72,9 por ciento de ellos no pueden vivir exclusivamente de su trabajo, y por la alt\u00edsima tasa de desempleo que sufren: el 65 % no lo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5896188w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5896188w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"537\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-01-31T18:13:09+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-01-31T18:13:09+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pilar Bardem, presidenta de Aisge afirma que \u00abhay 364 noches al a\u00f1o sin alfombra roja\u00bb | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 31 ene (EFE).- La presidenta de Aisge, Pilar Bardem, ha mostrado su preocupaci\u00f3n por el \u00edndice de precariedad que sufren los actores espa\u00f1oles, que apunta a que el 72,9 por ciento de ellos no pueden vivir exclusivamente de su trabajo, y por la alt\u00edsima tasa de desempleo que sufren: el 65 % no lo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5896188w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\\\/#article\",\"name\":\"Pilar Bardem, presidenta de Aisge afirma que \\u00abhay 364 noches al a\\u00f1o sin alfombra roja\\u00bb | El Digital de Asturias\",\"headline\":\"Pilar Bardem, presidenta de Aisge afirma que \\u00abhay 364 noches al a\\u00f1o sin alfombra roja\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/5896188w.jpg\",\"width\":800,\"height\":537},\"datePublished\":\"2014-01-31T17:13:09+01:00\",\"dateModified\":\"2014-01-31T17:13:09+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\\\/#listItem\",\"name\":\"Pilar Bardem, presidenta de Aisge afirma que \\u00abhay 364 noches al a\\u00f1o sin alfombra roja\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\\\/#listItem\",\"position\":3,\"name\":\"Pilar Bardem, presidenta de Aisge afirma que \\u00abhay 364 noches al a\\u00f1o sin alfombra roja\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\\\/\",\"name\":\"Pilar Bardem, presidenta de Aisge afirma que \\u00abhay 364 noches al a\\u00f1o sin alfombra roja\\u00bb | El Digital de Asturias\",\"description\":\"Madrid, 31 ene (EFE).- La presidenta de Aisge, Pilar Bardem, ha mostrado su preocupaci\\u00f3n por el \\u00edndice de precariedad que sufren los actores espa\\u00f1oles, que apunta a que el 72,9 por ciento de ellos no pueden vivir exclusivamente de su trabajo, y por la alt\\u00edsima tasa de desempleo que sufren: el 65 % no lo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/5896188w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\\\/#mainImage\",\"width\":800,\"height\":537},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\\\/#mainImage\"},\"datePublished\":\"2014-01-31T17:13:09+01:00\",\"dateModified\":\"2014-01-31T17:13:09+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Pilar Bardem, presidenta de Aisge afirma que \u00abhay 364 noches al a\u00f1o sin alfombra roja\u00bb | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Pilar Bardem, presidenta de Aisge afirma que \u00abhay 364 noches al a\u00f1o sin alfombra roja\u00bb | El Digital de Asturias","description":"Madrid, 31 ene (EFE).- La presidenta de Aisge, Pilar Bardem, ha mostrado su preocupaci\u00f3n por el \u00edndice de precariedad que sufren los actores espa\u00f1oles, que apunta a que el 72,9 por ciento de ellos no pueden vivir exclusivamente de su trabajo, y por la alt\u00edsima tasa de desempleo que sufren: el 65 % no lo","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/#article","name":"Pilar Bardem, presidenta de Aisge afirma que \u00abhay 364 noches al a\u00f1o sin alfombra roja\u00bb | El Digital de Asturias","headline":"Pilar Bardem, presidenta de Aisge afirma que \u00abhay 364 noches al a\u00f1o sin alfombra roja\u00bb","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5896188w.jpg","width":800,"height":537},"datePublished":"2014-01-31T17:13:09+01:00","dateModified":"2014-01-31T17:13:09+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/#listItem","name":"Pilar Bardem, presidenta de Aisge afirma que \u00abhay 364 noches al a\u00f1o sin alfombra roja\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/#listItem","position":3,"name":"Pilar Bardem, presidenta de Aisge afirma que \u00abhay 364 noches al a\u00f1o sin alfombra roja\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/","name":"Pilar Bardem, presidenta de Aisge afirma que \u00abhay 364 noches al a\u00f1o sin alfombra roja\u00bb | El Digital de Asturias","description":"Madrid, 31 ene (EFE).- La presidenta de Aisge, Pilar Bardem, ha mostrado su preocupaci\u00f3n por el \u00edndice de precariedad que sufren los actores espa\u00f1oles, que apunta a que el 72,9 por ciento de ellos no pueden vivir exclusivamente de su trabajo, y por la alt\u00edsima tasa de desempleo que sufren: el 65 % no lo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5896188w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/#mainImage","width":800,"height":537},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/#mainImage"},"datePublished":"2014-01-31T17:13:09+01:00","dateModified":"2014-01-31T17:13:09+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Pilar Bardem, presidenta de Aisge afirma que \u00abhay 364 noches al a\u00f1o sin alfombra roja\u00bb | El Digital de Asturias","og:description":"Madrid, 31 ene (EFE).- La presidenta de Aisge, Pilar Bardem, ha mostrado su preocupaci\u00f3n por el \u00edndice de precariedad que sufren los actores espa\u00f1oles, que apunta a que el 72,9 por ciento de ellos no pueden vivir exclusivamente de su trabajo, y por la alt\u00edsima tasa de desempleo que sufren: el 65 % no lo","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5896188w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5896188w.jpg","og:image:width":800,"og:image:height":537,"article:published_time":"2014-01-31T18:13:09+00:00","article:modified_time":"2014-01-31T18:13:09+00:00","twitter:card":"summary_large_image","twitter:title":"Pilar Bardem, presidenta de Aisge afirma que \u00abhay 364 noches al a\u00f1o sin alfombra roja\u00bb | El Digital de Asturias","twitter:description":"Madrid, 31 ene (EFE).- La presidenta de Aisge, Pilar Bardem, ha mostrado su preocupaci\u00f3n por el \u00edndice de precariedad que sufren los actores espa\u00f1oles, que apunta a que el 72,9 por ciento de ellos no pueden vivir exclusivamente de su trabajo, y por la alt\u00edsima tasa de desempleo que sufren: el 65 % no lo","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5896188w.jpg"},"aioseo_meta_data":{"post_id":"2493","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 07:58:13","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:43:39","updated":"2026-05-15 07:58:13"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/\" title=\"Pilar Bardem, presidenta de Aisge afirma que \u00abhay 364 noches al a\u00f1o sin alfombra roja\u00bb\">Pilar Bardem, presidenta de Aisge afirma que \u00abhay 364 noches al a\u00f1o sin alfombra roja\u00bb<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Pilar Bardem, presidenta de Aisge afirma que \u00abhay 364 noches al a\u00f1o sin alfombra roja\u00bb","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/pilar-bardem-presidenta-de-aisge-afirma-que-hay-364-noches-al-ano-sin-alfombra-roja\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/2493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=2493"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/2493\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/2494"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=2493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=2493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=2493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}