{"id":20841,"date":"2014-08-09T22:24:46","date_gmt":"2014-08-10T00:24:46","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=20841"},"modified":"2014-08-09T22:24:46","modified_gmt":"2014-08-10T00:24:46","slug":"las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/","title":{"rendered":"Las asociaciones donostiarras prenden la mecha de la Semana Grande"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-20842\" alt=\"6544952w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6544952w-360x243.jpg\" width=\"360\" height=\"243\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6544952w-360x243.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6544952w-650x440.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6544952w-768x519.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6544952w-150x101.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6544952w-450x304.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6544952w-696x471.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6544952w-621x420.jpg 621w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6544952w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>San Sebasti\u00e1n, 9 ago (EFE).- El gran ca\u00f1onazo disparado desde la terraza del Ayuntamiento, tras los sones del tradicional \u00abArtillero, dale fuego\u00bb entonado por un centenar de miembros de las 25 asociaciones que han participado en el programa festivo, ha protagonizado hoy el inicio de la Semana Grande donostiarra.<\/p>\n<p>El Ayuntamiento ha querido este a\u00f1o agradecer su labor a los ciudadanos comprometidos con la confecci\u00f3n de un programa de fiestas \u00abcada vez m\u00e1s participativo\u00bb, por lo que ha decidido que el protagonismo del arranque festivo recaiga en las 25 asociaciones que han colaborado activamente en el dise\u00f1o de los cientos de actividades que habr\u00e1 en San Sebasti\u00e1n hasta el pr\u00f3ximo 16 de agosto.<\/p>\n<p>Cuatro representantes de cada una de estas asociaciones, ataviados con las prendas propias de cada agrupaci\u00f3n, han ocupado el escenario en la terraza del Ayuntamiento, donde han celebrado con el canto del \u00abArtillero\u00bb, ante varios miles de donostiarras, el inicio de las fiestas estivales de la capital guipuzcoana.<\/p>\n<p>Patinadores, remeros, baloncestistas y representantes de todo tipo de actividades se han congregado en el escenario, donde han estado acompa\u00f1ados por concejales de todos los grupos municipales de la ciudad, que, con el pa\u00f1uelo azul al cuello, han cantado con ellos el \u00abArtillero\u00bb.<\/p>\n<p>Esta vez incluso se han animado a bailar la canci\u00f3n, lo que ha propiciado inesperados emparejamientos, como el protagonizado por la concejal del PP Mar\u00eda Jos\u00e9 Usandizaga y el alcalde, Juan Karlos Izagirre (Bildu), quienes han danzado agarrados.<\/p>\n<p>El alcalde, Juan Karlos Izagirre, se ha felicitado tras el ca\u00f1onazo de que la fiesta haya comenzado \u00absin lluvia\u00bb, en contra de lo pronosticado.<\/p>\n<p>El primer edil ha destacado que, por primera vez, ha sido una mujer la encargada de prender la mecha del ca\u00f1\u00f3n, lo que ha constituido \u00abun peque\u00f1o gesto\u00bb, tras lo que ha opinado que \u00abtodo lo que vaya en el camino a recorrer por la igualdad est\u00e1 bien hecho\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Sebasti\u00e1n, 9 ago (EFE).- El gran ca\u00f1onazo disparado desde la terraza del Ayuntamiento, tras los sones del tradicional \u00abArtillero, dale fuego\u00bb entonado por un centenar de miembros de las 25 asociaciones que han participado en el programa festivo, ha protagonizado hoy el inicio de la Semana Grande donostiarra. El Ayuntamiento ha querido este a\u00f1o<\/p>\n","protected":false},"author":1,"featured_media":20842,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":{"0":"post-20841","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-actualidad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"San Sebasti\u00e1n, 9 ago (EFE).- El gran ca\u00f1onazo disparado desde la terraza del Ayuntamiento, tras los sones del tradicional &quot;Artillero, dale fuego&quot; entonado por un centenar de miembros de las 25 asociaciones que han participado en el programa festivo, ha protagonizado hoy el inicio de la Semana Grande donostiarra. El Ayuntamiento ha querido este a\u00f1o\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Las asociaciones donostiarras prenden la mecha de la Semana Grande | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"San Sebasti\u00e1n, 9 ago (EFE).- El gran ca\u00f1onazo disparado desde la terraza del Ayuntamiento, tras los sones del tradicional &quot;Artillero, dale fuego&quot; entonado por un centenar de miembros de las 25 asociaciones que han participado en el programa festivo, ha protagonizado hoy el inicio de la Semana Grande donostiarra. El Ayuntamiento ha querido este a\u00f1o\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6544952w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6544952w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"541\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-08-10T00:24:46+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-08-10T00:24:46+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Las asociaciones donostiarras prenden la mecha de la Semana Grande | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"San Sebasti\u00e1n, 9 ago (EFE).- El gran ca\u00f1onazo disparado desde la terraza del Ayuntamiento, tras los sones del tradicional &quot;Artillero, dale fuego&quot; entonado por un centenar de miembros de las 25 asociaciones que han participado en el programa festivo, ha protagonizado hoy el inicio de la Semana Grande donostiarra. El Ayuntamiento ha querido este a\u00f1o\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6544952w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\\\/#article\",\"name\":\"Las asociaciones donostiarras prenden la mecha de la Semana Grande | El Digital de Asturias\",\"headline\":\"Las asociaciones donostiarras prenden la mecha de la Semana Grande\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/6544952w.jpg\",\"width\":800,\"height\":541},\"datePublished\":\"2014-08-09T22:24:46+02:00\",\"dateModified\":\"2014-08-09T22:24:46+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\\\/#listItem\",\"name\":\"Las asociaciones donostiarras prenden la mecha de la Semana Grande\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\\\/#listItem\",\"position\":3,\"name\":\"Las asociaciones donostiarras prenden la mecha de la Semana Grande\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\\\/\",\"name\":\"Las asociaciones donostiarras prenden la mecha de la Semana Grande | El Digital de Asturias\",\"description\":\"San Sebasti\\u00e1n, 9 ago (EFE).- El gran ca\\u00f1onazo disparado desde la terraza del Ayuntamiento, tras los sones del tradicional \\\"Artillero, dale fuego\\\" entonado por un centenar de miembros de las 25 asociaciones que han participado en el programa festivo, ha protagonizado hoy el inicio de la Semana Grande donostiarra. El Ayuntamiento ha querido este a\\u00f1o\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/6544952w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\\\/#mainImage\",\"width\":800,\"height\":541},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\\\/#mainImage\"},\"datePublished\":\"2014-08-09T22:24:46+02:00\",\"dateModified\":\"2014-08-09T22:24:46+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Las asociaciones donostiarras prenden la mecha de la Semana Grande | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Las asociaciones donostiarras prenden la mecha de la Semana Grande | El Digital de Asturias","description":"San Sebasti\u00e1n, 9 ago (EFE).- El gran ca\u00f1onazo disparado desde la terraza del Ayuntamiento, tras los sones del tradicional \"Artillero, dale fuego\" entonado por un centenar de miembros de las 25 asociaciones que han participado en el programa festivo, ha protagonizado hoy el inicio de la Semana Grande donostiarra. El Ayuntamiento ha querido este a\u00f1o","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/#article","name":"Las asociaciones donostiarras prenden la mecha de la Semana Grande | El Digital de Asturias","headline":"Las asociaciones donostiarras prenden la mecha de la Semana Grande","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6544952w.jpg","width":800,"height":541},"datePublished":"2014-08-09T22:24:46+02:00","dateModified":"2014-08-09T22:24:46+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/#listItem","name":"Las asociaciones donostiarras prenden la mecha de la Semana Grande"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/#listItem","position":3,"name":"Las asociaciones donostiarras prenden la mecha de la Semana Grande","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/","name":"Las asociaciones donostiarras prenden la mecha de la Semana Grande | El Digital de Asturias","description":"San Sebasti\u00e1n, 9 ago (EFE).- El gran ca\u00f1onazo disparado desde la terraza del Ayuntamiento, tras los sones del tradicional \"Artillero, dale fuego\" entonado por un centenar de miembros de las 25 asociaciones que han participado en el programa festivo, ha protagonizado hoy el inicio de la Semana Grande donostiarra. El Ayuntamiento ha querido este a\u00f1o","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6544952w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/#mainImage","width":800,"height":541},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/#mainImage"},"datePublished":"2014-08-09T22:24:46+02:00","dateModified":"2014-08-09T22:24:46+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Las asociaciones donostiarras prenden la mecha de la Semana Grande | El Digital de Asturias","og:description":"San Sebasti\u00e1n, 9 ago (EFE).- El gran ca\u00f1onazo disparado desde la terraza del Ayuntamiento, tras los sones del tradicional &quot;Artillero, dale fuego&quot; entonado por un centenar de miembros de las 25 asociaciones que han participado en el programa festivo, ha protagonizado hoy el inicio de la Semana Grande donostiarra. El Ayuntamiento ha querido este a\u00f1o","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6544952w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6544952w.jpg","og:image:width":800,"og:image:height":541,"article:published_time":"2014-08-10T00:24:46+00:00","article:modified_time":"2014-08-10T00:24:46+00:00","twitter:card":"summary_large_image","twitter:title":"Las asociaciones donostiarras prenden la mecha de la Semana Grande | El Digital de Asturias","twitter:description":"San Sebasti\u00e1n, 9 ago (EFE).- El gran ca\u00f1onazo disparado desde la terraza del Ayuntamiento, tras los sones del tradicional &quot;Artillero, dale fuego&quot; entonado por un centenar de miembros de las 25 asociaciones que han participado en el programa festivo, ha protagonizado hoy el inicio de la Semana Grande donostiarra. El Ayuntamiento ha querido este a\u00f1o","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6544952w.jpg"},"aioseo_meta_data":{"post_id":"20841","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-17 22:37:52","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 06:51:57","updated":"2025-09-17 22:37:52"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/\" title=\"Las asociaciones donostiarras prenden la mecha de la Semana Grande\">Las asociaciones donostiarras prenden la mecha de la Semana Grande<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Las asociaciones donostiarras prenden la mecha de la Semana Grande","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/las-asociaciones-donostiarras-prenden-la-mecha-de-la-semana-grande\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/20841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=20841"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/20841\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/20842"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=20841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=20841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=20841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}