{"id":20741,"date":"2014-08-08T23:07:08","date_gmt":"2014-08-09T01:07:08","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=20741"},"modified":"2014-08-08T23:07:08","modified_gmt":"2014-08-09T01:07:08","slug":"rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/","title":{"rendered":"Roc\u00edo M\u00e1rquez homenajea a los \u00abni\u00f1os\u00bb cantaores en la piel de Pepe Marchena"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-20742\" alt=\"6542479w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6542479w-360x250.jpg\" width=\"360\" height=\"250\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6542479w-360x250.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6542479w-650x452.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6542479w-768x534.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6542479w-150x104.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6542479w-450x313.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6542479w-100x70.jpg 100w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6542479w-218x150.jpg 218w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6542479w-696x484.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6542479w-604x420.jpg 604w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6542479w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Madrid, 8 ago (EFE).- Hubo una \u00e9poca en Espa\u00f1a en la que los cantaores empezaban a actuar siendo adolescentes, as\u00ed que \u00ablo que pegaba\u00bb era que el nombre art\u00edstico incluyera lo del \u00abni\u00f1o\u00bb de algo, como le sucedi\u00f3 en sus inicios a Pepe Marchena, el \u00abh\u00e9roe\u00bb que Roc\u00edo M\u00e1rquez ha querido para su segundo disco, que saldr\u00e1 en septiembre.<\/p>\n<p>Se titular\u00e1, precisamente, \u00abEl Ni\u00f1o\u00bb y ser\u00e1n diecisiete temas con algunas de las composiciones m\u00e1s celebradas de Jos\u00e9 Tejada Mart\u00edn (Marchena, 1903- Sevilla, 1976), el Ni\u00f1o de Marchena, que se presentar\u00e1 en la Bienal de Flamenco de Sevilla con un concierto el d\u00eda 14 y saldr\u00e1 a la venta el d\u00eda 23, explica en una entrevista con Efe la artista.<\/p>\n<p>Entretanto, la onubense (1985) no para de actuar y de salirse de los carriles del jondo para participar en espect\u00e1culos como el que presentar\u00e1 este domingo en los Jardines de Sabatini de Madrid: \u00abDesconcierto\u00bb, dirigido por Enrique Viana, junto a la pianista Rosa Torres-Pardo y el poeta Luis Garc\u00eda Montero.<\/p>\n<p>Con m\u00fasica de Enrique Granados, Isaac Alb\u00e9niz, Manuel de Falla, Joaqu\u00edn Turina, el Padre Soler y Federico Garc\u00eda Lorca, Luis Garc\u00eda Montero leer\u00e1 sus poemas \u00abentrelaz\u00e1ndolos\u00bb con la voz de M\u00e1rquez \u00aben un di\u00e1logo constante\u00bb.<\/p>\n<p>Luego, todo ser\u00e1 preparar su participaci\u00f3n en la Bienal de Sevilla con \u00abEl Ni\u00f1o\u00bb, en el que ha querido recalcar \u00abel punto juguet\u00f3n\u00bb de Marchena, que se divert\u00eda \u00abmuch\u00edsimo\u00bb improvisando.<\/p>\n<p>La car\u00e1tula del disco, que incluye un libreto con fotograf\u00edas de Marchena y de otros \u00abni\u00f1os\u00bb, como la Ni\u00f1a de los Peines o el Ni\u00f1o de la Alfalfa, es una foto de M\u00e1rquez un poco \u00abambigua\u00bb, con el pelo muy tirante, \u00ab&#8216;repein\u00e1&#8217; como un ni\u00f1o de comuni\u00f3n\u00bb, con pantal\u00f3n y chaqueta, \u00abun gui\u00f1o al toque exc\u00e9ntrico y dandi de Pepe\u00bb.<\/p>\n<p>\u00abEstoy content\u00edsima con lo que hemos hecho. La idea era que el centro fuera Marchena y que en torno a \u00e9l giraran todas las ideas, y eso lo hemos conseguido\u00bb, asegura.<\/p>\n<p>Por una parte, est\u00e1n las composiciones m\u00e1s tradicionales, es decir, sus \u00abseguiriyas\u00bb, cantes de levante, de ida y vuelta y sole\u00e1, palos en los que era experto, y por otra, un homenaje a su libertad creativa.<\/p>\n<p>\u00abMarchena estaba trabajando en un tablao de Badajoz y fue al teatro que hab\u00eda al lado, donde escuch\u00f3 un texto de \u00c1lvarez Quintero. Se lo pidi\u00f3 y ah\u00ed cre\u00f3 &#8216;La rosa&#8217;. Pas\u00f3 igual con &#8216;Romance a C\u00f3rdoba&#8217;. Si ve\u00eda un texto que le gustaba, creaba a partir de ah\u00ed\u00bb, detalla.<\/p>\n<p>Ha respetado sus \u00abmaneras\u00bb y melod\u00edas para reinterpretar guajiras o \u00abseguiriyas\u00bb, aunque sin copiarle, pero tambi\u00e9n ha incorporado, por ejemplo, un texto de Shakespeare sobre una rosa y otro de Juan Ram\u00f3n Jim\u00e9nez, \u00absiguiendo su energ\u00eda transgresora\u00bb.<\/p>\n<p>Otra pieza \u00abmuy interesante\u00bb, enumera, son sus colombianas, inspiradas en un \u00abzortziko\u00bb vasco y un corrido mejicano, que ella ha querido empezar \u00abpor corrido\u00bb.<\/p>\n<p>La preparaci\u00f3n del disco, producido por Faustino N\u00fa\u00f1ez y coordinado por Pedro Romero, le ha llevado un a\u00f1o y medio y est\u00e1 \u00absupercontenta\u00bb no solo con el resultado sino porque, \u00abencima\u00bb, ha contado con la colaboraci\u00f3n de \u00abmusicazos\u00bb como Pepe Habichuela, Manolo Franco, Manolo Herrera, Ra\u00fal Rodr\u00edguez, el Ni\u00f1o de Elche o Ra\u00fal Fern\u00e1ndez \u00abRefree\u00bb en la parte m\u00e1s experimental.<\/p>\n<p>Su participaci\u00f3n en la Bienal de Sevilla se completar\u00e1 con el concierto, el d\u00eda 17, \u00abCartuja a ras\u00bb, un encuentro multidisciplinar, con improvisaciones que buscan que \u00ablos artistas se salgan de s\u00ed mismos\u00bb.<\/p>\n<p>M\u00e1rquez, la \u00fanica que ha ganado cuatro grandes premios, incluyendo la L\u00e1mpara Minera, en el Festival Internacional del Cante de las Minas, empez\u00f3 cantando fandangos en una pe\u00f1a sin haber hecho ni la comuni\u00f3n y sac\u00f3 su primer disco en 2012, \u00abClaridad\u00bb.<\/p>\n<p>Por Concha Barrig\u00f3s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 8 ago (EFE).- Hubo una \u00e9poca en Espa\u00f1a en la que los cantaores empezaban a actuar siendo adolescentes, as\u00ed que \u00ablo que pegaba\u00bb era que el nombre art\u00edstico incluyera lo del \u00abni\u00f1o\u00bb de algo, como le sucedi\u00f3 en sus inicios a Pepe Marchena, el \u00abh\u00e9roe\u00bb que Roc\u00edo M\u00e1rquez ha querido para su segundo disco,<\/p>\n","protected":false},"author":1,"featured_media":20742,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":{"0":"post-20741","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-actualidad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 8 ago (EFE).- Hubo una \u00e9poca en Espa\u00f1a en la que los cantaores empezaban a actuar siendo adolescentes, as\u00ed que &quot;lo que pegaba&quot; era que el nombre art\u00edstico incluyera lo del &quot;ni\u00f1o&quot; de algo, como le sucedi\u00f3 en sus inicios a Pepe Marchena, el &quot;h\u00e9roe&quot; que Roc\u00edo M\u00e1rquez ha querido para su segundo disco,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Roc\u00edo M\u00e1rquez homenajea a los \u00abni\u00f1os\u00bb cantaores en la piel de Pepe Marchena | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 8 ago (EFE).- Hubo una \u00e9poca en Espa\u00f1a en la que los cantaores empezaban a actuar siendo adolescentes, as\u00ed que &quot;lo que pegaba&quot; era que el nombre art\u00edstico incluyera lo del &quot;ni\u00f1o&quot; de algo, como le sucedi\u00f3 en sus inicios a Pepe Marchena, el &quot;h\u00e9roe&quot; que Roc\u00edo M\u00e1rquez ha querido para su segundo disco,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6542479w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6542479w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"556\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-08-09T01:07:08+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-08-09T01:07:08+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Roc\u00edo M\u00e1rquez homenajea a los \u00abni\u00f1os\u00bb cantaores en la piel de Pepe Marchena | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 8 ago (EFE).- Hubo una \u00e9poca en Espa\u00f1a en la que los cantaores empezaban a actuar siendo adolescentes, as\u00ed que &quot;lo que pegaba&quot; era que el nombre art\u00edstico incluyera lo del &quot;ni\u00f1o&quot; de algo, como le sucedi\u00f3 en sus inicios a Pepe Marchena, el &quot;h\u00e9roe&quot; que Roc\u00edo M\u00e1rquez ha querido para su segundo disco,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6542479w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\\\/#article\",\"name\":\"Roc\\u00edo M\\u00e1rquez homenajea a los \\u00abni\\u00f1os\\u00bb cantaores en la piel de Pepe Marchena | El Digital de Asturias\",\"headline\":\"Roc\\u00edo M\\u00e1rquez homenajea a los \\u00abni\\u00f1os\\u00bb cantaores en la piel de Pepe Marchena\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/6542479w.jpg\",\"width\":800,\"height\":556},\"datePublished\":\"2014-08-08T23:07:08+02:00\",\"dateModified\":\"2014-08-08T23:07:08+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\\\/#listItem\",\"name\":\"Roc\\u00edo M\\u00e1rquez homenajea a los \\u00abni\\u00f1os\\u00bb cantaores en la piel de Pepe Marchena\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\\\/#listItem\",\"position\":3,\"name\":\"Roc\\u00edo M\\u00e1rquez homenajea a los \\u00abni\\u00f1os\\u00bb cantaores en la piel de Pepe Marchena\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\\\/\",\"name\":\"Roc\\u00edo M\\u00e1rquez homenajea a los \\u00abni\\u00f1os\\u00bb cantaores en la piel de Pepe Marchena | El Digital de Asturias\",\"description\":\"Madrid, 8 ago (EFE).- Hubo una \\u00e9poca en Espa\\u00f1a en la que los cantaores empezaban a actuar siendo adolescentes, as\\u00ed que \\\"lo que pegaba\\\" era que el nombre art\\u00edstico incluyera lo del \\\"ni\\u00f1o\\\" de algo, como le sucedi\\u00f3 en sus inicios a Pepe Marchena, el \\\"h\\u00e9roe\\\" que Roc\\u00edo M\\u00e1rquez ha querido para su segundo disco,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/6542479w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\\\/#mainImage\",\"width\":800,\"height\":556},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\\\/#mainImage\"},\"datePublished\":\"2014-08-08T23:07:08+02:00\",\"dateModified\":\"2014-08-08T23:07:08+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Roc\u00edo M\u00e1rquez homenajea a los \u00abni\u00f1os\u00bb cantaores en la piel de Pepe Marchena | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Roc\u00edo M\u00e1rquez homenajea a los \u00abni\u00f1os\u00bb cantaores en la piel de Pepe Marchena | El Digital de Asturias","description":"Madrid, 8 ago (EFE).- Hubo una \u00e9poca en Espa\u00f1a en la que los cantaores empezaban a actuar siendo adolescentes, as\u00ed que \"lo que pegaba\" era que el nombre art\u00edstico incluyera lo del \"ni\u00f1o\" de algo, como le sucedi\u00f3 en sus inicios a Pepe Marchena, el \"h\u00e9roe\" que Roc\u00edo M\u00e1rquez ha querido para su segundo disco,","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/#article","name":"Roc\u00edo M\u00e1rquez homenajea a los \u00abni\u00f1os\u00bb cantaores en la piel de Pepe Marchena | El Digital de Asturias","headline":"Roc\u00edo M\u00e1rquez homenajea a los \u00abni\u00f1os\u00bb cantaores en la piel de Pepe Marchena","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6542479w.jpg","width":800,"height":556},"datePublished":"2014-08-08T23:07:08+02:00","dateModified":"2014-08-08T23:07:08+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/#listItem","name":"Roc\u00edo M\u00e1rquez homenajea a los \u00abni\u00f1os\u00bb cantaores en la piel de Pepe Marchena"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/#listItem","position":3,"name":"Roc\u00edo M\u00e1rquez homenajea a los \u00abni\u00f1os\u00bb cantaores en la piel de Pepe Marchena","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/","name":"Roc\u00edo M\u00e1rquez homenajea a los \u00abni\u00f1os\u00bb cantaores en la piel de Pepe Marchena | El Digital de Asturias","description":"Madrid, 8 ago (EFE).- Hubo una \u00e9poca en Espa\u00f1a en la que los cantaores empezaban a actuar siendo adolescentes, as\u00ed que \"lo que pegaba\" era que el nombre art\u00edstico incluyera lo del \"ni\u00f1o\" de algo, como le sucedi\u00f3 en sus inicios a Pepe Marchena, el \"h\u00e9roe\" que Roc\u00edo M\u00e1rquez ha querido para su segundo disco,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6542479w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/#mainImage","width":800,"height":556},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/#mainImage"},"datePublished":"2014-08-08T23:07:08+02:00","dateModified":"2014-08-08T23:07:08+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Roc\u00edo M\u00e1rquez homenajea a los \u00abni\u00f1os\u00bb cantaores en la piel de Pepe Marchena | El Digital de Asturias","og:description":"Madrid, 8 ago (EFE).- Hubo una \u00e9poca en Espa\u00f1a en la que los cantaores empezaban a actuar siendo adolescentes, as\u00ed que &quot;lo que pegaba&quot; era que el nombre art\u00edstico incluyera lo del &quot;ni\u00f1o&quot; de algo, como le sucedi\u00f3 en sus inicios a Pepe Marchena, el &quot;h\u00e9roe&quot; que Roc\u00edo M\u00e1rquez ha querido para su segundo disco,","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6542479w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6542479w.jpg","og:image:width":800,"og:image:height":556,"article:published_time":"2014-08-09T01:07:08+00:00","article:modified_time":"2014-08-09T01:07:08+00:00","twitter:card":"summary_large_image","twitter:title":"Roc\u00edo M\u00e1rquez homenajea a los \u00abni\u00f1os\u00bb cantaores en la piel de Pepe Marchena | El Digital de Asturias","twitter:description":"Madrid, 8 ago (EFE).- Hubo una \u00e9poca en Espa\u00f1a en la que los cantaores empezaban a actuar siendo adolescentes, as\u00ed que &quot;lo que pegaba&quot; era que el nombre art\u00edstico incluyera lo del &quot;ni\u00f1o&quot; de algo, como le sucedi\u00f3 en sus inicios a Pepe Marchena, el &quot;h\u00e9roe&quot; que Roc\u00edo M\u00e1rquez ha querido para su segundo disco,","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6542479w.jpg"},"aioseo_meta_data":{"post_id":"20741","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-17 22:23:56","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 06:52:41","updated":"2025-09-17 22:23:56"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/\" title=\"Roc\u00edo M\u00e1rquez homenajea a los \u00abni\u00f1os\u00bb cantaores en la piel de Pepe Marchena\">Roc\u00edo M\u00e1rquez homenajea a los \u00abni\u00f1os\u00bb cantaores en la piel de Pepe Marchena<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Roc\u00edo M\u00e1rquez homenajea a los \u00abni\u00f1os\u00bb cantaores en la piel de Pepe Marchena","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/rocio-marquez-homenajea-a-los-ninos-cantaores-en-la-piel-de-pepe-marchena\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/20741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=20741"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/20741\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/20742"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=20741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=20741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=20741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}