{"id":20636,"date":"2014-08-08T07:45:53","date_gmt":"2014-08-08T09:45:53","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=20636"},"modified":"2014-08-08T07:45:53","modified_gmt":"2014-08-08T09:45:53","slug":"bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/","title":{"rendered":"Bille August y Fran\u00e7ois Ozon competir\u00e1n por la Concha de Oro en San Sebasti\u00e1n"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-20637\" alt=\"6537712w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6537712w-360x240.jpg\" width=\"360\" height=\"240\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6537712w-360x240.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6537712w-650x434.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6537712w-768x513.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6537712w-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6537712w-450x300.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6537712w-696x465.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6537712w-629x420.jpg 629w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6537712w-84x55.jpg 84w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6537712w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>San Sebasti\u00e1n, 7 ago (EFE).- El cineasta dan\u00e9s ganador de un Oscar Bille August y el director franc\u00e9s Fran\u00e7ois Ozon competir\u00e1n con sus \u00faltimos trabajos por la Concha de Oro en la 62 edici\u00f3n del Festival Internacional de Cine de San Sebasti\u00e1n.<\/p>\n<p>El certamen ha informado, en un comunicado, de la presencia de estos dos prestigiosos realizadores europeos en la Secci\u00f3n Oficial del Zinemaldia, adem\u00e1s de hacer p\u00fablicos otros cinco t\u00edtulos que competir\u00e1n por el m\u00e1ximo galard\u00f3n en San Sebasti\u00e1n.<\/p>\n<p>Junto a August y Ozon, han sido seleccionados para competir por la Concha de Oro pel\u00edculas de Michael Sturminger, Mcha\u00ebl R.Roskam, Mia Hansen-Love, Shim Sung-Bo y Christian Petzold.<\/p>\n<p>El Festival ha se\u00f1alado que la pr\u00f3xima semana podr\u00e1 anunciar nuevos t\u00edtulos que se sumar\u00e1n a estas siete pel\u00edculas en la secci\u00f3n competitiva del certamen, que se celebrar\u00e1 entre el 19 y el 27 de septiembre.<\/p>\n<p>Bille August, ganador del Oscar a la mejor pel\u00edcula extranjera en 1989 por \u00abPelle el conquistador\u00bb, con la que obtuvo tambi\u00e9n la Palma de Oro en Cannes, se presenta por primera vez en San Sebasti\u00e1n con \u00abSilent Heart\u00bb, un drama familiar protagonizado por Paprika Steen, Ghita N\u00f8rby y Morten Grunwald.<\/p>\n<p>Tras ganar su segunda Palma de Oro en 1992 con \u00abLas mejores intenciones\u00bb, August obtuvo el reconocimiento internacional que le permiti\u00f3 acometer proyectos de mayor envergadura y dirigir a estrellas de Hollywood como Meryl Streep y Jeremy Irons en \u00abLa casa de los esp\u00edritus\u00bb, Julia Ormond en \u00abSmila, misterio en la nieve\u00bb o Liam Neeson en \u00abLos Miserables\u00bb.<\/p>\n<p>Fran\u00e7ois Ozon vuelve al Festival de San Sebasti\u00e1n dos a\u00f1os despu\u00e9s de llevarse la Concha de Oro por \u00abEn la casa\u00bb y lo hace con su \u00faltimo proyecto, \u00abUne Nouvelle Amie\u00bb, interpretada por Romain Duris, Ana\u00efs Demoustier, Rapha\u00ebl Personnaz.<\/p>\n<p>La Secci\u00f3n Oficial permitir\u00e1 tambi\u00e9n ver la \u00faltima pel\u00edcula que rod\u00f3 James Gandolfini -que ser\u00e1 recordado por encarnar a Tony Soprano- antes de morir.<\/p>\n<p>Se trata de \u00abLa entrega\u00bb, el debut en Hollywood del cineasta belga Micha\u00ebl R. Roskam, que ha adaptado una novela de Dennis Lehane y ha contado en el reparto, adem\u00e1s de con Gandolfini, con Tom Hardy y Noomi Rapace, la actriz sueca de padre espa\u00f1ol que dio vida a Lisbeth Salander en la saga \u00abMillenium\u00bb.<\/p>\n<p>La directora francesa Mia-Hansen Love competir\u00e1 con \u00abEden\u00bb, un filme que recrea la vida nocturna parisina en plena eclosi\u00f3n de la m\u00fasica electr\u00f3nica en la d\u00e9cada de los 90, mientras que el coreano Shim Sung-bo, guionista de la inquietante \u00abMemories of Murder\u00bb, presenta en San Sebasti\u00e1n su debut tras las c\u00e1maras, \u00abHaemu\u00bb, un drama ambientado en un barco pesquero que transporta inmigrantes ilegales.<\/p>\n<p>Tambi\u00e9n participar\u00e1 en la Secci\u00f3n Oficial a concurso el austr\u00edaco Michael Sturminger, quien revisa el mito de Casanova con \u00abCasanova Variations\u00bb, una coproducci\u00f3n entre Francia, Austria y Alemania con John Malkovich como protagonista.<\/p>\n<p>Por \u00faltimo, el alem\u00e1n Chirstian Petzold, ganador del Oso de Plata al mejor director en el Festival de Berl\u00edn de 2012 por \u00abB\u00e1rbara\u00bb, concursa en San Sebasti\u00e1n con su \u00faltima pel\u00edcula, \u00abPhoenix\u00bb, en la que vuelve a confiar el papel protagonista a Nina Hoss.<\/p>\n<p>El Festival de San Sebasti\u00e1n, que se inaugurar\u00e1 con la proyecci\u00f3n fuera de concurso de \u00abEl Protector\u00bb, protagonizada por Denzel Washintong, Premio Donostia, 2014, dar\u00e1 a conocer m\u00e1s t\u00edtulos de la secci\u00f3n competitiva a partir de la pr\u00f3xima semana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Sebasti\u00e1n, 7 ago (EFE).- El cineasta dan\u00e9s ganador de un Oscar Bille August y el director franc\u00e9s Fran\u00e7ois Ozon competir\u00e1n con sus \u00faltimos trabajos por la Concha de Oro en la 62 edici\u00f3n del Festival Internacional de Cine de San Sebasti\u00e1n. El certamen ha informado, en un comunicado, de la presencia de estos dos<\/p>\n","protected":false},"author":1,"featured_media":20637,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":{"0":"post-20636","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-actualidad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"San Sebasti\u00e1n, 7 ago (EFE).- El cineasta dan\u00e9s ganador de un Oscar Bille August y el director franc\u00e9s Fran\u00e7ois Ozon competir\u00e1n con sus \u00faltimos trabajos por la Concha de Oro en la 62 edici\u00f3n del Festival Internacional de Cine de San Sebasti\u00e1n. El certamen ha informado, en un comunicado, de la presencia de estos dos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Bille August y Fran\u00e7ois Ozon competir\u00e1n por la Concha de Oro en San Sebasti\u00e1n | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"San Sebasti\u00e1n, 7 ago (EFE).- El cineasta dan\u00e9s ganador de un Oscar Bille August y el director franc\u00e9s Fran\u00e7ois Ozon competir\u00e1n con sus \u00faltimos trabajos por la Concha de Oro en la 62 edici\u00f3n del Festival Internacional de Cine de San Sebasti\u00e1n. El certamen ha informado, en un comunicado, de la presencia de estos dos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6537712w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6537712w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-08-08T09:45:53+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-08-08T09:45:53+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Bille August y Fran\u00e7ois Ozon competir\u00e1n por la Concha de Oro en San Sebasti\u00e1n | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"San Sebasti\u00e1n, 7 ago (EFE).- El cineasta dan\u00e9s ganador de un Oscar Bille August y el director franc\u00e9s Fran\u00e7ois Ozon competir\u00e1n con sus \u00faltimos trabajos por la Concha de Oro en la 62 edici\u00f3n del Festival Internacional de Cine de San Sebasti\u00e1n. El certamen ha informado, en un comunicado, de la presencia de estos dos\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6537712w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\\\/#article\",\"name\":\"Bille August y Fran\\u00e7ois Ozon competir\\u00e1n por la Concha de Oro en San Sebasti\\u00e1n | El Digital de Asturias\",\"headline\":\"Bille August y Fran\\u00e7ois Ozon competir\\u00e1n por la Concha de Oro en San Sebasti\\u00e1n\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/6537712w.jpg\",\"width\":800,\"height\":534},\"datePublished\":\"2014-08-08T07:45:53+02:00\",\"dateModified\":\"2014-08-08T07:45:53+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\\\/#listItem\",\"name\":\"Bille August y Fran\\u00e7ois Ozon competir\\u00e1n por la Concha de Oro en San Sebasti\\u00e1n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\\\/#listItem\",\"position\":3,\"name\":\"Bille August y Fran\\u00e7ois Ozon competir\\u00e1n por la Concha de Oro en San Sebasti\\u00e1n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\\\/\",\"name\":\"Bille August y Fran\\u00e7ois Ozon competir\\u00e1n por la Concha de Oro en San Sebasti\\u00e1n | El Digital de Asturias\",\"description\":\"San Sebasti\\u00e1n, 7 ago (EFE).- El cineasta dan\\u00e9s ganador de un Oscar Bille August y el director franc\\u00e9s Fran\\u00e7ois Ozon competir\\u00e1n con sus \\u00faltimos trabajos por la Concha de Oro en la 62 edici\\u00f3n del Festival Internacional de Cine de San Sebasti\\u00e1n. El certamen ha informado, en un comunicado, de la presencia de estos dos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/6537712w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\\\/#mainImage\",\"width\":800,\"height\":534},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\\\/#mainImage\"},\"datePublished\":\"2014-08-08T07:45:53+02:00\",\"dateModified\":\"2014-08-08T07:45:53+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Bille August y Fran\u00e7ois Ozon competir\u00e1n por la Concha de Oro en San Sebasti\u00e1n | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Bille August y Fran\u00e7ois Ozon competir\u00e1n por la Concha de Oro en San Sebasti\u00e1n | El Digital de Asturias","description":"San Sebasti\u00e1n, 7 ago (EFE).- El cineasta dan\u00e9s ganador de un Oscar Bille August y el director franc\u00e9s Fran\u00e7ois Ozon competir\u00e1n con sus \u00faltimos trabajos por la Concha de Oro en la 62 edici\u00f3n del Festival Internacional de Cine de San Sebasti\u00e1n. El certamen ha informado, en un comunicado, de la presencia de estos dos","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/#article","name":"Bille August y Fran\u00e7ois Ozon competir\u00e1n por la Concha de Oro en San Sebasti\u00e1n | El Digital de Asturias","headline":"Bille August y Fran\u00e7ois Ozon competir\u00e1n por la Concha de Oro en San Sebasti\u00e1n","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6537712w.jpg","width":800,"height":534},"datePublished":"2014-08-08T07:45:53+02:00","dateModified":"2014-08-08T07:45:53+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/#listItem","name":"Bille August y Fran\u00e7ois Ozon competir\u00e1n por la Concha de Oro en San Sebasti\u00e1n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/#listItem","position":3,"name":"Bille August y Fran\u00e7ois Ozon competir\u00e1n por la Concha de Oro en San Sebasti\u00e1n","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1778179047","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/","name":"Bille August y Fran\u00e7ois Ozon competir\u00e1n por la Concha de Oro en San Sebasti\u00e1n | El Digital de Asturias","description":"San Sebasti\u00e1n, 7 ago (EFE).- El cineasta dan\u00e9s ganador de un Oscar Bille August y el director franc\u00e9s Fran\u00e7ois Ozon competir\u00e1n con sus \u00faltimos trabajos por la Concha de Oro en la 62 edici\u00f3n del Festival Internacional de Cine de San Sebasti\u00e1n. El certamen ha informado, en un comunicado, de la presencia de estos dos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6537712w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/#mainImage","width":800,"height":534},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/#mainImage"},"datePublished":"2014-08-08T07:45:53+02:00","dateModified":"2014-08-08T07:45:53+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Bille August y Fran\u00e7ois Ozon competir\u00e1n por la Concha de Oro en San Sebasti\u00e1n | El Digital de Asturias","og:description":"San Sebasti\u00e1n, 7 ago (EFE).- El cineasta dan\u00e9s ganador de un Oscar Bille August y el director franc\u00e9s Fran\u00e7ois Ozon competir\u00e1n con sus \u00faltimos trabajos por la Concha de Oro en la 62 edici\u00f3n del Festival Internacional de Cine de San Sebasti\u00e1n. El certamen ha informado, en un comunicado, de la presencia de estos dos","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6537712w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6537712w.jpg","og:image:width":800,"og:image:height":534,"article:published_time":"2014-08-08T09:45:53+00:00","article:modified_time":"2014-08-08T09:45:53+00:00","twitter:card":"summary_large_image","twitter:title":"Bille August y Fran\u00e7ois Ozon competir\u00e1n por la Concha de Oro en San Sebasti\u00e1n | El Digital de Asturias","twitter:description":"San Sebasti\u00e1n, 7 ago (EFE).- El cineasta dan\u00e9s ganador de un Oscar Bille August y el director franc\u00e9s Fran\u00e7ois Ozon competir\u00e1n con sus \u00faltimos trabajos por la Concha de Oro en la 62 edici\u00f3n del Festival Internacional de Cine de San Sebasti\u00e1n. El certamen ha informado, en un comunicado, de la presencia de estos dos","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/08\/6537712w.jpg"},"aioseo_meta_data":{"post_id":"20636","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-17 22:10:46","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 06:53:41","updated":"2025-09-17 22:10:46"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/\" title=\"Bille August y Fran\u00e7ois Ozon competir\u00e1n por la Concha de Oro en San Sebasti\u00e1n\">Bille August y Fran\u00e7ois Ozon competir\u00e1n por la Concha de Oro en San Sebasti\u00e1n<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Bille August y Fran\u00e7ois Ozon competir\u00e1n por la Concha de Oro en San Sebasti\u00e1n","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/bille-august-y-francois-ozon-competiran-por-la-concha-de-oro-en-san-sebastian\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/20636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=20636"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/20636\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/20637"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=20636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=20636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=20636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}