{"id":2019,"date":"2014-01-27T21:25:13","date_gmt":"2014-01-27T22:25:13","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=2019"},"modified":"2014-01-27T21:25:13","modified_gmt":"2014-01-27T22:25:13","slug":"la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/","title":{"rendered":"La presidenta de General Motors asegura el futuro de la f\u00e1brica de R\u00fcsselsheim"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-2020\" alt=\"5879769w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5879769w-360x231.jpg\" width=\"360\" height=\"231\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5879769w-360x231.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5879769w-650x418.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5879769w-768x493.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5879769w-150x96.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5879769w-450x289.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5879769w-696x447.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5879769w-654x420.jpg 654w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5879769w-225x145.jpg 225w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5879769w-84x55.jpg 84w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5879769w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Fr\u00e1ncfort (Alemania), 27 ene (EFE).- La nueva presidenta y consejera delegada del fabricante automovil\u00edstico estadounidense General Motors, Mary Barra, ha asegurado el futuro de la f\u00e1brica de Opel en R\u00fcsselsheim (cerca de Fr\u00e1ncfort) con inversiones en un nuevo modelo.<\/p>\n<p>Barra dijo en su primera visita a una factor\u00eda extranjera que \u00abaseguraremos el futuro de la f\u00e1brica con un nuevo modelo\u00bb sin facilitar m\u00e1s detalles.<\/p>\n<p>\u00abPero pueden estar seguros de que esto ir\u00e1 de la mano con nuevas inversiones adicionales en Alemania\u00bb, a\u00f1adi\u00f3 la presidenta de General Motors.<\/p>\n<p>Opel produce el Insignia en R\u00fcsselsheim, f\u00e1brica que es tambi\u00e9n la sede central de la compa\u00f1\u00eda alemana, y a partir del pr\u00f3ximo a\u00f1o, tambi\u00e9n el Zafira.<\/p>\n<p>En la visita, Barra se reuni\u00f3 con los trabajadores de R\u00fcsselsheim y visit\u00f3 el Centro de Desarrollo T\u00e9cnico Internacional (ITDC por sus siglas en alem\u00e1n).<\/p>\n<p>Barra record\u00f3 que GM invertir\u00e1 4.000 millones de euros en Alemania y Europa hasta 2016 para que Opel pueda lanzar al mercado 13 nuevos productos y 13 nuevos modelos.<\/p>\n<p>Adem\u00e1s, el director general de GM, Daniel Ammann, ha sido nombrado sucesor de Steve Girsky, como presidente del consejo de supervisi\u00f3n de Opel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fr\u00e1ncfort (Alemania), 27 ene (EFE).- La nueva presidenta y consejera delegada del fabricante automovil\u00edstico estadounidense General Motors, Mary Barra, ha asegurado el futuro de la f\u00e1brica de Opel en R\u00fcsselsheim (cerca de Fr\u00e1ncfort) con inversiones en un nuevo modelo. Barra dijo en su primera visita a una factor\u00eda extranjera que \u00abaseguraremos el futuro de la<\/p>\n","protected":false},"author":1,"featured_media":2020,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[212],"tags":[],"class_list":["post-2019","post","type-post","status-publish","format-standard","has-post-thumbnail","category-motor"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Fr\u00e1ncfort (Alemania), 27 ene (EFE).- La nueva presidenta y consejera delegada del fabricante automovil\u00edstico estadounidense General Motors, Mary Barra, ha asegurado el futuro de la f\u00e1brica de Opel en R\u00fcsselsheim (cerca de Fr\u00e1ncfort) con inversiones en un nuevo modelo. Barra dijo en su primera visita a una factor\u00eda extranjera que &quot;aseguraremos el futuro de la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"motor\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La presidenta de General Motors asegura el futuro de la f\u00e1brica de R\u00fcsselsheim | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Fr\u00e1ncfort (Alemania), 27 ene (EFE).- La nueva presidenta y consejera delegada del fabricante automovil\u00edstico estadounidense General Motors, Mary Barra, ha asegurado el futuro de la f\u00e1brica de Opel en R\u00fcsselsheim (cerca de Fr\u00e1ncfort) con inversiones en un nuevo modelo. Barra dijo en su primera visita a una factor\u00eda extranjera que &quot;aseguraremos el futuro de la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5879769w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5879769w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-01-27T22:25:13+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-01-27T22:25:13+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La presidenta de General Motors asegura el futuro de la f\u00e1brica de R\u00fcsselsheim | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Fr\u00e1ncfort (Alemania), 27 ene (EFE).- La nueva presidenta y consejera delegada del fabricante automovil\u00edstico estadounidense General Motors, Mary Barra, ha asegurado el futuro de la f\u00e1brica de Opel en R\u00fcsselsheim (cerca de Fr\u00e1ncfort) con inversiones en un nuevo modelo. Barra dijo en su primera visita a una factor\u00eda extranjera que &quot;aseguraremos el futuro de la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5879769w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\\\/#article\",\"name\":\"La presidenta de General Motors asegura el futuro de la f\\u00e1brica de R\\u00fcsselsheim | El Digital de Asturias\",\"headline\":\"La presidenta de General Motors asegura el futuro de la f\\u00e1brica de R\\u00fcsselsheim\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/5879769w.jpg\",\"width\":800,\"height\":514},\"datePublished\":\"2014-01-27T21:25:13+01:00\",\"dateModified\":\"2014-01-27T21:25:13+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\\\/#webpage\"},\"articleSection\":\"Motor\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/motor\\\/#listItem\",\"name\":\"Motor\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/motor\\\/#listItem\",\"position\":2,\"name\":\"Motor\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/motor\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\\\/#listItem\",\"name\":\"La presidenta de General Motors asegura el futuro de la f\\u00e1brica de R\\u00fcsselsheim\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\\\/#listItem\",\"position\":3,\"name\":\"La presidenta de General Motors asegura el futuro de la f\\u00e1brica de R\\u00fcsselsheim\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/motor\\\/#listItem\",\"name\":\"Motor\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\\\/\",\"name\":\"La presidenta de General Motors asegura el futuro de la f\\u00e1brica de R\\u00fcsselsheim | El Digital de Asturias\",\"description\":\"Fr\\u00e1ncfort (Alemania), 27 ene (EFE).- La nueva presidenta y consejera delegada del fabricante automovil\\u00edstico estadounidense General Motors, Mary Barra, ha asegurado el futuro de la f\\u00e1brica de Opel en R\\u00fcsselsheim (cerca de Fr\\u00e1ncfort) con inversiones en un nuevo modelo. Barra dijo en su primera visita a una factor\\u00eda extranjera que \\\"aseguraremos el futuro de la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/5879769w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\\\/#mainImage\",\"width\":800,\"height\":514},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\\\/#mainImage\"},\"datePublished\":\"2014-01-27T21:25:13+01:00\",\"dateModified\":\"2014-01-27T21:25:13+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La presidenta de General Motors asegura el futuro de la f\u00e1brica de R\u00fcsselsheim | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"La presidenta de General Motors asegura el futuro de la f\u00e1brica de R\u00fcsselsheim | El Digital de Asturias","description":"Fr\u00e1ncfort (Alemania), 27 ene (EFE).- La nueva presidenta y consejera delegada del fabricante automovil\u00edstico estadounidense General Motors, Mary Barra, ha asegurado el futuro de la f\u00e1brica de Opel en R\u00fcsselsheim (cerca de Fr\u00e1ncfort) con inversiones en un nuevo modelo. Barra dijo en su primera visita a una factor\u00eda extranjera que \"aseguraremos el futuro de la","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/","robots":"max-image-preview:large","keywords":"motor","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/#article","name":"La presidenta de General Motors asegura el futuro de la f\u00e1brica de R\u00fcsselsheim | El Digital de Asturias","headline":"La presidenta de General Motors asegura el futuro de la f\u00e1brica de R\u00fcsselsheim","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5879769w.jpg","width":800,"height":514},"datePublished":"2014-01-27T21:25:13+01:00","dateModified":"2014-01-27T21:25:13+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/#webpage"},"articleSection":"Motor"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/motor\/#listItem","name":"Motor"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/motor\/#listItem","position":2,"name":"Motor","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/motor\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/#listItem","name":"La presidenta de General Motors asegura el futuro de la f\u00e1brica de R\u00fcsselsheim"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/#listItem","position":3,"name":"La presidenta de General Motors asegura el futuro de la f\u00e1brica de R\u00fcsselsheim","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/motor\/#listItem","name":"Motor"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/","name":"La presidenta de General Motors asegura el futuro de la f\u00e1brica de R\u00fcsselsheim | El Digital de Asturias","description":"Fr\u00e1ncfort (Alemania), 27 ene (EFE).- La nueva presidenta y consejera delegada del fabricante automovil\u00edstico estadounidense General Motors, Mary Barra, ha asegurado el futuro de la f\u00e1brica de Opel en R\u00fcsselsheim (cerca de Fr\u00e1ncfort) con inversiones en un nuevo modelo. Barra dijo en su primera visita a una factor\u00eda extranjera que \"aseguraremos el futuro de la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5879769w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/#mainImage","width":800,"height":514},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/#mainImage"},"datePublished":"2014-01-27T21:25:13+01:00","dateModified":"2014-01-27T21:25:13+01:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"La presidenta de General Motors asegura el futuro de la f\u00e1brica de R\u00fcsselsheim | El Digital de Asturias","og:description":"Fr\u00e1ncfort (Alemania), 27 ene (EFE).- La nueva presidenta y consejera delegada del fabricante automovil\u00edstico estadounidense General Motors, Mary Barra, ha asegurado el futuro de la f\u00e1brica de Opel en R\u00fcsselsheim (cerca de Fr\u00e1ncfort) con inversiones en un nuevo modelo. Barra dijo en su primera visita a una factor\u00eda extranjera que &quot;aseguraremos el futuro de la","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5879769w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5879769w.jpg","og:image:width":800,"og:image:height":514,"article:published_time":"2014-01-27T22:25:13+00:00","article:modified_time":"2014-01-27T22:25:13+00:00","twitter:card":"summary_large_image","twitter:title":"La presidenta de General Motors asegura el futuro de la f\u00e1brica de R\u00fcsselsheim | El Digital de Asturias","twitter:description":"Fr\u00e1ncfort (Alemania), 27 ene (EFE).- La nueva presidenta y consejera delegada del fabricante automovil\u00edstico estadounidense General Motors, Mary Barra, ha asegurado el futuro de la f\u00e1brica de Opel en R\u00fcsselsheim (cerca de Fr\u00e1ncfort) con inversiones en un nuevo modelo. Barra dijo en su primera visita a una factor\u00eda extranjera que &quot;aseguraremos el futuro de la","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/01\/5879769w.jpg"},"aioseo_meta_data":{"post_id":"2019","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 06:57:51","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 13:42:29","updated":"2026-05-15 06:57:51"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/motor\/\" title=\"Motor\">Motor<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/\" title=\"La presidenta de General Motors asegura el futuro de la f\u00e1brica de R\u00fcsselsheim\">La presidenta de General Motors asegura el futuro de la f\u00e1brica de R\u00fcsselsheim<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Motor","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/motor\/"},{"label":"La presidenta de General Motors asegura el futuro de la f\u00e1brica de R\u00fcsselsheim","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/la-presidenta-de-general-motors-asegura-el-futuro-de-la-fabrica-de-russelsheim\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/2019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=2019"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/2019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/2020"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=2019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=2019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=2019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}