{"id":16132,"date":"2014-06-16T16:52:45","date_gmt":"2014-06-16T18:52:45","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=16132"},"modified":"2014-06-16T16:52:45","modified_gmt":"2014-06-16T18:52:45","slug":"madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/","title":{"rendered":"Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda en el D\u00eda de la M\u00fasica este s\u00e1bado"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-16133\" alt=\"6373334w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6373334w-360x260.jpg\" width=\"360\" height=\"260\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6373334w-360x260.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6373334w-650x470.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6373334w-768x555.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6373334w-150x108.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6373334w-450x325.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6373334w-324x235.jpg 324w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6373334w-696x503.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6373334w-581x420.jpg 581w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6373334w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Madrid, 16 jun (EFE).- La ciudad de Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda durante los actos del D\u00eda Europeo de la M\u00fasica que se celebrar\u00e1 el pr\u00f3ximo s\u00e1bado, d\u00eda 21, ha anunciado hoy la alcaldesa de la capital, Ana Botella.<\/p>\n<p>La alcaldesa ha descubierto hoy una placa conmemorativa en el n\u00famero 17 de la calle Ilustraci\u00f3n, en la casa en la que Paco de Luc\u00eda residi\u00f3 de ni\u00f1o a su llegada a Madrid.<\/p>\n<p>Ana Botella ha destacado que all\u00ed fue \u00abdonde se forj\u00f3 uno de los m\u00e1s grandes artistas que ha dado la cultura espa\u00f1ola\u00bb y por eso el Ayuntamiento ha querido \u00abque quede para siempre este recuerdo con el que Madrid le honra\u00bb.<\/p>\n<p>\u00abEl pueblo de Madrid -ha a\u00f1adido la alcaldesa- quiere expresar con ello su sentimiento de admiraci\u00f3n, respeto y reconocimiento a este genio de la guitarra, que elev\u00f3 el arte flamenco a una nueva dimensi\u00f3n\u00bb, ha manifestado Botella, que se ha referido a Paco de Luc\u00eda como \u00abun hombre aut\u00e9ntico\u00bb y un \u00abextraordinario embajador\u00bb de lo espa\u00f1ol.<\/p>\n<p>Durante el D\u00eda Europeo de la M\u00fasica, los escenarios m\u00f3viles, una de las se\u00f1as de identidad de la festividad del D\u00eda Europeo de la M\u00fasica, volver\u00e1n a tomar las calles de Madrid llevando la m\u00fasica a los distritos de la capital.<\/p>\n<p>En esta ocasi\u00f3n ser\u00e1n dos los autobuses que se desplazar\u00e1n desde las 12 de la ma\u00f1ana hasta las 10 de la noche por los distritos de Hortaleza, Chamart\u00edn, Tetu\u00e1n, Chamber\u00ed, Salamanca, Moratalaz, Villa de Vallecas, Arganzuela, Usera y Carabanchel, ofreciendo una decena de actuaciones a cargo de formaciones flamencas que interpretar\u00e1n lo mejor del repertorio de Paco de Luc\u00eda.<\/p>\n<p>El momento m\u00e1s intenso de la jornada llegar\u00e1 a las 22 horas, cuando el esp\u00edritu de Paco de Luc\u00eda inundar\u00e1 la plaza Mayor de Madrid de la mano de grandes artistas que compartieron escenario con el m\u00fasico.<\/p>\n<p>Un concierto homenaje que contar\u00e1 en su primera parte con la Banda Sinf\u00f3nica Municipal de Madrid, dirigida por Rafael Sanz-Espert, y con Jorge Pardo y Toni Cuenca como solistas invitados, al que se sumar\u00e1n en la segunda parte Chano Dom\u00ednguez, Carles Benavent, Duquende, El Pira\u00f1a, El Farru, Rub\u00e9n Dantes, Parrita y Pepe de Luc\u00eda, entre otros.<\/p>\n<p>La plaza de Cibeles celebrar\u00e1 el D\u00eda Europeo de la M\u00fasica con un marat\u00f3n de conciertos a cargo de los ganadores de las \u00faltimas ediciones del Trofeo Rock Villa de Madrid.<\/p>\n<p>Por su parte, el parque de El Retiro acoger\u00e1 sendos maratones musicales: en el Templete de M\u00fasica el de Estudiantes de M\u00fasica con una veintena de formaciones musicales y en la plaza de Galicia el de coros, con un total de ocho actuaciones de diferentes formaciones.<\/p>\n<p>Adem\u00e1s, el barrio de Malasa\u00f1a recibir\u00e1 un carrusel de marionetas, t\u00edteres y teatro con m\u00fasica en directo.<\/p>\n<p>Los amantes de la \u00f3pera disfrutar\u00e1n con \u00abDon Giovanni\u00bb, en el Templo de Debod, y Matadero dedicar\u00e1 siete horas ininterrumpidas el viernes 20 y el s\u00e1bado 21 a una gran fiesta musical de destacados grupos y solistas: \u00abThe Big Stereo Party\u00bb.<\/p>\n<p>El Barrio de Las Letras, el Instituto Cervantes, las salas de m\u00fasica en vivo y el C\u00edrculo de Bellas Artes, entre otros espacios de la ciudad, completar\u00e1n con sus propuestas las actividades del D\u00eda Europeo de la M\u00fasica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 16 jun (EFE).- La ciudad de Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda durante los actos del D\u00eda Europeo de la M\u00fasica que se celebrar\u00e1 el pr\u00f3ximo s\u00e1bado, d\u00eda 21, ha anunciado hoy la alcaldesa de la capital, Ana Botella. La alcaldesa ha descubierto hoy una placa conmemorativa en el n\u00famero 17 de la<\/p>\n","protected":false},"author":1,"featured_media":16133,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-16132","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 16 jun (EFE).- La ciudad de Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda durante los actos del D\u00eda Europeo de la M\u00fasica que se celebrar\u00e1 el pr\u00f3ximo s\u00e1bado, d\u00eda 21, ha anunciado hoy la alcaldesa de la capital, Ana Botella. La alcaldesa ha descubierto hoy una placa conmemorativa en el n\u00famero 17 de la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda en el D\u00eda de la M\u00fasica este s\u00e1bado | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 16 jun (EFE).- La ciudad de Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda durante los actos del D\u00eda Europeo de la M\u00fasica que se celebrar\u00e1 el pr\u00f3ximo s\u00e1bado, d\u00eda 21, ha anunciado hoy la alcaldesa de la capital, Ana Botella. La alcaldesa ha descubierto hoy una placa conmemorativa en el n\u00famero 17 de la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6373334w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6373334w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"578\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-16T18:52:45+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-16T18:52:45+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda en el D\u00eda de la M\u00fasica este s\u00e1bado | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 16 jun (EFE).- La ciudad de Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda durante los actos del D\u00eda Europeo de la M\u00fasica que se celebrar\u00e1 el pr\u00f3ximo s\u00e1bado, d\u00eda 21, ha anunciado hoy la alcaldesa de la capital, Ana Botella. La alcaldesa ha descubierto hoy una placa conmemorativa en el n\u00famero 17 de la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6373334w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\\\/#article\",\"name\":\"Madrid rendir\\u00e1 homenaje a Paco de Luc\\u00eda en el D\\u00eda de la M\\u00fasica este s\\u00e1bado | El Digital de Asturias\",\"headline\":\"Madrid rendir\\u00e1 homenaje a Paco de Luc\\u00eda en el D\\u00eda de la M\\u00fasica este s\\u00e1bado\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6373334w.jpg\",\"width\":800,\"height\":578},\"datePublished\":\"2014-06-16T16:52:45+02:00\",\"dateModified\":\"2014-06-16T16:52:45+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\\\/#listItem\",\"name\":\"Madrid rendir\\u00e1 homenaje a Paco de Luc\\u00eda en el D\\u00eda de la M\\u00fasica este s\\u00e1bado\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\\\/#listItem\",\"position\":3,\"name\":\"Madrid rendir\\u00e1 homenaje a Paco de Luc\\u00eda en el D\\u00eda de la M\\u00fasica este s\\u00e1bado\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\\\/\",\"name\":\"Madrid rendir\\u00e1 homenaje a Paco de Luc\\u00eda en el D\\u00eda de la M\\u00fasica este s\\u00e1bado | El Digital de Asturias\",\"description\":\"Madrid, 16 jun (EFE).- La ciudad de Madrid rendir\\u00e1 homenaje a Paco de Luc\\u00eda durante los actos del D\\u00eda Europeo de la M\\u00fasica que se celebrar\\u00e1 el pr\\u00f3ximo s\\u00e1bado, d\\u00eda 21, ha anunciado hoy la alcaldesa de la capital, Ana Botella. La alcaldesa ha descubierto hoy una placa conmemorativa en el n\\u00famero 17 de la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6373334w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\\\/#mainImage\",\"width\":800,\"height\":578},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\\\/#mainImage\"},\"datePublished\":\"2014-06-16T16:52:45+02:00\",\"dateModified\":\"2014-06-16T16:52:45+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda en el D\u00eda de la M\u00fasica este s\u00e1bado | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda en el D\u00eda de la M\u00fasica este s\u00e1bado | El Digital de Asturias","description":"Madrid, 16 jun (EFE).- La ciudad de Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda durante los actos del D\u00eda Europeo de la M\u00fasica que se celebrar\u00e1 el pr\u00f3ximo s\u00e1bado, d\u00eda 21, ha anunciado hoy la alcaldesa de la capital, Ana Botella. La alcaldesa ha descubierto hoy una placa conmemorativa en el n\u00famero 17 de la","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/#article","name":"Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda en el D\u00eda de la M\u00fasica este s\u00e1bado | El Digital de Asturias","headline":"Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda en el D\u00eda de la M\u00fasica este s\u00e1bado","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6373334w.jpg","width":800,"height":578},"datePublished":"2014-06-16T16:52:45+02:00","dateModified":"2014-06-16T16:52:45+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/#listItem","name":"Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda en el D\u00eda de la M\u00fasica este s\u00e1bado"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/#listItem","position":3,"name":"Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda en el D\u00eda de la M\u00fasica este s\u00e1bado","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/","name":"Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda en el D\u00eda de la M\u00fasica este s\u00e1bado | El Digital de Asturias","description":"Madrid, 16 jun (EFE).- La ciudad de Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda durante los actos del D\u00eda Europeo de la M\u00fasica que se celebrar\u00e1 el pr\u00f3ximo s\u00e1bado, d\u00eda 21, ha anunciado hoy la alcaldesa de la capital, Ana Botella. La alcaldesa ha descubierto hoy una placa conmemorativa en el n\u00famero 17 de la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6373334w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/#mainImage","width":800,"height":578},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/#mainImage"},"datePublished":"2014-06-16T16:52:45+02:00","dateModified":"2014-06-16T16:52:45+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda en el D\u00eda de la M\u00fasica este s\u00e1bado | El Digital de Asturias","og:description":"Madrid, 16 jun (EFE).- La ciudad de Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda durante los actos del D\u00eda Europeo de la M\u00fasica que se celebrar\u00e1 el pr\u00f3ximo s\u00e1bado, d\u00eda 21, ha anunciado hoy la alcaldesa de la capital, Ana Botella. La alcaldesa ha descubierto hoy una placa conmemorativa en el n\u00famero 17 de la","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6373334w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6373334w.jpg","og:image:width":800,"og:image:height":578,"article:published_time":"2014-06-16T18:52:45+00:00","article:modified_time":"2014-06-16T18:52:45+00:00","twitter:card":"summary_large_image","twitter:title":"Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda en el D\u00eda de la M\u00fasica este s\u00e1bado | El Digital de Asturias","twitter:description":"Madrid, 16 jun (EFE).- La ciudad de Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda durante los actos del D\u00eda Europeo de la M\u00fasica que se celebrar\u00e1 el pr\u00f3ximo s\u00e1bado, d\u00eda 21, ha anunciado hoy la alcaldesa de la capital, Ana Botella. La alcaldesa ha descubierto hoy una placa conmemorativa en el n\u00famero 17 de la","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6373334w.jpg"},"aioseo_meta_data":{"post_id":"16132","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 13:58:46","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 07:51:46","updated":"2026-05-16 13:58:46"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/\" title=\"Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda en el D\u00eda de la M\u00fasica este s\u00e1bado\">Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda en el D\u00eda de la M\u00fasica este s\u00e1bado<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Madrid rendir\u00e1 homenaje a Paco de Luc\u00eda en el D\u00eda de la M\u00fasica este s\u00e1bado","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/madrid-rendira-homenaje-a-paco-de-lucia-en-el-dia-de-la-musica-este-sabado\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/16132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=16132"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/16132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/16133"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=16132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=16132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=16132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}