{"id":16084,"date":"2014-06-15T18:48:28","date_gmt":"2014-06-15T20:48:28","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=16084"},"modified":"2014-06-15T18:48:28","modified_gmt":"2014-06-15T20:48:28","slug":"rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/","title":{"rendered":"Rosana afirma que una canci\u00f3n \u00abno se termina hasta que no se comparte\u00bb"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-16085\" alt=\"6370360w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370360w-360x235.jpg\" width=\"360\" height=\"235\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370360w-360x235.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370360w-650x425.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370360w-768x502.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370360w-150x98.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370360w-450x294.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370360w-696x455.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370360w-741x486.jpg 741w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370360w-642x420.jpg 642w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370360w-84x55.jpg 84w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370360w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Miami (EE.UU.), 15 jun (EFE).- La cantautora espa\u00f1ola Rosana Arbel\u00f3 se\u00f1al\u00f3 que la m\u00fasica \u00abes un punto de encuentro con el mundo\u00bb y en ese sentido el proceso de creaci\u00f3n de una composici\u00f3n \u00abno se termina hasta que no se comparte\u00bb.<\/p>\n<p>De visita en la ciudad de Miami, donde promocion\u00f3 su m\u00e1s reciente lanzamiento discogr\u00e1fico, \u00ab8 Lunas\u00bb, la int\u00e9rprete se\u00f1al\u00f3 en una entrevista con Efe que el camino que ha transitado a lo largo de sus 17 a\u00f1os de trayectoria musical ha sido satisfactorio y lo ha hecho \u00abcon tranquilidad, con honestidad y sin prisa\u00bb.<\/p>\n<p>\u00abMi m\u00fasica es un cord\u00f3n umbilical con la humanidad. Me resultar\u00eda muy complicado comunicarme de otra manera\u00bb, confes\u00f3 la cantante, originaria de Lanzarote, en las Islas Canarias, y compositora de \u00e9xitos como \u00abEl Talism\u00e1n\u00bb, \u00abSin miedo\u00bb y \u00abSi t\u00fa no est\u00e1s aqu\u00ed\u00bb.<\/p>\n<p>Sobre su m\u00e1s reciente disco, el octavo de su carrera y en el que reversiona temas de su repertorio al lado de diversas voces de la m\u00fasica iberoamericana, Rosana neg\u00f3 que el \u00e1lbum se trate de una recopilaci\u00f3n de grandes \u00e9xitos interpretados a d\u00fao.<\/p>\n<p>Se\u00f1al\u00f3 que la premisa para elaborar el disco consisti\u00f3 en hacer cada canci\u00f3n de manera diferente y que ello la llevara \u00abhasta otra voz\u00bb, una v\u00eda para elegir a la lista de colaboradores, entre los que figuran Rub\u00e9n Blades, Andr\u00e9s Cepeda y Dani Mart\u00edn.<\/p>\n<p>\u00abLas canciones en ese \u00e1lbum se convirtieron en trajes a medida, para los invitados, y la finalidad era esa. Que el invitado\/invitada se sintiera c\u00f3modo en la habitaci\u00f3n donde se iba a hospedar. Yo ya fui la princesa del cuento en cada canci\u00f3n, necesitaban un alma nueva\u00bb, explic\u00f3.<\/p>\n<p>La compositora, nominada en 2012 al Premio Grammy Latino y con varios galardones en su haber, afirm\u00f3 que hoy en d\u00eda se observa mucha tristeza y una suerte de \u00abpandemia de desesperanza\u00bb, la cual propicia mucho enfado entre las personas.<\/p>\n<p>\u00abSi todos fu\u00e9ramos conscientes de que la vida no es tan larga ni el mundo es tan grande, pues probablemente vivir\u00edamos de otra manera y ese vivir de otra manera probablemente nos traer\u00eda much\u00edsima m\u00e1s paz\u00bb, reflexion\u00f3.<\/p>\n<p>Pr\u00f3xima a cumplir 51 a\u00f1os de edad, el 24 de octubre, y con m\u00e1s de 10 millones de discos vendido durante su carrera, Rosana se encuentra en un momento de su vida en el que valora m\u00e1s aspectos como \u00abocho segundos de la sonrisa de alguien que ocho d\u00edas de aplausos\u00bb.<\/p>\n<p>Rosana Arbel\u00f3 ofrecer\u00e1 un concierto la pr\u00f3xima semana en Ciudad de M\u00e9xico, tras lo cual tiene prevista una extensa gira por Argentina durante julio y agosto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miami (EE.UU.), 15 jun (EFE).- La cantautora espa\u00f1ola Rosana Arbel\u00f3 se\u00f1al\u00f3 que la m\u00fasica \u00abes un punto de encuentro con el mundo\u00bb y en ese sentido el proceso de creaci\u00f3n de una composici\u00f3n \u00abno se termina hasta que no se comparte\u00bb. De visita en la ciudad de Miami, donde promocion\u00f3 su m\u00e1s reciente lanzamiento discogr\u00e1fico,<\/p>\n","protected":false},"author":1,"featured_media":16085,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-16084","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Miami (EE.UU.), 15 jun (EFE).- La cantautora espa\u00f1ola Rosana Arbel\u00f3 se\u00f1al\u00f3 que la m\u00fasica &quot;es un punto de encuentro con el mundo&quot; y en ese sentido el proceso de creaci\u00f3n de una composici\u00f3n &quot;no se termina hasta que no se comparte&quot;. De visita en la ciudad de Miami, donde promocion\u00f3 su m\u00e1s reciente lanzamiento discogr\u00e1fico,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Rosana afirma que una canci\u00f3n \u00abno se termina hasta que no se comparte\u00bb | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Miami (EE.UU.), 15 jun (EFE).- La cantautora espa\u00f1ola Rosana Arbel\u00f3 se\u00f1al\u00f3 que la m\u00fasica &quot;es un punto de encuentro con el mundo&quot; y en ese sentido el proceso de creaci\u00f3n de una composici\u00f3n &quot;no se termina hasta que no se comparte&quot;. De visita en la ciudad de Miami, donde promocion\u00f3 su m\u00e1s reciente lanzamiento discogr\u00e1fico,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370360w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370360w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"523\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-15T20:48:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-15T20:48:28+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Rosana afirma que una canci\u00f3n \u00abno se termina hasta que no se comparte\u00bb | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Miami (EE.UU.), 15 jun (EFE).- La cantautora espa\u00f1ola Rosana Arbel\u00f3 se\u00f1al\u00f3 que la m\u00fasica &quot;es un punto de encuentro con el mundo&quot; y en ese sentido el proceso de creaci\u00f3n de una composici\u00f3n &quot;no se termina hasta que no se comparte&quot;. De visita en la ciudad de Miami, donde promocion\u00f3 su m\u00e1s reciente lanzamiento discogr\u00e1fico,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370360w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\\\/#article\",\"name\":\"Rosana afirma que una canci\\u00f3n \\u00abno se termina hasta que no se comparte\\u00bb | El Digital de Asturias\",\"headline\":\"Rosana afirma que una canci\\u00f3n \\u00abno se termina hasta que no se comparte\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6370360w.jpg\",\"width\":800,\"height\":523},\"datePublished\":\"2014-06-15T18:48:28+02:00\",\"dateModified\":\"2014-06-15T18:48:28+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\\\/#listItem\",\"name\":\"Rosana afirma que una canci\\u00f3n \\u00abno se termina hasta que no se comparte\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\\\/#listItem\",\"position\":3,\"name\":\"Rosana afirma que una canci\\u00f3n \\u00abno se termina hasta que no se comparte\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\\\/\",\"name\":\"Rosana afirma que una canci\\u00f3n \\u00abno se termina hasta que no se comparte\\u00bb | El Digital de Asturias\",\"description\":\"Miami (EE.UU.), 15 jun (EFE).- La cantautora espa\\u00f1ola Rosana Arbel\\u00f3 se\\u00f1al\\u00f3 que la m\\u00fasica \\\"es un punto de encuentro con el mundo\\\" y en ese sentido el proceso de creaci\\u00f3n de una composici\\u00f3n \\\"no se termina hasta que no se comparte\\\". De visita en la ciudad de Miami, donde promocion\\u00f3 su m\\u00e1s reciente lanzamiento discogr\\u00e1fico,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6370360w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\\\/#mainImage\",\"width\":800,\"height\":523},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\\\/#mainImage\"},\"datePublished\":\"2014-06-15T18:48:28+02:00\",\"dateModified\":\"2014-06-15T18:48:28+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Rosana afirma que una canci\u00f3n \u00abno se termina hasta que no se comparte\u00bb | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Rosana afirma que una canci\u00f3n \u00abno se termina hasta que no se comparte\u00bb | El Digital de Asturias","description":"Miami (EE.UU.), 15 jun (EFE).- La cantautora espa\u00f1ola Rosana Arbel\u00f3 se\u00f1al\u00f3 que la m\u00fasica \"es un punto de encuentro con el mundo\" y en ese sentido el proceso de creaci\u00f3n de una composici\u00f3n \"no se termina hasta que no se comparte\". De visita en la ciudad de Miami, donde promocion\u00f3 su m\u00e1s reciente lanzamiento discogr\u00e1fico,","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/#article","name":"Rosana afirma que una canci\u00f3n \u00abno se termina hasta que no se comparte\u00bb | El Digital de Asturias","headline":"Rosana afirma que una canci\u00f3n \u00abno se termina hasta que no se comparte\u00bb","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370360w.jpg","width":800,"height":523},"datePublished":"2014-06-15T18:48:28+02:00","dateModified":"2014-06-15T18:48:28+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/#listItem","name":"Rosana afirma que una canci\u00f3n \u00abno se termina hasta que no se comparte\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/#listItem","position":3,"name":"Rosana afirma que una canci\u00f3n \u00abno se termina hasta que no se comparte\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/","name":"Rosana afirma que una canci\u00f3n \u00abno se termina hasta que no se comparte\u00bb | El Digital de Asturias","description":"Miami (EE.UU.), 15 jun (EFE).- La cantautora espa\u00f1ola Rosana Arbel\u00f3 se\u00f1al\u00f3 que la m\u00fasica \"es un punto de encuentro con el mundo\" y en ese sentido el proceso de creaci\u00f3n de una composici\u00f3n \"no se termina hasta que no se comparte\". De visita en la ciudad de Miami, donde promocion\u00f3 su m\u00e1s reciente lanzamiento discogr\u00e1fico,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370360w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/#mainImage","width":800,"height":523},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/#mainImage"},"datePublished":"2014-06-15T18:48:28+02:00","dateModified":"2014-06-15T18:48:28+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Rosana afirma que una canci\u00f3n \u00abno se termina hasta que no se comparte\u00bb | El Digital de Asturias","og:description":"Miami (EE.UU.), 15 jun (EFE).- La cantautora espa\u00f1ola Rosana Arbel\u00f3 se\u00f1al\u00f3 que la m\u00fasica &quot;es un punto de encuentro con el mundo&quot; y en ese sentido el proceso de creaci\u00f3n de una composici\u00f3n &quot;no se termina hasta que no se comparte&quot;. De visita en la ciudad de Miami, donde promocion\u00f3 su m\u00e1s reciente lanzamiento discogr\u00e1fico,","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370360w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370360w.jpg","og:image:width":800,"og:image:height":523,"article:published_time":"2014-06-15T20:48:28+00:00","article:modified_time":"2014-06-15T20:48:28+00:00","twitter:card":"summary_large_image","twitter:title":"Rosana afirma que una canci\u00f3n \u00abno se termina hasta que no se comparte\u00bb | El Digital de Asturias","twitter:description":"Miami (EE.UU.), 15 jun (EFE).- La cantautora espa\u00f1ola Rosana Arbel\u00f3 se\u00f1al\u00f3 que la m\u00fasica &quot;es un punto de encuentro con el mundo&quot; y en ese sentido el proceso de creaci\u00f3n de una composici\u00f3n &quot;no se termina hasta que no se comparte&quot;. De visita en la ciudad de Miami, donde promocion\u00f3 su m\u00e1s reciente lanzamiento discogr\u00e1fico,","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370360w.jpg"},"aioseo_meta_data":{"post_id":"16084","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 13:52:10","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 07:53:07","updated":"2026-05-16 13:52:10"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/\" title=\"Rosana afirma que una canci\u00f3n \u00abno se termina hasta que no se comparte\u00bb\">Rosana afirma que una canci\u00f3n \u00abno se termina hasta que no se comparte\u00bb<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Rosana afirma que una canci\u00f3n \u00abno se termina hasta que no se comparte\u00bb","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/rosana-afirma-que-una-cancion-no-se-termina-hasta-que-no-se-comparte\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/16084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=16084"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/16084\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/16085"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=16084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=16084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=16084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}