{"id":16071,"date":"2014-06-15T18:02:32","date_gmt":"2014-06-15T20:02:32","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=16071"},"modified":"2014-06-15T18:02:32","modified_gmt":"2014-06-15T20:02:32","slug":"creado-el-primer-inventario-espanol-de-la-dieta-mediterranea","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/","title":{"rendered":"Creado el primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-16072\" alt=\"6370099w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370099w-360x247.jpg\" width=\"360\" height=\"247\" \/>Barcelona, 15 jun (EFE).- El primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea, impulsado por la especialista Anna Bach, pretende salvaguardar todos los aspectos y manifestaciones sociales que conforman la dieta mediterr\u00e1nea en el territorio espa\u00f1ol, reconocida por la Unesco Patrimonio Inmaterial de la Humanidad.<\/p>\n<p>El proyecto, que ha sido coordinado por la Fundaci\u00f3n Dieta Mediterr\u00e1nea, se inici\u00f3 como proyecto piloto financiado por el Ministerio de Cultura, y ha contado con la participaci\u00f3n de las comunidades aut\u00f3nomas de Andaluc\u00eda, Castilla La Mancha, Castilla y Le\u00f3n, Catalu\u00f1a y Murcia, alcance territorial que, seg\u00fan han explicado sus responsables, pretenden ampliar en futuras ediciones.<\/p>\n<p>El inventario informa acerca del paisaje, de las actividades agr\u00edcolas, ganaderas y pesqueras; del conocimiento y patrimonio gastron\u00f3mico, y de las principales ferias y fiestas relacionadas con la Dieta Mediterr\u00e1nea en los territorios implicados.<\/p>\n<p>Este gran registro documental informa y contribuye a potenciar el conocimiento de la Dieta Mediterr\u00e1nea, que la Unesco incluy\u00f3 en la Lista Representativa del Patrimonio Cultural Inmaterial.<\/p>\n<p>Con este Inventario, se pretende potenciar la comunicaci\u00f3n intercultural entre las comunidades aut\u00f3nomas y su sociedad civil, as\u00ed como dar a conocer a nivel intergeneracional la riqueza de los pueblos del Mediterr\u00e1neo y contribuir a la concienciaci\u00f3n y puesta en valor de la dieta mediterr\u00e1nea.<\/p>\n<p>El inventario se puede consultar en la p\u00e1gina web www.inventariodeladietamediterranea.com.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Barcelona, 15 jun (EFE).- El primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea, impulsado por la especialista Anna Bach, pretende salvaguardar todos los aspectos y manifestaciones sociales que conforman la dieta mediterr\u00e1nea en el territorio espa\u00f1ol, reconocida por la Unesco Patrimonio Inmaterial de la Humanidad. El proyecto, que ha sido coordinado por la Fundaci\u00f3n Dieta Mediterr\u00e1nea,<\/p>\n","protected":false},"author":1,"featured_media":16072,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-16071","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Barcelona, 15 jun (EFE).- El primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea, impulsado por la especialista Anna Bach, pretende salvaguardar todos los aspectos y manifestaciones sociales que conforman la dieta mediterr\u00e1nea en el territorio espa\u00f1ol, reconocida por la Unesco Patrimonio Inmaterial de la Humanidad. El proyecto, que ha sido coordinado por la Fundaci\u00f3n Dieta Mediterr\u00e1nea,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Creado el primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Barcelona, 15 jun (EFE).- El primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea, impulsado por la especialista Anna Bach, pretende salvaguardar todos los aspectos y manifestaciones sociales que conforman la dieta mediterr\u00e1nea en el territorio espa\u00f1ol, reconocida por la Unesco Patrimonio Inmaterial de la Humanidad. El proyecto, que ha sido coordinado por la Fundaci\u00f3n Dieta Mediterr\u00e1nea,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370099w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370099w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"551\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-15T20:02:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-15T20:02:32+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Creado el primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Barcelona, 15 jun (EFE).- El primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea, impulsado por la especialista Anna Bach, pretende salvaguardar todos los aspectos y manifestaciones sociales que conforman la dieta mediterr\u00e1nea en el territorio espa\u00f1ol, reconocida por la Unesco Patrimonio Inmaterial de la Humanidad. El proyecto, que ha sido coordinado por la Fundaci\u00f3n Dieta Mediterr\u00e1nea,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370099w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\\\/#article\",\"name\":\"Creado el primer inventario espa\\u00f1ol de la dieta mediterr\\u00e1nea | El Digital de Asturias\",\"headline\":\"Creado el primer inventario espa\\u00f1ol de la dieta mediterr\\u00e1nea\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6370099w.jpg\",\"width\":800,\"height\":551},\"datePublished\":\"2014-06-15T18:02:32+02:00\",\"dateModified\":\"2014-06-15T18:02:32+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\\\/#listItem\",\"name\":\"Creado el primer inventario espa\\u00f1ol de la dieta mediterr\\u00e1nea\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\\\/#listItem\",\"position\":3,\"name\":\"Creado el primer inventario espa\\u00f1ol de la dieta mediterr\\u00e1nea\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\\\/\",\"name\":\"Creado el primer inventario espa\\u00f1ol de la dieta mediterr\\u00e1nea | El Digital de Asturias\",\"description\":\"Barcelona, 15 jun (EFE).- El primer inventario espa\\u00f1ol de la dieta mediterr\\u00e1nea, impulsado por la especialista Anna Bach, pretende salvaguardar todos los aspectos y manifestaciones sociales que conforman la dieta mediterr\\u00e1nea en el territorio espa\\u00f1ol, reconocida por la Unesco Patrimonio Inmaterial de la Humanidad. El proyecto, que ha sido coordinado por la Fundaci\\u00f3n Dieta Mediterr\\u00e1nea,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6370099w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\\\/#mainImage\",\"width\":800,\"height\":551},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\\\/#mainImage\"},\"datePublished\":\"2014-06-15T18:02:32+02:00\",\"dateModified\":\"2014-06-15T18:02:32+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Creado el primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Creado el primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea | El Digital de Asturias","description":"Barcelona, 15 jun (EFE).- El primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea, impulsado por la especialista Anna Bach, pretende salvaguardar todos los aspectos y manifestaciones sociales que conforman la dieta mediterr\u00e1nea en el territorio espa\u00f1ol, reconocida por la Unesco Patrimonio Inmaterial de la Humanidad. El proyecto, que ha sido coordinado por la Fundaci\u00f3n Dieta Mediterr\u00e1nea,","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/#article","name":"Creado el primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea | El Digital de Asturias","headline":"Creado el primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370099w.jpg","width":800,"height":551},"datePublished":"2014-06-15T18:02:32+02:00","dateModified":"2014-06-15T18:02:32+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/#listItem","name":"Creado el primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/#listItem","position":3,"name":"Creado el primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/","name":"Creado el primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea | El Digital de Asturias","description":"Barcelona, 15 jun (EFE).- El primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea, impulsado por la especialista Anna Bach, pretende salvaguardar todos los aspectos y manifestaciones sociales que conforman la dieta mediterr\u00e1nea en el territorio espa\u00f1ol, reconocida por la Unesco Patrimonio Inmaterial de la Humanidad. El proyecto, que ha sido coordinado por la Fundaci\u00f3n Dieta Mediterr\u00e1nea,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370099w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/#mainImage","width":800,"height":551},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/#mainImage"},"datePublished":"2014-06-15T18:02:32+02:00","dateModified":"2014-06-15T18:02:32+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Creado el primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea | El Digital de Asturias","og:description":"Barcelona, 15 jun (EFE).- El primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea, impulsado por la especialista Anna Bach, pretende salvaguardar todos los aspectos y manifestaciones sociales que conforman la dieta mediterr\u00e1nea en el territorio espa\u00f1ol, reconocida por la Unesco Patrimonio Inmaterial de la Humanidad. El proyecto, que ha sido coordinado por la Fundaci\u00f3n Dieta Mediterr\u00e1nea,","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370099w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370099w.jpg","og:image:width":800,"og:image:height":551,"article:published_time":"2014-06-15T20:02:32+00:00","article:modified_time":"2014-06-15T20:02:32+00:00","twitter:card":"summary_large_image","twitter:title":"Creado el primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea | El Digital de Asturias","twitter:description":"Barcelona, 15 jun (EFE).- El primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea, impulsado por la especialista Anna Bach, pretende salvaguardar todos los aspectos y manifestaciones sociales que conforman la dieta mediterr\u00e1nea en el territorio espa\u00f1ol, reconocida por la Unesco Patrimonio Inmaterial de la Humanidad. El proyecto, que ha sido coordinado por la Fundaci\u00f3n Dieta Mediterr\u00e1nea,","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6370099w.jpg"},"aioseo_meta_data":{"post_id":"16071","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 13:52:02","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 07:53:07","updated":"2026-05-16 13:52:02"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/\" title=\"Creado el primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea\">Creado el primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Creado el primer inventario espa\u00f1ol de la dieta mediterr\u00e1nea","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/creado-el-primer-inventario-espanol-de-la-dieta-mediterranea\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/16071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=16071"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/16071\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/16072"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=16071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=16071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=16071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}