{"id":15933,"date":"2014-06-13T18:54:34","date_gmt":"2014-06-13T20:54:34","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=15933"},"modified":"2014-06-13T18:54:34","modified_gmt":"2014-06-13T20:54:34","slug":"el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/","title":{"rendered":"El Gobierno regula los medicamentos de terapia avanzada o celular"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-15934\" alt=\"6365631w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6365631w-360x239.jpg\" width=\"360\" height=\"239\" \/>Madrid, 13 jun (EFE).- El Gobierno ha regulado la autorizaci\u00f3n de medicamentos de terapia avanzada (curar con c\u00e9lulas) de fabricaci\u00f3n no industrial que comprenden los de terapia g\u00e9nica, celular som\u00e1tica, los productos de ingenier\u00eda tisular y los f\u00e1rmacos combinados de terapia avanzada.<\/p>\n<p>El Consejo de Ministros ha aprobado hoy, a propuesta de la ministra de Sanidad, Servicios Sociales e Igualdad, Ana Mato, el real decreto por el que se regulan estos productos.<\/p>\n<p>Se trata de la norma que recoge los requisitos y garant\u00edas que deben cumplir para obtener la autorizaci\u00f3n de uso por la Agencia Espa\u00f1ola de Medicamentos y Productos Sanitarios (AEMPS), as\u00ed como los requisitos de trazabilidad y farmacovigilancia una vez permitidos.<\/p>\n<p>De acuerdo con la legislaci\u00f3n europea, seg\u00fan ha informado Sanidad, los medicamentos de terapia avanzada de producci\u00f3n industrial tienen que ser autorizados mediante un procedimiento de evaluaci\u00f3n centralizado que, tras opini\u00f3n positiva por parte de la Agencia Europea de Medicamentos (EMA), da lugar a un permiso por parte de la Comisi\u00f3n Europea que es v\u00e1lido para toda la UE.<\/p>\n<p>Sin embargo, la regulaci\u00f3n establece una excepci\u00f3n para los medicamentos de terapia avanzada que no son objeto de una producci\u00f3n industrial.<\/p>\n<p>Se excluyen as\u00ed los preparados ocasionalmente, de acuerdo con normas de calidad espec\u00edficas, y empleados en un mismo Estado miembro, en un hospital y bajo la responsabilidad profesional exclusiva de un m\u00e9dico colegiado, con el fin de cumplir una prescripci\u00f3n facultativa \u00abindividual de un producto hecho a medida destinado a un solo paciente\u00bb.<\/p>\n<p>De este modo quedan sujetos a la autorizaci\u00f3n de las autoridades competentes del Estado miembro, quienes deben asegurarse de que la trazabilidad nacional y los requisitos de farmacovigilancia as\u00ed como las normas de calidad espec\u00edficas aplicables son equivalentes a los previstos a escala comunitaria.<\/p>\n<p>En el real decreto aprobado hoy se establecen los requisitos y garant\u00edas de calidad, seguridad y eficacia que deben cumplir para poder ser autorizado su uso por la AEMPS.<\/p>\n<p>Seg\u00fan la nueva normativa, todo medicamento de terapia avanzada ir\u00e1 acompa\u00f1ado de la suficiente informaci\u00f3n dirigida al paciente o usuario.<\/p>\n<p>Dicha informaci\u00f3n formar\u00e1 parte de la autorizaci\u00f3n de uso y deber\u00e1 ser \u00ablegible y clara\u00bb, asegurando su comprensi\u00f3n por el paciente y reduciendo \u00abal m\u00ednimo\u00bb los t\u00e9rminos de naturaleza t\u00e9cnica.<\/p>\n<p>La documentaci\u00f3n se podr\u00e1 adaptar a las particularidades que concurran en un tratamiento espec\u00edfico con medicamentos de terapia avanzada.<\/p>\n<p>Como norma general, el documento de informaci\u00f3n destinado al enfermo deber\u00e1 formar parte del consentimiento informado que cada hospital tenga homologado por su Comit\u00e9 de \u00c9tica Asistencial para cada uno de los procedimientos en los que se administre el f\u00e1rmaco.<\/p>\n<p>La autorizaci\u00f3n tendr\u00e1 una validez inicial de tres a\u00f1os y podr\u00e1 ser renovada peri\u00f3dicamente, con una validez de cinco a\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 13 jun (EFE).- El Gobierno ha regulado la autorizaci\u00f3n de medicamentos de terapia avanzada (curar con c\u00e9lulas) de fabricaci\u00f3n no industrial que comprenden los de terapia g\u00e9nica, celular som\u00e1tica, los productos de ingenier\u00eda tisular y los f\u00e1rmacos combinados de terapia avanzada. El Consejo de Ministros ha aprobado hoy, a propuesta de la ministra de<\/p>\n","protected":false},"author":1,"featured_media":15934,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-15933","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 13 jun (EFE).- El Gobierno ha regulado la autorizaci\u00f3n de medicamentos de terapia avanzada (curar con c\u00e9lulas) de fabricaci\u00f3n no industrial que comprenden los de terapia g\u00e9nica, celular som\u00e1tica, los productos de ingenier\u00eda tisular y los f\u00e1rmacos combinados de terapia avanzada. El Consejo de Ministros ha aprobado hoy, a propuesta de la ministra de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Gobierno regula los medicamentos de terapia avanzada o celular | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 13 jun (EFE).- El Gobierno ha regulado la autorizaci\u00f3n de medicamentos de terapia avanzada (curar con c\u00e9lulas) de fabricaci\u00f3n no industrial que comprenden los de terapia g\u00e9nica, celular som\u00e1tica, los productos de ingenier\u00eda tisular y los f\u00e1rmacos combinados de terapia avanzada. El Consejo de Ministros ha aprobado hoy, a propuesta de la ministra de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6365631w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6365631w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-13T20:54:34+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-13T20:54:34+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Gobierno regula los medicamentos de terapia avanzada o celular | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 13 jun (EFE).- El Gobierno ha regulado la autorizaci\u00f3n de medicamentos de terapia avanzada (curar con c\u00e9lulas) de fabricaci\u00f3n no industrial que comprenden los de terapia g\u00e9nica, celular som\u00e1tica, los productos de ingenier\u00eda tisular y los f\u00e1rmacos combinados de terapia avanzada. El Consejo de Ministros ha aprobado hoy, a propuesta de la ministra de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6365631w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\\\/#article\",\"name\":\"El Gobierno regula los medicamentos de terapia avanzada o celular | El Digital de Asturias\",\"headline\":\"El Gobierno regula los medicamentos de terapia avanzada o celular\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6365631w.jpg\",\"width\":800,\"height\":533},\"datePublished\":\"2014-06-13T18:54:34+02:00\",\"dateModified\":\"2014-06-13T18:54:34+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\\\/#listItem\",\"name\":\"El Gobierno regula los medicamentos de terapia avanzada o celular\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\\\/#listItem\",\"position\":3,\"name\":\"El Gobierno regula los medicamentos de terapia avanzada o celular\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\\\/\",\"name\":\"El Gobierno regula los medicamentos de terapia avanzada o celular | El Digital de Asturias\",\"description\":\"Madrid, 13 jun (EFE).- El Gobierno ha regulado la autorizaci\\u00f3n de medicamentos de terapia avanzada (curar con c\\u00e9lulas) de fabricaci\\u00f3n no industrial que comprenden los de terapia g\\u00e9nica, celular som\\u00e1tica, los productos de ingenier\\u00eda tisular y los f\\u00e1rmacos combinados de terapia avanzada. El Consejo de Ministros ha aprobado hoy, a propuesta de la ministra de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6365631w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\\\/#mainImage\",\"width\":800,\"height\":533},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\\\/#mainImage\"},\"datePublished\":\"2014-06-13T18:54:34+02:00\",\"dateModified\":\"2014-06-13T18:54:34+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Gobierno regula los medicamentos de terapia avanzada o celular | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El Gobierno regula los medicamentos de terapia avanzada o celular | El Digital de Asturias","description":"Madrid, 13 jun (EFE).- El Gobierno ha regulado la autorizaci\u00f3n de medicamentos de terapia avanzada (curar con c\u00e9lulas) de fabricaci\u00f3n no industrial que comprenden los de terapia g\u00e9nica, celular som\u00e1tica, los productos de ingenier\u00eda tisular y los f\u00e1rmacos combinados de terapia avanzada. El Consejo de Ministros ha aprobado hoy, a propuesta de la ministra de","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/#article","name":"El Gobierno regula los medicamentos de terapia avanzada o celular | El Digital de Asturias","headline":"El Gobierno regula los medicamentos de terapia avanzada o celular","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6365631w.jpg","width":800,"height":533},"datePublished":"2014-06-13T18:54:34+02:00","dateModified":"2014-06-13T18:54:34+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/#listItem","name":"El Gobierno regula los medicamentos de terapia avanzada o celular"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/#listItem","position":3,"name":"El Gobierno regula los medicamentos de terapia avanzada o celular","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/","name":"El Gobierno regula los medicamentos de terapia avanzada o celular | El Digital de Asturias","description":"Madrid, 13 jun (EFE).- El Gobierno ha regulado la autorizaci\u00f3n de medicamentos de terapia avanzada (curar con c\u00e9lulas) de fabricaci\u00f3n no industrial que comprenden los de terapia g\u00e9nica, celular som\u00e1tica, los productos de ingenier\u00eda tisular y los f\u00e1rmacos combinados de terapia avanzada. El Consejo de Ministros ha aprobado hoy, a propuesta de la ministra de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6365631w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/#mainImage","width":800,"height":533},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/#mainImage"},"datePublished":"2014-06-13T18:54:34+02:00","dateModified":"2014-06-13T18:54:34+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"El Gobierno regula los medicamentos de terapia avanzada o celular | El Digital de Asturias","og:description":"Madrid, 13 jun (EFE).- El Gobierno ha regulado la autorizaci\u00f3n de medicamentos de terapia avanzada (curar con c\u00e9lulas) de fabricaci\u00f3n no industrial que comprenden los de terapia g\u00e9nica, celular som\u00e1tica, los productos de ingenier\u00eda tisular y los f\u00e1rmacos combinados de terapia avanzada. El Consejo de Ministros ha aprobado hoy, a propuesta de la ministra de","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6365631w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6365631w.jpg","og:image:width":800,"og:image:height":533,"article:published_time":"2014-06-13T20:54:34+00:00","article:modified_time":"2014-06-13T20:54:34+00:00","twitter:card":"summary_large_image","twitter:title":"El Gobierno regula los medicamentos de terapia avanzada o celular | El Digital de Asturias","twitter:description":"Madrid, 13 jun (EFE).- El Gobierno ha regulado la autorizaci\u00f3n de medicamentos de terapia avanzada (curar con c\u00e9lulas) de fabricaci\u00f3n no industrial que comprenden los de terapia g\u00e9nica, celular som\u00e1tica, los productos de ingenier\u00eda tisular y los f\u00e1rmacos combinados de terapia avanzada. El Consejo de Ministros ha aprobado hoy, a propuesta de la ministra de","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6365631w.jpg"},"aioseo_meta_data":{"post_id":"15933","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 13:35:19","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 07:54:41","updated":"2026-05-16 13:35:19"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/\" title=\"El Gobierno regula los medicamentos de terapia avanzada o celular\">El Gobierno regula los medicamentos de terapia avanzada o celular<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"El Gobierno regula los medicamentos de terapia avanzada o celular","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/el-gobierno-regula-los-medicamentos-de-terapia-avanzada-o-celular\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=15933"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15933\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/15934"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=15933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=15933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=15933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}