{"id":15844,"date":"2014-06-13T00:28:21","date_gmt":"2014-06-13T02:28:21","guid":{"rendered":"http:\/\/eldigitaldeasturias.com\/magazine365\/?p=15844"},"modified":"2014-06-13T00:28:21","modified_gmt":"2014-06-13T02:28:21","slug":"auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon","status":"publish","type":"post","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/","title":{"rendered":"Auser\u00f3n afronta el reto de cantar con la Sinf\u00f3nica de Castilla y Le\u00f3n"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-15845\" alt=\"6362576w\" src=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6362576w-360x240.jpg\" width=\"360\" height=\"240\" srcset=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6362576w-360x240.jpg 360w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6362576w-650x434.jpg 650w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6362576w-768x513.jpg 768w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6362576w-150x100.jpg 150w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6362576w-450x300.jpg 450w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6362576w-696x465.jpg 696w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6362576w-629x420.jpg 629w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6362576w-84x55.jpg 84w, https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6362576w.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Valladolid, 12 jun (EFE).- El cantante Santiago Auser\u00f3n, exl\u00edder de Radio Futura, ha expresado hoy que afronta como un \u00abreto\u00bb el concierto que ofrecer\u00e1 el 12 de julio junto a la Orquesta Sinf\u00f3nica de Castilla y Le\u00f3n (OSCyL), en el que interpretar\u00e1 algunas de sus canciones y de la banda que lider\u00f3 en la d\u00e9cada de 1980.<\/p>\n<p>Este recital, cuyo t\u00edtulo es \u00abVagamundo\u00bb y que se celebrar\u00e1 en Valladolid, ser\u00e1 el primero que ofrezca Santiago Auser\u00f3n (Zaragoza, 1954) junto a una orquesta sinf\u00f3nica, algo que le emociona y que asumir\u00e1 con \u00abresponsabilidad\u00bb, debido al prestigio con el que cuenta la OSCyL, ha asegurado el compositor en la rueda de prensa de presentaci\u00f3n.<\/p>\n<p>\u00abTodav\u00eda no me imagino c\u00f3mo pueden sonar mis canciones con una orquesta sinf\u00f3nica. Tengo una enorme curiosidad\u00bb, ha explicado el cantante, quien ha asegurado que esta ocasi\u00f3n es para \u00e9l como un \u00abmilagro\u00bb.<\/p>\n<p>Respecto al repertorio que interpretar\u00e1 junto a la formaci\u00f3n castellanoleonesa, ha explicado que fue el encargado de dirigir a la orquesta en el concierto, Ricardo Casero, el que le propuso algunas de sus canciones y que \u00e9l mismo cerr\u00f3 la lista de temas.<\/p>\n<p>Algunas de las piezas que formar\u00e1n parte del concierto las ha elegido por su complejidad, otras por su sencillez y no faltar\u00e1n letras que han ganado \u00abestabilidad\u00bb con el paso del tiempo, ha indicado el cantante, que tras la desaparici\u00f3n de Radio Futura inici\u00f3 en 1993 su carrera en solitario bajo el nombre art\u00edstico de Juan Perro.<\/p>\n<p>El compositor ha calificado la iniciativa como \u00abvaliente\u00bb y ha indicado que espera que sirva para hacer otras cosas similares aunque \u00e9l no sea el protagonista.<\/p>\n<p>Auser\u00f3n ha explicado que se ha interesado por la composici\u00f3n de la OSCyL y ha recordado que anteriormente este tipo de formaciones musicales incorporaban muchos artistas extranjeros de gran nivel.<\/p>\n<p>\u00abAhora en la OSCyL la mayor parte de los componentes son espa\u00f1oles, j\u00f3venes y muy preparados, algo que empiezo a ver tambi\u00e9n en otros conjuntos\u00bb, ha asegurado.<\/p>\n<p>Adem\u00e1s, ha destacado la presencia de \u00abgrandes\u00bb y \u00abj\u00f3venes\u00bb m\u00fasicos improvisadores en el \u00e1mbito del jazz y del flamenco, que es \u00ababsolutamente prometedor para este pa\u00eds\u00bb, ha opinado.<\/p>\n<p>Preguntado por sus inicios en el mundo de la m\u00fasica, ha asegurado que en su generaci\u00f3n \u00abla curiosidad musical era polivalente\u00bb, ya que eran \u00abrockeros con oreja abierta a diferentes tipos de m\u00fasica\u00bb.<\/p>\n<p>\u00abSin embargo, ha tenido que pasar el tiempo para aprender a o\u00edr a los cl\u00e1sicos\u00bb, ha explicado el int\u00e9rprete, que ha opinado que \u00aben la m\u00fasica uno puede empezar por donde quiera\u00bb, pero tiene que pasar \u00abl\u00f3gicamente\u00bb por los cl\u00e1sicos, porque as\u00ed \u00ablo pide el aprendizaje de las sonoridades\u00bb.<\/p>\n<p>El director de pol\u00edticas culturales de la Junta de Castilla y Le\u00f3n, Jos\u00e9 Ram\u00f3n Alonso, ha explicado que \u00abVagamundo\u00bb es el sexto concierto extraordinario de la OSCyL en esta temporada tras otros como \u00abM\u00fasica de cine\u00bb, el dedicado a \u00abLas Edades del Hombre\u00bb, o el protagonizado por el guitarrista Vicente Amigo y titulado \u00abPoeta: Marinero en Tierra\u00bb, dedicado a Rafael Alberti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Valladolid, 12 jun (EFE).- El cantante Santiago Auser\u00f3n, exl\u00edder de Radio Futura, ha expresado hoy que afronta como un \u00abreto\u00bb el concierto que ofrecer\u00e1 el 12 de julio junto a la Orquesta Sinf\u00f3nica de Castilla y Le\u00f3n (OSCyL), en el que interpretar\u00e1 algunas de sus canciones y de la banda que lider\u00f3 en la d\u00e9cada<\/p>\n","protected":false},"author":1,"featured_media":15845,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-15844","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Valladolid, 12 jun (EFE).- El cantante Santiago Auser\u00f3n, exl\u00edder de Radio Futura, ha expresado hoy que afronta como un &quot;reto&quot; el concierto que ofrecer\u00e1 el 12 de julio junto a la Orquesta Sinf\u00f3nica de Castilla y Le\u00f3n (OSCyL), en el que interpretar\u00e1 algunas de sus canciones y de la banda que lider\u00f3 en la d\u00e9cada\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"keywords\" content=\"noticias y actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Auser\u00f3n afronta el reto de cantar con la Sinf\u00f3nica de Castilla y Le\u00f3n | El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Valladolid, 12 jun (EFE).- El cantante Santiago Auser\u00f3n, exl\u00edder de Radio Futura, ha expresado hoy que afronta como un &quot;reto&quot; el concierto que ofrecer\u00e1 el 12 de julio junto a la Orquesta Sinf\u00f3nica de Castilla y Le\u00f3n (OSCyL), en el que interpretar\u00e1 algunas de sus canciones y de la banda que lider\u00f3 en la d\u00e9cada\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6362576w.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6362576w.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-13T02:28:21+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-13T02:28:21+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Auser\u00f3n afronta el reto de cantar con la Sinf\u00f3nica de Castilla y Le\u00f3n | El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Valladolid, 12 jun (EFE).- El cantante Santiago Auser\u00f3n, exl\u00edder de Radio Futura, ha expresado hoy que afronta como un &quot;reto&quot; el concierto que ofrecer\u00e1 el 12 de julio junto a la Orquesta Sinf\u00f3nica de Castilla y Le\u00f3n (OSCyL), en el que interpretar\u00e1 algunas de sus canciones y de la banda que lider\u00f3 en la d\u00e9cada\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6362576w.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\\\/#article\",\"name\":\"Auser\\u00f3n afronta el reto de cantar con la Sinf\\u00f3nica de Castilla y Le\\u00f3n | El Digital de Asturias\",\"headline\":\"Auser\\u00f3n afronta el reto de cantar con la Sinf\\u00f3nica de Castilla y Le\\u00f3n\",\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6362576w.jpg\",\"width\":800,\"height\":534},\"datePublished\":\"2014-06-13T00:28:21+02:00\",\"dateModified\":\"2014-06-13T00:28:21+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\\\/#webpage\"},\"articleSection\":\"Noticias y Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"position\":2,\"name\":\"Noticias y Actualidad\",\"item\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\\\/#listItem\",\"name\":\"Auser\\u00f3n afronta el reto de cantar con la Sinf\\u00f3nica de Castilla y Le\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\\\/#listItem\",\"position\":3,\"name\":\"Auser\\u00f3n afronta el reto de cantar con la Sinf\\u00f3nica de Castilla y Le\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/category\\\/noticias-actualidad\\\/#listItem\",\"name\":\"Noticias y Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\",\"name\":\"El digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\\\/#authorImage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/litespeed\\\/avatar\\\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\\\/#webpage\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\\\/\",\"name\":\"Auser\\u00f3n afronta el reto de cantar con la Sinf\\u00f3nica de Castilla y Le\\u00f3n | El Digital de Asturias\",\"description\":\"Valladolid, 12 jun (EFE).- El cantante Santiago Auser\\u00f3n, exl\\u00edder de Radio Futura, ha expresado hoy que afronta como un \\\"reto\\\" el concierto que ofrecer\\u00e1 el 12 de julio junto a la Orquesta Sinf\\u00f3nica de Castilla y Le\\u00f3n (OSCyL), en el que interpretar\\u00e1 algunas de sus canciones y de la banda que lider\\u00f3 en la d\\u00e9cada\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/6362576w.jpg\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\\\/#mainImage\",\"width\":800,\"height\":534},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\\\/#mainImage\"},\"datePublished\":\"2014-06-13T00:28:21+02:00\",\"dateModified\":\"2014-06-13T00:28:21+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#website\",\"url\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/\",\"name\":\"El Digital de Asturias\",\"description\":\"Revista de ocio, turismo y estilo de vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldigitaldeasturias.com\\\/magazine365\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Auser\u00f3n afronta el reto de cantar con la Sinf\u00f3nica de Castilla y Le\u00f3n | El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Auser\u00f3n afronta el reto de cantar con la Sinf\u00f3nica de Castilla y Le\u00f3n | El Digital de Asturias","description":"Valladolid, 12 jun (EFE).- El cantante Santiago Auser\u00f3n, exl\u00edder de Radio Futura, ha expresado hoy que afronta como un \"reto\" el concierto que ofrecer\u00e1 el 12 de julio junto a la Orquesta Sinf\u00f3nica de Castilla y Le\u00f3n (OSCyL), en el que interpretar\u00e1 algunas de sus canciones y de la banda que lider\u00f3 en la d\u00e9cada","canonical_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/","robots":"max-image-preview:large","keywords":"noticias y actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/#article","name":"Auser\u00f3n afronta el reto de cantar con la Sinf\u00f3nica de Castilla y Le\u00f3n | El Digital de Asturias","headline":"Auser\u00f3n afronta el reto de cantar con la Sinf\u00f3nica de Castilla y Le\u00f3n","author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6362576w.jpg","width":800,"height":534},"datePublished":"2014-06-13T00:28:21+02:00","dateModified":"2014-06-13T00:28:21+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/#webpage"},"isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/#webpage"},"articleSection":"Noticias y Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","position":1,"name":"Home","item":"https:\/\/eldigitaldeasturias.com\/magazine365","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","position":2,"name":"Noticias y Actualidad","item":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/#listItem","name":"Auser\u00f3n afronta el reto de cantar con la Sinf\u00f3nica de Castilla y Le\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/#listItem","position":3,"name":"Auser\u00f3n afronta el reto de cantar con la Sinf\u00f3nica de Castilla y Le\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/#listItem","name":"Noticias y Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization","name":"El digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/#organizationLogo"},"image":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/#authorImage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/litespeed\/avatar\/e571bcf59a0edd6fa6838245a470f2fe.jpg?ver=1783622400","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/#webpage","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/","name":"Auser\u00f3n afronta el reto de cantar con la Sinf\u00f3nica de Castilla y Le\u00f3n | El Digital de Asturias","description":"Valladolid, 12 jun (EFE).- El cantante Santiago Auser\u00f3n, exl\u00edder de Radio Futura, ha expresado hoy que afronta como un \"reto\" el concierto que ofrecer\u00e1 el 12 de julio junto a la Orquesta Sinf\u00f3nica de Castilla y Le\u00f3n (OSCyL), en el que interpretar\u00e1 algunas de sus canciones y de la banda que lider\u00f3 en la d\u00e9cada","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website"},"breadcrumb":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/#breadcrumblist"},"author":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"creator":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6362576w.jpg","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/#mainImage","width":800,"height":534},"primaryImageOfPage":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/#mainImage"},"datePublished":"2014-06-13T00:28:21+02:00","dateModified":"2014-06-13T00:28:21+02:00"},{"@type":"WebSite","@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#website","url":"https:\/\/eldigitaldeasturias.com\/magazine365\/","name":"El Digital de Asturias","description":"Revista de ocio, turismo y estilo de vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldigitaldeasturias.com\/magazine365\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias \u2013 Revista de ocio, turismo y estilo de vida","og:type":"article","og:title":"Auser\u00f3n afronta el reto de cantar con la Sinf\u00f3nica de Castilla y Le\u00f3n | El Digital de Asturias","og:description":"Valladolid, 12 jun (EFE).- El cantante Santiago Auser\u00f3n, exl\u00edder de Radio Futura, ha expresado hoy que afronta como un &quot;reto&quot; el concierto que ofrecer\u00e1 el 12 de julio junto a la Orquesta Sinf\u00f3nica de Castilla y Le\u00f3n (OSCyL), en el que interpretar\u00e1 algunas de sus canciones y de la banda que lider\u00f3 en la d\u00e9cada","og:url":"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/","og:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6362576w.jpg","og:image:secure_url":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6362576w.jpg","og:image:width":800,"og:image:height":534,"article:published_time":"2014-06-13T02:28:21+00:00","article:modified_time":"2014-06-13T02:28:21+00:00","twitter:card":"summary_large_image","twitter:title":"Auser\u00f3n afronta el reto de cantar con la Sinf\u00f3nica de Castilla y Le\u00f3n | El Digital de Asturias","twitter:description":"Valladolid, 12 jun (EFE).- El cantante Santiago Auser\u00f3n, exl\u00edder de Radio Futura, ha expresado hoy que afronta como un &quot;reto&quot; el concierto que ofrecer\u00e1 el 12 de julio junto a la Orquesta Sinf\u00f3nica de Castilla y Le\u00f3n (OSCyL), en el que interpretar\u00e1 algunas de sus canciones y de la banda que lider\u00f3 en la d\u00e9cada","twitter:image":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-content\/uploads\/2014\/06\/6362576w.jpg"},"aioseo_meta_data":{"post_id":"15844","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 13:23:01","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-03-09 07:56:00","updated":"2026-05-16 13:23:01"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/\" title=\"Noticias y Actualidad\">Noticias y Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/\" title=\"Auser\u00f3n afronta el reto de cantar con la Sinf\u00f3nica de Castilla y Le\u00f3n\">Auser\u00f3n afronta el reto de cantar con la Sinf\u00f3nica de Castilla y Le\u00f3n<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldigitaldeasturias.com\/magazine365"},{"label":"Noticias y Actualidad","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/category\/noticias-actualidad\/"},{"label":"Auser\u00f3n afronta el reto de cantar con la Sinf\u00f3nica de Castilla y Le\u00f3n","link":"https:\/\/eldigitaldeasturias.com\/magazine365\/auseron-afronta-el-reto-de-cantar-con-la-sinfonica-de-castilla-y-leon\/"}],"_links":{"self":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/comments?post=15844"}],"version-history":[{"count":0,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/posts\/15844\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media\/15845"}],"wp:attachment":[{"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/media?parent=15844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/categories?post=15844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldigitaldeasturias.com\/magazine365\/wp-json\/wp\/v2\/tags?post=15844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}